{"id":359352,"date":"2024-09-17T17:39:12","date_gmt":"2024-09-17T15:39:12","guid":{"rendered":"https:\/\/weedy.fr\/blog\/?p=359352"},"modified":"2024-09-17T17:39:13","modified_gmt":"2024-09-17T15:39:13","slug":"os-beneficios-do-cbd-para-atletas-de-parkour","status":"publish","type":"post","link":"https:\/\/weedy.fr\/blog\/pt\/os-beneficios-do-cbd-para-atletas-de-parkour\/","title":{"rendered":"Os benef\u00edcios do CBD para atletas de Parkour"},"content":{"rendered":"<p>O <strong>Parkour<\/strong>, disciplina que combina a arte do movimento e a agilidade do corpo, vem ganhando popularidade nos \u00faltimos anos. Como qualquer esporte, envolve esfor\u00e7o f\u00edsico intenso e pode causar diversas dores ou les\u00f5es. Para promover a recupera\u00e7\u00e3o e melhorar o desempenho, muitos traceurs &#8211; como s\u00e3o chamados os praticantes de Parkour &#8211; que recorrem ao <strong>Canabidiol (<a href=\"https:\/\/weedy.fr\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD<\/a>)<\/strong>, uma mol\u00e9cula derivada da cannabis sem propriedades psicoativas. Neste artigo, apresentamos-lhe os benef\u00edcios do <a href=\"https:\/\/weedy.fr\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD<\/a> para tra\u00e7adores de Parkour.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/weedy.fr\/blog\/pt\/os-beneficios-do-cbd-para-atletas-de-parkour\/#Ajuda_a_aliviar_dores_musculares\" >Ajuda a aliviar dores musculares<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/weedy.fr\/blog\/pt\/os-beneficios-do-cbd-para-atletas-de-parkour\/#Um_metodo_natural_de_recuperacao\" >Um m\u00e9todo natural de recupera\u00e7\u00e3o<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/weedy.fr\/blog\/pt\/os-beneficios-do-cbd-para-atletas-de-parkour\/#Ajuda_a_reduzir_a_ansiedade_e_o_estresse\" >Ajuda a reduzir a ansiedade e o estresse<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/weedy.fr\/blog\/pt\/os-beneficios-do-cbd-para-atletas-de-parkour\/#Vapor_capsula_oleo_cada_um_tem_a_sua_solucao\" >Vapor, c\u00e1psula, \u00f3leo: cada um tem a sua solu\u00e7\u00e3o<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/weedy.fr\/blog\/pt\/os-beneficios-do-cbd-para-atletas-de-parkour\/#Suporta_sono\" >Suporta sono<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/weedy.fr\/blog\/pt\/os-beneficios-do-cbd-para-atletas-de-parkour\/#Sono_restaurador_o_aliado_dos_tracadores_do_Parkour\" >Sono restaurador: o aliado dos tra\u00e7adores do Parkour<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/weedy.fr\/blog\/pt\/os-beneficios-do-cbd-para-atletas-de-parkour\/#Promove_concentracao_e_desempenho\" >Promove concentra\u00e7\u00e3o e desempenho<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/weedy.fr\/blog\/pt\/os-beneficios-do-cbd-para-atletas-de-parkour\/#Suplementos_alimentares_especificos_para_atletas\" >Suplementos alimentares espec\u00edficos para atletas<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Ajuda_a_aliviar_dores_musculares\"><\/span>Ajuda a aliviar dores musculares<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Os treinos de Parkour colocam os m\u00fasculos \u00e0 prova, com repetidas quedas, tor\u00e7\u00f5es e distens\u00f5es. Inevitavelmente, isso leva a dores musculares, conhecidas como dor. O <strong>O <a href=\"https:\/\/weedy.fr\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD<\/a> \u00e9 conhecido pelas suas propriedades anti-inflamat\u00f3rias e analg\u00e9sicas-<\/strong> em particular gra\u00e7as \u00e0 sua a\u00e7\u00e3o no sistema endocanabin\u00f3ide, intrinsecamente ligado ao tratamento da dor. Consumi-lo ap\u00f3s o exerc\u00edcio f\u00edsico pode, portanto, ajudar os tra\u00e7adores a aliviar a tens\u00e3o e acalmar os m\u00fasculos.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Um_metodo_natural_de_recuperacao\"><\/span>Um m\u00e9todo natural de recupera\u00e7\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Para intensificar a recupera\u00e7\u00e3o, os tra\u00e7adores podem aplicar um b\u00e1lsamo t\u00f3pico de CBD diretamente nas \u00e1reas doloridas. Este m\u00e9todo natural evita a necessidade de produtos qu\u00edmicos ou farmac\u00eauticos, muitas vezes demasiado agressivos para o corpo, e tamb\u00e9m oferece um efeito direcionado na \u00e1rea afetada.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Ajuda_a_reduzir_a_ansiedade_e_o_estresse\"><\/span>Ajuda a reduzir a ansiedade e o estresse<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>O Parkour exige intensa concentra\u00e7\u00e3o e grande autoconfian\u00e7a para superar os obst\u00e1culos urbanos. Como em todos os desportos radicais, \u00e9 normal que os traceurs sintam alguma <strong>estresse e ansiedade antes de treinos ou competi\u00e7\u00f5es de parkour<\/strong>. O CBD tamb\u00e9m tem efeitos ansiol\u00edticos que podem ajudar a controlar essas emo\u00e7\u00f5es negativas. Ao regular a liberta\u00e7\u00e3o de cortisol, a hormona do stress, o CBD permite controlar melhor situa\u00e7\u00f5es de tens\u00e3o e promover o relaxamento f\u00edsico e mental.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Vapor_capsula_oleo_cada_um_tem_a_sua_solucao\"><\/span>Vapor, c\u00e1psula, \u00f3leo: cada um tem a sua solu\u00e7\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Para beneficiar dos benef\u00edcios ansiol\u00edticos do CBD, est\u00e3o dispon\u00edveis v\u00e1rias op\u00e7\u00f5es para os rastreadores:<\/p>\n<ul>\n<li><strong>\u00d3leo CBD:<\/strong> algumas gotas debaixo da l\u00edngua antes de uma sess\u00e3o de Parkour permitem uma ingest\u00e3o r\u00e1pida e discreta.<\/li>\n<li><strong>C\u00e1psulas de CBD<\/strong> : uma alternativa pr\u00e1tica e saborosa para consumir com um copo de \u00e1gua.<\/li>\n<li><strong>Vapor de CBD:<\/strong> este m\u00e9todo otimiza a biodisponibilidade do canabin\u00f3ide e proporciona rapidamente os seus efeitos relaxantes.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Suporta_sono\"><\/span>Suporta sono<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Uma boa noite de sono \u00e9 essencial para a recupera\u00e7\u00e3o muscular e o desempenho esportivo. Estudos sugeriram que o <strong>CBD pode melhorar a qualidade do sono<\/strong>, em particular agindo no c\u00e9rebro e no sistema endocanabinoide. Ao ajudar a reduzir a ansiedade e o stress, tamb\u00e9m promove um estado de calma prop\u00edcio ao adormecimento.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Sono_restaurador_o_aliado_dos_tracadores_do_Parkour\"><\/span>Sono restaurador: o aliado dos tra\u00e7adores do Parkour<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Ao contribuir para um sono mais profundo e restaurador, o CBD pode ser um recurso valioso para atletas de Parkour que desejam otimizar a sua regenera\u00e7\u00e3o f\u00edsica e mental. No longo prazo, isso resulta em aumento de desempenho e melhor dom\u00ednio da disciplina.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Promove_concentracao_e_desempenho\"><\/span>Promove concentra\u00e7\u00e3o e desempenho<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Parkour envolve muitos fatores t\u00e9cnicos, como precis\u00e3o, fluidez e equil\u00edbrio. L\u00e1 <strong>concentra\u00e7\u00e3o \u00e9, portanto, fundamental<\/strong> nesta disciplina. O CBD tem sido associado \u00e0 melhoria da cogni\u00e7\u00e3o, incluindo aten\u00e7\u00e3o e mem\u00f3ria, atrav\u00e9s da sua intera\u00e7\u00e3o com receptores neuronais.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Suplementos_alimentares_especificos_para_atletas\"><\/span>Suplementos alimentares espec\u00edficos para atletas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Entre os produtos ricos em CBD, os rastreadores podem optar por <strong>suplementos alimentares para atletas<\/strong>, refor\u00e7ando nutrientes essenciais para o desempenho e que podem ser consumidos antes ou durante o treino.<\/p>\n<p>Em suma, o CBD \u00e9 uma alternativa natural interessante para os corredores de Parkour que desejam melhorar o seu desempenho, ajudar o seu corpo a recuperar e a superar os desafios inerentes a esta exigente disciplina. Dependendo das necessidades individuais, existem muitos produtos adaptados \u00e0s prefer\u00eancias e estilo de vida de cada atleta. Observe tamb\u00e9m que o CBD est\u00e1 atualmente autorizado no desporto a n\u00edvel internacional &#8211; abaixo de uma certa concentra\u00e7\u00e3o de THC (0,2% na Uni\u00e3o Europeia).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Parkour, disciplina que combina a arte do movimento e a agilidade do corpo, vem ganhando popularidade nos \u00faltimos anos. Como qualquer esporte, envolve esfor\u00e7o f\u00edsico intenso e pode causar diversas dores ou les\u00f5es. Para promover a recupera\u00e7\u00e3o e melhorar o desempenho, muitos traceurs &#8211; como s\u00e3o chamados os praticantes de Parkour &#8211; que recorrem [&hellip;]<\/p>\n","protected":false},"author":95,"featured_media":352008,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[675],"tags":[],"class_list":["post-359352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-sobre-cbd-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Os benef\u00edcios do CBD para atletas de Parkour - Actualit\u00e9s CBD Blog - Weedy.fr<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/weedy.fr\/blog\/pt\/os-beneficios-do-cbd-para-atletas-de-parkour\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83c\udf31Os benef\u00edcios do CBD para atletas de Parkour - Weedy.Fr\ud83c\udf31\" \/>\n<meta property=\"og:description\" content=\"O Parkour, disciplina que combina a arte do movimento e a agilidade do corpo, vem ganhando popularidade nos \u00faltimos anos. Como qualquer esporte, envolve esfor\u00e7o f\u00edsico intenso e pode causar diversas dores ou les\u00f5es. Para promover a recupera\u00e7\u00e3o e melhorar o desempenho, muitos traceurs &#8211; como s\u00e3o chamados os praticantes de Parkour &#8211; que recorrem [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/weedy.fr\/blog\/pt\/os-beneficios-do-cbd-para-atletas-de-parkour\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualit\u00e9s CBD Blog - Weedy.fr\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/weedysocial\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-17T15:39:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-17T15:39:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/01\/les-bienfaits-du-cbd-pour-les-athletes-de-parkour.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1456\" \/>\n\t<meta property=\"og:image:height\" content=\"832\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alexandre Lacarr\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexandre Lacarr\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/os-beneficios-do-cbd-para-atletas-de-parkour\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/os-beneficios-do-cbd-para-atletas-de-parkour\\\/\"},\"author\":{\"name\":\"Alexandre Lacarr\u00e9\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#\\\/schema\\\/person\\\/54c87d7e580413b08a5b875474a54f4e\"},\"headline\":\"Os benef\u00edcios do CBD para atletas de Parkour\",\"datePublished\":\"2024-09-17T15:39:12+00:00\",\"dateModified\":\"2024-09-17T15:39:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/os-beneficios-do-cbd-para-atletas-de-parkour\\\/\"},\"wordCount\":701,\"publisher\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/os-beneficios-do-cbd-para-atletas-de-parkour\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/les-bienfaits-du-cbd-pour-les-athletes-de-parkour.jpg\",\"articleSection\":[\"Not\u00edcias sobre CBD\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/os-beneficios-do-cbd-para-atletas-de-parkour\\\/\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/os-beneficios-do-cbd-para-atletas-de-parkour\\\/\",\"name\":\"Os benef\u00edcios do CBD para atletas de Parkour - Actualit\u00e9s CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/os-beneficios-do-cbd-para-atletas-de-parkour\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/os-beneficios-do-cbd-para-atletas-de-parkour\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/les-bienfaits-du-cbd-pour-les-athletes-de-parkour.jpg\",\"datePublished\":\"2024-09-17T15:39:12+00:00\",\"dateModified\":\"2024-09-17T15:39:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/os-beneficios-do-cbd-para-atletas-de-parkour\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/os-beneficios-do-cbd-para-atletas-de-parkour\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/os-beneficios-do-cbd-para-atletas-de-parkour\\\/#primaryimage\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/les-bienfaits-du-cbd-pour-les-athletes-de-parkour.jpg\",\"contentUrl\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/les-bienfaits-du-cbd-pour-les-athletes-de-parkour.jpg\",\"width\":1456,\"height\":832,\"caption\":\"Les bienfaits du CBD pour les athl\u00e8tes de Parkour\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/os-beneficios-do-cbd-para-atletas-de-parkour\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias sobre CBD\",\"item\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/category\\\/noticias-sobre-cbd-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Os benef\u00edcios do CBD para atletas de Parkour\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/\",\"name\":\"Actualit\u00e9s CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualit\u00e9 du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-carre.jpg\",\"contentUrl\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/weedysocial\",\"https:\\\/\\\/www.instagram.com\\\/weedyfrance\\\/\"],\"description\":\"Leader en france sur la vente de produits \u00e0 base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#\\\/schema\\\/person\\\/54c87d7e580413b08a5b875474a54f4e\",\"name\":\"Alexandre Lacarr\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g\",\"caption\":\"Alexandre Lacarr\u00e9\"},\"description\":\"Alexandre Lacarr\u00e9 est reconnu comme un leader innovant et influent dans l'industrie du cannabidiol (CBD). Alexandre a d\u00e9but\u00e9 sa carri\u00e8re dans le secteur des biotechnologies, o\u00f9 il a acquis une expertise pr\u00e9cieuse en recherche et d\u00e9veloppement. Passionn\u00e9 par les potentiels th\u00e9rapeutiques des compos\u00e9s naturels, il s'est rapidement orient\u00e9 vers l'industrie naissante du CBD.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/alexandre-henri-lacarr-785850186\\\/\"],\"honorificPrefix\":\"Mr\",\"gender\":\"homme\",\"knowsAbout\":[\"CBD\",\"Cannabis\",\"Copywriter\"],\"worksFor\":\"Weedy.fr\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/author\\\/fiacre\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Os benef\u00edcios do CBD para atletas de Parkour - Actualit\u00e9s CBD Blog - Weedy.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/weedy.fr\/blog\/pt\/os-beneficios-do-cbd-para-atletas-de-parkour\/","og_locale":"fr_FR","og_type":"article","og_title":"\ud83c\udf31Os benef\u00edcios do CBD para atletas de Parkour - Weedy.Fr\ud83c\udf31","og_description":"O Parkour, disciplina que combina a arte do movimento e a agilidade do corpo, vem ganhando popularidade nos \u00faltimos anos. Como qualquer esporte, envolve esfor\u00e7o f\u00edsico intenso e pode causar diversas dores ou les\u00f5es. Para promover a recupera\u00e7\u00e3o e melhorar o desempenho, muitos traceurs &#8211; como s\u00e3o chamados os praticantes de Parkour &#8211; que recorrem [&hellip;]","og_url":"https:\/\/weedy.fr\/blog\/pt\/os-beneficios-do-cbd-para-atletas-de-parkour\/","og_site_name":"Actualit\u00e9s CBD Blog - Weedy.fr","article_publisher":"https:\/\/www.facebook.com\/weedysocial","article_published_time":"2024-09-17T15:39:12+00:00","article_modified_time":"2024-09-17T15:39:13+00:00","og_image":[{"width":1456,"height":832,"url":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/01\/les-bienfaits-du-cbd-pour-les-athletes-de-parkour.jpg","type":"image\/jpeg"}],"author":"Alexandre Lacarr\u00e9","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Alexandre Lacarr\u00e9","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/weedy.fr\/blog\/pt\/os-beneficios-do-cbd-para-atletas-de-parkour\/#article","isPartOf":{"@id":"https:\/\/weedy.fr\/blog\/pt\/os-beneficios-do-cbd-para-atletas-de-parkour\/"},"author":{"name":"Alexandre Lacarr\u00e9","@id":"https:\/\/weedy.fr\/blog\/#\/schema\/person\/54c87d7e580413b08a5b875474a54f4e"},"headline":"Os benef\u00edcios do CBD para atletas de Parkour","datePublished":"2024-09-17T15:39:12+00:00","dateModified":"2024-09-17T15:39:13+00:00","mainEntityOfPage":{"@id":"https:\/\/weedy.fr\/blog\/pt\/os-beneficios-do-cbd-para-atletas-de-parkour\/"},"wordCount":701,"publisher":{"@id":"https:\/\/weedy.fr\/blog\/#organization"},"image":{"@id":"https:\/\/weedy.fr\/blog\/pt\/os-beneficios-do-cbd-para-atletas-de-parkour\/#primaryimage"},"thumbnailUrl":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/01\/les-bienfaits-du-cbd-pour-les-athletes-de-parkour.jpg","articleSection":["Not\u00edcias sobre CBD"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/weedy.fr\/blog\/pt\/os-beneficios-do-cbd-para-atletas-de-parkour\/","url":"https:\/\/weedy.fr\/blog\/pt\/os-beneficios-do-cbd-para-atletas-de-parkour\/","name":"Os benef\u00edcios do CBD para atletas de Parkour - Actualit\u00e9s CBD Blog - Weedy.fr","isPartOf":{"@id":"https:\/\/weedy.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/weedy.fr\/blog\/pt\/os-beneficios-do-cbd-para-atletas-de-parkour\/#primaryimage"},"image":{"@id":"https:\/\/weedy.fr\/blog\/pt\/os-beneficios-do-cbd-para-atletas-de-parkour\/#primaryimage"},"thumbnailUrl":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/01\/les-bienfaits-du-cbd-pour-les-athletes-de-parkour.jpg","datePublished":"2024-09-17T15:39:12+00:00","dateModified":"2024-09-17T15:39:13+00:00","breadcrumb":{"@id":"https:\/\/weedy.fr\/blog\/pt\/os-beneficios-do-cbd-para-atletas-de-parkour\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/weedy.fr\/blog\/pt\/os-beneficios-do-cbd-para-atletas-de-parkour\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/weedy.fr\/blog\/pt\/os-beneficios-do-cbd-para-atletas-de-parkour\/#primaryimage","url":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/01\/les-bienfaits-du-cbd-pour-les-athletes-de-parkour.jpg","contentUrl":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/01\/les-bienfaits-du-cbd-pour-les-athletes-de-parkour.jpg","width":1456,"height":832,"caption":"Les bienfaits du CBD pour les athl\u00e8tes de Parkour"},{"@type":"BreadcrumbList","@id":"https:\/\/weedy.fr\/blog\/pt\/os-beneficios-do-cbd-para-atletas-de-parkour\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https:\/\/weedy.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias sobre CBD","item":"https:\/\/weedy.fr\/blog\/category\/noticias-sobre-cbd-pt\/"},{"@type":"ListItem","position":3,"name":"Os benef\u00edcios do CBD para atletas de Parkour"}]},{"@type":"WebSite","@id":"https:\/\/weedy.fr\/blog\/#website","url":"https:\/\/weedy.fr\/blog\/","name":"Actualit\u00e9s CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualit\u00e9 du CBD et du chanvre en France","publisher":{"@id":"https:\/\/weedy.fr\/blog\/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/weedy.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/weedy.fr\/blog\/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https:\/\/weedy.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/weedy.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/05\/logo-carre.jpg","contentUrl":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/05\/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https:\/\/weedy.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/weedysocial","https:\/\/www.instagram.com\/weedyfrance\/"],"description":"Leader en france sur la vente de produits \u00e0 base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https:\/\/weedy.fr\/blog\/#\/schema\/person\/54c87d7e580413b08a5b875474a54f4e","name":"Alexandre Lacarr\u00e9","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g","caption":"Alexandre Lacarr\u00e9"},"description":"Alexandre Lacarr\u00e9 est reconnu comme un leader innovant et influent dans l'industrie du cannabidiol (CBD). Alexandre a d\u00e9but\u00e9 sa carri\u00e8re dans le secteur des biotechnologies, o\u00f9 il a acquis une expertise pr\u00e9cieuse en recherche et d\u00e9veloppement. Passionn\u00e9 par les potentiels th\u00e9rapeutiques des compos\u00e9s naturels, il s'est rapidement orient\u00e9 vers l'industrie naissante du CBD.","sameAs":["https:\/\/www.linkedin.com\/in\/alexandre-henri-lacarr-785850186\/"],"honorificPrefix":"Mr","gender":"homme","knowsAbout":["CBD","Cannabis","Copywriter"],"worksFor":"Weedy.fr","url":"https:\/\/weedy.fr\/blog\/author\/fiacre\/"}]}},"_links":{"self":[{"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/posts\/359352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/users\/95"}],"replies":[{"embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/comments?post=359352"}],"version-history":[{"count":1,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/posts\/359352\/revisions"}],"predecessor-version":[{"id":359353,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/posts\/359352\/revisions\/359353"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/media\/352008"}],"wp:attachment":[{"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/media?parent=359352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/categories?post=359352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/tags?post=359352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}