{"id":359784,"date":"2024-09-17T17:47:24","date_gmt":"2024-09-17T15:47:24","guid":{"rendered":"https:\/\/weedy.fr\/blog\/?p=359784"},"modified":"2024-09-17T17:47:24","modified_gmt":"2024-09-17T15:47:24","slug":"que-medicamentos-voce-deve-evitar-ao-tomar-cbd","status":"publish","type":"post","link":"https:\/\/weedy.fr\/blog\/pt\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\/","title":{"rendered":"Que medicamentos voc\u00ea deve evitar ao tomar CBD?"},"content":{"rendered":"<p>Canabidiol ou <strong>CDB<\/strong>, \u00e9 cada vez mais utilizado para aliviar diversas doen\u00e7as e dist\u00farbios. Embora considerado seguro e inofensivo para a maioria das pessoas, deve-se ter cautela com certos medicamentos para evitar intera\u00e7\u00f5es prejudiciais e efeitos colaterais. Neste artigo, revisaremos os medicamentos que n\u00e3o devem ser tomados com <a href=\"https:\/\/weedy.fr\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD<\/a>.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/weedy.fr\/blog\/pt\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\/#Medicamentos_que_interagem_com_o_sistema_P450\" >Medicamentos que interagem com o sistema P450<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/weedy.fr\/blog\/pt\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\/#Antidepressivos_sob_substratos_do_CYP3A4\" >Antidepressivos sob substratos do CYP3A4<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/weedy.fr\/blog\/pt\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\/#Disturbios_lipidicos_estatinas_e_fibratos_sob_substratos_do_CYP3A4\" >Dist\u00farbios lip\u00eddicos: estatinas e fibratos sob substratos do CYP3A4<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/weedy.fr\/blog\/pt\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\/#Antidepressivos_e_outros_medicamentos_para_ansiedade\" >Antidepressivos e outros medicamentos para ansiedade<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/weedy.fr\/blog\/pt\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\/#Inibidor_seletivo_de_norepinefrina-dopamina\" >Inibidor seletivo de norepinefrina-dopamina<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/weedy.fr\/blog\/pt\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\/#Anticoagulantes_e_agentes_antiplaquetarios\" >Anticoagulantes e agentes antiplaquet\u00e1rios<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/weedy.fr\/blog\/pt\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\/#Antiepilepticos\" >Antiepil\u00e9pticos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/weedy.fr\/blog\/pt\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\/#Anti-hipertensivos_e_betabloqueadores\" >Anti-hipertensivos e betabloqueadores<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Medicamentos_que_interagem_com_o_sistema_P450\"><\/span>Medicamentos que interagem com o sistema P450<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>O f\u00edgado \u00e9 um \u00f3rg\u00e3o essencial no metabolismo dos medicamentos porque converte essas subst\u00e2ncias em compostos inativos que podem ser excretados do corpo. Uma enzima espec\u00edfica, chamada citocromo P450 (CYP), desempenha um papel crucial neste processo. Estudos mostram que o <a href=\"https:\/\/weedy.fr\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD<\/a> pode inibir certas enzimas CYP, incluindo CYP3A4 e 2C. Portanto, se voc\u00ea estiver tomando medicamentos que tamb\u00e9m s\u00e3o metabolizados nessa enzima, existe o risco de intera\u00e7\u00f5es medicamentosas.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Antidepressivos_sob_substratos_do_CYP3A4\"><\/span>Antidepressivos sob substratos do CYP3A4<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Serotonina-norepinefrina:<\/li>\n<ul>\n<li>Duloxetina<\/li>\n<li>Venlafaxina<\/li>\n<\/ul>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Disturbios_lipidicos_estatinas_e_fibratos_sob_substratos_do_CYP3A4\"><\/span>Dist\u00farbios lip\u00eddicos: estatinas e fibratos sob substratos do CYP3A4<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li>Estatinas:<\/li>\n<ul>\n<li>Lovastatina<\/li>\n<li>Cerivastatina (retirada do mercado)<\/li>\n<li>Sinvastatina<\/li>\n<\/ul>\n<li>Fibrato:<\/li>\n<ul>\n<li>Fenofibrato<\/li>\n<\/ul>\n<\/ul>\n<p><strong>Note que esta lista n\u00e3o \u00e9 exaustiva e que \u00e9 crucial consultar um profissional de sa\u00fade antes de utilizar o <a href=\"https:\/\/weedy.fr\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD<\/a> juntamente com qualquer tratamento.<\/strong><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Antidepressivos_e_outros_medicamentos_para_ansiedade\"><\/span>Antidepressivos e outros medicamentos para ansiedade<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Os efeitos relaxantes do CBD s\u00e3o frequentemente utilizados para aliviar sintomas de ansiedade. No entanto, o uso simult\u00e2neo de certos antidepressivos pode resultar em uma intera\u00e7\u00e3o indesejada. Em particular, existem relat\u00f3rios que sugerem que o CBD pode interagir com certos inibidores seletivos da recapta\u00e7\u00e3o da serotonina (ISRS), tais como:<\/p>\n<ul>\n<li>Vortioxetina (Brintellix\u00ae)<\/li>\n<li>Fluvoxamina (Floxyfral\u00ae)<\/li>\n<li>Faboxetina (Fetzima\u00ae)<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Inibidor_seletivo_de_norepinefrina-dopamina\"><\/span>Inibidor seletivo de norepinefrina-dopamina<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Bupropiona<\/li>\n<li>Atomoxetina<\/li>\n<\/ul>\n<p>\u00c9 essencial discutir a adi\u00e7\u00e3o de CBD \u00e0 sua rotina se voc\u00ea estiver fazendo esse tipo de tratamento para evitar efeitos colaterais.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Anticoagulantes_e_agentes_antiplaquetarios\"><\/span>Anticoagulantes e agentes antiplaquet\u00e1rios<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Os efeitos anti-inflamat\u00f3rios do CBD podem beneficiar algumas pessoas com problemas de coagula\u00e7\u00e3o sangu\u00ednea. No entanto, \u00e9 poss\u00edvel que o CBD interfira com certos medicamentos anticoagulantes e antiplaquet\u00e1rios, tais como:<\/p>\n<ul>\n<li>Varfarina (Coumadin\u00ae)<\/li>\n<li>Clopidogrel (Plavix\u00ae)<\/li>\n<li>Ticagrelor (Brilinta\u00ae)<\/li>\n<\/ul>\n<p>Lembre-se de que \u00e9 importante conversar com seu m\u00e9dico sobre o uso de CBD se voc\u00ea estiver seguindo tratamento anticoagulante ou antiplaquet\u00e1rio.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Antiepilepticos\"><\/span>Antiepil\u00e9pticos<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Embora o CBD tenha demonstrado efic\u00e1cia no tratamento de algumas formas de epilepsia em crian\u00e7as, pode causar intera\u00e7\u00f5es quando tomado com outros medicamentos antiepil\u00e9pticos, tais como:<\/p>\n<ul>\n<li>Carbamazepina (Tegretol\u00ae)<\/li>\n<li>Valproato de s\u00f3dio (D\u00e9pakine\u00ae).<\/li>\n<li>Fenobarbital (Gard\u00e9nal\u00ae)<\/li>\n<\/ul>\n<p>O uso de CBD com estes medicamentos pode alterar a sua efic\u00e1cia ou causar efeitos secund\u00e1rios. Portanto, \u00e9 essencial consultar um profissional de sa\u00fade antes de adicionar o CBD ao seu tratamento para a epilepsia.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Anti-hipertensivos_e_betabloqueadores\"><\/span>Anti-hipertensivos e betabloqueadores<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>O CBD pode interagir potencialmente com certos medicamentos usados \u200b\u200bpara tratar a hipertens\u00e3o, como:\n<\/p>\n<ul>\n<li>Metoprolol (Lopressor\u00ae).<\/li>\n<li>Carvedilol (Coreg\u00ae).<\/li>\n<li>Bisoprolol (Zebeta\u00ae).<\/li>\n<\/ul>\n<p>Em resumo, o CBD \u00e9 utilizado com seguran\u00e7a por muitas pessoas sem problemas. No entanto, \u00e9 importante estar ciente das potenciais intera\u00e7\u00f5es entre o CBD e os medicamentos que voc\u00ea est\u00e1 tomando. Consulte sempre um profissional de sa\u00fade antes de adicionar CBD ao seu regime de tratamento, especialmente se estiver a tomar algum dos medicamentos mencionados acima.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Canabidiol ou CDB, \u00e9 cada vez mais utilizado para aliviar diversas doen\u00e7as e dist\u00farbios. Embora considerado seguro e inofensivo para a maioria das pessoas, deve-se ter cautela com certos medicamentos para evitar intera\u00e7\u00f5es prejudiciais e efeitos colaterais. Neste artigo, revisaremos os medicamentos que n\u00e3o devem ser tomados com CBD. Medicamentos que interagem com o sistema [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":352082,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[672],"tags":[],"class_list":["post-359784","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude-e-bem-estar-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Que medicamentos voc\u00ea deve evitar ao tomar CBD? - Actualit\u00e9s CBD Blog - Weedy.fr<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/weedy.fr\/blog\/pt\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83c\udf31Que medicamentos voc\u00ea deve evitar ao tomar CBD? - Weedy.Fr\ud83c\udf31\" \/>\n<meta property=\"og:description\" content=\"Canabidiol ou CDB, \u00e9 cada vez mais utilizado para aliviar diversas doen\u00e7as e dist\u00farbios. Embora considerado seguro e inofensivo para a maioria das pessoas, deve-se ter cautela com certos medicamentos para evitar intera\u00e7\u00f5es prejudiciais e efeitos colaterais. Neste artigo, revisaremos os medicamentos que n\u00e3o devem ser tomados com CBD. Medicamentos que interagem com o sistema [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/weedy.fr\/blog\/pt\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualit\u00e9s CBD Blog - Weedy.fr\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/weedysocial\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-17T15:47:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/01\/quels-medicaments-eviter-lorsquon-prend-du-cbd.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1456\" \/>\n\t<meta property=\"og:image:height\" content=\"832\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"arthur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"arthur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\\\/\"},\"author\":{\"name\":\"arthur\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#\\\/schema\\\/person\\\/0a05724dbfcfa68f2ce947d2ebf0f435\"},\"headline\":\"Que medicamentos voc\u00ea deve evitar ao tomar CBD?\",\"datePublished\":\"2024-09-17T15:47:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\\\/\"},\"wordCount\":520,\"publisher\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/quels-medicaments-eviter-lorsquon-prend-du-cbd.jpg\",\"articleSection\":[\"Sa\u00fade e Bem-estar\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\\\/\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\\\/\",\"name\":\"Que medicamentos voc\u00ea deve evitar ao tomar CBD? - Actualit\u00e9s CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/quels-medicaments-eviter-lorsquon-prend-du-cbd.jpg\",\"datePublished\":\"2024-09-17T15:47:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/quels-medicaments-eviter-lorsquon-prend-du-cbd.jpg\",\"contentUrl\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/quels-medicaments-eviter-lorsquon-prend-du-cbd.jpg\",\"width\":1456,\"height\":832,\"caption\":\"Quels m\u00e9dicaments \u00e9viter lorsqu'on prend du CBD ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sa\u00fade e Bem-estar\",\"item\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/category\\\/saude-e-bem-estar-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Que medicamentos voc\u00ea deve evitar ao tomar CBD?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/\",\"name\":\"Actualit\u00e9s CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualit\u00e9 du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-carre.jpg\",\"contentUrl\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/weedysocial\",\"https:\\\/\\\/www.instagram.com\\\/weedyfrance\\\/\"],\"description\":\"Leader en france sur la vente de produits \u00e0 base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#\\\/schema\\\/person\\\/0a05724dbfcfa68f2ce947d2ebf0f435\",\"name\":\"arthur\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"caption\":\"arthur\"},\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/author\\\/arthur\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Que medicamentos voc\u00ea deve evitar ao tomar CBD? - Actualit\u00e9s CBD Blog - Weedy.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/weedy.fr\/blog\/pt\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\/","og_locale":"fr_FR","og_type":"article","og_title":"\ud83c\udf31Que medicamentos voc\u00ea deve evitar ao tomar CBD? - Weedy.Fr\ud83c\udf31","og_description":"Canabidiol ou CDB, \u00e9 cada vez mais utilizado para aliviar diversas doen\u00e7as e dist\u00farbios. Embora considerado seguro e inofensivo para a maioria das pessoas, deve-se ter cautela com certos medicamentos para evitar intera\u00e7\u00f5es prejudiciais e efeitos colaterais. Neste artigo, revisaremos os medicamentos que n\u00e3o devem ser tomados com CBD. Medicamentos que interagem com o sistema [&hellip;]","og_url":"https:\/\/weedy.fr\/blog\/pt\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\/","og_site_name":"Actualit\u00e9s CBD Blog - Weedy.fr","article_publisher":"https:\/\/www.facebook.com\/weedysocial","article_published_time":"2024-09-17T15:47:24+00:00","og_image":[{"width":1456,"height":832,"url":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/01\/quels-medicaments-eviter-lorsquon-prend-du-cbd.jpg","type":"image\/jpeg"}],"author":"arthur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"arthur","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/weedy.fr\/blog\/pt\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\/#article","isPartOf":{"@id":"https:\/\/weedy.fr\/blog\/pt\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\/"},"author":{"name":"arthur","@id":"https:\/\/weedy.fr\/blog\/#\/schema\/person\/0a05724dbfcfa68f2ce947d2ebf0f435"},"headline":"Que medicamentos voc\u00ea deve evitar ao tomar CBD?","datePublished":"2024-09-17T15:47:24+00:00","mainEntityOfPage":{"@id":"https:\/\/weedy.fr\/blog\/pt\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\/"},"wordCount":520,"publisher":{"@id":"https:\/\/weedy.fr\/blog\/#organization"},"image":{"@id":"https:\/\/weedy.fr\/blog\/pt\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\/#primaryimage"},"thumbnailUrl":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/01\/quels-medicaments-eviter-lorsquon-prend-du-cbd.jpg","articleSection":["Sa\u00fade e Bem-estar"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/weedy.fr\/blog\/pt\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\/","url":"https:\/\/weedy.fr\/blog\/pt\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\/","name":"Que medicamentos voc\u00ea deve evitar ao tomar CBD? - Actualit\u00e9s CBD Blog - Weedy.fr","isPartOf":{"@id":"https:\/\/weedy.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/weedy.fr\/blog\/pt\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\/#primaryimage"},"image":{"@id":"https:\/\/weedy.fr\/blog\/pt\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\/#primaryimage"},"thumbnailUrl":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/01\/quels-medicaments-eviter-lorsquon-prend-du-cbd.jpg","datePublished":"2024-09-17T15:47:24+00:00","breadcrumb":{"@id":"https:\/\/weedy.fr\/blog\/pt\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/weedy.fr\/blog\/pt\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/weedy.fr\/blog\/pt\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\/#primaryimage","url":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/01\/quels-medicaments-eviter-lorsquon-prend-du-cbd.jpg","contentUrl":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/01\/quels-medicaments-eviter-lorsquon-prend-du-cbd.jpg","width":1456,"height":832,"caption":"Quels m\u00e9dicaments \u00e9viter lorsqu'on prend du CBD ?"},{"@type":"BreadcrumbList","@id":"https:\/\/weedy.fr\/blog\/pt\/que-medicamentos-voce-deve-evitar-ao-tomar-cbd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https:\/\/weedy.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Sa\u00fade e Bem-estar","item":"https:\/\/weedy.fr\/blog\/category\/saude-e-bem-estar-pt\/"},{"@type":"ListItem","position":3,"name":"Que medicamentos voc\u00ea deve evitar ao tomar CBD?"}]},{"@type":"WebSite","@id":"https:\/\/weedy.fr\/blog\/#website","url":"https:\/\/weedy.fr\/blog\/","name":"Actualit\u00e9s CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualit\u00e9 du CBD et du chanvre en France","publisher":{"@id":"https:\/\/weedy.fr\/blog\/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/weedy.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/weedy.fr\/blog\/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https:\/\/weedy.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/weedy.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/05\/logo-carre.jpg","contentUrl":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/05\/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https:\/\/weedy.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/weedysocial","https:\/\/www.instagram.com\/weedyfrance\/"],"description":"Leader en france sur la vente de produits \u00e0 base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https:\/\/weedy.fr\/blog\/#\/schema\/person\/0a05724dbfcfa68f2ce947d2ebf0f435","name":"arthur","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","caption":"arthur"},"url":"https:\/\/weedy.fr\/blog\/author\/arthur\/"}]}},"_links":{"self":[{"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/posts\/359784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/comments?post=359784"}],"version-history":[{"count":1,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/posts\/359784\/revisions"}],"predecessor-version":[{"id":359785,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/posts\/359784\/revisions\/359785"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/media\/352082"}],"wp:attachment":[{"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/media?parent=359784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/categories?post=359784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/tags?post=359784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}