{"id":360200,"date":"2024-09-17T17:56:22","date_gmt":"2024-09-17T15:56:22","guid":{"rendered":"https:\/\/weedy.fr\/blog\/?p=360200"},"modified":"2024-09-17T17:56:23","modified_gmt":"2024-09-17T15:56:23","slug":"substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado","status":"publish","type":"post","link":"https:\/\/weedy.fr\/blog\/pt\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\/","title":{"rendered":"Substituto do tabaco: 3 alternativas para substitu\u00ed-lo em um baseado"},"content":{"rendered":"\n<p>Um \u00e9 legal, o outro n\u00e3o. No entanto, quando estabelecemos a lista dos perigos que representam, o <strong>tabaco<\/strong> realmente n\u00e3o parece melhor do que o <strong>maconha<\/strong>. Ambos, consumidos na combust\u00e3o (fuma\u00e7a), produzem <strong>toxinas cancer\u00edgenas<\/strong> e apresentar um <strong>risco de v\u00edcio<\/strong>.<\/p>\n\n\n\n<p>\u00c9 dif\u00edcil defend\u00ea-los realmente, mas uma coisa \u00e9 certa: fumar maconha misturada com tabaco \u00e9 pior do que consumi-la sozinha. Para evitar os efeitos combinados quando voc\u00ea n\u00e3o quer parar de fumar cannabis, \u00e9 necess\u00e1ria uma solu\u00e7\u00e3o: encontrar um <strong>substituto do tabaco<\/strong> !<\/p>\n\n\n\n<p>Veja como substituir o tabaco em um baseado.<\/p>\n\n\n<div class=\"wp-block-image size-full wp-image-308953\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/weedy.fr\/wp-content\/uploads\/2022\/05\/Effets-negatifs-tabac-min.jpg\" alt=\"efeitos negativos tabaco min\" class=\"wp-image-308953\"><figcaption class=\"wp-element-caption\">O tabaco cont\u00e9m nicotina, uma subst\u00e2ncia que causa depend\u00eancia e depend\u00eancia f\u00edsica<\/figcaption><\/figure>\n<\/div>\n\n\n<p><em>Aviso: em Fran\u00e7a e em muitos outros pa\u00edses, fumar cannabis \u00e9 ilegal. Este artigo n\u00e3o constitui de forma alguma um incitamento \u00e0 ilegalidade, mas simplesmente oferece alternativas ao tabaco. Cabe a voc\u00ea certificar-se de que est\u00e1 em um pa\u00eds onde a lei permite o consumo de cannabis. <\/em><\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/weedy.fr\/blog\/pt\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\/#3_opcoes_para_substituir_o_tabaco_em_um_baseado\" >3 op\u00e7\u00f5es para substituir o tabaco em um baseado<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/weedy.fr\/blog\/pt\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\/#1_Substitua_o_tabaco_por_outra_planta\" >1. Substitua o tabaco por outra planta<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/weedy.fr\/blog\/pt\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\/#2_Use_um_vaporizador_de_ervas_secas\" >2. Use um vaporizador de ervas secas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/weedy.fr\/blog\/pt\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\/#3_Mude_para_cigarros_eletronicos\" >3. Mude para cigarros eletr\u00f4nicos<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/weedy.fr\/blog\/pt\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\/#Como_fumar_um_baseado_sem_tabaco\" >Como fumar um baseado sem tabaco?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/weedy.fr\/blog\/pt\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\/#Substitutos_mais_saudaveis_%E2%80%8B%E2%80%8Bpara_tabaco_e_cannabis\" >Substitutos mais saud\u00e1veis \u200b\u200bpara tabaco e cannabis<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\" id=\"h-3-options-pour-remplacer-le-tabac-dans-un-joint\"><span class=\"ez-toc-section\" id=\"3_opcoes_para_substituir_o_tabaco_em_um_baseado\"><\/span>3 op\u00e7\u00f5es para substituir o tabaco em um baseado<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Uma junta cl\u00e1ssica geralmente consiste em um <strong>mistura de flores de cannabis esfareladas ou resina e tabaco para enrolar<\/strong>. A combina\u00e7\u00e3o n\u00e3o \u00e9 necessariamente feliz, entretanto. Para limitar os riscos, parar de fumar mais facilmente ou n\u00e3o querer dar outro mergulho por causa de um baseado, voc\u00ea deve, portanto, ser capaz de <strong>abandonar o tabaco<\/strong>. \u00c9 poss\u00edvel, e n\u00e3o implica necessariamente que voc\u00ea fume apenas puros!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-remplacer-le-tabac-par-une-autre-plante\"><span class=\"ez-toc-section\" id=\"1_Substitua_o_tabaco_por_outra_planta\"><\/span>1. Substitua o tabaco por outra planta<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n<div class=\"wp-block-image size-full wp-image-308954\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/weedy.fr\/wp-content\/uploads\/2022\/05\/Rouler-un-joint-sans-tabac-min.jpg\" alt=\"enrolar um baseado sem tabaco min\" class=\"wp-image-308954\"><figcaption class=\"wp-element-caption\">\u00c9 poss\u00edvel enrolar um baseado sem tabaco, usando cannabis pura ou outras plantas secas<\/figcaption><\/figure>\n<\/div>\n\n\n<p>A maneira mais f\u00e1cil de fumar um baseado sem tabaco \u00e9, claro, usar apenas maconha pura. No entanto, esta \u00e9 uma solu\u00e7\u00e3o bastante radical, especialmente porque a concentra\u00e7\u00e3o de canabin\u00f3ides na cannabis nem sempre \u00e9 f\u00e1cil ou poss\u00edvel de saber.<\/p>\n\n\n\n<p>Para evitar se encontrar mais <em>pedra<\/em> do que Charden, \u00e9 ent\u00e3o poss\u00edvel misturar sua erva com outras plantas secas. V\u00e1rias op\u00e7\u00f5es est\u00e3o dispon\u00edveis para voc\u00ea, com suas vantagens e desvantagens:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>S\u00e1bio<\/strong>: o substituto mais comum do tabaco no baseado, \u00e9 bastante forte e produz uma fuma\u00e7a espessa.<\/li>\n\n\n\n<li><strong>Camomila<\/strong>: doce e frutado, queima bem e \u00e9 conhecido pelos seus (leves) efeitos calmantes.<\/li>\n\n\n\n<li><strong>erva-de-gato<\/strong>: catnip em um baseado? Por que n\u00e3o, desde o <a href=\"http:\/\/www.wikiphyto.org\/wiki\/Cataire\" target=\"_blank\" rel=\"noopener\">erva-de-gato<\/a> \u00e9 perfeitamente comest\u00edvel e muito arom\u00e1tico com notas marcadas de menta.<\/li>\n\n\n\n<li><strong>Saltar<\/strong>: prima da cannabis (\u00e0s vezes afirma-se que <a href=\"https:\/\/weedy.fr\/blog\/du-cannabidiol-dans-le-houblon\/\">l\u00fapulo cont\u00e9m canabidiol<\/a>), \u00e9 mais picante e amargo, mas rico em terpenos. Para ser reservado aos amantes de gostos assertivos!<\/li>\n\n\n\n<li><strong>Passiflora<\/strong>: conhecido por fazer voc\u00ea cochilar, o <a href=\"https:\/\/www.gammvert.fr\/conseils\/conseils-de-jardinage\/les-7-bienfaits-de-la-passiflore\" target=\"_blank\" rel=\"noopener\">passiflora<\/a> \u00e9 prefer\u00edvel no final do dia e evitado quando voc\u00ea precisa se sentar ao volante (<a href=\"https:\/\/weedy.fr\/blog\/conduire-sous-cbd\/\">fumar maconha e dirigir<\/a> nunca v\u00e3o bem juntos de qualquer maneira).<\/li>\n\n\n\n<li><strong>L\u00f3tus<\/strong>: branco, traz notas almiscaradas. Azul, \u00e9 para ser reservado para quem gosta de amargor.<\/li>\n<\/ul>\n\n\n\n<p><em>Aten\u00e7\u00e3o: todas estas plantas s\u00e3o legais, mas t\u00eam efeitos mais ou menos pronunciados. Certifique-se de pesquisar os substitutos do tabaco que voc\u00ea usa e diminua a dosagem quando n\u00e3o estiver familiarizado com um produto. Cuidado tamb\u00e9m com plantas t\u00f3xicas! <\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-utiliser-un-vaporisateur-pour-herbe-seche\"><span class=\"ez-toc-section\" id=\"2_Use_um_vaporizador_de_ervas_secas\"><\/span>2. Use um vaporizador de ervas secas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Um spray para mat\u00e9ria vegetal (como <a href=\"https:\/\/weedy.fr\/product\/pax-3-complete-kit-vaporisateur-portable-pour-matieres-vegetales\">Pax 3<\/a> por exemplo) permite fumar um baseado sem tabaco, de forma f\u00e1cil e discreta. A maioria dos vaporizadores modernos permite que voc\u00ea <strong>controlar a temperatura de aquecimento<\/strong> com o toque de um bot\u00e3o e pode at\u00e9 ser controlado remotamente via smartphone. Ao aquecer menos, os vaporizadores evitam que a erva queime, <strong>evitando a libera\u00e7\u00e3o de alcatr\u00e3o e mon\u00f3xido de carbono<\/strong>. Gra\u00e7as ao volume limitado do tanque, voc\u00ea fuma a quantidade desejada, <strong>sem perda de material e sem necessidade de tabaco<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-3-passer-a-la-cigarette-electronique\"><span class=\"ez-toc-section\" id=\"3_Mude_para_cigarros_eletronicos\"><\/span>3. Mude para cigarros eletr\u00f4nicos<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n<div class=\"wp-block-image size-full wp-image-308952\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/weedy.fr\/wp-content\/uploads\/2022\/05\/Cigarette-electronique-sans-combustion-ni-tabac-min.jpg\" alt=\"cigarro eletr\u00f4nico sem combust\u00e3o ou tabaco min\" class=\"wp-image-308952\"><figcaption class=\"wp-element-caption\">O cigarro eletr\u00f4nico evita a combust\u00e3o e, portanto, reduz os riscos para o consumidor<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Por fim, \u00e9 poss\u00edvel trocar sua boa e velha erva ou resina por um e-l\u00edquido com sabores de sua prefer\u00eancia. O mais l\u00f3gico \u00e9 ent\u00e3o recorrer ao <a href=\"https:\/\/weedy.fr\/product-category\/e-liquides-cbd\/\">L\u00edquidos para cigarros eletr\u00f4nicos CBD<\/a>. O canabidiol de fato tem todas as vantagens da maconha, al\u00e9m da legalidade! Voc\u00ea encontrar\u00e1 facilmente os gestos do fumante, o sabor das variedades cult de cannabis e <a href=\"https:\/\/weedy.fr\/effets-therapeutiques-cbd\">os efeitos calmantes do CBD<\/a>.<\/p>\n\n\n\n<p>A ideia de encontrar um substituto para o tabaco neste caso passa obviamente por evitar e-l\u00edquidos que contenham nicotina!<\/p>\n\n\n\n<p><em>Voc\u00ea quer descobrir o cigarro eletr\u00f4nico <strong>com menor custo<\/strong> ? NOSSO <\/em><a href=\"https:\/\/weedy.fr\/product\/vape-kit-cbd\"><em>Kit vaporizador CBD<\/em><\/a><em> \u00e9 uma maneira super simples de conseguir isso. Voc\u00ea pode aproveitar <strong>cinco sabores para escolher<\/strong>, dispon\u00edvel em <\/em><a href=\"https:\/\/weedy.fr\/product\/cartouche-cbd\"><em>cartuchos individuais de CBD<\/em><\/a><em> (Amn\u00e9sia, Banana Kush, Strawberry Haze, Super Lemon Haze, Super Skunk). <\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-comment-fumer-un-joint-sans-tabac-nbsp\"><span class=\"ez-toc-section\" id=\"Como_fumar_um_baseado_sem_tabaco\"><\/span>Como fumar um baseado sem tabaco?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Fumar um baseado com ou sem tabaco n\u00e3o faz nenhuma diferen\u00e7a significativa a n\u00edvel t\u00e9cnico. Dependendo da mistura utilizada, pode ser necess\u00e1rio, no entanto, esfarelar a relva mais ou menos finamente e compactar mais ou menos o baseado. Catnip, por exemplo, queima rapidamente.<\/p>\n\n\n\n<p>\u00c9 preciso triturar bem e embalar para n\u00e3o ver a cannabis cair na ponta do cone sem queimar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-substituts-plus-sains-au-tabac-et-au-cannabis\"><span class=\"ez-toc-section\" id=\"Substitutos_mais_saudaveis_%E2%80%8B%E2%80%8Bpara_tabaco_e_cannabis\"><\/span>Substitutos mais saud\u00e1veis \u200b\u200bpara tabaco e cannabis<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Todos os substitutos do tabaco aqui discutidos envolvem o aquecimento do material. Certamente, evitar a combust\u00e3o \u00e9 um primeiro passo para um padr\u00e3o de consumo mais saud\u00e1vel. No entanto, algumas toxinas ainda s\u00e3o liberadas. Para desfrutar dos efeitos da cannabis mantendo-se legal e cuidando da sua sa\u00fade, o canabidiol \u00e9 uma alternativa ideal.<\/p>\n\n\n\n<p><strong>N\u00e3o psicoativo, n\u00e3o viciante<\/strong> e conhecido por seu <a href=\"https:\/\/weedy.fr\/blog\/cbd-contre-douleur\/\">efeitos calmantes e analg\u00e9sicos<\/a>, pode at\u00e9 facilitar a abstin\u00eancia da nicotina e do THC e, portanto, ajudar a <a href=\"https:\/\/weedy.fr\/blog\/arreter-de-fumer-du-cannabis\/\">Pare de fumar<\/a>.<\/p>\n\n\n\n<p>O <a href=\"https:\/\/weedy.fr\/product-category\/huiles-cbd\/\">\u00d3leos CBD<\/a>, <a href=\"https:\/\/weedy.fr\/product-category\/cbd-alimentaire\/infusions-cbd\/\">infus\u00f5es de c\u00e2nhamo<\/a> e outros produtos de bem-estar <a href=\"https:\/\/weedy.fr\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD<\/a> s\u00e3o certamente o primeiro caminho a seguir. Se isso n\u00e3o for suficiente, \u00e9 sempre poss\u00edvel usar paralelo <strong>substitutos da nicotina<\/strong> (goma de mascar, adesivo).<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Um \u00e9 legal, o outro n\u00e3o. No entanto, quando estabelecemos a lista dos perigos que representam, o tabaco realmente n\u00e3o parece melhor do que o maconha. Ambos, consumidos na combust\u00e3o (fuma\u00e7a), produzem toxinas cancer\u00edgenas e apresentar um risco de v\u00edcio. \u00c9 dif\u00edcil defend\u00ea-los realmente, mas uma coisa \u00e9 certa: fumar maconha misturada com tabaco \u00e9 [&hellip;]<\/p>\n","protected":false},"author":41,"featured_media":351747,"comment_status":"open","ping_status":"closed","sticky":false,"template":"padr\u00e3o\n","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[669],"tags":[],"class_list":["post-360200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estilo-de-vida-cbd-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Substituto do tabaco: 3 alternativas para substitu\u00ed-lo em um baseado - Actualit\u00e9s CBD Blog - Weedy.fr<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/weedy.fr\/blog\/pt\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83c\udf31Substituto do tabaco: 3 alternativas para substitu\u00ed-lo em um baseado - Weedy.Fr\ud83c\udf31\" \/>\n<meta property=\"og:description\" content=\"Um \u00e9 legal, o outro n\u00e3o. No entanto, quando estabelecemos a lista dos perigos que representam, o tabaco realmente n\u00e3o parece melhor do que o maconha. Ambos, consumidos na combust\u00e3o (fuma\u00e7a), produzem toxinas cancer\u00edgenas e apresentar um risco de v\u00edcio. \u00c9 dif\u00edcil defend\u00ea-los realmente, mas uma coisa \u00e9 certa: fumar maconha misturada com tabaco \u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/weedy.fr\/blog\/pt\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualit\u00e9s CBD Blog - Weedy.fr\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/weedysocial\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/weedysocial\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-17T15:56:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-17T15:56:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2022\/06\/cbd-substitut-tabac-weedy.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julien Cordobes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julien Cordobes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\\\/\"},\"author\":{\"name\":\"Julien Cordobes\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#\\\/schema\\\/person\\\/72583fcd87d7cf46afe11d530945bc7e\"},\"headline\":\"Substituto do tabaco: 3 alternativas para substitu\u00ed-lo em um baseado\",\"datePublished\":\"2024-09-17T15:56:22+00:00\",\"dateModified\":\"2024-09-17T15:56:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\\\/\"},\"wordCount\":994,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cbd-substitut-tabac-weedy.jpg\",\"articleSection\":[\"Estilo de vida CBD\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\\\/\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\\\/\",\"name\":\"Substituto do tabaco: 3 alternativas para substitu\u00ed-lo em um baseado - Actualit\u00e9s CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cbd-substitut-tabac-weedy.jpg\",\"datePublished\":\"2024-09-17T15:56:22+00:00\",\"dateModified\":\"2024-09-17T15:56:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cbd-substitut-tabac-weedy.jpg\",\"contentUrl\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cbd-substitut-tabac-weedy.jpg\",\"width\":1600,\"height\":800,\"caption\":\"cbd-substitut-tabac-weedy\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estilo de vida CBD\",\"item\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/category\\\/estilo-de-vida-cbd-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Substituto do tabaco: 3 alternativas para substitu\u00ed-lo em um baseado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/\",\"name\":\"Actualit\u00e9s CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualit\u00e9 du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-carre.jpg\",\"contentUrl\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/weedysocial\",\"https:\\\/\\\/www.instagram.com\\\/weedyfrance\\\/\"],\"description\":\"Leader en france sur la vente de produits \u00e0 base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#\\\/schema\\\/person\\\/72583fcd87d7cf46afe11d530945bc7e\",\"name\":\"Julien Cordobes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"caption\":\"Julien Cordobes\"},\"description\":\"R\u00e9dacteur en chef sp\u00e9cialis\u00e9 en CBD Julien, n\u00e9 le 17 juillet 1978 en r\u00e9gion Parisienne, est un \u00e9minent r\u00e9dacteur et expert dans le domaine des produits \u00e0 base de CBD. Suite \u00e0 ses \u00e9tudes en biologie et en m\u00e9decine alternative, Julien a d\u00e9velopp\u00e9 une passion pour les rem\u00e8des naturels, dont le CBD. En 2022, il int\u00e8gre l\u2019\u00e9quipe du site Weedy.fr en qualit\u00e9 d\u2019expert et de contributeur r\u00e9gulier. Gr\u00e2ce \u00e0 son expertise scientifique et une \u00e9criture claire, Julien aide \u00e0 d\u00e9mystifier les aspects complexes du CBD, tout en mettant en lumi\u00e8re ses bienfaits et applications potentielles \u00e0 travers ses articles et participations \u00e0 des conf\u00e9rences.\",\"sameAs\":[\"https:\\\/\\\/weedy.fr\",\"https:\\\/\\\/www.facebook.com\\\/weedysocial\\\/\",\"https:\\\/\\\/www.instagram.com\\\/weedyfrance\",\"https:\\\/\\\/www.pinterest.fr\\\/WeedyFrance\\\/\"],\"honorificPrefix\":\"Mr\",\"birthDate\":\"1978-07-17\",\"gender\":\"male\",\"knowsAbout\":[\"CBD\",\"Cannabis\",\"Copywriter\"],\"knowsLanguage\":[\"French\"],\"jobTitle\":\"Editor-in-chief specializing in CBD\",\"worksFor\":\"Weedy.fr\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/author\\\/cbd_blog_owner\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Substituto do tabaco: 3 alternativas para substitu\u00ed-lo em um baseado - Actualit\u00e9s CBD Blog - Weedy.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/weedy.fr\/blog\/pt\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\/","og_locale":"fr_FR","og_type":"article","og_title":"\ud83c\udf31Substituto do tabaco: 3 alternativas para substitu\u00ed-lo em um baseado - Weedy.Fr\ud83c\udf31","og_description":"Um \u00e9 legal, o outro n\u00e3o. No entanto, quando estabelecemos a lista dos perigos que representam, o tabaco realmente n\u00e3o parece melhor do que o maconha. Ambos, consumidos na combust\u00e3o (fuma\u00e7a), produzem toxinas cancer\u00edgenas e apresentar um risco de v\u00edcio. \u00c9 dif\u00edcil defend\u00ea-los realmente, mas uma coisa \u00e9 certa: fumar maconha misturada com tabaco \u00e9 [&hellip;]","og_url":"https:\/\/weedy.fr\/blog\/pt\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\/","og_site_name":"Actualit\u00e9s CBD Blog - Weedy.fr","article_publisher":"https:\/\/www.facebook.com\/weedysocial","article_author":"https:\/\/www.facebook.com\/weedysocial\/","article_published_time":"2024-09-17T15:56:22+00:00","article_modified_time":"2024-09-17T15:56:23+00:00","og_image":[{"width":1600,"height":800,"url":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2022\/06\/cbd-substitut-tabac-weedy.jpg","type":"image\/jpeg"}],"author":"Julien Cordobes","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Julien Cordobes","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/weedy.fr\/blog\/pt\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\/#article","isPartOf":{"@id":"https:\/\/weedy.fr\/blog\/pt\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\/"},"author":{"name":"Julien Cordobes","@id":"https:\/\/weedy.fr\/blog\/#\/schema\/person\/72583fcd87d7cf46afe11d530945bc7e"},"headline":"Substituto do tabaco: 3 alternativas para substitu\u00ed-lo em um baseado","datePublished":"2024-09-17T15:56:22+00:00","dateModified":"2024-09-17T15:56:23+00:00","mainEntityOfPage":{"@id":"https:\/\/weedy.fr\/blog\/pt\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\/"},"wordCount":994,"commentCount":0,"publisher":{"@id":"https:\/\/weedy.fr\/blog\/#organization"},"image":{"@id":"https:\/\/weedy.fr\/blog\/pt\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\/#primaryimage"},"thumbnailUrl":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2022\/06\/cbd-substitut-tabac-weedy.jpg","articleSection":["Estilo de vida CBD"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/weedy.fr\/blog\/pt\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/weedy.fr\/blog\/pt\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\/","url":"https:\/\/weedy.fr\/blog\/pt\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\/","name":"Substituto do tabaco: 3 alternativas para substitu\u00ed-lo em um baseado - Actualit\u00e9s CBD Blog - Weedy.fr","isPartOf":{"@id":"https:\/\/weedy.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/weedy.fr\/blog\/pt\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\/#primaryimage"},"image":{"@id":"https:\/\/weedy.fr\/blog\/pt\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\/#primaryimage"},"thumbnailUrl":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2022\/06\/cbd-substitut-tabac-weedy.jpg","datePublished":"2024-09-17T15:56:22+00:00","dateModified":"2024-09-17T15:56:23+00:00","breadcrumb":{"@id":"https:\/\/weedy.fr\/blog\/pt\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/weedy.fr\/blog\/pt\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/weedy.fr\/blog\/pt\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\/#primaryimage","url":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2022\/06\/cbd-substitut-tabac-weedy.jpg","contentUrl":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2022\/06\/cbd-substitut-tabac-weedy.jpg","width":1600,"height":800,"caption":"cbd-substitut-tabac-weedy"},{"@type":"BreadcrumbList","@id":"https:\/\/weedy.fr\/blog\/pt\/substituto-do-tabaco-3-alternativas-para-substitui-lo-em-um-baseado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https:\/\/weedy.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Estilo de vida CBD","item":"https:\/\/weedy.fr\/blog\/category\/estilo-de-vida-cbd-pt\/"},{"@type":"ListItem","position":3,"name":"Substituto do tabaco: 3 alternativas para substitu\u00ed-lo em um baseado"}]},{"@type":"WebSite","@id":"https:\/\/weedy.fr\/blog\/#website","url":"https:\/\/weedy.fr\/blog\/","name":"Actualit\u00e9s CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualit\u00e9 du CBD et du chanvre en France","publisher":{"@id":"https:\/\/weedy.fr\/blog\/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/weedy.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/weedy.fr\/blog\/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https:\/\/weedy.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/weedy.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/05\/logo-carre.jpg","contentUrl":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/05\/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https:\/\/weedy.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/weedysocial","https:\/\/www.instagram.com\/weedyfrance\/"],"description":"Leader en france sur la vente de produits \u00e0 base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https:\/\/weedy.fr\/blog\/#\/schema\/person\/72583fcd87d7cf46afe11d530945bc7e","name":"Julien Cordobes","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","caption":"Julien Cordobes"},"description":"R\u00e9dacteur en chef sp\u00e9cialis\u00e9 en CBD Julien, n\u00e9 le 17 juillet 1978 en r\u00e9gion Parisienne, est un \u00e9minent r\u00e9dacteur et expert dans le domaine des produits \u00e0 base de CBD. Suite \u00e0 ses \u00e9tudes en biologie et en m\u00e9decine alternative, Julien a d\u00e9velopp\u00e9 une passion pour les rem\u00e8des naturels, dont le CBD. En 2022, il int\u00e8gre l\u2019\u00e9quipe du site Weedy.fr en qualit\u00e9 d\u2019expert et de contributeur r\u00e9gulier. Gr\u00e2ce \u00e0 son expertise scientifique et une \u00e9criture claire, Julien aide \u00e0 d\u00e9mystifier les aspects complexes du CBD, tout en mettant en lumi\u00e8re ses bienfaits et applications potentielles \u00e0 travers ses articles et participations \u00e0 des conf\u00e9rences.","sameAs":["https:\/\/weedy.fr","https:\/\/www.facebook.com\/weedysocial\/","https:\/\/www.instagram.com\/weedyfrance","https:\/\/www.pinterest.fr\/WeedyFrance\/"],"honorificPrefix":"Mr","birthDate":"1978-07-17","gender":"male","knowsAbout":["CBD","Cannabis","Copywriter"],"knowsLanguage":["French"],"jobTitle":"Editor-in-chief specializing in CBD","worksFor":"Weedy.fr","url":"https:\/\/weedy.fr\/blog\/author\/cbd_blog_owner\/"}]}},"_links":{"self":[{"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/posts\/360200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/comments?post=360200"}],"version-history":[{"count":1,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/posts\/360200\/revisions"}],"predecessor-version":[{"id":360201,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/posts\/360200\/revisions\/360201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/media\/351747"}],"wp:attachment":[{"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/media?parent=360200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/categories?post=360200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/tags?post=360200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}