{"id":360388,"date":"2024-09-17T18:01:26","date_gmt":"2024-09-17T16:01:26","guid":{"rendered":"https:\/\/weedy.fr\/blog\/?p=360388"},"modified":"2024-09-17T18:01:28","modified_gmt":"2024-09-17T16:01:28","slug":"was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol","status":"publish","type":"post","link":"https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\/","title":{"rendered":"Was ist THCP oder \u03949-Tetrahydrocannabiphorol?"},"content":{"rendered":"\n<p>Die Welt des Cannabis entwickelt sich rasant weiter und mit ihr auch unser Verst\u00e4ndnis der vielen darin enthaltenen Verbindungen. Unter ihnen sind die <strong><a href=\"https:\/\/weedy.fr\/product-category\/thcp\/\" data-internallinksmanager029f6b8e52c=\"5\" title=\"thcp\">THCP<\/a><\/strong> zieht aufgrund seiner einzigartigen Eigenschaften und seines Potenzials immer mehr Interesse auf sich.<\/p>\n\n\n\n<p>Es wurde Ende der 2010er Jahre in der Cannabispflanze entdeckt und fasziniert seit jeher mit seiner Kraft <strong>bis zu 33-mal st\u00e4rker als THC<\/strong> ! Aber was genau sind das? <strong>Effekte<\/strong>, welche <strong>Derivate<\/strong> gibt es auf dem Markt und, was noch wichtiger ist, ist es m\u00f6glich <strong>ohne Risiko konsumieren<\/strong> ? <a href=\"https:\/\/weedy.fr\/\" data-internallinksmanager029f6b8e52c=\"8\" title=\"weedy\">Weedy.fr<\/a> zieht Bilanz der Situation.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\/#THCP_Was_ist_das\" >THCP: Was ist das?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\/#Ist_THCP_legal\" >Ist THCP legal?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\/#THCP_vs_CBDP_was_sind_die_Unterschiede\" >THCP vs. CBDP, was sind die Unterschiede?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\/#Interaktion_mit_dem_Endocannabinoidsystem\" >Interaktion mit dem Endocannabinoidsystem<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\/#Mogliche_Auswirkungen_von_THCP\" >M\u00f6gliche Auswirkungen von THCP<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\/#THCP-Produkte\" >THCP-Produkte<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\/#Nebenwirkungen_und_Vorsichtsmasnahmen_fur_die_Anwendung\" >Nebenwirkungen und Vorsichtsma\u00dfnahmen f\u00fcr die Anwendung<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\/#Mogliche_Nebenwirkungen\" >M\u00f6gliche Nebenwirkungen<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\" id=\"h-le-thcp-nbsp-qu-est-ce-que-c-est-nbsp\"><span class=\"ez-toc-section\" id=\"THCP_Was_ist_das\"><\/span>THCP: Was ist das?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n<div class=\"wp-block-image size-full wp-image-348715\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/weedy.fr\/wp-content\/uploads\/2023\/08\/Definition-THCP-cannabinoide-naturel-min.jpg\" alt=\"Definition THCP nat\u00fcrliches Cannabinoid min\" class=\"wp-image-348715\"><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/weedy.fr\/product-category\/thcp\/\" data-internallinksmanager029f6b8e52c=\"5\" title=\"thcp\">THCP<\/a> (\u03949-Tetrahydrocannabiphorol) ist ein von Cannabis produziertes Molek\u00fcl<\/figcaption><\/figure>\n<\/div>\n\n\n<p><a href=\"https:\/\/weedy.fr\/product-category\/thcp\/\" data-internallinksmanager029f6b8e52c=\"5\" title=\"thcp\">THCP<\/a>, oder <strong>\u03949-Tetrahydrocannabiphorol<\/strong>ist ein Cannabinoid, das erst vor relativ kurzer Zeit Einzug in die Cannabisszene gehalten hat. Im Gegensatz zu den bekanntesten Cannabinoiden, wie z <a href=\"https:\/\/weedy.fr\/\">CBD<\/a> und die <a href=\"https:\/\/weedy.fr\/quest-ce-que-le-thc\">THC<\/a>, es wurde nicht in den 1960er Jahren entdeckt und isoliert, sondern im Jahr 2019.<\/p>\n\n\n\n<p>Zu dieser Zeit arbeitete ein Team italienischer Forscher an Cannabis und seinen Cannabisprodukten <a href=\"https:\/\/weedy.fr\/blog\/cannabinoides-le-cannabis-nest-pas-le-seul-produire\/\">Cannabinoide<\/a>. Allerdings erwarten sie nicht unbedingt, Neues zu entdecken. W\u00e4hrend ihrer <a href=\"https:\/\/www.nature.com\/articles\/s41598-019-56785-1\" target=\"_blank\" rel=\"noopener\">Studie<\/a> <em><\/em>, isolierten sie zwei neue Molek\u00fcle: THCP und <strong>CBDP (Cannabidiphorol)<\/strong>. Allerdings ist es THCP, das die meiste Aufmerksamkeit auf sich zieht. Es hat tats\u00e4chlich eine bemerkenswerte strukturelle \u00c4hnlichkeit mit THC, dem Hauptbestandteil <strong>psychotrope Verbindung<\/strong> Cannabis. Was THCP jedoch auszeichnet, ist seine potenzielle F\u00e4higkeit, sich mit noch gr\u00f6\u00dferer Affinit\u00e4t an Cannabinoidrezeptoren im K\u00f6rper zu binden. Es ist also so <strong>st\u00e4rker als THC<\/strong>, und das ist nicht die einzige Besonderheit.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-le-thcp-est-il-legal-nbsp\"><span class=\"ez-toc-section\" id=\"Ist_THCP_legal\"><\/span>Ist THCP legal?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Ja. Als ich diese Zeilen schrieb, <strong>Der Kauf von THCP in Frankreich ist legal<\/strong>, unter den gleichen Bedingungen wie andere Cannabis-Derivate. Ein THCP-haltiges Produkt muss daher aus einer Pflanze gewonnen worden sein, die zu einem geh\u00f6rt <strong>zugelassene Sorte<\/strong> und wessen <strong>Der THC-Gehalt \u00fcberschreitet nicht 0,3 %<\/strong>. Nur THC, <a href=\"https:\/\/weedy.fr\/blog\/hhc-quelle-difference-avec-cbd\/\">HHC<\/a> und einige ihrer Derivate sind derzeit verboten, da sie als Bet\u00e4ubungsmittel gelten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-thcp-vs-cbdp-quelles-differences-nbsp\"><span class=\"ez-toc-section\" id=\"THCP_vs_CBDP_was_sind_die_Unterschiede\"><\/span>THCP vs. CBDP, was sind die Unterschiede?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>CBDP wird wie THCP auf nat\u00fcrliche Weise von Cannabis produziert. Beide resultieren im \u00dcbrigen aus der Transformation von <a href=\"https:\/\/weedy.fr\/blog\/cbg-definition\/\">CBG (Cannabigerol)<\/a>, wie viele andere Cannabinoide. Wie der Name schon sagt, ist THCP ein Derivat von THC und CBDP ein Derivat von <a href=\"https:\/\/weedy.fr\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD<\/a>. Allerdings haben sowohl THCP als auch CBDP eine l\u00e4ngere Linkerkette oder Seitenkette. Ohne in einen Chemieunterricht zu gehen, hei\u00dft das <strong>ihre Wirkung und Wirksamkeit sind unterschiedlich<\/strong> da sie unterschiedlich mit dem Endocannabinoidsystem interagieren.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-interaction-avec-le-systeme-endocannabinoide\"><span class=\"ez-toc-section\" id=\"Interaktion_mit_dem_Endocannabinoidsystem\"><\/span>Interaktion mit dem Endocannabinoidsystem<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n<div class=\"wp-block-image size-full wp-image-348717\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/weedy.fr\/wp-content\/uploads\/2023\/08\/Effets-THCP-min.jpg\" alt=\"THCP-Mindesteffekte\" class=\"wp-image-348717\"><figcaption class=\"wp-element-caption\">THCP h\u00e4tte insbesondere Auswirkungen auf Stimmung, Schmerzen und Appetit<\/figcaption><\/figure>\n<\/div>\n\n\n<p>DER <a href=\"https:\/\/weedy.fr\/blog\/systeme-endocannabinoide-definition\/\">Endocannabinoid-System<\/a> (SEC) ist eine Reihe von Rezeptoren (CB1 und CB2 genannt), die im gesamten menschlichen K\u00f6rper und allgemeiner im K\u00f6rper von S\u00e4ugetieren verteilt sind. Insbesondere hat er eine <strong>Einfluss auf das Nervensystem und das Immunsystem<\/strong>. Eine seiner Besonderheiten ist die Interaktion mit Cannabinoiden, unabh\u00e4ngig davon, ob sie von unserem K\u00f6rper auf nat\u00fcrliche Weise produziert werden (<strong>Endocannabinoide<\/strong>) oder dass sie von Pflanzen stammen (die <strong>Phytocannabinoide<\/strong>, wie sie in Cannabis vorkommen).<\/p>\n\n\n\n<p>Aufgrund seiner besonderen Struktur k\u00f6nnte THCP einen st\u00e4rkeren Einfluss auf diese Rezeptoren haben, was wiederum der Fall sein k\u00f6nnte <strong>Einfluss auf verschiedene physiologische Prozesse <\/strong>wie die <strong>Schmerz<\/strong>, L&rsquo;<strong>Appetit<\/strong> und die<strong>Stimmung<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-effets-potentiels-du-thcp\"><span class=\"ez-toc-section\" id=\"Mogliche_Auswirkungen_von_THCP\"><\/span>M\u00f6gliche Auswirkungen von THCP<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Obwohl sich die Forschung zu THCP noch in einem fr\u00fchen Stadium befindet, deuten vorl\u00e4ufige Studien darauf hin, dass es unterschiedliche Auswirkungen auf unseren K\u00f6rper und Geist haben kann. Es k\u00f6nnte also insbesondere sein:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Analgetikum<\/li>\n\n\n\n<li>entz\u00fcndungshemmend (und daher schmerzstillend)<\/li>\n\n\n\n<li>Antiemetikum (es w\u00fcrde \u00dcbelkeit und Erbrechen reduzieren)<\/li>\n\n\n\n<li>Anxiolytisch<\/li>\n\n\n\n<li>und m\u00f6glicherweise andere Wirkungen, die denen \u00e4hneln, die bei anderen Cannabinoiden beobachtet werden<\/li>\n<\/ul>\n\n\n\n<p>Seine N\u00e4he zu THC bedeutet, dass es auch so ist <strong>psychoaktiv<\/strong>. Mit anderen Worten: Es macht high. Andererseits scheint es <strong>agieren Sie schneller und kraftvoller<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-produits-a-base-de-thcp\"><span class=\"ez-toc-section\" id=\"THCP-Produkte\"><\/span>THCP-Produkte<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n<div class=\"wp-block-image size-full wp-image-348718\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/weedy.fr\/wp-content\/uploads\/2023\/08\/Produits-cannabis-THCP-min.jpg\" alt=\"Cannabisprodukte thcp min\" class=\"wp-image-348718\"><figcaption class=\"wp-element-caption\">Von Blumen \u00fcber Harze bis hin zu Lebensmitteln gibt es viele THCP-Derivate<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Mit zunehmender Bekanntheit von THCP w\u00e4chst auch die Anzahl der auf dem Markt erh\u00e4ltlichen Produkte. Da es sich um ein nat\u00fcrliches Cannabinoid handelt, k\u00f6nnen wir das <strong>Kaufen Sie Blumen, Pollen und Harze, die reich an THCP sind<\/strong>. Wir finden auch <strong>THCP-Isolate<\/strong> in allen Arten von Derivaten, von Konzentraten bis hin zu Vape-Produkten, einschlie\u00dflich essbarer Derivate (insbesondere S\u00fc\u00dfigkeiten). Dennoch bleibt es wichtig, sich \u00fcber die Qualit\u00e4t des Produkts und die Entwicklung der Vorschriften zu informieren, um potenzielle Risiken im Zusammenhang mit seinem Konsum zu vermeiden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-effets-secondaires-et-precautions-d-usage\"><span class=\"ez-toc-section\" id=\"Nebenwirkungen_und_Vorsichtsmasnahmen_fur_die_Anwendung\"><\/span>Nebenwirkungen und Vorsichtsma\u00dfnahmen f\u00fcr die Anwendung<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n<div class=\"wp-block-image size-full wp-image-348716\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/weedy.fr\/wp-content\/uploads\/2023\/08\/Effets-secondaires-THCP-min.jpg\" alt=\"thcp min Nebenwirkungen\" class=\"wp-image-348716\"><figcaption class=\"wp-element-caption\">Wie THC kann THCP Stimmungsschwankungen und kognitive Ver\u00e4nderungen verursachen<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Wie bei jedem Wirkstoff kann auch THCP vorhanden sein <strong>Nebenwirkungen<\/strong>. Erste Studien deuten darauf hin, dass Auswirkungen wie z <strong>Stimmungsschwankungen<\/strong>, des <strong>kognitive Ver\u00e4nderungen<\/strong> Und <strong>Magen-Darm-St\u00f6rungen<\/strong> k\u00f6nnte passieren. Es ist wichtig zu beachten, dass diese Ergebnisse vorl\u00e4ufig sind und dass die Forschung weiterhin ein umfassenderes Bild der positiven und negativen Auswirkungen von THCP erhalten muss.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-effets-secondaires-potentiels\"><span class=\"ez-toc-section\" id=\"Mogliche_Nebenwirkungen\"><\/span>M\u00f6gliche Nebenwirkungen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Past\u00f6ser Mund<\/li>\n\n\n\n<li>Erm\u00fcdung<\/li>\n\n\n\n<li>Schl\u00e4frigkeit<\/li>\n\n\n\n<li>Rote Augen<\/li>\n\n\n\n<li>Erh\u00f6hter Appetit<\/li>\n\n\n\n<li>Magen-Darm-St\u00f6rung<\/li>\n\n\n\n<li>Tachykardie<\/li>\n\n\n\n<li>Stimmungsschwankungen<\/li>\n\n\n\n<li>Kognitive Ver\u00e4nderungen (Verwirrung, leichte Paranoia)<\/li>\n<\/ul>\n\n\n\n<p>Kurz gesagt, THCP ist ein aufregendes und vielversprechendes Cannabinoid, das sicherlich viele zuk\u00fcnftige Forschungen zu Cannabis beeinflussen wird. Seine Wirkung auf das Endocannabinoidsystem verleiht ihm eine <strong>interessantes Potenzial<\/strong>, sondern stellt auch seine in Frage <strong>m\u00f6gliche langfristige Gefahren<\/strong> oder auf bestimmte Kategorien von Menschen. Wie bei <a href=\"https:\/\/weedy.fr\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD<\/a> und THC k\u00f6nnen wir tats\u00e4chlich davon ausgehen, dass ein Risiko besteht<a href=\"https:\/\/weedy.fr\/blog\/interactions-medicamenteuses-et-cbd\/\">Arzneimittelwechselwirkung<\/a> mit bestimmten Behandlungen. Die Tatsache, dass es psychoaktiv ist, k\u00f6nnte auch zu einem Verbot oder in jedem Fall f\u00fchren <strong>in naher Zukunft reguliert werden<\/strong>.<\/p>\n\n\n\n<p>Derzeit sind <a href=\"https:\/\/weedy.fr\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD<\/a>-Produkte nach wie vor die sicherste und ges\u00fcndeste M\u00f6glichkeit, von der Wirkung von Cannabis zu profitieren. Tats\u00e4chlich ist es v\u00f6llig legal, macht nicht high und war bereits Gegenstand zahlreicher Untersuchungen. Wenn Sie davon profitieren m\u00f6chten, gehen Sie in den Laden, um sie (wieder) zu entdecken <a href=\"https:\/\/weedy.fr\/product-category\/fleurs-de-cbd\/\">Blumen<\/a>, <a href=\"https:\/\/weedy.fr\/product-category\/resines-cbd\/\">Harze<\/a>, <a href=\"https:\/\/weedy.fr\/product-category\/huiles-cbd\/\">\u00d6le<\/a>, <a href=\"https:\/\/weedy.fr\/product-category\/cbd-alimentaire\/infusions-cbd\/\">Aufg\u00fcsse<\/a>, Wellnessprodukte oder <a href=\"https:\/\/weedy.fr\/product-category\/e-liquides-cbd\/\">CBD-Vape-Produkte<\/a>.<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Die Welt des Cannabis entwickelt sich rasant weiter und mit ihr auch unser Verst\u00e4ndnis der vielen darin enthaltenen Verbindungen. Unter ihnen sind die THCP zieht aufgrund seiner einzigartigen Eigenschaften und seines Potenzials immer mehr Interesse auf sich. Es wurde Ende der 2010er Jahre in der Cannabispflanze entdeckt und fasziniert seit jeher mit seiner Kraft bis [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":351503,"comment_status":"open","ping_status":"closed","sticky":false,"template":"Standard\n","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":"\n"},"categories":[695],"tags":[],"class_list":["post-360388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anbau-von-cbd-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Was ist THCP oder \u03949-Tetrahydrocannabiphorol? - Actualit\u00e9s CBD Blog - Weedy.fr<\/title>\n<meta name=\"description\" content=\"Entdecken Sie THCP, ein Cannabinoid, das m\u00f6glicherweise st\u00e4rker ist als THC. Entdecken Sie seine Eigenschaften und Wirkung\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-\u03b49-tetrahydrocannabiphorol\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83c\udf31Was ist THCP oder \u03949-Tetrahydrocannabiphorol? - Weedy.Fr\ud83c\udf31\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie THCP, ein Cannabinoid, das m\u00f6glicherweise st\u00e4rker ist als THC. Entdecken Sie seine Eigenschaften und Wirkung\" \/>\n<meta property=\"og:url\" content=\"https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-\u03b49-tetrahydrocannabiphorol\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualit\u00e9s CBD Blog - Weedy.fr\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/weedysocial\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-17T16:01:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-17T16:01:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2023\/08\/thcp-cest-quoi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"arthur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"arthur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/de\\\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/de\\\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\\\/\"},\"author\":{\"name\":\"arthur\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#\\\/schema\\\/person\\\/0a05724dbfcfa68f2ce947d2ebf0f435\"},\"headline\":\"Was ist THCP oder \u03949-Tetrahydrocannabiphorol?\",\"datePublished\":\"2024-09-17T16:01:26+00:00\",\"dateModified\":\"2024-09-17T16:01:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/de\\\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\\\/\"},\"wordCount\":974,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/de\\\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/thcp-cest-quoi.jpg\",\"articleSection\":[\"Anbau von CBD\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/weedy.fr\\\/blog\\\/de\\\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/de\\\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\\\/\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/de\\\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\\\/\",\"name\":\"Was ist THCP oder \u03949-Tetrahydrocannabiphorol? - Actualit\u00e9s CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/de\\\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/de\\\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/thcp-cest-quoi.jpg\",\"datePublished\":\"2024-09-17T16:01:26+00:00\",\"dateModified\":\"2024-09-17T16:01:28+00:00\",\"description\":\"Entdecken Sie THCP, ein Cannabinoid, das m\u00f6glicherweise st\u00e4rker ist als THC. Entdecken Sie seine Eigenschaften und Wirkung\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/de\\\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/weedy.fr\\\/blog\\\/de\\\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/de\\\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\\\/#primaryimage\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/thcp-cest-quoi.jpg\",\"contentUrl\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/thcp-cest-quoi.jpg\",\"width\":1600,\"height\":800,\"caption\":\"thcp-cest-quoi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/de\\\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anbau von CBD\",\"item\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/category\\\/anbau-von-cbd-de\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Was ist THCP oder \u03949-Tetrahydrocannabiphorol?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/\",\"name\":\"Actualit\u00e9s CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualit\u00e9 du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-carre.jpg\",\"contentUrl\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/weedysocial\",\"https:\\\/\\\/www.instagram.com\\\/weedyfrance\\\/\"],\"description\":\"Leader en france sur la vente de produits \u00e0 base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#\\\/schema\\\/person\\\/0a05724dbfcfa68f2ce947d2ebf0f435\",\"name\":\"arthur\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"caption\":\"arthur\"},\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/author\\\/arthur\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Was ist THCP oder \u03949-Tetrahydrocannabiphorol? - Actualit\u00e9s CBD Blog - Weedy.fr","description":"Entdecken Sie THCP, ein Cannabinoid, das m\u00f6glicherweise st\u00e4rker ist als THC. Entdecken Sie seine Eigenschaften und Wirkung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-\u03b49-tetrahydrocannabiphorol\/","og_locale":"fr_FR","og_type":"article","og_title":"\ud83c\udf31Was ist THCP oder \u03949-Tetrahydrocannabiphorol? - Weedy.Fr\ud83c\udf31","og_description":"Entdecken Sie THCP, ein Cannabinoid, das m\u00f6glicherweise st\u00e4rker ist als THC. Entdecken Sie seine Eigenschaften und Wirkung","og_url":"https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-\u03b49-tetrahydrocannabiphorol\/","og_site_name":"Actualit\u00e9s CBD Blog - Weedy.fr","article_publisher":"https:\/\/www.facebook.com\/weedysocial","article_published_time":"2024-09-17T16:01:26+00:00","article_modified_time":"2024-09-17T16:01:28+00:00","og_image":[{"width":1600,"height":800,"url":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2023\/08\/thcp-cest-quoi.jpg","type":"image\/jpeg"}],"author":"arthur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"arthur","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\/#article","isPartOf":{"@id":"https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\/"},"author":{"name":"arthur","@id":"https:\/\/weedy.fr\/blog\/#\/schema\/person\/0a05724dbfcfa68f2ce947d2ebf0f435"},"headline":"Was ist THCP oder \u03949-Tetrahydrocannabiphorol?","datePublished":"2024-09-17T16:01:26+00:00","dateModified":"2024-09-17T16:01:28+00:00","mainEntityOfPage":{"@id":"https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\/"},"wordCount":974,"commentCount":0,"publisher":{"@id":"https:\/\/weedy.fr\/blog\/#organization"},"image":{"@id":"https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\/#primaryimage"},"thumbnailUrl":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2023\/08\/thcp-cest-quoi.jpg","articleSection":["Anbau von CBD"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\/","url":"https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\/","name":"Was ist THCP oder \u03949-Tetrahydrocannabiphorol? - Actualit\u00e9s CBD Blog - Weedy.fr","isPartOf":{"@id":"https:\/\/weedy.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\/#primaryimage"},"image":{"@id":"https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\/#primaryimage"},"thumbnailUrl":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2023\/08\/thcp-cest-quoi.jpg","datePublished":"2024-09-17T16:01:26+00:00","dateModified":"2024-09-17T16:01:28+00:00","description":"Entdecken Sie THCP, ein Cannabinoid, das m\u00f6glicherweise st\u00e4rker ist als THC. Entdecken Sie seine Eigenschaften und Wirkung","breadcrumb":{"@id":"https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\/#primaryimage","url":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2023\/08\/thcp-cest-quoi.jpg","contentUrl":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2023\/08\/thcp-cest-quoi.jpg","width":1600,"height":800,"caption":"thcp-cest-quoi"},{"@type":"BreadcrumbList","@id":"https:\/\/weedy.fr\/blog\/de\/was-ist-thcp-oder-%ce%b49-tetrahydrocannabiphorol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https:\/\/weedy.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Anbau von CBD","item":"https:\/\/weedy.fr\/blog\/category\/anbau-von-cbd-de\/"},{"@type":"ListItem","position":3,"name":"Was ist THCP oder \u03949-Tetrahydrocannabiphorol?"}]},{"@type":"WebSite","@id":"https:\/\/weedy.fr\/blog\/#website","url":"https:\/\/weedy.fr\/blog\/","name":"Actualit\u00e9s CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualit\u00e9 du CBD et du chanvre en France","publisher":{"@id":"https:\/\/weedy.fr\/blog\/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/weedy.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/weedy.fr\/blog\/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https:\/\/weedy.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/weedy.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/05\/logo-carre.jpg","contentUrl":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/05\/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https:\/\/weedy.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/weedysocial","https:\/\/www.instagram.com\/weedyfrance\/"],"description":"Leader en france sur la vente de produits \u00e0 base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https:\/\/weedy.fr\/blog\/#\/schema\/person\/0a05724dbfcfa68f2ce947d2ebf0f435","name":"arthur","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","caption":"arthur"},"url":"https:\/\/weedy.fr\/blog\/author\/arthur\/"}]}},"_links":{"self":[{"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/posts\/360388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/comments?post=360388"}],"version-history":[{"count":1,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/posts\/360388\/revisions"}],"predecessor-version":[{"id":360389,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/posts\/360388\/revisions\/360389"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/media\/351503"}],"wp:attachment":[{"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/media?parent=360388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/categories?post=360388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/tags?post=360388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}