{"id":360448,"date":"2024-09-17T18:02:50","date_gmt":"2024-09-17T16:02:50","guid":{"rendered":"https:\/\/weedy.fr\/blog\/?p=360448"},"modified":"2024-09-17T18:02:51","modified_gmt":"2024-09-17T16:02:51","slug":"sono-oleo-cbd-ou-cbg-para-dormir","status":"publish","type":"post","link":"https:\/\/weedy.fr\/blog\/pt\/sono-oleo-cbd-ou-cbg-para-dormir\/","title":{"rendered":"Sono: \u00f3leo CBD ou CBG para dormir?"},"content":{"rendered":"<p>Todos sabemos que uma noite ruim pode arruinar um dia. A longo prazo, por\u00e9m, a falta de sono pode ter implica\u00e7\u00f5es muito mais graves para a nossa sa\u00fade f\u00edsica, mental e emocional. A falta de energia \u00e9 a mais \u00f3bvia, mas pode vir acompanhada de problemas de concentra\u00e7\u00e3o, enfraquecimento do nosso sistema imunit\u00e1rio e impactar as nossas rela\u00e7\u00f5es pessoais e profissionais.<\/p>\n<p>Calmante, o <strong>canabidiol (<a href=\"https:\/\/weedy.fr\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD<\/a>)<\/strong> tem sido amplamente utilizado h\u00e1 v\u00e1rios anos para encontrar um<strong> melhor qualidade de sono<\/strong>. No entanto, est\u00e1 longe de ser o \u00fanico canabin\u00f3ide que promove o relaxamento. Seu primo <strong>canabigerol (<a href=\"https:\/\/weedy.fr\/blog\/tout-savoir-sur-le-cbg-le-cannabinoide-oublie-du-cannabis\/\" data-internallinksmanager029f6b8e52c=\"11\" title=\"cbg - cannabigerol\">CBG<\/a>)<\/strong> tamb\u00e9m \u00e9 um <strong>relaxante natural<\/strong>.<\/p>\n<p>Ent\u00e3o, \u00e9 melhor levar <strong><a href=\"https:\/\/weedy.fr\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD<\/a> ou <a href=\"https:\/\/weedy.fr\/blog\/tout-savoir-sur-le-cbg-le-cannabinoide-oublie-du-cannabis\/\" data-internallinksmanager029f6b8e52c=\"11\" title=\"cbg - cannabigerol\">CBG<\/a> para dormir<\/strong> ? E, al\u00e9m disso, temos mesmo que escolher? Respostas imediatamente.<br \/>\n<img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-344333\" src=\"https:\/\/weedy.fr\/wp-content\/uploads\/2023\/06\/CBD-ou-CBG-pour-dormir-min.jpg\" alt=\"cbd ou cbg para dormir min\" width=\"900\" height=\"600\"><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/weedy.fr\/blog\/pt\/sono-oleo-cbd-ou-cbg-para-dormir\/#Por_que_dormimos_mal\" >Por que dormimos mal?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/weedy.fr\/blog\/pt\/sono-oleo-cbd-ou-cbg-para-dormir\/#Efeitos_dos_oleos_CBD_e_CBG_para_um_sono_melhor\" >Efeitos dos \u00f3leos CBD e CBG para um sono melhor<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/weedy.fr\/blog\/pt\/sono-oleo-cbd-ou-cbg-para-dormir\/#CBD_e_sono\" >CBD e sono<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/weedy.fr\/blog\/pt\/sono-oleo-cbd-ou-cbg-para-dormir\/#CBG_e_sono\" >CBG e sono<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/weedy.fr\/blog\/pt\/sono-oleo-cbd-ou-cbg-para-dormir\/#Para_concluir_deve_escolher_entre_CBD_e_CBG\" >Para concluir: deve escolher entre CBD e CBG?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/weedy.fr\/blog\/pt\/sono-oleo-cbd-ou-cbg-para-dormir\/#Quais_derivados_de_CBD_ou_CBG_para_dormir\" >Quais derivados de CBD ou CBG para dormir?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/weedy.fr\/blog\/pt\/sono-oleo-cbd-ou-cbg-para-dormir\/#Alguns_exemplos_de_derivados_que_podem_melhorar_a_qualidade_do_sono\" >Alguns exemplos de derivados que podem melhorar a qualidade do sono<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Por_que_dormimos_mal\"><\/span>Por que dormimos mal?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Segundo o Inserm, <a href=\"https:\/\/www.inserm.fr\/dossier\/insomnie\/\" target=\"_blank\" rel=\"noopener\">15 a 20% dos franceses<\/a> s\u00e3o afetados pelo<strong>ins\u00f4nia<\/strong>, 50% dos quais apresentam forma grave. Sem chegar a esse extremo, <a href=\"https:\/\/www.geo.fr\/voyage\/le-sommeil-des-francais-en-12-chiffres-cles-186164\" target=\"_blank\" rel=\"noopener\">73% dos franceses<\/a> declarar <strong>acorde pelo menos uma vez por noite<\/strong> por 10 minutos ou mais. Tudo isso para dizer que dormir mal infelizmente n\u00e3o \u00e9 um fen\u00f4meno isolado.<\/p>\n<p>As raz\u00f5es para isso s\u00e3o m\u00faltiplas e variam de um indiv\u00edduo para outro. Aqui est\u00e3o alguns dos mais comuns:<\/p>\n<ul>\n<li><strong>Estresse e ansiedade<\/strong>: O estresse di\u00e1rio, as preocupa\u00e7\u00f5es e os transtornos de ansiedade podem dificultar o adormecimento e a manuten\u00e7\u00e3o do sono profundo.<\/li>\n<li><strong>Problemas de sono<\/strong> : ins\u00f4nia, apn\u00e9ia do sono, s\u00edndrome das pernas inquietas em particular.<\/li>\n<li><strong>Fatores ambientais<\/strong> : luz, ru\u00eddo, temperatura ou mesmo conforto da cama.<\/li>\n<li><strong>Maus h\u00e1bitos<\/strong>: hor\u00e1rios irregulares de sono, cochilos excessivos, consumo de cafe\u00edna ou outros estimulantes antes de dormir, uso excessivo de dispositivos eletr\u00f4nicos (computador, tablet ou smartphone que emitem luz azul).<\/li>\n<li><strong>Condi\u00e7\u00f5es M\u00e9dicas<\/strong> : principalmente dor.<\/li>\n<li><strong>Drogas<\/strong> : certos medicamentos podem estimular a ins\u00f4nia ou, pelo contr\u00e1rio, a sonol\u00eancia.<\/li>\n<li><strong>Problemas de sa\u00fade mental<\/strong>.<\/li>\n<\/ul>\n<p>Em caso de ins\u00f3nia prolongada, o acompanhamento m\u00e9dico personalizado \u00e9 obviamente fortemente recomendado. Alguns <strong>m\u00e9todos naturais<\/strong>, incluindo a toma de canabin\u00f3ides como <a href=\"https:\/\/weedy.fr\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD<\/a> e CBG, pode, no entanto, ajudar a remediar esta situa\u00e7\u00e3o.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Efeitos_dos_oleos_CBD_e_CBG_para_um_sono_melhor\"><\/span>Efeitos dos \u00f3leos CBD e CBG para um sono melhor<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img decoding=\"async\" class=\"size-full wp-image-344335\" src=\"https:\/\/weedy.fr\/wp-content\/uploads\/2023\/06\/Effets-CBD-CBG-sommeil-min.jpg\" alt=\"efeitos cbd cbg sono min\" width=\"900\" height=\"675\"><br \/>\nOs \u00f3leos CBD e CBG s\u00e3o compostos \u00e0 base de \u00f3leo vegetal (c\u00e2nhamo ou MCT, por exemplo) e enriquecidos com extra\u00e7\u00e3o de canabin\u00f3ides. Permitem, portanto, uma <strong>dosagem precisa<\/strong> da sua quantidade e <strong>maximizar assim os efeitos do CBD, CBG<\/strong> ou ambas as mol\u00e9culas combinadas.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"CBD_e_sono\"><\/span>CBD e sono<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>O CBD \u00e9 o canabin\u00f3ide cujos efeitos s\u00e3o mais conhecidos. A a\u00e7\u00e3o direta de <a href=\"https:\/\/weedy.fr\/blog\/bien-dormir-grace-au-cbd\/\">CBD no sono<\/a> no entanto, ainda \u00e9 pouco compreendido e os mais c\u00e9pticos evocam um simples efeito placebo. No entanto, de acordo com indiv\u00edduos e estudos, at\u00e9 mais de 50% dos seus consumidores declaram que <strong>O \u00f3leo CBD os ajuda a dormir melhor<\/strong>.<\/p>\n<p>Mais especificamente, o CBD poderia ajudar:<\/p>\n<ul>\n<li>Relaxe antes de adormecer,<\/li>\n<li>Adormecer mais r\u00e1pido,<\/li>\n<li>Durma mais profundamente,<\/li>\n<li>Voltar a dormir mais facilmente \u00e0 noite<\/li>\n<li>Sinta-se menos cansado durante o dia.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"CBG_e_sono\"><\/span>CBG e sono<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Pesquisa sobre o <a href=\"https:\/\/weedy.fr\/blog\/cbg-definition\/\">CBG<\/a>, O <a href=\"https:\/\/weedy.frhttps:\/\/weedy.fr\/blog\/quest-ce-que-le-cbga\/\">CBGA<\/a> (sua forma \u00e1cida) e sua influ\u00eancia no sono ainda s\u00e3o limitadas. No entanto, o<strong>a\u00e7\u00e3o relaxante do CBG<\/strong> parece o mais \u00f3bvio, e \u00e9 por isso que \u00e9 amplamente utilizado no <a href=\"https:\/\/weedy.fr\/blog\/effets-du-cbd-et-sport\/\">esporte<\/a>. No que diz respeito ao sono, as suas propriedades previstas s\u00e3o bastante interessantes:<\/p>\n<ul>\n<li><strong>Relaxamento<\/strong>: tal como o CBD, o CBG \u00e9 conhecido pelas suas propriedades relaxantes, promovendo um estado de calma e relaxamento.<\/li>\n<li><strong>Intera\u00e7\u00e3o com o sistema endocanabinoide<\/strong> (SEC): \u00e9 capaz de interagir com receptores ECS, que desempenham papel na regula\u00e7\u00e3o de diversos processos fisiol\u00f3gicos, incluindo o ciclo sono-vig\u00edlia.<\/li>\n<li><strong>A\u00e7\u00e3o sobre a serotonina <\/strong>: O CBG pode promover a produ\u00e7\u00e3o de serotonina, um neurotransmissor envolvido na regula\u00e7\u00e3o do humor e do sono.<\/li>\n<li><strong>Anti-inflamat\u00f3rio<\/strong>: ao promover o relaxamento muscular e reduzir a inflama\u00e7\u00e3o, o CBG pode reduzir a dor que perturba o sono.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Para_concluir_deve_escolher_entre_CBD_e_CBG\"><\/span>Para concluir: deve escolher entre CBD e CBG?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img decoding=\"async\" class=\"size-full wp-image-344336\" src=\"https:\/\/weedy.fr\/wp-content\/uploads\/2023\/06\/Huile-CBG-et-CBG-pour-mieux-dormir-min.jpg\" alt=\"\u00f3leo cbg e cbg para dormir melhor min\" width=\"900\" height=\"600\"><br \/>\nVoc\u00ea ter\u00e1 entendido, CBD e CBG s\u00e3o mol\u00e9culas com numerosos <strong>efeitos virtuosos e complementares<\/strong>. Eles tamb\u00e9m s\u00e3o produzidos pela mesma f\u00e1brica e <strong>pode combinar perfeitamente<\/strong>. N\u00e3o h\u00e1, portanto, raz\u00e3o para escolher entre as duas e h\u00e1 cada vez mais derivados de qualidade combinando as duas mol\u00e9culas, ou mesmo outras.<\/p>\n<p>Os canabin\u00f3ides est\u00e3o de facto longe de ter dito a sua \u00faltima palavra e o <a href=\"https:\/\/weedy.fr\/blog\/quest-ce-que-le-cbn-cannabinol\/\">canabinol (CBN)<\/a> tamb\u00e9m \u00e9 estudado por sua a\u00e7\u00e3o na qualidade do sono.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Quais_derivados_de_CBD_ou_CBG_para_dormir\"><\/span>Quais derivados de CBD ou CBG para dormir?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-344334\" src=\"https:\/\/weedy.fr\/wp-content\/uploads\/2023\/06\/Derive-CBG-sommeil-min.jpg\" alt=\"derivado cbg sono min\" width=\"900\" height=\"600\"><br \/>\nProdutos crus (<a href=\"https:\/\/weedy.fr\/product-category\/fleurs-de-cbd\/\">Flores CBD<\/a>) ou muito pouco processado (<a href=\"https:\/\/weedy.fr\/product-category\/resines-cbd\/\">resinas e p\u00f3lenes<\/a>) cont\u00eam naturalmente canabin\u00f3ides. Na grande maioria dos casos, isto envolve um produto com <strong>mais CBD do que CBG<\/strong> ou qualquer outra subst\u00e2ncia.<\/p>\n<p>Para poder gerenciar com precis\u00e3o as taxas e ajustar a quantidade de CBD e\/ou CBG ao que voc\u00ea deseja, \u00e9 mais simples escolher um derivado que utilize <strong>extratos<\/strong>. O <a href=\"https:\/\/weedy.fr\/product-category\/huiles-cbd\/\">\u00d3leos CBD e CBG<\/a> s\u00e3o ent\u00e3o os produtos mais comuns <strong>f\u00e1cil de acessar<\/strong>, <strong>conveniente de usar<\/strong> E <strong>saud\u00e1vel<\/strong> no seu consumo.<\/p>\n<p>Tamb\u00e9m \u00e9 poss\u00edvel consumir um <a href=\"https:\/\/weedy.fr\/product-category\/cbd-alimentaire\/infusions-cbd\/\">infus\u00e3o de c\u00e2nhamo<\/a>, idealmente complementado com alguns <strong>Gotas de \u00f3leo CBD + CBG<\/strong> de sua escolha. Isto permite adicionar gordura essencial ao <strong>boa assimila\u00e7\u00e3o de canabin\u00f3ides<\/strong> pelo corpo e aumenta o conte\u00fado de CBD e CBG da bebida.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Alguns_exemplos_de_derivados_que_podem_melhorar_a_qualidade_do_sono\"><\/span>Alguns exemplos de derivados que podem melhorar a qualidade do sono<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><a href=\"https:\/\/weedy.fr\/product\/huile-sport-5\">\u00d3leo esportivo CBD + CBG<\/a> (5 a 40% de canabin\u00f3ides)<\/li>\n<li><a href=\"https:\/\/weedy.fr\/product\/huile-relax-5\">\u00d3leo CBD + CBN Relaxante<\/a> (5 a 30% de canabin\u00f3ides)<\/li>\n<li><a href=\"https:\/\/weedy.fr\/product\/huile-equilibre-20\">CBD + CBG + CBN + \u00d3leo de Equil\u00edbrio CBC<\/a> (5 a 30% de canabin\u00f3ides)<\/li>\n<li><a href=\"https:\/\/weedy.fr\/product-category\/cbd-alimentaire\/infusions-cbd\/\">Ch\u00e1 de c\u00e2nhamo CBD para noite calma<\/a><\/li>\n<li><a href=\"https:\/\/weedy.fr\">Infus\u00e3o relaxante<\/a><\/li>\n<li><a href=\"https:\/\/weedy.fr\/product\/bubble-hash-cbd-cbg-ketama\">Bubble hash CBD\/CBG Ketama<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Todos sabemos que uma noite ruim pode arruinar um dia. A longo prazo, por\u00e9m, a falta de sono pode ter implica\u00e7\u00f5es muito mais graves para a nossa sa\u00fade f\u00edsica, mental e emocional. A falta de energia \u00e9 a mais \u00f3bvia, mas pode vir acompanhada de problemas de concentra\u00e7\u00e3o, enfraquecimento do nosso sistema imunit\u00e1rio e impactar [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":352579,"comment_status":"open","ping_status":"closed","sticky":false,"template":"padr\u00e3o\n","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[672],"tags":[],"class_list":["post-360448","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude-e-bem-estar-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sono: \u00f3leo CBD ou CBG para dormir? - Actualit\u00e9s CBD Blog - Weedy.fr<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/weedy.fr\/blog\/pt\/sono-oleo-cbd-ou-cbg-para-dormir\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83c\udf31Sono: \u00f3leo CBD ou CBG para dormir? - Weedy.Fr\ud83c\udf31\" \/>\n<meta property=\"og:description\" content=\"Todos sabemos que uma noite ruim pode arruinar um dia. A longo prazo, por\u00e9m, a falta de sono pode ter implica\u00e7\u00f5es muito mais graves para a nossa sa\u00fade f\u00edsica, mental e emocional. A falta de energia \u00e9 a mais \u00f3bvia, mas pode vir acompanhada de problemas de concentra\u00e7\u00e3o, enfraquecimento do nosso sistema imunit\u00e1rio e impactar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/weedy.fr\/blog\/pt\/sono-oleo-cbd-ou-cbg-para-dormir\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualit\u00e9s CBD Blog - Weedy.fr\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/weedysocial\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-17T16:02:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-17T16:02:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/05\/sommeil-huile-de-cbd-ou-cbg-pour-dormir.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1792\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"arthur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"arthur\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/sono-oleo-cbd-ou-cbg-para-dormir\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/sono-oleo-cbd-ou-cbg-para-dormir\\\/\"},\"author\":{\"name\":\"arthur\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#\\\/schema\\\/person\\\/0a05724dbfcfa68f2ce947d2ebf0f435\"},\"headline\":\"Sono: \u00f3leo CBD ou CBG para dormir?\",\"datePublished\":\"2024-09-17T16:02:50+00:00\",\"dateModified\":\"2024-09-17T16:02:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/sono-oleo-cbd-ou-cbg-para-dormir\\\/\"},\"wordCount\":959,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/sono-oleo-cbd-ou-cbg-para-dormir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/sommeil-huile-de-cbd-ou-cbg-pour-dormir.jpg\",\"articleSection\":[\"Sa\u00fade e Bem-estar\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/sono-oleo-cbd-ou-cbg-para-dormir\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/sono-oleo-cbd-ou-cbg-para-dormir\\\/\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/sono-oleo-cbd-ou-cbg-para-dormir\\\/\",\"name\":\"Sono: \u00f3leo CBD ou CBG para dormir? - Actualit\u00e9s CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/sono-oleo-cbd-ou-cbg-para-dormir\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/sono-oleo-cbd-ou-cbg-para-dormir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/sommeil-huile-de-cbd-ou-cbg-pour-dormir.jpg\",\"datePublished\":\"2024-09-17T16:02:50+00:00\",\"dateModified\":\"2024-09-17T16:02:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/sono-oleo-cbd-ou-cbg-para-dormir\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/sono-oleo-cbd-ou-cbg-para-dormir\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/sono-oleo-cbd-ou-cbg-para-dormir\\\/#primaryimage\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/sommeil-huile-de-cbd-ou-cbg-pour-dormir.jpg\",\"contentUrl\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/sommeil-huile-de-cbd-ou-cbg-pour-dormir.jpg\",\"width\":1792,\"height\":1024,\"caption\":\"Sleep: CBD or CBG oil for sleep?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/sono-oleo-cbd-ou-cbg-para-dormir\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sa\u00fade e Bem-estar\",\"item\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/category\\\/saude-e-bem-estar-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sono: \u00f3leo CBD ou CBG para dormir?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/\",\"name\":\"Actualit\u00e9s CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualit\u00e9 du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-carre.jpg\",\"contentUrl\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/weedysocial\",\"https:\\\/\\\/www.instagram.com\\\/weedyfrance\\\/\"],\"description\":\"Leader en france sur la vente de produits \u00e0 base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#\\\/schema\\\/person\\\/0a05724dbfcfa68f2ce947d2ebf0f435\",\"name\":\"arthur\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"caption\":\"arthur\"},\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/author\\\/arthur\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sono: \u00f3leo CBD ou CBG para dormir? - Actualit\u00e9s CBD Blog - Weedy.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/weedy.fr\/blog\/pt\/sono-oleo-cbd-ou-cbg-para-dormir\/","og_locale":"fr_FR","og_type":"article","og_title":"\ud83c\udf31Sono: \u00f3leo CBD ou CBG para dormir? - Weedy.Fr\ud83c\udf31","og_description":"Todos sabemos que uma noite ruim pode arruinar um dia. A longo prazo, por\u00e9m, a falta de sono pode ter implica\u00e7\u00f5es muito mais graves para a nossa sa\u00fade f\u00edsica, mental e emocional. A falta de energia \u00e9 a mais \u00f3bvia, mas pode vir acompanhada de problemas de concentra\u00e7\u00e3o, enfraquecimento do nosso sistema imunit\u00e1rio e impactar [&hellip;]","og_url":"https:\/\/weedy.fr\/blog\/pt\/sono-oleo-cbd-ou-cbg-para-dormir\/","og_site_name":"Actualit\u00e9s CBD Blog - Weedy.fr","article_publisher":"https:\/\/www.facebook.com\/weedysocial","article_published_time":"2024-09-17T16:02:50+00:00","article_modified_time":"2024-09-17T16:02:51+00:00","og_image":[{"width":1792,"height":1024,"url":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/05\/sommeil-huile-de-cbd-ou-cbg-pour-dormir.jpg","type":"image\/jpeg"}],"author":"arthur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"arthur","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/weedy.fr\/blog\/pt\/sono-oleo-cbd-ou-cbg-para-dormir\/#article","isPartOf":{"@id":"https:\/\/weedy.fr\/blog\/pt\/sono-oleo-cbd-ou-cbg-para-dormir\/"},"author":{"name":"arthur","@id":"https:\/\/weedy.fr\/blog\/#\/schema\/person\/0a05724dbfcfa68f2ce947d2ebf0f435"},"headline":"Sono: \u00f3leo CBD ou CBG para dormir?","datePublished":"2024-09-17T16:02:50+00:00","dateModified":"2024-09-17T16:02:51+00:00","mainEntityOfPage":{"@id":"https:\/\/weedy.fr\/blog\/pt\/sono-oleo-cbd-ou-cbg-para-dormir\/"},"wordCount":959,"commentCount":0,"publisher":{"@id":"https:\/\/weedy.fr\/blog\/#organization"},"image":{"@id":"https:\/\/weedy.fr\/blog\/pt\/sono-oleo-cbd-ou-cbg-para-dormir\/#primaryimage"},"thumbnailUrl":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/05\/sommeil-huile-de-cbd-ou-cbg-pour-dormir.jpg","articleSection":["Sa\u00fade e Bem-estar"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/weedy.fr\/blog\/pt\/sono-oleo-cbd-ou-cbg-para-dormir\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/weedy.fr\/blog\/pt\/sono-oleo-cbd-ou-cbg-para-dormir\/","url":"https:\/\/weedy.fr\/blog\/pt\/sono-oleo-cbd-ou-cbg-para-dormir\/","name":"Sono: \u00f3leo CBD ou CBG para dormir? - Actualit\u00e9s CBD Blog - Weedy.fr","isPartOf":{"@id":"https:\/\/weedy.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/weedy.fr\/blog\/pt\/sono-oleo-cbd-ou-cbg-para-dormir\/#primaryimage"},"image":{"@id":"https:\/\/weedy.fr\/blog\/pt\/sono-oleo-cbd-ou-cbg-para-dormir\/#primaryimage"},"thumbnailUrl":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/05\/sommeil-huile-de-cbd-ou-cbg-pour-dormir.jpg","datePublished":"2024-09-17T16:02:50+00:00","dateModified":"2024-09-17T16:02:51+00:00","breadcrumb":{"@id":"https:\/\/weedy.fr\/blog\/pt\/sono-oleo-cbd-ou-cbg-para-dormir\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/weedy.fr\/blog\/pt\/sono-oleo-cbd-ou-cbg-para-dormir\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/weedy.fr\/blog\/pt\/sono-oleo-cbd-ou-cbg-para-dormir\/#primaryimage","url":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/05\/sommeil-huile-de-cbd-ou-cbg-pour-dormir.jpg","contentUrl":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/05\/sommeil-huile-de-cbd-ou-cbg-pour-dormir.jpg","width":1792,"height":1024,"caption":"Sleep: CBD or CBG oil for sleep?"},{"@type":"BreadcrumbList","@id":"https:\/\/weedy.fr\/blog\/pt\/sono-oleo-cbd-ou-cbg-para-dormir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https:\/\/weedy.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Sa\u00fade e Bem-estar","item":"https:\/\/weedy.fr\/blog\/category\/saude-e-bem-estar-pt\/"},{"@type":"ListItem","position":3,"name":"Sono: \u00f3leo CBD ou CBG para dormir?"}]},{"@type":"WebSite","@id":"https:\/\/weedy.fr\/blog\/#website","url":"https:\/\/weedy.fr\/blog\/","name":"Actualit\u00e9s CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualit\u00e9 du CBD et du chanvre en France","publisher":{"@id":"https:\/\/weedy.fr\/blog\/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/weedy.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/weedy.fr\/blog\/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https:\/\/weedy.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/weedy.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/05\/logo-carre.jpg","contentUrl":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/05\/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https:\/\/weedy.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/weedysocial","https:\/\/www.instagram.com\/weedyfrance\/"],"description":"Leader en france sur la vente de produits \u00e0 base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https:\/\/weedy.fr\/blog\/#\/schema\/person\/0a05724dbfcfa68f2ce947d2ebf0f435","name":"arthur","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","caption":"arthur"},"url":"https:\/\/weedy.fr\/blog\/author\/arthur\/"}]}},"_links":{"self":[{"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/posts\/360448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/comments?post=360448"}],"version-history":[{"count":1,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/posts\/360448\/revisions"}],"predecessor-version":[{"id":360449,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/posts\/360448\/revisions\/360449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/media\/352579"}],"wp:attachment":[{"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/media?parent=360448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/categories?post=360448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/tags?post=360448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}