{"id":360816,"date":"2024-09-17T18:21:25","date_gmt":"2024-09-17T16:21:25","guid":{"rendered":"https:\/\/weedy.fr\/blog\/?p=360816"},"modified":"2024-09-17T18:21:26","modified_gmt":"2024-09-17T16:21:26","slug":"menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer","status":"publish","type":"post","link":"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/","title":{"rendered":"Menopausa, ondas de calor: o que o CBD pode fazer?"},"content":{"rendered":"<p>Uma pesquisa realizada nos Estados Unidos mostrou que <strong>27% das mulheres usaram cannabis<\/strong>, de uma forma ou de outra, para <strong>aliviar os sintomas da menopausa<\/strong>. No entanto, os reais efeitos da cannabis e dos seus canabin\u00f3ides (THC, <a href=\"https:\/\/weedy.fr\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD<\/a>, etc.) na menopausa ainda s\u00e3o pouco conhecidos e, para os consumidores, \u00e9 muitas vezes uma quest\u00e3o de testar o que funciona ou n\u00e3o.<\/p>\n<p>Por exemplo, o que pode <strong><a href=\"https:\/\/weedy.fr\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD<\/a> contra ondas de calor <\/strong>? Quais produtos consumir e por qu\u00ea? Que dosagem de <a href=\"https:\/\/weedy.fr\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD<\/a> favorecer durante a menopausa? <a href=\"https:\/\/weedy.fr\/\" data-internallinksmanager029f6b8e52c=\"8\" title=\"weedy\">Weedy.fr<\/a> faz um balan\u00e7o do que sabemos e ajuda voc\u00ea melhor <strong>entenda se e como consumir cannabis CBD durante a menopausa<\/strong>.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/#Cannabis_e_menopausa_a_ideia_nao_e_nova\" >Cannabis e menopausa: a ideia n\u00e3o \u00e9 nova<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/#CBD_contra_ondas_de_calor\" >CBD contra ondas de calor<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/#Outros_beneficios_do_CBD_para_a_menopausa\" >Outros benef\u00edcios do CBD para a menopausa<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/#Principais_sintomas_da_menopausa\" >Principais sintomas da menopausa<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/#CBD_para_combater_disturbios_do_sono_ligados_a_menopausa\" >CBD para combater dist\u00farbios do sono ligados \u00e0 menopausa<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/#Regular_o_humor_com_CBD\" >Regular o humor com CBD<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/#Aliviar_a_dor\" >Aliviar a dor<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/#Controle_a_sensacao_de_fome\" >Controle a sensa\u00e7\u00e3o de fome<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/#Oleo_de_canhamo_para_hidratar_a_pele_e_o_cabelo\" >\u00d3leo de c\u00e2nhamo para hidratar a pele e o cabelo<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/#Produtos_CBD_para_menopausa_e_ondas_de_calor\" >Produtos CBD para menopausa e ondas de calor<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/#Como_dosar_o_CBD_durante_a_menopausa\" >Como dosar o CBD durante a menopausa?<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Cannabis_e_menopausa_a_ideia_nao_e_nova\"><\/span>Cannabis e menopausa: a ideia n\u00e3o \u00e9 nova<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-315075\" src=\"https:\/\/weedy.fr\/wp-content\/uploads\/2022\/07\/CBD-contre-les-bouffees-de-chaleur-min.jpg\" alt=\"cbd contra ondas de calor min\" width=\"900\" height=\"600\"><br \/>\nEncontramos vest\u00edgios escritos do<strong>uso de cannabis contra a menopausa desde 1800<\/strong>. Ainda mais surpreendente \u00e9 que encontramos casos documentados em livros m\u00e9dicos ao mesmo tempo! E estes s\u00e3o apenas os casos conhecidos porque, recordemos, o c\u00e2nhamo (Cannabis L. Sativa) \u00e9 uma planta domesticada do <a href=\"https:\/\/www.lemonde.fr\/sciences\/article\/2021\/07\/27\/la-domestication-du-cannabis-une-histoire-vieille-de-12-000-ans_6089628_1650684.html\" target=\"_blank\" rel=\"noopener\">in\u00edcio do Neol\u00edtico<\/a>.<\/p>\n<p>H\u00e1 12 mil anos, certas variedades j\u00e1 eram utilizadas pelas suas propriedades. Na altura, pens\u00e1vamos simplesmente que a cannabis era m\u00e1gica e est\u00e1vamos longe de imaginar que continha dezenas, at\u00e9 mesmo centenas de canabin\u00f3ides. E portanto tantos compostos ativos, capazes de interagir mais ou menos fortemente com o nosso sistema endocanabinoide (SEC).<\/p>\n<p>O <a href=\"https:\/\/weedy.fr\/\">CDB<\/a> que acalma est\u00e1, portanto, longe de ser identificado, da mesma forma que o <a href=\"https:\/\/weedy.fr\/quest-ce-que-le-thc\">THC<\/a> e seus efeitos alucinantes.<\/p>\n<p>Sendo o THC proibido em Fran\u00e7a por ser considerado um narc\u00f3tico, como na maioria dos outros pa\u00edses europeus, a aten\u00e7\u00e3o recai logicamente sobre o canabidiol, 100% legal.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"CBD_contra_ondas_de_calor\"><\/span>CBD contra ondas de calor<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>At\u00e9 <a href=\"https:\/\/lamenopause.fr\/chiffres-clefs-de-menopause\/\" target=\"_blank\" rel=\"noopener\">70% das mulheres<\/a> sofrem de ondas de calor durante a menopausa. Esse sintoma n\u00e3o \u00e9 apenas desagrad\u00e1vel, mas dura em m\u00e9dia 7,4 anos! Portanto, \u00e9 dif\u00edcil ignor\u00e1-lo, at\u00e9 porque al\u00e9m da sensa\u00e7\u00e3o de calor intenso que o acompanha, algumas pessoas tamb\u00e9m experimentam <strong>vermelhid\u00e3o<\/strong>, do <strong>suores<\/strong>, do <strong>calafrios<\/strong> e, em casos mais raros, <strong>tontura<\/strong>.<\/p>\n<p>Todas as solu\u00e7\u00f5es, especialmente as naturais, s\u00e3o, portanto, boas de tomar. No entanto, seria bem-vindo ter alguns dados cient\u00edficos um pouco mais documentados do que as recomenda\u00e7\u00f5es do seu vizinho.<\/p>\n<p>Para compreender melhor as esperan\u00e7as depositadas no <strong>consumo de CBD contra ondas de calor<\/strong>, vamos dar uma olhada no que acontece no corpo e causa ondas de calor durante a menopausa:<\/p>\n<ol>\n<li>O SEC, atrav\u00e9s de canabin\u00f3ides produzidos naturalmente pelo corpo (endocanabin\u00f3ides), participa na <strong>regula\u00e7\u00e3o da temperatura do corpo humano<\/strong>.<\/li>\n<li>O <strong>estrog\u00eanio<\/strong> est\u00e3o notavelmente envolvidos no metabolismo do SEC. Na \u00e9poca da menopausa, entretanto, sua taxa cai drasticamente, pois os ov\u00e1rios param de produzi-los.<\/li>\n<li>Devido \u00e0 diminui\u00e7\u00e3o da quantidade de estrog\u00eanios (principalmente estradiol), <strong>o \u201ctermostato\u201d natural<\/strong> fica perturbado, causando o aparecimento de ondas de calor.<\/li>\n<\/ol>\n<p>Conhecendo esse fen\u00f4meno, parece razo\u00e1vel pensar que<strong>atuar no SEC \u00e9 uma boa maneira de pelo menos reduzir a intensidade das ondas de calor durante a menopausa<\/strong>. E nada melhor do que canabinoides para isso? Al\u00e9m disso, a possibilidade de reduzir as ondas de calor pode n\u00e3o ser a \u00fanica vantagem do CBD durante a menopausa.<br \/>\n<img decoding=\"async\" class=\"size-full wp-image-315076\" src=\"https:\/\/weedy.fr\/wp-content\/uploads\/2022\/07\/CBD-et-menopause-min.jpg\" alt=\"CBD e menopausa min\" width=\"900\" height=\"600\"><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Outros_beneficios_do_CBD_para_a_menopausa\"><\/span>Outros benef\u00edcios do CBD para a menopausa<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>As ondas de calor est\u00e3o longe de ser o \u00fanico sintoma da menopausa. Dependendo de factores t\u00e3o diversos como a gen\u00e9tica, o ambiente e at\u00e9 a etnia, podem ser diversos e variados.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Principais_sintomas_da_menopausa\"><\/span>Principais sintomas da menopausa<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Ondas de calor<\/li>\n<li>Mudan\u00e7as (depois cessa\u00e7\u00e3o) do ciclo menstrual<\/li>\n<li>Ins\u00f4nia e outros dist\u00farbios do sono<\/li>\n<li>Fadiga<\/li>\n<li>Irritabilidade<\/li>\n<li>Pele, cabelo e vagina secos<\/li>\n<li>Dores de cabe\u00e7a<\/li>\n<li>Ganho de peso<\/li>\n<li>Incontin\u00eancia urin\u00e1ria<\/li>\n<li>Aumento do risco de osteoporose<\/li>\n<li>Aumento do risco de doen\u00e7as cardiovasculares<\/li>\n<\/ul>\n<p>N\u00e3o h\u00e1 motivo para alegria, mas felizmente \u00e9 poss\u00edvel que certos sintomas nunca apare\u00e7am e, se necess\u00e1rio, podem ser tratados ou pelo menos aliviados. Nos casos mais restritivos, um <strong>terapia de reposi\u00e7\u00e3o hormonal<\/strong> (THM) \u00e9 poss\u00edvel.<\/p>\n<p>Contudo, n\u00e3o \u00e9 sem <strong>efeitos colaterais<\/strong> (aumento do risco de cancro, acidente vascular cerebral e trombose venosa) e n\u00e3o parece prevenir o risco cardiovascular. Existem outros tratamentos n\u00e3o hormonais, cada um <strong>medicamento<\/strong> acompanhado de suas vantagens e desvantagens.<\/p>\n<p>Isto explica por que muitas mulheres preferem recorrer, sempre que poss\u00edvel sem riscos para a sua sa\u00fade, a <strong>mais rem\u00e9dios naturais<\/strong>. O CBD poderia ent\u00e3o ajudar a reduzir v\u00e1rios sintomas.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"CBD_para_combater_disturbios_do_sono_ligados_a_menopausa\"><\/span>CBD para combater dist\u00farbios do sono ligados \u00e0 menopausa<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>O SEC est\u00e1 disperso em diferentes locais do corpo. \u00c9, portanto, ativo em v\u00e1rios mecanismos do corpo humano. Ele \u00e9, portanto, particularmente respons\u00e1vel por <strong>manuten\u00e7\u00e3o da homeostase<\/strong>, um processo regulat\u00f3rio ligado, entre outras coisas, \u00e0 temperatura e \u00e0 circula\u00e7\u00e3o sangu\u00ednea.<\/p>\n<p>Ao agir nesse sentido, a CDB poderia contribuir notavelmente para <strong>adormecer com mais facilidade<\/strong> ent\u00e3o para <a href=\"https:\/\/weedy.fr\/blog\/bien-dormir-grace-au-cbd\/\">durma melhor<\/a> durante toda a noite.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Regular_o_humor_com_CBD\"><\/span>Regular o humor com CBD<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>O <strong>mudan\u00e7as de humor<\/strong> s\u00e3o um sintoma comum da menopausa ou qualquer outra perturba\u00e7\u00e3o hormonal. Eles podem ser acompanhados por um <strong>estado depressivo<\/strong> mais ou menos pronunciado. Mais uma vez, o CBD pode ajudar gra\u00e7as ao seu <strong>propriedades relaxantes<\/strong>. Na verdade, \u00e9 conhecido por sua capacidade de <a href=\"https:\/\/weedy.fr\/blog\/cbd-et-anxiete\/\">acalmar ataques de p\u00e2nico e ansiedade<\/a>, permitindo regular o humor.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Aliviar_a_dor\"><\/span>Aliviar a dor<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Durante a menopausa, as dores mais comuns s\u00e3o <a href=\"https:\/\/weedy.fr\/blog\/cbd-contre-le-mal-de-tete\/\">dor de cabe\u00e7a<\/a>. A interrup\u00e7\u00e3o do ciclo menstrual tamb\u00e9m pode despertar dores ligadas a<a href=\"https:\/\/weedy.fr\/blog\/cbd-et-endometriose\/\">endometriose<\/a>.<\/p>\n<p>Alguns estudos mostram a capacidade do CBD de <strong>acalme-os<\/strong> <strong>sinais de dor<\/strong>, em particular gra\u00e7as \u00e0 sua a\u00e7\u00e3o sobre certos horm\u00f4nios, incluindo <strong>serotonina<\/strong> que atua a n\u00edvel cerebral na regula\u00e7\u00e3o de diversas fun\u00e7\u00f5es fisiol\u00f3gicas (sono, dor, apetite, humor).<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Controle_a_sensacao_de_fome\"><\/span>Controle a sensa\u00e7\u00e3o de fome<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>N\u00e3o vamos cair em clich\u00eas, ao contr\u00e1rio do que alguns vendedores inescrupulosos de CBD \u00e0s vezes sugerem, este canabin\u00f3ide <a href=\"https:\/\/weedy.fr\/blog\/cbd-faire-perdre-du-poids\/\">n\u00e3o faz voc\u00ea perder peso<\/a>. No entanto, parece prov\u00e1vel que a CBD possa participar em <strong>controle da sensa\u00e7\u00e3o de fome<\/strong>. Portanto, n\u00e3o leva \u00e0 perda direta de peso, mas pode influenciar o nosso apetite de forma mais geral. Continua!<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Oleo_de_canhamo_para_hidratar_a_pele_e_o_cabelo\"><\/span>\u00d3leo de c\u00e2nhamo para hidratar a pele e o cabelo<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Finalmente, n\u00e3o devemos esquecer que o CBD \u00e9 extra\u00eddo do c\u00e2nhamo. Hidratante e nutritivo,<a href=\"https:\/\/weedy.fr\/blog\/tout-savoir-sur-lhuile-de-chanvre\/\">\u00f3leo de c\u00e2nhamo<\/a> \u00e9 um produto natural de escolha para <strong>aliviar a pele seca e couro cabeludo irritado<\/strong>, ou para restaurar o brilho dos cabelos opacos.<\/p>\n<p>Consumido na forma de sementes ou farinha, o c\u00e2nhamo tamb\u00e9m \u00e9 um <strong>superalimento<\/strong> repleto de fibras, prote\u00ednas e \u00e1cidos graxos que ajudam, entre outras coisas, a <strong>cuide da sua sa\u00fade cardiovascular<\/strong>.<br \/>\n<img decoding=\"async\" class=\"size-full wp-image-315074\" src=\"https:\/\/weedy.fr\/wp-content\/uploads\/2022\/07\/CBD-contre-la-menopause-min.jpg\" alt=\"CBD contra a menopausa min\" width=\"900\" height=\"600\"><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Produtos_CBD_para_menopausa_e_ondas_de_calor\"><\/span>Produtos CBD para menopausa e ondas de calor<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Sem ser uma cura milagrosa, o CBD parece ser capaz de ajudar a combater muitos dos efeitos indesejados da menopausa. Resta saber a quais produtos recorrer. O primeiro instinto a ter \u00e9 estar interessado na qualidade do CBD.<\/p>\n<p>Qualquer que seja o produto escolhido, \u00e9 importante privilegiar o CBD de boa qualidade, o que \u00e9 poss\u00edvel favorecendo:<\/p>\n<ul>\n<li>Um CBD de um <strong>agricultura amiga do ambiente<\/strong> (sem pesticidas ou metais pesados),<\/li>\n<li>UM <strong>extra\u00e7\u00e3o limpa<\/strong>, idealmente CO<sub>2<\/sub> (no caso de produtos processados, como \u00f3leo ou cremes CBD em particular),<\/li>\n<li>UM <strong>lista de ingredientes<\/strong> t\u00e3o limitado e natural quanto poss\u00edvel (evite conservantes e intensificadores de sabor).<\/li>\n<\/ul>\n<p>Depois de seguir essas regras, cabe a voc\u00ea encontrar o produto que melhor se adapta a voc\u00ea. O <a href=\"https:\/\/weedy.fr\/\">Loja CBD Weedy.fr<\/a> est\u00e1 cheio deles, todos atendendo a esses crit\u00e9rios! Uma tomada por <strong>via sublingual<\/strong> (debaixo da l\u00edngua) ou oral \u00e9, no entanto, o mais saud\u00e1vel. O <a href=\"https:\/\/weedy.fr\/product-category\/huiles-cbd\/\">\u00d3leos CBD<\/a> s\u00e3o, portanto, amplamente recomendados no contexto da menopausa, uma vez que s\u00e3o saud\u00e1veis, pr\u00e1ticos de usar e t\u00eam efeitos r\u00e1pidos.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Como_dosar_o_CBD_durante_a_menopausa\"><\/span>Como dosar o CBD durante a menopausa?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Existem muito poucos estudos cient\u00edficos aprofundados sobre as liga\u00e7\u00f5es entre o CBD e a menopausa. <strong>A dosagem ideal, portanto, n\u00e3o \u00e9 conhecida<\/strong> e provavelmente teria pouco interesse, uma vez que todos reagimos de forma diferente aos canabin\u00f3ides.<\/p>\n<p>Recomenda-se, portanto, <strong>comece com uma dose baixa<\/strong> (siga as instru\u00e7\u00f5es de uso do seu produto CBD), depois aumente aos poucos at\u00e9 obter os efeitos desejados. N\u00e3o h\u00e1 necessidade de temer: <a href=\"https:\/\/weedy.fr\/blog\/effets-secondaires-cbd\/\">efeitos colaterais do CBD<\/a> s\u00e3o raros e tamb\u00e9m \u00e9 imposs\u00edvel uma overdose. Contudo, uma overdose n\u00e3o seria \u00fatil e representaria uma despesa desnecess\u00e1ria.<\/p>\n<p>Uma boa regra geral \u00e9 come\u00e7ar com <strong>um miligrama de CBD por dia por 5 quilogramas de peso corporal<\/strong> (12 miligramas para uma pessoa de 60 kg, por exemplo). Em caso de d\u00favida, nosso guia dedicado para <a href=\"https:\/\/weedy.fr\/blog\/cbd-et-dosage\/\">Dosagem de CBD<\/a> d\u00e1-lhe exemplos concretos, adaptados ao tipo de produto selecionado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma pesquisa realizada nos Estados Unidos mostrou que 27% das mulheres usaram cannabis, de uma forma ou de outra, para aliviar os sintomas da menopausa. No entanto, os reais efeitos da cannabis e dos seus canabin\u00f3ides (THC, CBD, etc.) na menopausa ainda s\u00e3o pouco conhecidos e, para os consumidores, \u00e9 muitas vezes uma quest\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":41,"featured_media":352621,"comment_status":"open","ping_status":"closed","sticky":false,"template":"padr\u00e3o\n","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[672],"tags":[],"class_list":["post-360816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude-e-bem-estar-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Menopausa, ondas de calor: o que o CBD pode fazer? - Actualit\u00e9s CBD Blog - Weedy.fr<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83c\udf31Menopausa, ondas de calor: o que o CBD pode fazer? - Weedy.Fr\ud83c\udf31\" \/>\n<meta property=\"og:description\" content=\"Uma pesquisa realizada nos Estados Unidos mostrou que 27% das mulheres usaram cannabis, de uma forma ou de outra, para aliviar os sintomas da menopausa. No entanto, os reais efeitos da cannabis e dos seus canabin\u00f3ides (THC, CBD, etc.) na menopausa ainda s\u00e3o pouco conhecidos e, para os consumidores, \u00e9 muitas vezes uma quest\u00e3o de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualit\u00e9s CBD Blog - Weedy.fr\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/weedysocial\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/weedysocial\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-17T16:21:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-17T16:21:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/05\/menopause-bouffees-de-chaleur-que-peut-le-cbd.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1792\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julien Cordobes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julien Cordobes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\\\/\"},\"author\":{\"name\":\"Julien Cordobes\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#\\\/schema\\\/person\\\/72583fcd87d7cf46afe11d530945bc7e\"},\"headline\":\"Menopausa, ondas de calor: o que o CBD pode fazer?\",\"datePublished\":\"2024-09-17T16:21:25+00:00\",\"dateModified\":\"2024-09-17T16:21:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\\\/\"},\"wordCount\":1467,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/menopause-bouffees-de-chaleur-que-peut-le-cbd.jpg\",\"articleSection\":[\"Sa\u00fade e Bem-estar\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\\\/\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\\\/\",\"name\":\"Menopausa, ondas de calor: o que o CBD pode fazer? - Actualit\u00e9s CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/menopause-bouffees-de-chaleur-que-peut-le-cbd.jpg\",\"datePublished\":\"2024-09-17T16:21:25+00:00\",\"dateModified\":\"2024-09-17T16:21:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/menopause-bouffees-de-chaleur-que-peut-le-cbd.jpg\",\"contentUrl\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/menopause-bouffees-de-chaleur-que-peut-le-cbd.jpg\",\"width\":1792,\"height\":1024,\"caption\":\"Menopause, hot flashes: what can CBD do?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/pt\\\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sa\u00fade e Bem-estar\",\"item\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/category\\\/saude-e-bem-estar-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Menopausa, ondas de calor: o que o CBD pode fazer?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/\",\"name\":\"Actualit\u00e9s CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualit\u00e9 du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-carre.jpg\",\"contentUrl\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/weedysocial\",\"https:\\\/\\\/www.instagram.com\\\/weedyfrance\\\/\"],\"description\":\"Leader en france sur la vente de produits \u00e0 base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/#\\\/schema\\\/person\\\/72583fcd87d7cf46afe11d530945bc7e\",\"name\":\"Julien Cordobes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"caption\":\"Julien Cordobes\"},\"description\":\"R\u00e9dacteur en chef sp\u00e9cialis\u00e9 en CBD Julien, n\u00e9 le 17 juillet 1978 en r\u00e9gion Parisienne, est un \u00e9minent r\u00e9dacteur et expert dans le domaine des produits \u00e0 base de CBD. Suite \u00e0 ses \u00e9tudes en biologie et en m\u00e9decine alternative, Julien a d\u00e9velopp\u00e9 une passion pour les rem\u00e8des naturels, dont le CBD. En 2022, il int\u00e8gre l\u2019\u00e9quipe du site Weedy.fr en qualit\u00e9 d\u2019expert et de contributeur r\u00e9gulier. Gr\u00e2ce \u00e0 son expertise scientifique et une \u00e9criture claire, Julien aide \u00e0 d\u00e9mystifier les aspects complexes du CBD, tout en mettant en lumi\u00e8re ses bienfaits et applications potentielles \u00e0 travers ses articles et participations \u00e0 des conf\u00e9rences.\",\"sameAs\":[\"https:\\\/\\\/weedy.fr\",\"https:\\\/\\\/www.facebook.com\\\/weedysocial\\\/\",\"https:\\\/\\\/www.instagram.com\\\/weedyfrance\",\"https:\\\/\\\/www.pinterest.fr\\\/WeedyFrance\\\/\"],\"honorificPrefix\":\"Mr\",\"birthDate\":\"1978-07-17\",\"gender\":\"male\",\"knowsAbout\":[\"CBD\",\"Cannabis\",\"Copywriter\"],\"knowsLanguage\":[\"French\"],\"jobTitle\":\"Editor-in-chief specializing in CBD\",\"worksFor\":\"Weedy.fr\",\"url\":\"https:\\\/\\\/weedy.fr\\\/blog\\\/author\\\/cbd_blog_owner\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Menopausa, ondas de calor: o que o CBD pode fazer? - Actualit\u00e9s CBD Blog - Weedy.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/","og_locale":"fr_FR","og_type":"article","og_title":"\ud83c\udf31Menopausa, ondas de calor: o que o CBD pode fazer? - Weedy.Fr\ud83c\udf31","og_description":"Uma pesquisa realizada nos Estados Unidos mostrou que 27% das mulheres usaram cannabis, de uma forma ou de outra, para aliviar os sintomas da menopausa. No entanto, os reais efeitos da cannabis e dos seus canabin\u00f3ides (THC, CBD, etc.) na menopausa ainda s\u00e3o pouco conhecidos e, para os consumidores, \u00e9 muitas vezes uma quest\u00e3o de [&hellip;]","og_url":"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/","og_site_name":"Actualit\u00e9s CBD Blog - Weedy.fr","article_publisher":"https:\/\/www.facebook.com\/weedysocial","article_author":"https:\/\/www.facebook.com\/weedysocial\/","article_published_time":"2024-09-17T16:21:25+00:00","article_modified_time":"2024-09-17T16:21:26+00:00","og_image":[{"width":1792,"height":1024,"url":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/05\/menopause-bouffees-de-chaleur-que-peut-le-cbd.jpg","type":"image\/jpeg"}],"author":"Julien Cordobes","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Julien Cordobes","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/#article","isPartOf":{"@id":"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/"},"author":{"name":"Julien Cordobes","@id":"https:\/\/weedy.fr\/blog\/#\/schema\/person\/72583fcd87d7cf46afe11d530945bc7e"},"headline":"Menopausa, ondas de calor: o que o CBD pode fazer?","datePublished":"2024-09-17T16:21:25+00:00","dateModified":"2024-09-17T16:21:26+00:00","mainEntityOfPage":{"@id":"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/"},"wordCount":1467,"commentCount":0,"publisher":{"@id":"https:\/\/weedy.fr\/blog\/#organization"},"image":{"@id":"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/#primaryimage"},"thumbnailUrl":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/05\/menopause-bouffees-de-chaleur-que-peut-le-cbd.jpg","articleSection":["Sa\u00fade e Bem-estar"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/","url":"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/","name":"Menopausa, ondas de calor: o que o CBD pode fazer? - Actualit\u00e9s CBD Blog - Weedy.fr","isPartOf":{"@id":"https:\/\/weedy.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/#primaryimage"},"image":{"@id":"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/#primaryimage"},"thumbnailUrl":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/05\/menopause-bouffees-de-chaleur-que-peut-le-cbd.jpg","datePublished":"2024-09-17T16:21:25+00:00","dateModified":"2024-09-17T16:21:26+00:00","breadcrumb":{"@id":"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/#primaryimage","url":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/05\/menopause-bouffees-de-chaleur-que-peut-le-cbd.jpg","contentUrl":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/05\/menopause-bouffees-de-chaleur-que-peut-le-cbd.jpg","width":1792,"height":1024,"caption":"Menopause, hot flashes: what can CBD do?"},{"@type":"BreadcrumbList","@id":"https:\/\/weedy.fr\/blog\/pt\/menopausa-ondas-de-calor-o-que-o-cbd-pode-fazer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https:\/\/weedy.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Sa\u00fade e Bem-estar","item":"https:\/\/weedy.fr\/blog\/category\/saude-e-bem-estar-pt\/"},{"@type":"ListItem","position":3,"name":"Menopausa, ondas de calor: o que o CBD pode fazer?"}]},{"@type":"WebSite","@id":"https:\/\/weedy.fr\/blog\/#website","url":"https:\/\/weedy.fr\/blog\/","name":"Actualit\u00e9s CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualit\u00e9 du CBD et du chanvre en France","publisher":{"@id":"https:\/\/weedy.fr\/blog\/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/weedy.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/weedy.fr\/blog\/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https:\/\/weedy.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/weedy.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/05\/logo-carre.jpg","contentUrl":"https:\/\/weedy.fr\/blog\/wp-content\/uploads\/2024\/05\/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https:\/\/weedy.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/weedysocial","https:\/\/www.instagram.com\/weedyfrance\/"],"description":"Leader en france sur la vente de produits \u00e0 base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https:\/\/weedy.fr\/blog\/#\/schema\/person\/72583fcd87d7cf46afe11d530945bc7e","name":"Julien Cordobes","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","caption":"Julien Cordobes"},"description":"R\u00e9dacteur en chef sp\u00e9cialis\u00e9 en CBD Julien, n\u00e9 le 17 juillet 1978 en r\u00e9gion Parisienne, est un \u00e9minent r\u00e9dacteur et expert dans le domaine des produits \u00e0 base de CBD. Suite \u00e0 ses \u00e9tudes en biologie et en m\u00e9decine alternative, Julien a d\u00e9velopp\u00e9 une passion pour les rem\u00e8des naturels, dont le CBD. En 2022, il int\u00e8gre l\u2019\u00e9quipe du site Weedy.fr en qualit\u00e9 d\u2019expert et de contributeur r\u00e9gulier. Gr\u00e2ce \u00e0 son expertise scientifique et une \u00e9criture claire, Julien aide \u00e0 d\u00e9mystifier les aspects complexes du CBD, tout en mettant en lumi\u00e8re ses bienfaits et applications potentielles \u00e0 travers ses articles et participations \u00e0 des conf\u00e9rences.","sameAs":["https:\/\/weedy.fr","https:\/\/www.facebook.com\/weedysocial\/","https:\/\/www.instagram.com\/weedyfrance","https:\/\/www.pinterest.fr\/WeedyFrance\/"],"honorificPrefix":"Mr","birthDate":"1978-07-17","gender":"male","knowsAbout":["CBD","Cannabis","Copywriter"],"knowsLanguage":["French"],"jobTitle":"Editor-in-chief specializing in CBD","worksFor":"Weedy.fr","url":"https:\/\/weedy.fr\/blog\/author\/cbd_blog_owner\/"}]}},"_links":{"self":[{"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/posts\/360816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/comments?post=360816"}],"version-history":[{"count":1,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/posts\/360816\/revisions"}],"predecessor-version":[{"id":360817,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/posts\/360816\/revisions\/360817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/media\/352621"}],"wp:attachment":[{"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/media?parent=360816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/categories?post=360816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/weedy.fr\/blog\/wp-json\/wp\/v2\/tags?post=360816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}