{"id":359040,"date":"2024-09-17T17:33:38","date_gmt":"2024-09-17T15:33:38","guid":{"rendered":"https://weedy.fr/blog/?p=359040"},"modified":"2024-09-17T17:33:39","modified_gmt":"2024-09-17T15:33:39","slug":"canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel","status":"publish","type":"post","link":"https://weedy.fr/blog/pt/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel/","title":{"rendered":"Canabidiol ou CBD: Por que este novo produto é discutível?"},"content":{"rendered":"\n<p>Canabidiol ou CBDest<strong>uma molécula presente na cannabis.</strong>A molécula mais conhecida é o THC ou Tetrahidrocanabinol.<strong>É esta molécula que proporciona efeitos psicotrópicos</strong>quando a cannabis é fumada. Os produtos que o contêm são, portanto, ilegais.</p>\n\n\n\n<p><strong>O canabidiol não causa um efeito eufórico no corpo humano, ao contrário da cannabis.</strong>Pelo contrário, o <a href=\"https://weedy.fr/de\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> é utilizado num contexto médico e tem<strong>muitos benefícios para a saúde.</strong>É consumido principalmente para relaxar, aliviar o estresse, tratar inflamações e pode até desempenhar um papel no desmame de vícios. Também pode ter propriedades anti-envelhecimento, anti-dor, antioxidante e anti-rugas. O canabidiol também é usado por atletas para aliviar a dor pós-treino.</p>\n\n\n\n<p>Deve-se notar que<strong>a comunidade científica ainda não dispõe de dados suficientes para esclarecer estes efeitos.</strong>São necessários mais estudos científicos objectivos a longo prazo.</p>\n\n\n\n<p><strong>É consumido de diferentes formas:</strong></p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Óleos</li>\n\n\n\n<li>Infusão</li>\n\n\n\n<li>Cápsulas</li>\n\n\n\n<li>Vaporizar líquidos</li>\n\n\n\n<li>Cristais para dissolver em uma bebida ou prato</li>\n\n\n\n<li>Cremes e bálsamos</li>\n\n\n\n<li>Flores de cânhamo</li>\n</ul>\n\n\n\n<p>Ao contrário do THC,<strong>O <a href=\"https://weedy.fr/de\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> não causa dependência e não é prejudicial à saúde.</strong></p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire</p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle</span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http://www.w3.org/2000/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"></path></svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http://www.w3.org/2000/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"></path></svg></span></span></span></a></span></div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 \"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https://weedy.fr/de/blog/pt/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel/#As_razoes_do_debate_em_torno_do_canabidiol_CBD\">As razões do debate em torno do canabidiol (CBD)</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https://weedy.fr/de/blog/pt/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel/#O_que_lembrar\">O que lembrar</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https://weedy.fr/de/blog/pt/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel/#Weedy_garante\">Weedy garante</a></li></ul></nav></div>\n<h2 class=\"wp-block-heading\" id=\"h-les-raisons-du-debat-autour-du-cannabidiol-cbd\"><span class=\"ez-toc-section\" id=\"As_razoes_do_debate_em_torno_do_canabidiol_CBD\"></span>As razões do debate em torno do canabidiol (CBD)<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p>Desde o início de 2018, dezenas de lojas que oferecem canabidiol (<a href=\"https://weedy.fr/de\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a>) abriram as suas portas em toda a França. Seja em Paris, Marselha, Grenoble, Caen, Besançon ou mesmo Reims,<strong>As lojas CBD têm feito muito sucesso desde que foram inauguradas.</strong>O CBD foi divulgado como cannabis light, o que contribuiu em grande parte para o hype, mas também levou a uma certa ambiguidade.</p>\n\n\n\n<p><strong>Desde o início de julho de 2018, os traders em questão já não estão tão calmos.</strong>Várias lojas foram invadidas e seus proprietários foram presos e depois libertados.<strong>Porque a lei francesa não é clara em relação a este novo produto.</strong></p>\n\n\n\n<p>Até à data, a Agência Nacional de Segurança de Medicamentos (ANSM) considera que a cannabis é ilegal na sua totalidade.<strong>A agência não faz distinção entre CBD e THC.</strong>Porém, em França, é o consumo de THC que é proibido.</p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>O artigo R.5132-86 do código de saúde pública prevê que<em>“a produção, fabricação, transporte</em><em>de canábis, da sua planta e da sua resina, dos produtos que a contenham ou dos obtidos a partir da canábis, da sua planta ou da sua resina.</em></p>\n</blockquote>\n\n\n\n<p>No entanto, na Europa e para uso terapêutico, podem ser cultivadas e distribuídas variedades de cânhamo com um nível de THC inferior a 0,2%.<strong>É o caso do canabidiol.</strong>Existe, portanto, uma contradição entre os textos europeus e franceses.</p>\n\n\n\n<p><strong>As principais razões para o debate em torno do CBD em França são:</strong></p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Incerteza jurídica</li>\n\n\n\n<li>Rastreabilidade</li>\n</ul>\n\n\n\n<p>Com efeito, em França,<strong>não existe nenhuma lei que proíba ou legalize especificamente a venda de canabidiol.</strong>Estamos num limbo jurídico. Até à data, os primeiros empresários que comercializaram cannabis sem THC são pessoas de vanguarda que aproveitam este vazio legal.</p>\n\n\n\n<p>Também surge<strong>a preocupação com a rastreabilidade</strong>. A venda de canabidiol é muito difícil de monitorizar e o cumprimento do limite de 0,2% de THC também é difícil de controlar. Alguns traficantes podem muito bem usar o seu negócio para vender cannabis ilegalmente.</p>\n\n\n\n<p>Na dúvida, e enquanto espera poder esclarecer a lei, o governo decidiu em 2018 encerrar os negócios físicos que vendem canabidiol.<strong>Isto, portanto, não se aplica ao comércio online como <a href=\"https://weedy.fr/de\" data-internallinksmanager029f6b8e52c=\"8\" title=\"weedy\">Weedy.fr</a>.</strong></p>\n\n\n\n<p><strong>Explicações em fotos:</strong></p>\n\n\n\n<p><strong>O debate poderá terminar em breve.</strong>A ANSM divulgará em breve o seu relatório sobre a cannabis terapêutica. Assim, o vazio jurídico em torno da comercialização do CBD em França desapareceria.</p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-ce-qu-il-faut-retenir\"><span class=\"ez-toc-section\" id=\"O_que_lembrar\"></span><strong>O que lembrar</strong><span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Todas as variedades de cânhamo autorizadas para fins industriais e comerciais são regulamentadas e listadas.</li>\n\n\n\n<li>Independentemente da variedade, as flores ou folhas de cânhamo não estão autorizadas para comercialização. Somente sementes e fibras podem ser utilizadas.</li>\n\n\n\n<li>Fabricantes e vendedores de produtos que contenham CBD estão proibidos de utilizá-lo<strong>reivindicar virtudes terapêuticas ou indicar que se trata de um medicamento.</strong></li>\n\n\n\n<li>Também é proibido anunciar as virtudes terapêuticas do CBD, exceto<strong>medicamentos autorizados pela ANSM ou pela Comissão</strong><strong>Europeu.</strong></li>\n\n\n\n<li>Os produtos CBD não devem conter THC em qualquer quantidade. Na verdade, quando falamos de um nível de THC de 0,3%,<strong>este é um limiar de presença na própria planta e não no produto acabado.</strong></li>\n</ul>\n\n\n\n<p>É neste último ponto que os comerciantes físicos que oferecem canabidiol podem ter tido problemas com a justiça francesa. Muitas destas “cafeterias” destacaram o baixo teor de THC nos seus produtos (menos de 0,2%) e não na própria fábrica. Recordamos, em França,<strong>é proibida a presença de THC em produtos acabados.</strong></p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-les-garanties-de-weedy\"><span class=\"ez-toc-section\" id=\"Weedy_garante\"></span>Weedy garante<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p><a href=\"https://weedy.fr/de\" data-internallinksmanager029f6b8e52c=\"8\" title=\"weedy\">Weedy</a> é uma marca da empresa Natura Verdea S.r.l com sede na Itália. Todos os produtos oferecidos no <a href=\"https://weedy.fr/de\" data-internallinksmanager029f6b8e52c=\"8\" title=\"weedy\">Weedy</a> cumprem todos estes pontos legais na França e na União Europeia.<strong>Todos os nossos produtos são sujeitos a análises rigorosas através de diferentes métodos</strong>(cromatografia gasosa, cromatografia em camada fina) para certificar que o nível de THC é inferior a 0,2%.</p>\n\n\n\n<p>Na <a href=\"https://weedy.fr/de\" data-internallinksmanager029f6b8e52c=\"8\" title=\"weedy\">Weedy</a>, oferecemos CBD na forma de e-líquidos, pólen ou flores. Observe que todas as nossas flores e resinas de cannabis CBD não se destinam ao consumo. -&gt;Veja nossos produtos.</p>\n\n\n\n<p>Nossos produtos são embalados a vácuo e lacrados em envelopes neutros<strong>para lhe garantir a máxima discrição</strong>. São entregues no prazo de 72 horas, último prazo, e não terá preocupações alfandegárias porque os produtos beneficiam da legislação europeia sobre a livre circulação de mercadorias dentro dos países membros da UE.<strong>Garantimos produtos 100% legais no que diz respeito à legislação europeia e à qualidade.</strong></p>\n\n\n\n<p>Em caso de não conformidade de um produto vendido, o mesmo poderá ser devolvido à empresa <a href=\"https://weedy.fr/de\" data-internallinksmanager029f6b8e52c=\"8\" title=\"weedy\">Weedy</a> que o receberá de volta, trocará ou reembolsará. Todas as reclamações, pedidos de troca ou reembolso devem ser feitos eletronicamente para o seguinte endereço: sav@<a href=\"https://weedy.fr/de\" data-internallinksmanager029f6b8e52c=\"8\" title=\"weedy\">weedy.fr</a>, no prazo máximo de trinta dias após a entrega.</p>\n\n\n\n<p>A venda dos produtos apresentados no site da <a href=\"https://weedy.fr/de\" data-internallinksmanager029f6b8e52c=\"8\" title=\"weedy\">Weedy</a> é estritamente<strong>proibido a qualquer menor de 18 anos.</strong>Todos os produtos que ostentam as palavras “Cannabis CBD” no nome são flores destinadas à decoração. Eles não devem ser fumados ou consumidos. A <a href=\"https://weedy.fr/de\" data-internallinksmanager029f6b8e52c=\"8\" title=\"weedy\">Weedy</a> não pode ser responsabilizada pelo uso indevido de seus produtos.</p>\n\n\n\n<p><strong>Site útil:</strong></p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>https://www.drogues.gouv.fr/</li>\n\n\n\n<li>https://www.psychoactif.org/</li>\n</ul>\n\n","protected":false},"excerpt":{"rendered":"<p>Canabidiol ou CBDestuma molécula presente na cannabis.A molécula mais conhecida é o THC ou Tetrahidrocanabinol.É esta molécula que proporciona efeitos psicotrópicosquando a cannabis é fumada. Os produtos que o contêm são, portanto, ilegais. O canabidiol não causa um efeito eufórico no corpo humano, ao contrário da cannabis.Pelo contrário, o CBD é utilizado num contexto médico [&hellip;]</p>\n","protected":false},"author":41,"featured_media":351716,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[389],"tags":[],"class_list":["post-359040","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https://yoast.com/product/yoast-seo-premium-wordpress/ -->\n<title>Canabidiol ou CBD: Por que este novo produto é discutível? - Actualités CBD Blog - Weedy.fr</title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" />\n<link rel=\"canonical\" href=\"https://weedy.fr/blog/pt/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel/\" />\n<meta property=\"og:locale\" content=\"fr_FR\" />\n<meta property=\"og:type\" content=\"article\" />\n<meta property=\"og:title\" content=\"🌱Canabidiol ou CBD: Por que este novo produto é discutível? - Weedy.Fr🌱\" />\n<meta property=\"og:description\" content=\"Canabidiol ou CBDestuma molécula presente na cannabis.A molécula mais conhecida é o THC ou Tetrahidrocanabinol.É esta molécula que proporciona efeitos psicotrópicosquando a cannabis é fumada. Os produtos que o contêm são, portanto, ilegais. O canabidiol não causa um efeito eufórico no corpo humano, ao contrário da cannabis.Pelo contrário, o CBD é utilizado num contexto médico [&hellip;]\" />\n<meta property=\"og:url\" content=\"https://weedy.fr/blog/pt/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel/\" />\n<meta property=\"og:site_name\" content=\"Actualités CBD Blog - Weedy.fr\" />\n<meta property=\"article:publisher\" content=\"https://www.facebook.com/weedysocial\" />\n<meta property=\"article:author\" content=\"https://www.facebook.com/weedysocial/\" />\n<meta property=\"article:published_time\" content=\"2024-09-17T15:33:38+00:00\" />\n<meta property=\"article:modified_time\" content=\"2024-09-17T15:33:39+00:00\" />\n<meta property=\"og:image\" content=\"https://weedy.fr/blog/wp-content/uploads/2023/10/medicament-cannabis-uk.jpg\" />\n\t<meta property=\"og:image:width\" content=\"1600\" />\n\t<meta property=\"og:image:height\" content=\"800\" />\n\t<meta property=\"og:image:type\" content=\"image/jpeg\" />\n<meta name=\"author\" content=\"Julien Cordobes\" />\n<meta name=\"twitter:card\" content=\"summary_large_image\" />\n<meta name=\"twitter:label1\" content=\"Écrit par\" />\n\t<meta name=\"twitter:data1\" content=\"Julien Cordobes\" />\n\t<meta name=\"twitter:label2\" content=\"Durée de lecture estimée\" />\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" />\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\/\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel\\/#article\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel\\/\"},\"author\":{\"name\":\"Julien Cordobes\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/72583fcd87d7cf46afe11d530945bc7e\"},\"headline\":\"Canabidiol ou CBD: Por que este novo produto é discutível?\",\"datePublished\":\"2024-09-17T15:33:38+00:00\",\"dateModified\":\"2024-09-17T15:33:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel\\/\"},\"wordCount\":1129,\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2023\\/10\\/medicament-cannabis-uk.jpg\",\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel\\/\",\"name\":\"Canabidiol ou CBD: Por que este novo produto é discutível? - Actualités CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2023\\/10\\/medicament-cannabis-uk.jpg\",\"datePublished\":\"2024-09-17T15:33:38+00:00\",\"dateModified\":\"2024-09-17T15:33:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\/\\/weedy.fr\\/blog\\/pt\\/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel\\/#primaryimage\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2023\\/10\\/medicament-cannabis-uk.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2023\\/10\\/medicament-cannabis-uk.jpg\",\"width\":1600,\"height\":800,\"caption\":\"medicament-cannabis-uk\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Non classé\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/category\\/non-classe-pt\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Canabidiol ou CBD: Por que este novo produto é discutível?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"name\":\"Actualités CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualité du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\/\\/weedy.fr\\/blog\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\"},\"sameAs\":[\"https:\\/\\/www.facebook.com\\/weedysocial\",\"https:\\/\\/www.instagram.com\\/weedyfrance\\/\"],\"description\":\"Leader en france sur la vente de produits à base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/72583fcd87d7cf46afe11d530945bc7e\",\"name\":\"Julien Cordobes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"url\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"caption\":\"Julien Cordobes\"},\"description\":\"Rédacteur en chef spécialisé en CBD Julien, né le 17 juillet 1978 en région Parisienne, est un éminent rédacteur et expert dans le domaine des produits à base de CBD. Suite à ses études en biologie et en médecine alternative, Julien a développé une passion pour les remèdes naturels, dont le CBD. En 2022, il intègre l’équipe du site Weedy.fr en qualité d’expert et de contributeur régulier. Grâce à son expertise scientifique et une écriture claire, Julien aide à démystifier les aspects complexes du CBD, tout en mettant en lumière ses bienfaits et applications potentielles à travers ses articles et participations à des conférences.\",\"sameAs\":[\"https:\\/\\/weedy.fr\",\"https:\\/\\/www.facebook.com\\/weedysocial\\/\",\"https:\\/\\/www.instagram.com\\/weedyfrance\",\"https:\\/\\/www.pinterest.fr\\/WeedyFrance\\/\"],\"honorificPrefix\":\"Mr\",\"birthDate\":\"1978-07-17\",\"gender\":\"male\",\"knowsAbout\":[\"CBD\",\"Cannabis\",\"Copywriter\"],\"knowsLanguage\":[\"French\"],\"jobTitle\":\"Editor-in-chief specializing in CBD\",\"worksFor\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/author\\/cbd_blog_owner\\/\"}]}</script>\n<!-- / Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Canabidiol ou CBD: Por que este novo produto é discutível? - Actualités CBD Blog - Weedy.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://weedy.fr/blog/pt/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel/","og_locale":"fr_FR","og_type":"article","og_title":"🌱Canabidiol ou CBD: Por que este novo produto é discutível? - Weedy.Fr🌱","og_description":"Canabidiol ou CBDestuma molécula presente na cannabis.A molécula mais conhecida é o THC ou Tetrahidrocanabinol.É esta molécula que proporciona efeitos psicotrópicosquando a cannabis é fumada. Os produtos que o contêm são, portanto, ilegais. O canabidiol não causa um efeito eufórico no corpo humano, ao contrário da cannabis.Pelo contrário, o CBD é utilizado num contexto médico [&hellip;]","og_url":"https://weedy.fr/blog/pt/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel/","og_site_name":"Actualités CBD Blog - Weedy.fr","article_publisher":"https://www.facebook.com/weedysocial","article_author":"https://www.facebook.com/weedysocial/","article_published_time":"2024-09-17T15:33:38+00:00","article_modified_time":"2024-09-17T15:33:39+00:00","og_image":[{"width":1600,"height":800,"url":"https://weedy.fr/de/blog/wp-content/uploads/2023/10/medicament-cannabis-uk.jpg","type":"image/jpeg"}],"author":"Julien Cordobes","twitter_card":"summary_large_image","twitter_misc":{"Écrit par":"Julien Cordobes","Durée de lecture estimée":"6 minutes"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"Article","@id":"https://weedy.fr/blog/pt/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel/#article","isPartOf":{"@id":"https://weedy.fr/blog/pt/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel/"},"author":{"name":"Julien Cordobes","@id":"https://weedy.fr/blog/#/schema/person/72583fcd87d7cf46afe11d530945bc7e"},"headline":"Canabidiol ou CBD: Por que este novo produto é discutível?","datePublished":"2024-09-17T15:33:38+00:00","dateModified":"2024-09-17T15:33:39+00:00","mainEntityOfPage":{"@id":"https://weedy.fr/blog/pt/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel/"},"wordCount":1129,"publisher":{"@id":"https://weedy.fr/blog/#organization"},"image":{"@id":"https://weedy.fr/blog/pt/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2023/10/medicament-cannabis-uk.jpg","inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https://weedy.fr/blog/pt/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel/","url":"https://weedy.fr/de/blog/pt/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel/","name":"Canabidiol ou CBD: Por que este novo produto é discutível? - Actualités CBD Blog - Weedy.fr","isPartOf":{"@id":"https://weedy.fr/blog/#website"},"primaryImageOfPage":{"@id":"https://weedy.fr/blog/pt/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel/#primaryimage"},"image":{"@id":"https://weedy.fr/blog/pt/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2023/10/medicament-cannabis-uk.jpg","datePublished":"2024-09-17T15:33:38+00:00","dateModified":"2024-09-17T15:33:39+00:00","breadcrumb":{"@id":"https://weedy.fr/blog/pt/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https://weedy.fr/blog/pt/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/pt/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel/#primaryimage","url":"https://weedy.fr/de/blog/wp-content/uploads/2023/10/medicament-cannabis-uk.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2023/10/medicament-cannabis-uk.jpg","width":1600,"height":800,"caption":"medicament-cannabis-uk"},{"@type":"BreadcrumbList","@id":"https://weedy.fr/blog/pt/canabidiol-ou-cbd-por-que-este-novo-produto-e-discutivel/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https://weedy.fr/blog/"},{"@type":"ListItem","position":2,"name":"Non classé","item":"https://weedy.fr/blog/category/non-classe-pt/"},{"@type":"ListItem","position":3,"name":"Canabidiol ou CBD: Por que este novo produto é discutível?"}]},{"@type":"WebSite","@id":"https://weedy.fr/blog/#website","url":"https://weedy.fr/de/blog/","name":"Actualités CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualité du CBD et du chanvre en France","publisher":{"@id":"https://weedy.fr/blog/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://weedy.fr/blog/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https://weedy.fr/blog/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https://weedy.fr/de/blog/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/#/schema/logo/image/","url":"https://weedy.fr/de/blog/wp-content/uploads/2024/05/logo-carre.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https://weedy.fr/blog/#/schema/logo/image/"},"sameAs":["https://www.facebook.com/weedysocial","https://www.instagram.com/weedyfrance/"],"description":"Leader en france sur la vente de produits à base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https://weedy.fr/blog/#/schema/person/72583fcd87d7cf46afe11d530945bc7e","name":"Julien Cordobes","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","url":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","caption":"Julien Cordobes"},"description":"Rédacteur en chef spécialisé en CBD Julien, né le 17 juillet 1978 en région Parisienne, est un éminent rédacteur et expert dans le domaine des produits à base de CBD. Suite à ses études en biologie et en médecine alternative, Julien a développé une passion pour les remèdes naturels, dont le CBD. En 2022, il intègre l’équipe du site Weedy.fr en qualité d’expert et de contributeur régulier. Grâce à son expertise scientifique et une écriture claire, Julien aide à démystifier les aspects complexes du CBD, tout en mettant en lumière ses bienfaits et applications potentielles à travers ses articles et participations à des conférences.","sameAs":["https://weedy.fr","https://www.facebook.com/weedysocial/","https://www.instagram.com/weedyfrance","https://www.pinterest.fr/WeedyFrance/"],"honorificPrefix":"Mr","birthDate":"1978-07-17","gender":"male","knowsAbout":["CBD","Cannabis","Copywriter"],"knowsLanguage":["French"],"jobTitle":"Editor-in-chief specializing in CBD","worksFor":"Weedy.fr","url":"https://weedy.fr/de/blog/author/cbd_blog_owner/"}]}},"_links":{"self":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts"}],"about":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/users/41"}],"replies":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/comments?post=359040"}],"version-history":[{"count":1,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359040/revisions"}],"predecessor-version":[{"id":359041,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359040/revisions/359041"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/media/351716"}],"wp:attachment":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/media?parent=359040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/categories?post=359040"},{"taxonomy":"post_tag","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/tags?post=359040"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}