{"id":361152,"date":"2024-09-17T18:38:20","date_gmt":"2024-09-17T16:38:20","guid":{"rendered":"https://weedy.fr/blog/?p=361152"},"modified":"2024-09-17T18:38:21","modified_gmt":"2024-09-17T16:38:21","slug":"infografico-principais-numeros-do-mercado-de-cbd-na-franca","status":"publish","type":"post","link":"https://weedy.fr/blog/pt/infografico-principais-numeros-do-mercado-de-cbd-na-franca/","title":{"rendered":" Principais números do mercado de CBD na França"},"content":{"rendered":"<p>Desde a explosão de <strong>Mercado <a href=\"https://weedy.fr/de\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> na França</strong> em 2018, ouvimos tudo (e às vezes qualquer coisa) sobre isso. É preciso dizer que, embora o sucesso do canabidiol seja certo, nem sempre é fácil medir a sua importância.</p>\n<p>Este é particularmente o caso no que diz respeito aos benefícios que gera e ao tipo de consumidores envolvidos. Porém, quanto mais o tempo passa e <strong>quanto mais estudos houver sobre isso</strong>. <strong>Reunimos num infográfico todos os números-chave que você precisa saber para compreender completamente o mercado de <a href=\"https://weedy.fr/de\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> na França.</strong>…e suas oportunidades!</p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-264647\" src=\"https://weedy.fr/wp-content/uploads/2021/10/Marche-du-CBD-en-France-Infographie-Weedy-web.png\" alt=\"mercado cbd na frança infográfico weedy web\" width=\"1920\" height=\"6032\"></p>\n<p><em>Informação ao leitor: os números e estatísticas utilizados neste artigo provêm de diversos estudos e pesquisas, realizadas principalmente na França e nos Estados Unidos. </em><a href=\"https://modelesdebusinessplan.com/blogs/infos/marche-cbd-chiffres-donnees-statistiques\" target=\"_blank\" rel=\"noopener\"><em>Eles estão reunidos aqui</em></a><em>. </em></p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire</p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle</span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http://www.w3.org/2000/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"></path></svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http://www.w3.org/2000/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"></path></svg></span></span></span></a></span></div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 \"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https://weedy.fr/de/blog/pt/infografico-principais-numeros-do-mercado-de-cbd-na-franca/#CBD_em_Franca_um_mercado_de_15_mil_milhoes_de_euros\">CBD em França: um mercado de 1,5 mil milhões de euros?</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https://weedy.fr/de/blog/pt/infografico-principais-numeros-do-mercado-de-cbd-na-franca/#70_dos_consumidores_de_CBD_sao_homens\">70% dos consumidores de CBD são homens</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https://weedy.fr/de/blog/pt/infografico-principais-numeros-do-mercado-de-cbd-na-franca/#3_principais_razoes_para_usar_CBD\">3 principais razões para usar CBD</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https://weedy.fr/de/blog/pt/infografico-principais-numeros-do-mercado-de-cbd-na-franca/#A_Franca_e_o_maior_produtor_de_canhamo_da_Europa\">A França é o maior produtor de cânhamo da Europa</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https://weedy.fr/de/blog/pt/infografico-principais-numeros-do-mercado-de-cbd-na-franca/#51_dos_franceses_a_favor_da_legalizacao_da_cannabis\">51% dos franceses a favor da legalização da cannabis</a></li></ul></nav></div>\n<h2><span class=\"ez-toc-section\" id=\"CBD_em_Franca_um_mercado_de_15_mil_milhoes_de_euros\"></span>CBD em França: um mercado de 1,5 mil milhões de euros?<span class=\"ez-toc-section-end\"></span></h2>\n<p>O peso do mercado da CDB, em França como noutras partes do mundo, ainda é difícil de avaliar. Dependendo dos estudos, os números variam bastante. Assim, o mercado global de <a href=\"https://weedy.fr/de\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> geraria <strong>3 mil milhões de euros</strong> todos os anos, segundo alguns, quando o OFDT (Observatório Francês da Droga e da Toxicodependência) menciona <strong>9 mil milhões de euros</strong> por ano apenas para a Europa&#8230; mas considerando a cannabis como um todo, o que não é necessariamente comparável.</p>\n<p>No entanto, todos concordam que a França ainda desempenha apenas um papel muito secundário no mercado europeu (12% do mercado mundial). Se actualmente a Alemanha e o Reino Unido recebem a maior parte das receitas da CDB, o <strong>Potencial francês</strong> existe. Alguns especialistas acreditam que <strong>o mercado de CBD poderia trazer até </strong><a href=\"https://www.challenges.fr/economie/le-cannabis-pourrait-representer-jusqu-a-1-5-milliard_643400\" target=\"_blank\" rel=\"noopener\"><strong>1,5 mil milhões de euros</strong></a><strong> por ano para a França</strong> dentro de alguns anos. Para fazer isso, porém, o Estado teria que parar de pisar no freio.</p>\n<p>O ensaio clínico em curso até 2023 talvez permita finalmente <strong>aproveite a cannabis medicinal</strong>. Certas áreas cinzentas na lei, especialmente no que diz respeito ao desejo do governo de<a href=\"https://weedy.fr/de/blog/actu-legalite-du-cbd/\">proibir a comercialização de folhas e flores de CBD</a>, também ainda precisam ser esclarecidos.</p>\n<h2><span class=\"ez-toc-section\" id=\"70_dos_consumidores_de_CBD_sao_homens\"></span>70% dos consumidores de CBD são homens<span class=\"ez-toc-section-end\"></span></h2>\n<p>Muitas vezes nos perguntamos quem são os consumidores de CBD, às vezes com o estereótipo do drogado, bastante jovem e um pouco hippie, em mente. No entanto, esses clichês estão longe da realidade. Mas então, quem é o consumidor típico de CBD? Já é um público bastante masculino com <strong>70% homens</strong> consumidores em comparação com 30% das mulheres. A faixa etária em causa é, no entanto, muito mais dispersa do que se poderia pensar, com <strong>53% dos consumidores de CBD com menos de 35 anos</strong> e 47% têm 35 anos ou mais, dos quais 19% têm mais de 45 anos.</p>\n<p>Finalmente, com <strong>10% das pessoas que já experimentaram pelo menos o CBD</strong>, a França está bastante abaixo da média europeia, já nos 16%, o que nos permite ver um bom <strong>espaço para melhorias para o mercado francês de CBD</strong>.</p>\n<h2><span class=\"ez-toc-section\" id=\"3_principais_razoes_para_usar_CBD\"></span>3 principais razões para usar CBD<span class=\"ez-toc-section-end\"></span></h2>\n<p>Em França, os dados públicos ainda são escassos para compreender as expectativas precisas dos consumidores em termos da utilização do CBD. Devemos, portanto, voltar-nos para os Estados Unidos. Um grande vencedor se destaca amplamente, já que <strong>40% dos consumidores de CBD dizem que o utilizam para combater a dor</strong>. Muito atrás, mas ainda com 20% dos votos, vem o <a href=\"https://weedy.fr/de/blog/cbd-et-anxiete/\">lutar contra a ansiedade</a> então, em 11%, o desejo de <a href=\"https://weedy.fr/de/blog/bien-dormir-grace-au-cbd/\">durma melhor graças ao CBD</a>. Problemas de pele (<a href=\"https://weedy.fr/de/blog/lutter-contre-acne-grace-au-cbd/\">acne</a>, <a href=\"https://weedy.fr/de/blog/huile-de-chanvre-et-psoriasis/\">psoríase</a>, <a href=\"https://weedy.fr/de/blog/produits-solaires-cbd/\">queimadura solar</a>, etc.) e usar para <a href=\"https://weedy.fr/de/blog/cbd-pour-les-animaux/\">animais de estimação</a> vem na retaguarda, com apenas 1% dos consumidores a indicar que têm este tipo de expectativa.</p>\n<h2><span class=\"ez-toc-section\" id=\"A_Franca_e_o_maior_produtor_de_canhamo_da_Europa\"></span>A França é o maior produtor de cânhamo da Europa<span class=\"ez-toc-section-end\"></span></h2>\n<p><img decoding=\"async\" class=\"size-full wp-image-264648\" src=\"https://weedy.fr/wp-content/uploads/2021/10/Culture-de-chanvre-CBD-en-France-min.jpg\" alt=\"Cultivo de cânhamo CBD na França min\" width=\"700\" height=\"466\"><br>\nMuitas vezes esquecemo-nos disto, pois o Governo toma regularmente posição contra a cannabis, mas, com <strong>18.000 hectares de cultivo</strong>, a França é o principal produtor europeu de cânhamo… que é, em última análise, a mesma planta com um nível regulamentado de THC. No mundo, a China ocupa o primeiro lugar do pódio, seguida pela <a href=\"https://weedy.fr/de/blog/legalisation-du-cannabis-au-canada/\">Canadá</a> que só conseguiu ultrapassar a produção francesa após a legalização total da cannabis (médica e recreativa), em outubro de 2018.</p>\n<p>Segundo algumas estimativas, um hectare de cânhamo cultivado promete ao produtor <strong>2.500€ de rendimento por hectare</strong>, que é <strong>8 vezes mais que um hectare de trigo</strong> ! Por enquanto, o <a href=\"https://weedy.fr/de/blog/la-culture-du-chanvre-en-france/\">Cânhamo francês</a> é amplamente utilizado para usos industriais e agrícolas (corda, cobertura morta para animais, têxteis, etc.). Se a situação se tornasse mais simples para os agricultores, o potencial do cânhamo francês poderia ser aumentado, explicando em parte como alcançar os 1,5 mil milhões de euros em receitas anuais que o mercado do CBD em França poderia gerar.</p>\n<h2><span class=\"ez-toc-section\" id=\"51_dos_franceses_a_favor_da_legalizacao_da_cannabis\"></span>51% dos franceses a favor da legalização da cannabis<span class=\"ez-toc-section-end\"></span></h2>\n<p>Finalmente, para finalizar esta visão geral do mercado <a href=\"https://weedy.fr/de\">CDB na França</a>, é importante voltar por alguns momentos à opinião geral sobre a cannabis. UM <a href=\"https://www.ifop.com/publication/les-francais-et-le-cannabis-la-longue-marche-de-lopinion-vers-la-depenalisation-2/\" target=\"_blank\" rel=\"noopener\">pesquisa publicada pelo Ifop</a> em junho de 2021 destacou de facto que, pela primeira vez desde o início da existência deste tipo de barómetro de opinião, <strong>mais da metade dos franceses são a favor da descriminalização da cannabis</strong>. Não estamos aqui a falar de CBD, mas sim de cannabis de qualquer tipo, tanto para uso terapêutico como recreativo.</p>\n<p>Se estivermos interessados <strong>cannabis medicinal</strong> por si só, os números sobem ainda mais, com <strong>78% dos franceses</strong> que lhe são favoráveis. Finalmente, <strong>11%</strong> indicar consumir cannabis por um <strong>uso recreativo</strong>, o que quer que a lei diga.</p>\n<p>Dois elementos importantes devem ser mencionados aqui:</p>\n<ul>\n<li>Há mais franceses que fumam cannabis do que franceses que consomem CBD, embora não seja prejudicial.</li>\n<li>Este número é um dos mais elevados da Europa, apesar das leis que são bastante mais repressivas do que em qualquer outro lugar.</li>\n</ul>\n<p><strong>Portanto, não há apenas lugar para o mercado de CBD em França</strong>, mas também argumentos a favor do seu desenvolvimento do ponto de vista da procura, da saúde pública e <strong>oportunidades financeiras</strong> que ele representa.</p>\n","protected":false},"excerpt":{"rendered":"<p>Desde a explosão de Mercado CBD na França em 2018, ouvimos tudo (e às vezes qualquer coisa) sobre isso. É preciso dizer que, embora o sucesso do canabidiol seja certo, nem sempre é fácil medir a sua importância. Este é particularmente o caso no que diz respeito aos benefícios que gera e ao tipo de [&hellip;]</p>\n","protected":false},"author":97,"featured_media":352661,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"padrão\n","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[675],"tags":[],"class_list":["post-361152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-sobre-cbd-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https://yoast.com/product/yoast-seo-premium-wordpress/ -->\n<title>[INFOGRÁFICO] Principais números do mercado de CBD na França - Actualités CBD Blog - Weedy.fr</title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" />\n<link rel=\"canonical\" href=\"https://weedy.fr/blog/pt/infografico-principais-numeros-do-mercado-de-cbd-na-franca/\" />\n<meta property=\"og:locale\" content=\"fr_FR\" />\n<meta property=\"og:type\" content=\"article\" />\n<meta property=\"og:title\" content=\"🌱[INFOGRÁFICO] Principais números do mercado de CBD na França - Weedy.Fr🌱\" />\n<meta property=\"og:description\" content=\"Desde a explosão de Mercado CBD na França em 2018, ouvimos tudo (e às vezes qualquer coisa) sobre isso. É preciso dizer que, embora o sucesso do canabidiol seja certo, nem sempre é fácil medir a sua importância. Este é particularmente o caso no que diz respeito aos benefícios que gera e ao tipo de [&hellip;]\" />\n<meta property=\"og:url\" content=\"https://weedy.fr/blog/pt/infografico-principais-numeros-do-mercado-de-cbd-na-franca/\" />\n<meta property=\"og:site_name\" content=\"Actualités CBD Blog - Weedy.fr\" />\n<meta property=\"article:publisher\" content=\"https://www.facebook.com/weedysocial\" />\n<meta property=\"article:published_time\" content=\"2024-09-17T16:38:20+00:00\" />\n<meta property=\"article:modified_time\" content=\"2024-09-17T16:38:21+00:00\" />\n<meta property=\"og:image\" content=\"https://weedy.fr/blog/wp-content/uploads/2024/05/infographie-les-chiffres-cles-du-marche-du-cbd-en-france.jpg\" />\n\t<meta property=\"og:image:width\" content=\"1792\" />\n\t<meta property=\"og:image:height\" content=\"1024\" />\n\t<meta property=\"og:image:type\" content=\"image/jpeg\" />\n<meta name=\"author\" content=\"arthur\" />\n<meta name=\"twitter:card\" content=\"summary_large_image\" />\n<meta name=\"twitter:label1\" content=\"Écrit par\" />\n\t<meta name=\"twitter:data1\" content=\"arthur\" />\n\t<meta name=\"twitter:label2\" content=\"Durée de lecture estimée\" />\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" />\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\/\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/infografico-principais-numeros-do-mercado-de-cbd-na-franca\\/#article\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/infografico-principais-numeros-do-mercado-de-cbd-na-franca\\/\"},\"author\":{\"name\":\"arthur\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/0a05724dbfcfa68f2ce947d2ebf0f435\"},\"headline\":\"Principais números do mercado de CBD na França\",\"datePublished\":\"2024-09-17T16:38:20+00:00\",\"dateModified\":\"2024-09-17T16:38:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/infografico-principais-numeros-do-mercado-de-cbd-na-franca\\/\"},\"wordCount\":1039,\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/infografico-principais-numeros-do-mercado-de-cbd-na-franca\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/infographie-les-chiffres-cles-du-marche-du-cbd-en-france.jpg\",\"articleSection\":[\"Notícias sobre CBD\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/infografico-principais-numeros-do-mercado-de-cbd-na-franca\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/infografico-principais-numeros-do-mercado-de-cbd-na-franca\\/\",\"name\":\"[INFOGRÁFICO] Principais números do mercado de CBD na França - Actualités CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/infografico-principais-numeros-do-mercado-de-cbd-na-franca\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/infografico-principais-numeros-do-mercado-de-cbd-na-franca\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/infographie-les-chiffres-cles-du-marche-du-cbd-en-france.jpg\",\"datePublished\":\"2024-09-17T16:38:20+00:00\",\"dateModified\":\"2024-09-17T16:38:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/infografico-principais-numeros-do-mercado-de-cbd-na-franca\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\/\\/weedy.fr\\/blog\\/pt\\/infografico-principais-numeros-do-mercado-de-cbd-na-franca\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/infografico-principais-numeros-do-mercado-de-cbd-na-franca\\/#primaryimage\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/infographie-les-chiffres-cles-du-marche-du-cbd-en-france.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/infographie-les-chiffres-cles-du-marche-du-cbd-en-france.jpg\",\"width\":1792,\"height\":1024,\"caption\":\"[INFOGRAPHIC] Key figures for the CBD market in France\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/infografico-principais-numeros-do-mercado-de-cbd-na-franca\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notícias sobre CBD\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/category\\/noticias-sobre-cbd-pt\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Principais números do mercado de CBD na França\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"name\":\"Actualités CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualité du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\/\\/weedy.fr\\/blog\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\"},\"sameAs\":[\"https:\\/\\/www.facebook.com\\/weedysocial\",\"https:\\/\\/www.instagram.com\\/weedyfrance\\/\"],\"description\":\"Leader en france sur la vente de produits à base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/0a05724dbfcfa68f2ce947d2ebf0f435\",\"name\":\"arthur\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"url\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"caption\":\"arthur\"},\"url\":\"https:\\/\\/weedy.fr\\/blog\\/author\\/arthur\\/\"}]}</script>\n<!-- / Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"[INFOGRÁFICO] Principais números do mercado de CBD na França - Actualités CBD Blog - Weedy.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://weedy.fr/blog/pt/infografico-principais-numeros-do-mercado-de-cbd-na-franca/","og_locale":"fr_FR","og_type":"article","og_title":"🌱[INFOGRÁFICO] Principais números do mercado de CBD na França - Weedy.Fr🌱","og_description":"Desde a explosão de Mercado CBD na França em 2018, ouvimos tudo (e às vezes qualquer coisa) sobre isso. É preciso dizer que, embora o sucesso do canabidiol seja certo, nem sempre é fácil medir a sua importância. Este é particularmente o caso no que diz respeito aos benefícios que gera e ao tipo de [&hellip;]","og_url":"https://weedy.fr/blog/pt/infografico-principais-numeros-do-mercado-de-cbd-na-franca/","og_site_name":"Actualités CBD Blog - Weedy.fr","article_publisher":"https://www.facebook.com/weedysocial","article_published_time":"2024-09-17T16:38:20+00:00","article_modified_time":"2024-09-17T16:38:21+00:00","og_image":[{"width":1792,"height":1024,"url":"https://weedy.fr/de/blog/wp-content/uploads/2024/05/infographie-les-chiffres-cles-du-marche-du-cbd-en-france.jpg","type":"image/jpeg"}],"author":"arthur","twitter_card":"summary_large_image","twitter_misc":{"Écrit par":"arthur","Durée de lecture estimée":"5 minutes"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"Article","@id":"https://weedy.fr/blog/pt/infografico-principais-numeros-do-mercado-de-cbd-na-franca/#article","isPartOf":{"@id":"https://weedy.fr/blog/pt/infografico-principais-numeros-do-mercado-de-cbd-na-franca/"},"author":{"name":"arthur","@id":"https://weedy.fr/blog/#/schema/person/0a05724dbfcfa68f2ce947d2ebf0f435"},"headline":"Principais números do mercado de CBD na França","datePublished":"2024-09-17T16:38:20+00:00","dateModified":"2024-09-17T16:38:21+00:00","mainEntityOfPage":{"@id":"https://weedy.fr/blog/pt/infografico-principais-numeros-do-mercado-de-cbd-na-franca/"},"wordCount":1039,"publisher":{"@id":"https://weedy.fr/blog/#organization"},"image":{"@id":"https://weedy.fr/blog/pt/infografico-principais-numeros-do-mercado-de-cbd-na-franca/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/infographie-les-chiffres-cles-du-marche-du-cbd-en-france.jpg","articleSection":["Notícias sobre CBD"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https://weedy.fr/blog/pt/infografico-principais-numeros-do-mercado-de-cbd-na-franca/","url":"https://weedy.fr/de/blog/pt/infografico-principais-numeros-do-mercado-de-cbd-na-franca/","name":"[INFOGRÁFICO] Principais números do mercado de CBD na França - Actualités CBD Blog - Weedy.fr","isPartOf":{"@id":"https://weedy.fr/blog/#website"},"primaryImageOfPage":{"@id":"https://weedy.fr/blog/pt/infografico-principais-numeros-do-mercado-de-cbd-na-franca/#primaryimage"},"image":{"@id":"https://weedy.fr/blog/pt/infografico-principais-numeros-do-mercado-de-cbd-na-franca/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/infographie-les-chiffres-cles-du-marche-du-cbd-en-france.jpg","datePublished":"2024-09-17T16:38:20+00:00","dateModified":"2024-09-17T16:38:21+00:00","breadcrumb":{"@id":"https://weedy.fr/blog/pt/infografico-principais-numeros-do-mercado-de-cbd-na-franca/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https://weedy.fr/blog/pt/infografico-principais-numeros-do-mercado-de-cbd-na-franca/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/pt/infografico-principais-numeros-do-mercado-de-cbd-na-franca/#primaryimage","url":"https://weedy.fr/de/blog/wp-content/uploads/2024/05/infographie-les-chiffres-cles-du-marche-du-cbd-en-france.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/infographie-les-chiffres-cles-du-marche-du-cbd-en-france.jpg","width":1792,"height":1024,"caption":"[INFOGRAPHIC] Key figures for the CBD market in France"},{"@type":"BreadcrumbList","@id":"https://weedy.fr/blog/pt/infografico-principais-numeros-do-mercado-de-cbd-na-franca/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https://weedy.fr/blog/"},{"@type":"ListItem","position":2,"name":"Notícias sobre CBD","item":"https://weedy.fr/blog/category/noticias-sobre-cbd-pt/"},{"@type":"ListItem","position":3,"name":"Principais números do mercado de CBD na França"}]},{"@type":"WebSite","@id":"https://weedy.fr/blog/#website","url":"https://weedy.fr/de/blog/","name":"Actualités CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualité du CBD et du chanvre en France","publisher":{"@id":"https://weedy.fr/blog/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://weedy.fr/blog/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https://weedy.fr/blog/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https://weedy.fr/de/blog/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/#/schema/logo/image/","url":"https://weedy.fr/de/blog/wp-content/uploads/2024/05/logo-carre.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https://weedy.fr/blog/#/schema/logo/image/"},"sameAs":["https://www.facebook.com/weedysocial","https://www.instagram.com/weedyfrance/"],"description":"Leader en france sur la vente de produits à base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https://weedy.fr/blog/#/schema/person/0a05724dbfcfa68f2ce947d2ebf0f435","name":"arthur","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://secure.gravatar.com/avatar/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","url":"https://secure.gravatar.com/avatar/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","caption":"arthur"},"url":"https://weedy.fr/de/blog/author/arthur/"}]}},"_links":{"self":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/361152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts"}],"about":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/users/97"}],"replies":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/comments?post=361152"}],"version-history":[{"count":1,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/361152/revisions"}],"predecessor-version":[{"id":361153,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/361152/revisions/361153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/media/352661"}],"wp:attachment":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/media?parent=361152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/categories?post=361152"},{"taxonomy":"post_tag","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/tags?post=361152"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}