{"id":359400,"date":"2024-09-17T17:40:27","date_gmt":"2024-09-17T15:40:27","guid":{"rendered":"https://weedy.fr/blog/?p=359400"},"modified":"2024-09-17T17:40:28","modified_gmt":"2024-09-17T15:40:28","slug":"o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos","status":"publish","type":"post","link":"https://weedy.fr/blog/pt/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos/","title":{"rendered":"O CBD e a sua influência na memória: o que dizem os estudos?"},"content":{"rendered":"<p>Num contexto onde o uso da cannabis para fins terapêuticos é cada vez mais difundido, é fundamental estudar os potenciais efeitos dos diferentes componentes desta planta no nosso organismo. Entre eles, o canabidiol (<a href=\"https://weedy.fr/en\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a>) está atraindo grande interesse na investigação científica pelas suas supostas propriedades medicinais sem causar efeitos psicoativos indesejados, como os associados ao tetrahidrocanabinol (THC). Neste artigo faremos uma revisão da pesquisa realizada sobre <strong>o impacto do <a href=\"https://weedy.fr/en\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> na memória</strong>, bem como as diferentes hipóteses levantadas sobre os mecanismos subjacentes a estes efeitos.</p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire</p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle</span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http://www.w3.org/2000/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"></path></svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http://www.w3.org/2000/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"></path></svg></span></span></span></a></span></div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 \"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https://weedy.fr/en/blog/pt/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos/#Os_efeitos_da_cannabis_na_memoria_uma_questao_complexa\">Os efeitos da cannabis na memória: uma questão complexa</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https://weedy.fr/en/blog/pt/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos/#CBD_um_ator_diferente_no_sistema_endocanabinoide\">CBD: um ator diferente no sistema endocanabinoide</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https://weedy.fr/en/blog/pt/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos/#O_estado_atual_da_pesquisa_sobre_CBD_e_memoria\">O estado atual da pesquisa sobre CBD e memória</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https://weedy.fr/en/blog/pt/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos/#Efeito_protetor_do_CBD_contra_os_defices_de_memoria_induzidos_pelo_THC\">Efeito protetor do CBD contra os défices de memória induzidos pelo THC</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https://weedy.fr/en/blog/pt/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos/#Efeito_neuroprotetor_do_CBD_implicacoes_para_a_memoria\">Efeito neuroprotetor do CBD: implicações para a memória</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https://weedy.fr/en/blog/pt/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos/#Acao_anti-inflamatoria_e_ansiolitica_do_CBD_efeitos_na_memoria\">Ação anti-inflamatória e ansiolítica do CBD: efeitos na memória?</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https://weedy.fr/en/blog/pt/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos/#Em_resumo_qual_o_papel_do_CBD_na_modulacao_da_memoria\">Em resumo: qual o papel do CBD na modulação da memória?</a></li></ul></nav></div>\n<h2><span class=\"ez-toc-section\" id=\"Os_efeitos_da_cannabis_na_memoria_uma_questao_complexa\"></span>Os efeitos da cannabis na memória: uma questão complexa<span class=\"ez-toc-section-end\"></span></h2>\n<p>Para abordar a questão da relação entre o <a href=\"https://weedy.fr/en\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> e a memória, deve primeiro recordar-se que a cannabis contém várias centenas de substâncias ativas, algumas das quais foram identificadas como tendo efeitos potencialmente deletérios no funcionamento cognitivo. Assim, vários estudos têm investigado <strong>os efeitos do THC, o principal componente psicoativo da cannabis</strong>, que actua principalmente ligando-se aos receptores CB1 do sistema endocanabinóide e pode causar défices de memória de curto prazo, particularmente em consumidores regulares ou precoces de cannabis.</p>\n<h2><span class=\"ez-toc-section\" id=\"CBD_um_ator_diferente_no_sistema_endocanabinoide\"></span>CBD: um ator diferente no sistema endocanabinoide<span class=\"ez-toc-section-end\"></span></h2>\n<p>No entanto, ao contrário do THC, o CBD tem uma afinidade muito menor pelos receptores CB1 e parece interagir com outros alvos do sistema endocanabinoide e dos sistemas de neurotransmissão. Como resultado, não tem efeito psicoativo e não causa os distúrbios cognitivos geralmente atribuídos ao consumo de THC. Pelo contrário, vários estudos sugerem que <strong>O CBD poderia ter efeitos benéficos em certos aspectos da memória, em particular protegendo contra certos défices induzidos pelo THC</strong>. Então, o que exatamente é isso?</p>\n<h2><span class=\"ez-toc-section\" id=\"O_estado_atual_da_pesquisa_sobre_CBD_e_memoria\"></span>O estado atual da pesquisa sobre CBD e memória<span class=\"ez-toc-section-end\"></span></h2>\n<p>Ainda existem poucos estudos específicos que investiguem os efeitos isolados do CBD na memória humana, principalmente devido à complexidade e às variações metodológicas dos trabalhos realizados até agora. Dito isto, vários experimentos realizados em animais e em modelos celulares mostraram resultados promissores, destacando diferentes mecanismos potenciais que poderiam estar envolvidos.</p>\n<h3><span class=\"ez-toc-section\" id=\"Efeito_protetor_do_CBD_contra_os_defices_de_memoria_induzidos_pelo_THC\"></span>Efeito protetor do CBD contra os défices de memória induzidos pelo THC<span class=\"ez-toc-section-end\"></span></h3>\n<p>Um estudo em ratos mostrou que o tratamento com CBD pode aliviar os défices de memória espacial induzidos pela exposição ao THC. Os autores sugerem que este efeito pode estar ligado à moderação da ativação do receptor CB1 pelo CBD, que <strong>limitaria os efeitos deletérios do THC na plasticidade sináptica</strong>, um mecanismo chave na consolidação da memória.</p>\n<h3><span class=\"ez-toc-section\" id=\"Efeito_neuroprotetor_do_CBD_implicacoes_para_a_memoria\"></span>Efeito neuroprotetor do CBD: implicações para a memória<span class=\"ez-toc-section-end\"></span></h3>\n<p>Outros estudos destacaram as propriedades neuroprotetoras do CBD, que poderiam desempenhar um papel importante na prevenção ou tratamento de certas doenças neurodegenerativas caracterizadas por défices de memória. Por exemplo, foi demonstrado que o CBD pode proteger os neurónios contra a morte celular causada por diferentes formas de stress oxidativo, inflamatório ou excitotóxico, e promover a sobrevivência neuronal.</p>\n<ul>\n<li><strong>Doença de Alzheimer:</strong> Um modelo experimental de rato com doença de Alzheimer mostrou que o CBD pode melhorar a cognição e a memória, reduzindo a neuroinflamação e promovendo a redução das placas amilóides.\n</li>\n<li><strong>Esclerose lateral amiotrófica (ELA):</strong> um estudo realizado em ratos demonstrou um efeito benéfico do CBD na sobrevivência dos neurônios motores e nas funções cognitivas num modelo de ELA, sugerindo potencial terapêutico para esta condição.\n</li>\n</ul>\n<h3><span class=\"ez-toc-section\" id=\"Acao_anti-inflamatoria_e_ansiolitica_do_CBD_efeitos_na_memoria\"></span>Ação anti-inflamatória e ansiolítica do CBD: efeitos na memória?<span class=\"ez-toc-section-end\"></span></h3>\n<p>Está bem documentado que <strong>inflamação e estresse podem contribuir para alterações no funcionamento da memória</strong>, em particular interrompendo os processos de consolidação, armazenamento e recuperação. Além disso, a ansiedade também pode contribuir para problemas de memória.</p>\n<p>Neste contexto, é interessante notar que vários estudos demonstraram que o CBD tem propriedades anti-inflamatórias e ansiolíticas que podem ajudar a preservar ou melhorar as funções da memória. Em particular, foi demonstrado que o CBD reduz a libertação de citocinas inflamatórias, modula a neurotransmissão serotonérgica e aumenta a neurogénese do hipocampo, todos mecanismos que podem ter um efeito benéfico na memória.</p>\n<h2><span class=\"ez-toc-section\" id=\"Em_resumo_qual_o_papel_do_CBD_na_modulacao_da_memoria\"></span>Em resumo: qual o papel do CBD na modulação da memória?<span class=\"ez-toc-section-end\"></span></h2>\n<p>Estudos realizados até o momento sugerem, portanto, que <strong>O CBD pode ter efeitos positivos em certos aspectos da memória</strong>, nomeadamente protegendo contra défices induzidos pelo THC, exercendo ações neuroprotetoras, anti-inflamatórias e ansiolíticas e promovendo a plasticidade sináptica e a neurogénese. No entanto, vale lembrar que estes resultados provêm principalmente de estudos realizados em modelos animais e celulares, e que ainda há muito a descobrir e compreender sobre o real impacto do CBD na memória humana.</p>\n<p>No entanto, estas descobertas iniciais abrem caminho para uma investigação mais aprofundada que poderá ajudar a compreender melhor os mecanismos subjacentes aos efeitos do CBD e as suas interações com outros componentes da cannabis. Entretanto, é fundamental utilizar os produtos CBD de forma responsável e de acordo com a legislação em vigor, estando atento aos possíveis efeitos adversos no nosso organismo.</p>\n","protected":false},"excerpt":{"rendered":"<p>Num contexto onde o uso da cannabis para fins terapêuticos é cada vez mais difundido, é fundamental estudar os potenciais efeitos dos diferentes componentes desta planta no nosso organismo. Entre eles, o canabidiol (CBD) está atraindo grande interesse na investigação científica pelas suas supostas propriedades medicinais sem causar efeitos psicoativos indesejados, como os associados ao [&hellip;]</p>\n","protected":false},"author":95,"featured_media":352167,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[675],"tags":[],"class_list":["post-359400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-sobre-cbd-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https://yoast.com/product/yoast-seo-premium-wordpress/ -->\n<title>O CBD e a sua influência na memória: o que dizem os estudos? - Actualités CBD Blog - Weedy.fr</title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" />\n<link rel=\"canonical\" href=\"https://weedy.fr/blog/pt/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos/\" />\n<meta property=\"og:locale\" content=\"fr_FR\" />\n<meta property=\"og:type\" content=\"article\" />\n<meta property=\"og:title\" content=\"🌱O CBD e a sua influência na memória: o que dizem os estudos? - Weedy.Fr🌱\" />\n<meta property=\"og:description\" content=\"Num contexto onde o uso da cannabis para fins terapêuticos é cada vez mais difundido, é fundamental estudar os potenciais efeitos dos diferentes componentes desta planta no nosso organismo. Entre eles, o canabidiol (CBD) está atraindo grande interesse na investigação científica pelas suas supostas propriedades medicinais sem causar efeitos psicoativos indesejados, como os associados ao [&hellip;]\" />\n<meta property=\"og:url\" content=\"https://weedy.fr/blog/pt/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos/\" />\n<meta property=\"og:site_name\" content=\"Actualités CBD Blog - Weedy.fr\" />\n<meta property=\"article:publisher\" content=\"https://www.facebook.com/weedysocial\" />\n<meta property=\"article:published_time\" content=\"2024-09-17T15:40:27+00:00\" />\n<meta property=\"article:modified_time\" content=\"2024-09-17T15:40:28+00:00\" />\n<meta property=\"og:image\" content=\"https://weedy.fr/blog/wp-content/uploads/2024/01/le-cbd-et-son-influence-sur-la-memoire-que-disent-les-etudes.jpg\" />\n\t<meta property=\"og:image:width\" content=\"1456\" />\n\t<meta property=\"og:image:height\" content=\"832\" />\n\t<meta property=\"og:image:type\" content=\"image/jpeg\" />\n<meta name=\"author\" content=\"Alexandre Lacarré\" />\n<meta name=\"twitter:card\" content=\"summary_large_image\" />\n<meta name=\"twitter:label1\" content=\"Écrit par\" />\n\t<meta name=\"twitter:data1\" content=\"Alexandre Lacarré\" />\n\t<meta name=\"twitter:label2\" content=\"Durée de lecture estimée\" />\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" />\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\/\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos\\/#article\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos\\/\"},\"author\":{\"name\":\"Alexandre Lacarré\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/54c87d7e580413b08a5b875474a54f4e\"},\"headline\":\"O CBD e a sua influência na memória: o que dizem os estudos?\",\"datePublished\":\"2024-09-17T15:40:27+00:00\",\"dateModified\":\"2024-09-17T15:40:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos\\/\"},\"wordCount\":894,\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/le-cbd-et-son-influence-sur-la-memoire-que-disent-les-etudes.jpg\",\"articleSection\":[\"Notícias sobre CBD\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos\\/\",\"name\":\"O CBD e a sua influência na memória: o que dizem os estudos? - Actualités CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/le-cbd-et-son-influence-sur-la-memoire-que-disent-les-etudes.jpg\",\"datePublished\":\"2024-09-17T15:40:27+00:00\",\"dateModified\":\"2024-09-17T15:40:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\/\\/weedy.fr\\/blog\\/pt\\/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos\\/#primaryimage\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/le-cbd-et-son-influence-sur-la-memoire-que-disent-les-etudes.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/le-cbd-et-son-influence-sur-la-memoire-que-disent-les-etudes.jpg\",\"width\":1456,\"height\":832,\"caption\":\"Le CBD et son influence sur la mémoire : que disent les études ?, études, cannabis, impact\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notícias sobre CBD\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/category\\/noticias-sobre-cbd-pt\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"O CBD e a sua influência na memória: o que dizem os estudos?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"name\":\"Actualités CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualité du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\/\\/weedy.fr\\/blog\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\"},\"sameAs\":[\"https:\\/\\/www.facebook.com\\/weedysocial\",\"https:\\/\\/www.instagram.com\\/weedyfrance\\/\"],\"description\":\"Leader en france sur la vente de produits à base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/54c87d7e580413b08a5b875474a54f4e\",\"name\":\"Alexandre Lacarré\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g\",\"url\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g\",\"caption\":\"Alexandre Lacarré\"},\"description\":\"Alexandre Lacarré est reconnu comme un leader innovant et influent dans l'industrie du cannabidiol (CBD). Alexandre a débuté sa carrière dans le secteur des biotechnologies, où il a acquis une expertise précieuse en recherche et développement. Passionné par les potentiels thérapeutiques des composés naturels, il s'est rapidement orienté vers l'industrie naissante du CBD.\",\"sameAs\":[\"https:\\/\\/www.linkedin.com\\/in\\/alexandre-henri-lacarr-785850186\\/\"],\"honorificPrefix\":\"Mr\",\"gender\":\"homme\",\"knowsAbout\":[\"CBD\",\"Cannabis\",\"Copywriter\"],\"worksFor\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/author\\/fiacre\\/\"}]}</script>\n<!-- / Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"O CBD e a sua influência na memória: o que dizem os estudos? - Actualités CBD Blog - Weedy.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://weedy.fr/blog/pt/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos/","og_locale":"fr_FR","og_type":"article","og_title":"🌱O CBD e a sua influência na memória: o que dizem os estudos? - Weedy.Fr🌱","og_description":"Num contexto onde o uso da cannabis para fins terapêuticos é cada vez mais difundido, é fundamental estudar os potenciais efeitos dos diferentes componentes desta planta no nosso organismo. Entre eles, o canabidiol (CBD) está atraindo grande interesse na investigação científica pelas suas supostas propriedades medicinais sem causar efeitos psicoativos indesejados, como os associados ao [&hellip;]","og_url":"https://weedy.fr/blog/pt/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos/","og_site_name":"Actualités CBD Blog - Weedy.fr","article_publisher":"https://www.facebook.com/weedysocial","article_published_time":"2024-09-17T15:40:27+00:00","article_modified_time":"2024-09-17T15:40:28+00:00","og_image":[{"width":1456,"height":832,"url":"https://weedy.fr/en/blog/wp-content/uploads/2024/01/cbd-and-its-influence-on-memory-what-the-studies-say.jpg","type":"image/jpeg"}],"author":"Alexandre Lacarré","twitter_card":"summary_large_image","twitter_misc":{"Écrit par":"Alexandre Lacarré","Durée de lecture estimée":"4 minutes"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"Article","@id":"https://weedy.fr/blog/pt/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos/#article","isPartOf":{"@id":"https://weedy.fr/blog/pt/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos/"},"author":{"name":"Alexandre Lacarré","@id":"https://weedy.fr/blog/#/schema/person/54c87d7e580413b08a5b875474a54f4e"},"headline":"O CBD e a sua influência na memória: o que dizem os estudos?","datePublished":"2024-09-17T15:40:27+00:00","dateModified":"2024-09-17T15:40:28+00:00","mainEntityOfPage":{"@id":"https://weedy.fr/blog/pt/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos/"},"wordCount":894,"publisher":{"@id":"https://weedy.fr/blog/#organization"},"image":{"@id":"https://weedy.fr/blog/pt/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/le-cbd-et-son-influence-sur-la-memoire-que-disent-les-etudes.jpg","articleSection":["Notícias sobre CBD"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https://weedy.fr/blog/pt/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos/","url":"https://weedy.fr/en/blog/pt/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos/","name":"O CBD e a sua influência na memória: o que dizem os estudos? - Actualités CBD Blog - Weedy.fr","isPartOf":{"@id":"https://weedy.fr/blog/#website"},"primaryImageOfPage":{"@id":"https://weedy.fr/blog/pt/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos/#primaryimage"},"image":{"@id":"https://weedy.fr/blog/pt/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/le-cbd-et-son-influence-sur-la-memoire-que-disent-les-etudes.jpg","datePublished":"2024-09-17T15:40:27+00:00","dateModified":"2024-09-17T15:40:28+00:00","breadcrumb":{"@id":"https://weedy.fr/blog/pt/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https://weedy.fr/blog/pt/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/pt/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos/#primaryimage","url":"https://weedy.fr/en/blog/wp-content/uploads/2024/01/cbd-and-its-influence-on-memory-what-the-studies-say.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/le-cbd-et-son-influence-sur-la-memoire-que-disent-les-etudes.jpg","width":1456,"height":832,"caption":"Le CBD et son influence sur la mémoire : que disent les études ?, études, cannabis, impact"},{"@type":"BreadcrumbList","@id":"https://weedy.fr/blog/pt/o-cbd-e-a-sua-influencia-na-memoria-o-que-dizem-os-estudos/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https://weedy.fr/blog/"},{"@type":"ListItem","position":2,"name":"Notícias sobre CBD","item":"https://weedy.fr/blog/category/noticias-sobre-cbd-pt/"},{"@type":"ListItem","position":3,"name":"O CBD e a sua influência na memória: o que dizem os estudos?"}]},{"@type":"WebSite","@id":"https://weedy.fr/blog/#website","url":"https://weedy.fr/en/blog/","name":"Actualités CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualité du CBD et du chanvre en France","publisher":{"@id":"https://weedy.fr/blog/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://weedy.fr/blog/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https://weedy.fr/blog/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https://weedy.fr/en/blog/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/#/schema/logo/image/","url":"https://weedy.fr/en/blog/wp-content/uploads/2024/05/logo-carre.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https://weedy.fr/blog/#/schema/logo/image/"},"sameAs":["https://www.facebook.com/weedysocial","https://www.instagram.com/weedyfrance/"],"description":"Leader en france sur la vente de produits à base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https://weedy.fr/blog/#/schema/person/54c87d7e580413b08a5b875474a54f4e","name":"Alexandre Lacarré","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://secure.gravatar.com/avatar/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g","url":"https://secure.gravatar.com/avatar/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g","caption":"Alexandre Lacarré"},"description":"Alexandre Lacarré est reconnu comme un leader innovant et influent dans l'industrie du cannabidiol (CBD). Alexandre a débuté sa carrière dans le secteur des biotechnologies, où il a acquis une expertise précieuse en recherche et développement. Passionné par les potentiels thérapeutiques des composés naturels, il s'est rapidement orienté vers l'industrie naissante du CBD.","sameAs":["https://www.linkedin.com/in/alexandre-henri-lacarr-785850186/"],"honorificPrefix":"Mr","gender":"homme","knowsAbout":["CBD","Cannabis","Copywriter"],"worksFor":"Weedy.fr","url":"https://weedy.fr/en/blog/author/fiacre/"}]}},"_links":{"self":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts"}],"about":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/users/95"}],"replies":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/comments?post=359400"}],"version-history":[{"count":1,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359400/revisions"}],"predecessor-version":[{"id":359401,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359400/revisions/359401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/media/352167"}],"wp:attachment":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/media?parent=359400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/categories?post=359400"},{"taxonomy":"post_tag","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/tags?post=359400"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}