{"id":359480,"date":"2024-09-17T17:41:49","date_gmt":"2024-09-17T15:41:49","guid":{"rendered":"https://weedy.fr/blog/?p=359480"},"modified":"2024-09-17T17:41:50","modified_gmt":"2024-09-17T15:41:50","slug":"os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho","status":"publish","type":"post","link":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho/","title":{"rendered":"Os benefícios do CBD no futebol americano: gestão da dor, melhoria do sono e otimização do desempenho"},"content":{"rendered":"<p>O <a href=\"https://weedy.fr/en\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> (canabidiol) é uma molécula presente nas plantas de canábis que desperta um interesse crescente, nomeadamente devido aos seus numerosos benefícios terapêuticos. Seu uso agora se estende ao esporte profissional e mais especificamente ao futebol americano. Neste artigo discutiremos alguns dos principais benefícios do <a href=\"https://weedy.fr/en\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> para atletas de elite: tratamento da dor, melhoria do sono e gestão do humor e do stress.</p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire</p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle</span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http://www.w3.org/2000/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"></path></svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http://www.w3.org/2000/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"></path></svg></span></span></span></a></span></div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 \"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https://weedy.fr/en/blog/pt/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho/#Uma_alternativa_ao_tratamento_da_dor\">Uma alternativa ao tratamento da dor</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https://weedy.fr/en/blog/pt/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho/#Como_o_CBD_atua_na_dor\">Como o CBD atua na dor?</a><ul class=\"ez-toc-list-level-4\"><li class=\"ez-toc-heading-level-4\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https://weedy.fr/en/blog/pt/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho/#Dosagem_e_administracao_de_CBD_para_tratamento_da_dor_em_atletas\">Dosagem e administração de CBD para tratamento da dor em atletas</a></li></ul></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https://weedy.fr/en/blog/pt/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho/#Melhore_a_qualidade_do_sono_para_uma_recuperacao_ideal\">Melhore a qualidade do sono para uma recuperação ideal</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https://weedy.fr/en/blog/pt/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho/#Como_usar_o_CBD_para_promover_o_sono\">Como usar o CBD para promover o sono?</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https://weedy.fr/en/blog/pt/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho/#Gerencie_o_humor_e_o_estresse_para_um_melhor_desempenho\">Gerencie o humor e o estresse para um melhor desempenho</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https://weedy.fr/en/blog/pt/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho/#Integre_o_CBD_numa_rotina_diaria_para_otimizar_os_resultados\">Integre o CBD numa rotina diária para otimizar os resultados</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https://weedy.fr/en/blog/pt/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho/#Conclusao_CBD_um_potencial_aliado_dos_atletas_de_alto_nivel\">Conclusão: CBD, um potencial aliado dos atletas de alto nível?</a></li></ul></nav></div>\n<h2><span class=\"ez-toc-section\" id=\"Uma_alternativa_ao_tratamento_da_dor\"></span>Uma alternativa ao tratamento da dor<span class=\"ez-toc-section-end\"></span></h2>\n<p>Infelizmente, a dor crónica ou aguda é comum entre atletas de elite e pode ter um impacto direto no seu desempenho, recuperação e qualidade de vida. O tratamento da dor nestes atletas baseia-se frequentemente no uso de anti-inflamatórios não esteróides (AINEs), que podem causar efeitos secundários graves quando consumidos regularmente e durante um longo período.</p>\n<p>É aqui que <strong>CDB</strong>, que parece ser uma alternativa menos prejudicial aos AINEs. Na verdade, vários estudos demonstraram que o <a href=\"https://weedy.fr/en\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> tem propriedades anti-inflamatórias e analgésicas que podem ajudar a aliviar a dor. Estes efeitos podem ser particularmente interessantes para atletas de contacto, como jogadores de futebol americano, que são frequentemente expostos a choques violentos e repetidos.</p>\n<h3><span class=\"ez-toc-section\" id=\"Como_o_CBD_atua_na_dor\"></span>Como o CBD atua na dor?<span class=\"ez-toc-section-end\"></span></h3>\n<p>O mecanismo exacto de acção pelo qual o CBD alivia a dor ainda é pouco compreendido, mas é geralmente aceite que envolve interacção com receptores do sistema endocanabinóide. Este sistema consiste em dois receptores principais: CB1 e CB2. Os efeitos analgésicos do CBD podem estar ligados a uma modulação dos sinais enviados por estes recetores no cérebro e na medula espinal.</p>\n<h4><span class=\"ez-toc-section\" id=\"Dosagem_e_administracao_de_CBD_para_tratamento_da_dor_em_atletas\"></span>Dosagem e administração de CBD para tratamento da dor em atletas<span class=\"ez-toc-section-end\"></span></h4>\n<p>Atualmente não há recomendações específicas de dosagem de CBD para alívio da dor em atletas. No entanto, alguns especialistas sugerem começar com uma dose baixa (alguns miligramas por dia) antes de aumentar gradualmente esta dose até obter um efeito satisfatório. A forma de administração também pode variar (óleo sublingual, cápsulas, cremes, etc.), sendo aconselhável escolher a que melhor se adapta a cada indivíduo.</p>\n<h2><span class=\"ez-toc-section\" id=\"Melhore_a_qualidade_do_sono_para_uma_recuperacao_ideal\"></span>Melhore a qualidade do sono para uma recuperação ideal<span class=\"ez-toc-section-end\"></span></h2>\n<p>Para atletas de alto nível, uma boa noite de sono é essencial para permitir que o corpo se recupere de forma eficaz após um treino ou competição. Infelizmente, vários fatores de estresse e o ritmo acelerado de vida de um atleta profissional às vezes podem dificultar um sono reparador.</p>\n<p>O <strong>CDB</strong> poderia desempenhar um papel benéfico aqui, melhorando a qualidade do sono dos atletas. Vários estudos destacaram as propriedades reguladoras do CBD nos ciclos sono-vigília, bem como o seu potencial para induzir o relaxamento, facilitando o adormecimento.</p>\n<h3><span class=\"ez-toc-section\" id=\"Como_usar_o_CBD_para_promover_o_sono\"></span>Como usar o CBD para promover o sono?<span class=\"ez-toc-section-end\"></span></h3>\n<p>Para beneficiar dos efeitos do CBD no sono, recomenda-se tomá-lo aproximadamente 30 a 60 minutos antes de deitar. A dose dependerá de cada indivíduo, mas pode-se adotar uma abordagem semelhante à mencionada anteriormente para o manejo da dor, começando com uma dose baixa e ajustando gradativamente conforme necessário.</p>\n<h2><span class=\"ez-toc-section\" id=\"Gerencie_o_humor_e_o_estresse_para_um_melhor_desempenho\"></span>Gerencie o humor e o estresse para um melhor desempenho<span class=\"ez-toc-section-end\"></span></h2>\n<p>As competições, os constrangimentos ligados ao estilo de vida dos atletas de alto nível e a pressão constante pelo desempenho podem muitas vezes gerar stress e impactar negativamente o humor dos jogadores de futebol americano. No entanto, sabemos que um estado psicológico estável e positivo é crucial para lhe permitir dar o seu melhor durante os treinos e competições.</p>\n<p>O CBD ganhou recentemente atenção pelos seus potenciais efeitos sobre a ansiedade e a depressão. Esta molécula parece ser capaz de regular positivamente o humor e reduzir manifestações de estresse, como espasmos musculares involuntários, que podem ter impacto direto no desempenho dos atletas.</p>\n<h3><span class=\"ez-toc-section\" id=\"Integre_o_CBD_numa_rotina_diaria_para_otimizar_os_resultados\"></span>Integre o CBD numa rotina diária para otimizar os resultados<span class=\"ez-toc-section-end\"></span></h3>\n<p>Para obter os benefícios do CBD na gestão do humor e no alívio do stress, pode ser interessante integrar esta molécula na sua rotina desportiva diária. As aplicações regulares de CBD em diferentes formas (óleos, cápsulas, etc.) podem ajudar a manter um estado de espírito estável e calmo nos jogadores de futebol americano, promovendo assim uma melhor concentração e desempenho ao longo do tempo.</p>\n<h2><span class=\"ez-toc-section\" id=\"Conclusao_CBD_um_potencial_aliado_dos_atletas_de_alto_nivel\"></span>Conclusão: CBD, um potencial aliado dos atletas de alto nível?<span class=\"ez-toc-section-end\"></span></h2>\n<p>Em resumo, o CBD apresenta vários benefícios potenciais para os jogadores de futebol americano em termos das suas propriedades analgésicas, do seu impacto favorável no sono e da sua capacidade de regular positivamente o humor e o stress. É claro que cada indivíduo é diferente e as necessidades pessoais devem ser avaliadas para fazer uma utilização óptima do CBD em conformidade com a legislação em vigor.</p>\n","protected":false},"excerpt":{"rendered":"<p>O CBD (canabidiol) é uma molécula presente nas plantas de canábis que desperta um interesse crescente, nomeadamente devido aos seus numerosos benefícios terapêuticos. Seu uso agora se estende ao esporte profissional e mais especificamente ao futebol americano. Neste artigo discutiremos alguns dos principais benefícios do CBD para atletas de elite: tratamento da dor, melhoria do [&hellip;]</p>\n","protected":false},"author":97,"featured_media":351974,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[675],"tags":[],"class_list":["post-359480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-sobre-cbd-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https://yoast.com/product/yoast-seo-premium-wordpress/ -->\n<title>Os benefícios do CBD no futebol americano: gestão da dor, melhoria do sono e otimização do desempenho - Actualités CBD Blog - Weedy.fr</title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" />\n<link rel=\"canonical\" href=\"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho/\" />\n<meta property=\"og:locale\" content=\"fr_FR\" />\n<meta property=\"og:type\" content=\"article\" />\n<meta property=\"og:title\" content=\"🌱Os benefícios do CBD no futebol americano: gestão da dor, melhoria do sono e otimização do desempenho - Weedy.Fr🌱\" />\n<meta property=\"og:description\" content=\"O CBD (canabidiol) é uma molécula presente nas plantas de canábis que desperta um interesse crescente, nomeadamente devido aos seus numerosos benefícios terapêuticos. Seu uso agora se estende ao esporte profissional e mais especificamente ao futebol americano. Neste artigo discutiremos alguns dos principais benefícios do CBD para atletas de elite: tratamento da dor, melhoria do [&hellip;]\" />\n<meta property=\"og:url\" content=\"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho/\" />\n<meta property=\"og:site_name\" content=\"Actualités CBD Blog - Weedy.fr\" />\n<meta property=\"article:publisher\" content=\"https://www.facebook.com/weedysocial\" />\n<meta property=\"article:published_time\" content=\"2024-09-17T15:41:49+00:00\" />\n<meta property=\"article:modified_time\" content=\"2024-09-17T15:41:50+00:00\" />\n<meta property=\"og:image\" content=\"https://weedy.fr/blog/wp-content/uploads/2024/01/les-bienfaits-du-cbd-dans-le-football-americain-gestion-de-la-douleur-amelioration-du-sommeil-et-optimisation-des-performances.jpg\" />\n\t<meta property=\"og:image:width\" content=\"1456\" />\n\t<meta property=\"og:image:height\" content=\"832\" />\n\t<meta property=\"og:image:type\" content=\"image/jpeg\" />\n<meta name=\"author\" content=\"arthur\" />\n<meta name=\"twitter:card\" content=\"summary_large_image\" />\n<meta name=\"twitter:label1\" content=\"Écrit par\" />\n\t<meta name=\"twitter:data1\" content=\"arthur\" />\n\t<meta name=\"twitter:label2\" content=\"Durée de lecture estimée\" />\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" />\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\/\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho\\/#article\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho\\/\"},\"author\":{\"name\":\"arthur\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/0a05724dbfcfa68f2ce947d2ebf0f435\"},\"headline\":\"Os benefícios do CBD no futebol americano: gestão da dor, melhoria do sono e otimização do desempenho\",\"datePublished\":\"2024-09-17T15:41:49+00:00\",\"dateModified\":\"2024-09-17T15:41:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho\\/\"},\"wordCount\":822,\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/les-bienfaits-du-cbd-dans-le-football-americain-gestion-de-la-douleur-amelioration-du-sommeil-et-optimisation-des-performances.jpg\",\"articleSection\":[\"Notícias sobre CBD\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho\\/\",\"name\":\"Os benefícios do CBD no futebol americano: gestão da dor, melhoria do sono e otimização do desempenho - Actualités CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/les-bienfaits-du-cbd-dans-le-football-americain-gestion-de-la-douleur-amelioration-du-sommeil-et-optimisation-des-performances.jpg\",\"datePublished\":\"2024-09-17T15:41:49+00:00\",\"dateModified\":\"2024-09-17T15:41:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho\\/#primaryimage\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/les-bienfaits-du-cbd-dans-le-football-americain-gestion-de-la-douleur-amelioration-du-sommeil-et-optimisation-des-performances.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/les-bienfaits-du-cbd-dans-le-football-americain-gestion-de-la-douleur-amelioration-du-sommeil-et-optimisation-des-performances.jpg\",\"width\":1456,\"height\":832,\"caption\":\"Les bienfaits du CBD dans le football américain : gestion de la douleur, amélioration du sommeil et optimisation des performances\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notícias sobre CBD\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/category\\/noticias-sobre-cbd-pt\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Os benefícios do CBD no futebol americano: gestão da dor, melhoria do sono e otimização do desempenho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"name\":\"Actualités CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualité du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\/\\/weedy.fr\\/blog\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\"},\"sameAs\":[\"https:\\/\\/www.facebook.com\\/weedysocial\",\"https:\\/\\/www.instagram.com\\/weedyfrance\\/\"],\"description\":\"Leader en france sur la vente de produits à base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/0a05724dbfcfa68f2ce947d2ebf0f435\",\"name\":\"arthur\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"url\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"caption\":\"arthur\"},\"url\":\"https:\\/\\/weedy.fr\\/blog\\/author\\/arthur\\/\"}]}</script>\n<!-- / Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Os benefícios do CBD no futebol americano: gestão da dor, melhoria do sono e otimização do desempenho - Actualités CBD Blog - Weedy.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho/","og_locale":"fr_FR","og_type":"article","og_title":"🌱Os benefícios do CBD no futebol americano: gestão da dor, melhoria do sono e otimização do desempenho - Weedy.Fr🌱","og_description":"O CBD (canabidiol) é uma molécula presente nas plantas de canábis que desperta um interesse crescente, nomeadamente devido aos seus numerosos benefícios terapêuticos. Seu uso agora se estende ao esporte profissional e mais especificamente ao futebol americano. Neste artigo discutiremos alguns dos principais benefícios do CBD para atletas de elite: tratamento da dor, melhoria do [&hellip;]","og_url":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho/","og_site_name":"Actualités CBD Blog - Weedy.fr","article_publisher":"https://www.facebook.com/weedysocial","article_published_time":"2024-09-17T15:41:49+00:00","article_modified_time":"2024-09-17T15:41:50+00:00","og_image":[{"width":1456,"height":832,"url":"https://weedy.fr/en/blog/wp-content/uploads/2024/01/the-benefits-of-cbd-in-american-soccer-pain-management-improved-sleep-and-optimized-performance.jpg","type":"image/jpeg"}],"author":"arthur","twitter_card":"summary_large_image","twitter_misc":{"Écrit par":"arthur","Durée de lecture estimée":"4 minutes"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"Article","@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho/#article","isPartOf":{"@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho/"},"author":{"name":"arthur","@id":"https://weedy.fr/blog/#/schema/person/0a05724dbfcfa68f2ce947d2ebf0f435"},"headline":"Os benefícios do CBD no futebol americano: gestão da dor, melhoria do sono e otimização do desempenho","datePublished":"2024-09-17T15:41:49+00:00","dateModified":"2024-09-17T15:41:50+00:00","mainEntityOfPage":{"@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho/"},"wordCount":822,"publisher":{"@id":"https://weedy.fr/blog/#organization"},"image":{"@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/les-bienfaits-du-cbd-dans-le-football-americain-gestion-de-la-douleur-amelioration-du-sommeil-et-optimisation-des-performances.jpg","articleSection":["Notícias sobre CBD"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho/","url":"https://weedy.fr/en/blog/pt/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho/","name":"Os benefícios do CBD no futebol americano: gestão da dor, melhoria do sono e otimização do desempenho - Actualités CBD Blog - Weedy.fr","isPartOf":{"@id":"https://weedy.fr/blog/#website"},"primaryImageOfPage":{"@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho/#primaryimage"},"image":{"@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/les-bienfaits-du-cbd-dans-le-football-americain-gestion-de-la-douleur-amelioration-du-sommeil-et-optimisation-des-performances.jpg","datePublished":"2024-09-17T15:41:49+00:00","dateModified":"2024-09-17T15:41:50+00:00","breadcrumb":{"@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho/#primaryimage","url":"https://weedy.fr/en/blog/wp-content/uploads/2024/01/the-benefits-of-cbd-in-american-soccer-pain-management-improved-sleep-and-optimized-performance.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/les-bienfaits-du-cbd-dans-le-football-americain-gestion-de-la-douleur-amelioration-du-sommeil-et-optimisation-des-performances.jpg","width":1456,"height":832,"caption":"Les bienfaits du CBD dans le football américain : gestion de la douleur, amélioration du sommeil et optimisation des performances"},{"@type":"BreadcrumbList","@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-futebol-americano-gestao-da-dor-melhoria-do-sono-e-otimizacao-do-desempenho/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https://weedy.fr/blog/"},{"@type":"ListItem","position":2,"name":"Notícias sobre CBD","item":"https://weedy.fr/blog/category/noticias-sobre-cbd-pt/"},{"@type":"ListItem","position":3,"name":"Os benefícios do CBD no futebol americano: gestão da dor, melhoria do sono e otimização do desempenho"}]},{"@type":"WebSite","@id":"https://weedy.fr/blog/#website","url":"https://weedy.fr/en/blog/","name":"Actualités CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualité du CBD et du chanvre en France","publisher":{"@id":"https://weedy.fr/blog/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://weedy.fr/blog/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https://weedy.fr/blog/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https://weedy.fr/en/blog/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/#/schema/logo/image/","url":"https://weedy.fr/en/blog/wp-content/uploads/2024/05/logo-carre.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https://weedy.fr/blog/#/schema/logo/image/"},"sameAs":["https://www.facebook.com/weedysocial","https://www.instagram.com/weedyfrance/"],"description":"Leader en france sur la vente de produits à base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https://weedy.fr/blog/#/schema/person/0a05724dbfcfa68f2ce947d2ebf0f435","name":"arthur","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://secure.gravatar.com/avatar/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","url":"https://secure.gravatar.com/avatar/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","caption":"arthur"},"url":"https://weedy.fr/en/blog/author/arthur/"}]}},"_links":{"self":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts"}],"about":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/users/97"}],"replies":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/comments?post=359480"}],"version-history":[{"count":1,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359480/revisions"}],"predecessor-version":[{"id":359481,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359480/revisions/359481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/media/351974"}],"wp:attachment":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/media?parent=359480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/categories?post=359480"},{"taxonomy":"post_tag","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/tags?post=359480"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}