{"id":359656,"date":"2024-09-17T17:44:56","date_gmt":"2024-09-17T15:44:56","guid":{"rendered":"https://weedy.fr/blog/?p=359656"},"modified":"2024-09-17T17:44:57","modified_gmt":"2024-09-17T15:44:57","slug":"interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber","status":"publish","type":"post","link":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber/","title":{"rendered":"Interação entre CBD e diabetes tipo 1: o que você precisa saber"},"content":{"rendered":"<p>O <strong>diabetes tipo 1</strong> é uma doença autoimune caracterizada pela produção insuficiente ou inexistente de insulina. Esse hormônio regula os níveis de glicose no sangue, por isso as pessoas com essa forma de diabetes precisam monitorar os níveis de açúcar no sangue e fazer tratamento com insulina.</p>\n<p>Durante vários anos, os cientistas têm estado interessados ​​no potencial da <strong>canabidiol (<a href=\"https://weedy.fr/en\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a>)</strong>, molécula não psicoativa presente na planta da cannabis, para tratamento de diversas doenças, inclusive diabetes. Este artigo explora as diferentes facetas da interação entre o <a href=\"https://weedy.fr/en\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> e o diabetes tipo 1.</p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire</p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle</span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http://www.w3.org/2000/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"></path></svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http://www.w3.org/2000/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"></path></svg></span></span></span></a></span></div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 \"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https://weedy.fr/en/blog/pt/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber/#Efeitos_do_CBD_no_acucar_no_sangue_e_no_metabolismo_da_glicose\">Efeitos do CBD no açúcar no sangue e no metabolismo da glicose</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https://weedy.fr/en/blog/pt/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber/#CBD_e_complicacoes_do_diabetes_tipo_1\">CBD e complicações do diabetes tipo 1</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https://weedy.fr/en/blog/pt/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber/#Deveriamos_recomendar_fumar_cannabis_para_tratar_diabetes_tipo_1\">Deveríamos recomendar fumar cannabis para tratar diabetes tipo 1?</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https://weedy.fr/en/blog/pt/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber/#Doses_e_formas_de_administracao_do_CBD\">Doses e formas de administração do CBD</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https://weedy.fr/en/blog/pt/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber/#Conclusao_provisoria\">Conclusão provisória</a></li></ul></nav></div>\n<h2><span class=\"ez-toc-section\" id=\"Efeitos_do_CBD_no_acucar_no_sangue_e_no_metabolismo_da_glicose\"></span>Efeitos do CBD no açúcar no sangue e no metabolismo da glicose<span class=\"ez-toc-section-end\"></span></h2>\n<p>A regulação do açúcar no sangue é crucial para pessoas com diabetes. Os investigadores estudaram os efeitos do <a href=\"https://weedy.fr/en\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> no metabolismo da glicose e observaram vários fenómenos interessantes:</p>\n<ul>\n<li>O CBD demonstrou capacidade de reduzir níveis elevados de glicose em ratos com diabetes induzido (<em>Jornal Britânico de Farmacologia</em>, 2006).</li>\n<li>Outro efeito observado é a potencialização dos efeitos da insulina. O CBD parece melhorar a ação deste hormônio, aumentando sua biodisponibilidade, ou a quantidade de insulina realmente utilizada pelo organismo (<em>Revista de Farmácia e Farmacologia</em>, 2006).</li>\n<li>O CBD também pode influenciar o metabolismo da gordura. Um estudo realizado em 2013 sugeriu que a molécula atua nas células de gordura branca e marrom, promovendo a transformação das primeiras nas últimas (<em>Comunicações de pesquisa bioquímica e biofísica</em>). Esta ação pode ajudar a prevenir o acúmulo de lipídios no fígado e melhorar a sensibilidade à insulina.</li>\n</ul>\n<p>Todas estas observações apoiam a ideia de que o <strong>CBD pode ajudar a regular o açúcar no sangue</strong> e oferecem algum alívio às pessoas com diabetes tipo 1. No entanto, é importante lembrar que a maioria destes estudos foram realizados em modelos animais e não são necessariamente transferíveis para humanos.</p>\n<h2><span class=\"ez-toc-section\" id=\"CBD_e_complicacoes_do_diabetes_tipo_1\"></span>CBD e complicações do diabetes tipo 1<span class=\"ez-toc-section-end\"></span></h2>\n<p>Além de influenciar os níveis de açúcar no sangue, o CBD tem propriedades que podem ser benéficas na prevenção ou no alívio de certas complicações relacionadas com a diabetes:</p>\n<ul>\n<li><strong>Propriedades anti-inflamatórias</strong> : O diabetes tipo 1 geralmente causa inflamação crônica dos vasos sanguíneos e órgãos. Foi demonstrado que o CBD reduz os marcadores de inflamação, como mostra um estudo publicado na revista <em>PLOS UM</em> em 2015.</li>\n<li><strong>Efeitos neuroprotetores</strong> : uma complicação comum do diabetes é a neuropatia diabética, que resulta em dor, formigamento e perda de sensibilidade. Pesquisas em modelos animais mostraram que o CBD pode reduzir a neuroinflamação e os sintomas de neuropatia (<em>Revista de Medicina Experimental</em>, 2012; <em>Jornal Europeu da Dor</em>, 2016).</li>\n<li><strong>Retardando a progressão da retinopatia diabética</strong> : essa complicação atinge quase 80% dos diabéticos e pode levar a problemas de visão ou até cegueira. Uma equipa de investigadores destacou um efeito protetor do CBD contra os danos oxidativos que afetam as células da retina e promovem o aparecimento desta patologia (<em>Jornal Americano de Patologia</em>, 2006).</li>\n</ul>\n<h3><span class=\"ez-toc-section\" id=\"Deveriamos_recomendar_fumar_cannabis_para_tratar_diabetes_tipo_1\"></span>Deveríamos recomendar fumar cannabis para tratar diabetes tipo 1?<span class=\"ez-toc-section-end\"></span></h3>\n<p>É importante distinguir o <strong>CBD de outros constituintes da cannabis</strong>, em particular o tetrahidrocanabinol (THC) que tem efeitos psicoativos e pode causar distúrbios cognitivos e afetar a qualidade de vida das pessoas com diabetes. Além disso, a fumaça da cannabis é prejudicial aos pulmões e pode piorar certas complicações do diabetes.</p>\n<h2><span class=\"ez-toc-section\" id=\"Doses_e_formas_de_administracao_do_CBD\"></span>Doses e formas de administração do CBD<span class=\"ez-toc-section-end\"></span></h2>\n<p>Ao falar sobre a interação entre o CBD e o diabetes tipo 1, é essencial considerar a dosagem e os métodos de administração. Na verdade, a forma como o CBD é absorvido pelo organismo pode influenciar os seus efeitos nos níveis de açúcar no sangue.</p>\n<p>Os pesquisadores descobriram que os efeitos do CBD na redução do açúcar no sangue eram dependentes da dose (<em>PLOS UM</em>, 2013): doses moderadas apresentavam potencial terapêutico, enquanto doses altas pareciam menos eficazes ou até contraproducentes. Assim, seria recomendável optar por uma posologia adaptada às necessidades de cada paciente.</p>\n<p>Quanto ao meio de administração, existem diversas opções:</p>\n<ul>\n<li>Ingestão sublingual, utilizando óleos ou pastilhas contendo CBD; este método permite a absorção direta pelas mucosas orais e evita a passagem pelo sistema digestivo.</li>\n<li>Cápsulas orais, para absorção mais lenta mas prolongada; essa opção pode ser interessante para quem busca um efeito duradouro ao longo do dia.</li>\n<li>Cremes e bálsamos, especialmente para aliviar dores associadas à neuropatia ou prevenir problemas de pele frequentemente encontrados em diabéticos.</li>\n</ul>\n<p>Embora os estudos sejam animadores, é importante ressaltar que <strong>CBD não é um tratamento milagroso para diabetes tipo 1</strong>. Pode, no entanto, ser considerado um complemento ao tratamento médico tradicional, após consulta com um profissional de saúde.</p>\n<h2><span class=\"ez-toc-section\" id=\"Conclusao_provisoria\"></span>Conclusão provisória<span class=\"ez-toc-section-end\"></span></h2>\n<p>As interações entre o CBD e a diabetes tipo 1 abrem caminho para abordagens terapêuticas interessantes no tratamento desta doença e das suas complicações. No entanto, é essencial continuar a investigação para compreender melhor como integrar esta molécula nos tratamentos atuais e garantir a eficácia e segurança dos pacientes diabéticos que optam pelo uso do CBD.</p>\n","protected":false},"excerpt":{"rendered":"<p>O diabetes tipo 1 é uma doença autoimune caracterizada pela produção insuficiente ou inexistente de insulina. Esse hormônio regula os níveis de glicose no sangue, por isso as pessoas com essa forma de diabetes precisam monitorar os níveis de açúcar no sangue e fazer tratamento com insulina. Durante vários anos, os cientistas têm estado interessados [&hellip;]</p>\n","protected":false},"author":41,"featured_media":352114,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[672],"tags":[],"class_list":["post-359656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude-e-bem-estar-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https://yoast.com/product/yoast-seo-premium-wordpress/ -->\n<title>Interação entre CBD e diabetes tipo 1: o que você precisa saber - Actualités CBD Blog - Weedy.fr</title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" />\n<link rel=\"canonical\" href=\"https://weedy.fr/blog/pt/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber/\" />\n<meta property=\"og:locale\" content=\"fr_FR\" />\n<meta property=\"og:type\" content=\"article\" />\n<meta property=\"og:title\" content=\"🌱Interação entre CBD e diabetes tipo 1: o que você precisa saber - Weedy.Fr🌱\" />\n<meta property=\"og:description\" content=\"O diabetes tipo 1 é uma doença autoimune caracterizada pela produção insuficiente ou inexistente de insulina. Esse hormônio regula os níveis de glicose no sangue, por isso as pessoas com essa forma de diabetes precisam monitorar os níveis de açúcar no sangue e fazer tratamento com insulina. Durante vários anos, os cientistas têm estado interessados [&hellip;]\" />\n<meta property=\"og:url\" content=\"https://weedy.fr/blog/pt/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber/\" />\n<meta property=\"og:site_name\" content=\"Actualités CBD Blog - Weedy.fr\" />\n<meta property=\"article:publisher\" content=\"https://www.facebook.com/weedysocial\" />\n<meta property=\"article:author\" content=\"https://www.facebook.com/weedysocial/\" />\n<meta property=\"article:published_time\" content=\"2024-09-17T15:44:56+00:00\" />\n<meta property=\"article:modified_time\" content=\"2024-09-17T15:44:57+00:00\" />\n<meta property=\"og:image\" content=\"https://weedy.fr/blog/wp-content/uploads/2024/01/interaction-entre-le-cbd-et-le-diabete-de-type-1-ce-que-vous-devez-savoir.jpg\" />\n\t<meta property=\"og:image:width\" content=\"1456\" />\n\t<meta property=\"og:image:height\" content=\"832\" />\n\t<meta property=\"og:image:type\" content=\"image/jpeg\" />\n<meta name=\"author\" content=\"Julien Cordobes\" />\n<meta name=\"twitter:card\" content=\"summary_large_image\" />\n<meta name=\"twitter:label1\" content=\"Écrit par\" />\n\t<meta name=\"twitter:data1\" content=\"Julien Cordobes\" />\n\t<meta name=\"twitter:label2\" content=\"Durée de lecture estimée\" />\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" />\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\/\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber\\/#article\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber\\/\"},\"author\":{\"name\":\"Julien Cordobes\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/72583fcd87d7cf46afe11d530945bc7e\"},\"headline\":\"Interação entre CBD e diabetes tipo 1: o que você precisa saber\",\"datePublished\":\"2024-09-17T15:44:56+00:00\",\"dateModified\":\"2024-09-17T15:44:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber\\/\"},\"wordCount\":880,\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/interaction-entre-le-cbd-et-le-diabete-de-type-1-ce-que-vous-devez-savoir.jpg\",\"articleSection\":[\"Saúde e Bem-estar\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber\\/\",\"name\":\"Interação entre CBD e diabetes tipo 1: o que você precisa saber - Actualités CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/interaction-entre-le-cbd-et-le-diabete-de-type-1-ce-que-vous-devez-savoir.jpg\",\"datePublished\":\"2024-09-17T15:44:56+00:00\",\"dateModified\":\"2024-09-17T15:44:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber\\/#primaryimage\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/interaction-entre-le-cbd-et-le-diabete-de-type-1-ce-que-vous-devez-savoir.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/interaction-entre-le-cbd-et-le-diabete-de-type-1-ce-que-vous-devez-savoir.jpg\",\"width\":1456,\"height\":832,\"caption\":\"Interaction entre le CBD et le diabète de type 1 : ce que vous devez savoir, glycémie, diabétiques, cannabis\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Saúde e Bem-estar\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/category\\/saude-e-bem-estar-pt\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Interação entre CBD e diabetes tipo 1: o que você precisa saber\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"name\":\"Actualités CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualité du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\/\\/weedy.fr\\/blog\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\"},\"sameAs\":[\"https:\\/\\/www.facebook.com\\/weedysocial\",\"https:\\/\\/www.instagram.com\\/weedyfrance\\/\"],\"description\":\"Leader en france sur la vente de produits à base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/72583fcd87d7cf46afe11d530945bc7e\",\"name\":\"Julien Cordobes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"url\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"caption\":\"Julien Cordobes\"},\"description\":\"Rédacteur en chef spécialisé en CBD Julien, né le 17 juillet 1978 en région Parisienne, est un éminent rédacteur et expert dans le domaine des produits à base de CBD. Suite à ses études en biologie et en médecine alternative, Julien a développé une passion pour les remèdes naturels, dont le CBD. En 2022, il intègre l’équipe du site Weedy.fr en qualité d’expert et de contributeur régulier. Grâce à son expertise scientifique et une écriture claire, Julien aide à démystifier les aspects complexes du CBD, tout en mettant en lumière ses bienfaits et applications potentielles à travers ses articles et participations à des conférences.\",\"sameAs\":[\"https:\\/\\/weedy.fr\",\"https:\\/\\/www.facebook.com\\/weedysocial\\/\",\"https:\\/\\/www.instagram.com\\/weedyfrance\",\"https:\\/\\/www.pinterest.fr\\/WeedyFrance\\/\"],\"honorificPrefix\":\"Mr\",\"birthDate\":\"1978-07-17\",\"gender\":\"male\",\"knowsAbout\":[\"CBD\",\"Cannabis\",\"Copywriter\"],\"knowsLanguage\":[\"French\"],\"jobTitle\":\"Editor-in-chief specializing in CBD\",\"worksFor\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/author\\/cbd_blog_owner\\/\"}]}</script>\n<!-- / Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Interação entre CBD e diabetes tipo 1: o que você precisa saber - Actualités CBD Blog - Weedy.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber/","og_locale":"fr_FR","og_type":"article","og_title":"🌱Interação entre CBD e diabetes tipo 1: o que você precisa saber - Weedy.Fr🌱","og_description":"O diabetes tipo 1 é uma doença autoimune caracterizada pela produção insuficiente ou inexistente de insulina. Esse hormônio regula os níveis de glicose no sangue, por isso as pessoas com essa forma de diabetes precisam monitorar os níveis de açúcar no sangue e fazer tratamento com insulina. Durante vários anos, os cientistas têm estado interessados [&hellip;]","og_url":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber/","og_site_name":"Actualités CBD Blog - Weedy.fr","article_publisher":"https://www.facebook.com/weedysocial","article_author":"https://www.facebook.com/weedysocial/","article_published_time":"2024-09-17T15:44:56+00:00","article_modified_time":"2024-09-17T15:44:57+00:00","og_image":[{"width":1456,"height":832,"url":"https://weedy.fr/en/blog/wp-content/uploads/2024/01/interaction-entre-le-cbd-et-le-diabete-de-type-1-ce-que-vous-devez-savoir.jpg","type":"image/jpeg"}],"author":"Julien Cordobes","twitter_card":"summary_large_image","twitter_misc":{"Écrit par":"Julien Cordobes","Durée de lecture estimée":"4 minutes"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"Article","@id":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber/#article","isPartOf":{"@id":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber/"},"author":{"name":"Julien Cordobes","@id":"https://weedy.fr/blog/#/schema/person/72583fcd87d7cf46afe11d530945bc7e"},"headline":"Interação entre CBD e diabetes tipo 1: o que você precisa saber","datePublished":"2024-09-17T15:44:56+00:00","dateModified":"2024-09-17T15:44:57+00:00","mainEntityOfPage":{"@id":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber/"},"wordCount":880,"publisher":{"@id":"https://weedy.fr/blog/#organization"},"image":{"@id":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/interaction-entre-le-cbd-et-le-diabete-de-type-1-ce-que-vous-devez-savoir.jpg","articleSection":["Saúde e Bem-estar"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber/","url":"https://weedy.fr/en/blog/pt/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber/","name":"Interação entre CBD e diabetes tipo 1: o que você precisa saber - Actualités CBD Blog - Weedy.fr","isPartOf":{"@id":"https://weedy.fr/blog/#website"},"primaryImageOfPage":{"@id":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber/#primaryimage"},"image":{"@id":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/interaction-entre-le-cbd-et-le-diabete-de-type-1-ce-que-vous-devez-savoir.jpg","datePublished":"2024-09-17T15:44:56+00:00","dateModified":"2024-09-17T15:44:57+00:00","breadcrumb":{"@id":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https://weedy.fr/blog/pt/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber/#primaryimage","url":"https://weedy.fr/en/blog/wp-content/uploads/2024/01/interaction-entre-le-cbd-et-le-diabete-de-type-1-ce-que-vous-devez-savoir.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/interaction-entre-le-cbd-et-le-diabete-de-type-1-ce-que-vous-devez-savoir.jpg","width":1456,"height":832,"caption":"Interaction entre le CBD et le diabète de type 1 : ce que vous devez savoir, glycémie, diabétiques, cannabis"},{"@type":"BreadcrumbList","@id":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-diabetes-tipo-1-o-que-voce-precisa-saber/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https://weedy.fr/blog/"},{"@type":"ListItem","position":2,"name":"Saúde e Bem-estar","item":"https://weedy.fr/blog/category/saude-e-bem-estar-pt/"},{"@type":"ListItem","position":3,"name":"Interação entre CBD e diabetes tipo 1: o que você precisa saber"}]},{"@type":"WebSite","@id":"https://weedy.fr/blog/#website","url":"https://weedy.fr/en/blog/","name":"Actualités CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualité du CBD et du chanvre en France","publisher":{"@id":"https://weedy.fr/blog/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://weedy.fr/blog/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https://weedy.fr/blog/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https://weedy.fr/en/blog/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/#/schema/logo/image/","url":"https://weedy.fr/en/blog/wp-content/uploads/2024/05/logo-carre.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https://weedy.fr/blog/#/schema/logo/image/"},"sameAs":["https://www.facebook.com/weedysocial","https://www.instagram.com/weedyfrance/"],"description":"Leader en france sur la vente de produits à base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https://weedy.fr/blog/#/schema/person/72583fcd87d7cf46afe11d530945bc7e","name":"Julien Cordobes","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","url":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","caption":"Julien Cordobes"},"description":"Rédacteur en chef spécialisé en CBD Julien, né le 17 juillet 1978 en région Parisienne, est un éminent rédacteur et expert dans le domaine des produits à base de CBD. Suite à ses études en biologie et en médecine alternative, Julien a développé une passion pour les remèdes naturels, dont le CBD. En 2022, il intègre l’équipe du site Weedy.fr en qualité d’expert et de contributeur régulier. Grâce à son expertise scientifique et une écriture claire, Julien aide à démystifier les aspects complexes du CBD, tout en mettant en lumière ses bienfaits et applications potentielles à travers ses articles et participations à des conférences.","sameAs":["https://weedy.fr","https://www.facebook.com/weedysocial/","https://www.instagram.com/weedyfrance","https://www.pinterest.fr/WeedyFrance/"],"honorificPrefix":"Mr","birthDate":"1978-07-17","gender":"male","knowsAbout":["CBD","Cannabis","Copywriter"],"knowsLanguage":["French"],"jobTitle":"Editor-in-chief specializing in CBD","worksFor":"Weedy.fr","url":"https://weedy.fr/en/blog/author/cbd_blog_owner/"}]}},"_links":{"self":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts"}],"about":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/users/41"}],"replies":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/comments?post=359656"}],"version-history":[{"count":1,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359656/revisions"}],"predecessor-version":[{"id":359657,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359656/revisions/359657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/media/352114"}],"wp:attachment":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/media?parent=359656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/categories?post=359656"},{"taxonomy":"post_tag","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/tags?post=359656"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}