{"id":359880,"date":"2024-09-17T17:48:58","date_gmt":"2024-09-17T15:48:58","guid":{"rendered":"https://weedy.fr/blog/?p=359880"},"modified":"2024-09-17T17:48:59","modified_gmt":"2024-09-17T15:48:59","slug":"os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber","status":"publish","type":"post","link":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber/","title":{"rendered":"Os benefícios do CBD para cães: tudo o que você precisa saber"},"content":{"rendered":"<p>O <strong>CDB</strong>, ou canabidiol, é um composto encontrado na planta cannabis e que desperta cada vez mais interesse pelas suas propriedades benéficas à saúde humana. Mas sabia que o <a href=\"https://weedy.fr/en\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> também pode ser benéfico para os nossos amigos cães? Neste artigo, exploraremos os benefícios potenciais do <a href=\"https://weedy.fr/en\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> para cães, bem como os cuidados que você pode tomar para garantir sua segurança.</p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire</p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle</span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http://www.w3.org/2000/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"></path></svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http://www.w3.org/2000/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"></path></svg></span></span></span></a></span></div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 \"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https://weedy.fr/en/blog/pt/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber/#O_que_e_o_CBD_e_como_funciona_nos_caes\">O que é o CBD e como funciona nos cães?</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https://weedy.fr/en/blog/pt/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber/#Os_beneficios_potenciais_do_CBD_para_caes\">Os benefícios potenciais do CBD para cães</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https://weedy.fr/en/blog/pt/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber/#Dosagem_e_Administracao_de_CBD_em_Caes\">Dosagem e Administração de CBD em Cães</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https://weedy.fr/en/blog/pt/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber/#Possiveis_efeitos_colaterais_do_CBD_em_caes\">Possíveis efeitos colaterais do CBD em cães</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https://weedy.fr/en/blog/pt/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber/#Alguns_cuidados_a_seguir\">Alguns cuidados a seguir</a></li></ul></li></ul></nav></div>\n<h2><span class=\"ez-toc-section\" id=\"O_que_e_o_CBD_e_como_funciona_nos_caes\"></span>O que é o CBD e como funciona nos cães?<span class=\"ez-toc-section-end\"></span></h2>\n<p>O canabidiol (<a href=\"https://weedy.fr/en\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a>) é um dos muitos canabinóides presentes na cannabis. Ao contrário do seu homólogo psicotrópico, o tetrahidrocanabinol (THC), o CBD não tem efeito psicoativo e, portanto, não causa sentimentos de euforia ou euforia. Por outro lado, possui inúmeras propriedades terapêuticas reconhecidas pela comunidade científica.</p>\n<p>Os cães também possuem um sistema endocanabinoide, assim como os humanos. Este último desempenha um papel crucial em muitas funções fisiológicas, como a regulação da dor, do humor, do sono, do apetite e da resposta imunitária. O CBD interage com este sistema ligando-se aos receptores CB1 e CB2, ajudando assim a promover o equilíbrio e o bom funcionamento do corpo.</p>\n<h2><span class=\"ez-toc-section\" id=\"Os_beneficios_potenciais_do_CBD_para_caes\"></span>Os benefícios potenciais do CBD para cães<span class=\"ez-toc-section-end\"></span></h2>\n<p>Embora a investigação sobre o CBD em animais ainda seja limitada, vários estudos e testemunhos destacam os potenciais benefícios do CBD para cães. Aqui estão alguns desses benefícios:</p>\n<ul>\n<li><strong>Alívio da dor</strong> : Algumas pesquisas sugerem que o CBD pode ajudar a reduzir a percepção da dor nos nossos amigos caninos. Isto pode ser de particular interesse em cães com artrite, displasia da anca ou outras condições dolorosas relacionadas com a idade ou doenças crónicas.</li>\n<li><strong>Ansiedade e estresse</strong> : O CBD é conhecido pelos seus efeitos ansiolíticos e relaxantes, ajudando a acalmar cães ansiosos ou stressados, ao mesmo tempo que melhora a sua qualidade de vida.</li>\n<li><strong>Distúrbios do sono</strong> : Graças à sua ação no sistema endocanabinoide e nos neurotransmissores, o CBD pode ajudar a regular o sono e promover um descanso reparador em cães que sofrem de insônia ou com dificuldade para dormir.</li>\n<li><strong>Problemas dermatológicos</strong> : As propriedades anti-inflamatórias e curativas do CBD podem ajudar a resolver os vários problemas de pele frequentemente encontrados em cães, como comichão, irritação, dermatite e até alergias.</li>\n<li><strong>O sistema imunológico</strong> : O CBD também atua no sistema imunológico, ajudando a fortalecer as defesas naturais do corpo e prevenindo assim certas condições e infecções comuns.</li>\n</ul>\n<h3><span class=\"ez-toc-section\" id=\"Dosagem_e_Administracao_de_CBD_em_Caes\"></span>Dosagem e Administração de CBD em Cães<span class=\"ez-toc-section-end\"></span></h3>\n<p>É importante ressaltar que não existe uma dosagem universal para todos os cães, pois diversos fatores influenciam a resposta de cada animal ao CBD. Dentre esses fatores, podemos citar o peso do cão, sua raça, sua idade, seu estado geral de saúde ou mesmo a concentração de CBD do produto utilizado.</p>\n<p>No entanto, uma regra geral é começar com uma dosagem baixa e ajustar gradualmente, se necessário. Por exemplo, podemos começar com uma dose de 1 mg de CBD por 5 kg de peso corporal e depois aumentar esta quantidade se os efeitos esperados não forem suficientes.</p>\n<p>Existem várias formas de produtos de CBD especialmente concebidos para os nossos companheiros de quatro patas: óleos, cápsulas, guloseimas ou bálsamos, cada um com os seus benefícios e facilidade de administração. Você deve escolher aquele que melhor se adapta às suas necessidades e às do seu animal de estimação.</p>\n<h2><span class=\"ez-toc-section\" id=\"Possiveis_efeitos_colaterais_do_CBD_em_caes\"></span>Possíveis efeitos colaterais do CBD em cães<span class=\"ez-toc-section-end\"></span></h2>\n<p>O CBD é frequentemente considerado um produto seguro e bem tolerado, tanto por humanos como por animais. No entanto, deve ser mencionado que alguns efeitos colaterais menores podem ocorrer em alguns cães. Aqui estão alguns deles:</p>\n<ul>\n<li><strong>Sonolência</strong> : O CBD pode causar leve sedação, especialmente quando as doses são grandes. Portanto, é aconselhável monitorar a reação do seu cão e ajustar a dosagem de acordo.</li>\n<li><strong>Diarréia</strong> : Problemas digestivos como diarreia ou náusea podem ocorrer em alguns cães, especialmente quando consomem CBD pela primeira vez ou se o produto utilizado contém aditivos potencialmente irritantes.</li>\n<li><strong>Apetite</strong> : O CBD pode modular temporariamente o apetite dos cães, causando diminuição ou aumento do apetite dependendo do caso.</li>\n</ul>\n<p>Em qualquer caso, é importante levar em consideração o conselho do seu veterinário antes de administrar CBD ao seu cão, especialmente se este sofrer de uma patologia específica ou estiver em tratamento medicamentoso.</p>\n<h3><span class=\"ez-toc-section\" id=\"Alguns_cuidados_a_seguir\"></span>Alguns cuidados a seguir<span class=\"ez-toc-section-end\"></span></h3>\n<p>Ao considerar a utilização do CBD para ajudar o seu cão, é essencial escolher um produto de qualidade que se adapte às necessidades específicas do seu animal de estimação. Aqui estão alguns pontos-chave a serem verificados:</p>\n<ol>\n<li>Opte por produtos desenvolvidos especificamente para animais de estimação: eles normalmente têm concentrações mais baixas de CBD e não contêm aditivos potencialmente prejudiciais aos cães, como adoçantes artificiais.</li>\n<li>Verifique a origem do produto: certifique-se de escolher um produto feito de cânhamo cultivado sem pesticidas, herbicidas ou outros produtos químicos potencialmente tóxicos.</li>\n<li>Escolha um produto rico em CBD, mas com baixo teor de THC: o THC pode ser particularmente perigoso para os nossos amigos caninos, causando efeitos secundários graves, incluindo intoxicação. A legislação francesa limita a concentração de THC em produtos à base de cânhamo a um máximo de 0,2%.</li>\n</ol>\n<p>Em resumo, o CBD pode representar uma alternativa natural interessante para melhorar a qualidade de vida dos nossos cães. No entanto, é essencial ter em conta as precauções habituais e reconhecer que ainda existem muitas zonas cinzentas relativamente aos efeitos a longo prazo e à interação com outros tratamentos. O conselho do seu veterinário, bem como a cautela e a observação cuidadosa do seu cão enquanto toma CBD, continuam a ser essenciais.</p>\n","protected":false},"excerpt":{"rendered":"<p>O CDB, ou canabidiol, é um composto encontrado na planta cannabis e que desperta cada vez mais interesse pelas suas propriedades benéficas à saúde humana. Mas sabia que o CBD também pode ser benéfico para os nossos amigos cães? Neste artigo, exploraremos os benefícios potenciais do CBD para cães, bem como os cuidados que você [&hellip;]</p>\n","protected":false},"author":41,"featured_media":351972,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[675],"tags":[],"class_list":["post-359880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-sobre-cbd-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https://yoast.com/product/yoast-seo-premium-wordpress/ -->\n<title>Os benefícios do CBD para cães: tudo o que você precisa saber - Actualités CBD Blog - Weedy.fr</title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" />\n<link rel=\"canonical\" href=\"https://weedy.fr/blog/pt/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber/\" />\n<meta property=\"og:locale\" content=\"fr_FR\" />\n<meta property=\"og:type\" content=\"article\" />\n<meta property=\"og:title\" content=\"🌱Os benefícios do CBD para cães: tudo o que você precisa saber - Weedy.Fr🌱\" />\n<meta property=\"og:description\" content=\"O CDB, ou canabidiol, é um composto encontrado na planta cannabis e que desperta cada vez mais interesse pelas suas propriedades benéficas à saúde humana. Mas sabia que o CBD também pode ser benéfico para os nossos amigos cães? Neste artigo, exploraremos os benefícios potenciais do CBD para cães, bem como os cuidados que você [&hellip;]\" />\n<meta property=\"og:url\" content=\"https://weedy.fr/blog/pt/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber/\" />\n<meta property=\"og:site_name\" content=\"Actualités CBD Blog - Weedy.fr\" />\n<meta property=\"article:publisher\" content=\"https://www.facebook.com/weedysocial\" />\n<meta property=\"article:author\" content=\"https://www.facebook.com/weedysocial/\" />\n<meta property=\"article:published_time\" content=\"2024-09-17T15:48:58+00:00\" />\n<meta property=\"article:modified_time\" content=\"2024-09-17T15:48:59+00:00\" />\n<meta property=\"og:image\" content=\"https://weedy.fr/blog/wp-content/uploads/2024/01/les-bienfaits-du-cbd-pour-les-chiens-tout-ce-quil-faut-savoir.jpg\" />\n\t<meta property=\"og:image:width\" content=\"1456\" />\n\t<meta property=\"og:image:height\" content=\"832\" />\n\t<meta property=\"og:image:type\" content=\"image/jpeg\" />\n<meta name=\"author\" content=\"Julien Cordobes\" />\n<meta name=\"twitter:card\" content=\"summary_large_image\" />\n<meta name=\"twitter:label1\" content=\"Écrit par\" />\n\t<meta name=\"twitter:data1\" content=\"Julien Cordobes\" />\n\t<meta name=\"twitter:label2\" content=\"Durée de lecture estimée\" />\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" />\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\/\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber\\/#article\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber\\/\"},\"author\":{\"name\":\"Julien Cordobes\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/72583fcd87d7cf46afe11d530945bc7e\"},\"headline\":\"Os benefícios do CBD para cães: tudo o que você precisa saber\",\"datePublished\":\"2024-09-17T15:48:58+00:00\",\"dateModified\":\"2024-09-17T15:48:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber\\/\"},\"wordCount\":1012,\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/les-bienfaits-du-cbd-pour-les-chiens-tout-ce-quil-faut-savoir.jpg\",\"articleSection\":[\"Notícias sobre CBD\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber\\/\",\"name\":\"Os benefícios do CBD para cães: tudo o que você precisa saber - Actualités CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/les-bienfaits-du-cbd-pour-les-chiens-tout-ce-quil-faut-savoir.jpg\",\"datePublished\":\"2024-09-17T15:48:58+00:00\",\"dateModified\":\"2024-09-17T15:48:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber\\/#primaryimage\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/les-bienfaits-du-cbd-pour-les-chiens-tout-ce-quil-faut-savoir.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/les-bienfaits-du-cbd-pour-les-chiens-tout-ce-quil-faut-savoir.jpg\",\"width\":1456,\"height\":832,\"caption\":\"Les bienfaits du CBD pour les chiens : tout ce qu'il faut savoir\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notícias sobre CBD\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/category\\/noticias-sobre-cbd-pt\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Os benefícios do CBD para cães: tudo o que você precisa saber\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"name\":\"Actualités CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualité du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\/\\/weedy.fr\\/blog\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\"},\"sameAs\":[\"https:\\/\\/www.facebook.com\\/weedysocial\",\"https:\\/\\/www.instagram.com\\/weedyfrance\\/\"],\"description\":\"Leader en france sur la vente de produits à base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/72583fcd87d7cf46afe11d530945bc7e\",\"name\":\"Julien Cordobes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"url\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"caption\":\"Julien Cordobes\"},\"description\":\"Rédacteur en chef spécialisé en CBD Julien, né le 17 juillet 1978 en région Parisienne, est un éminent rédacteur et expert dans le domaine des produits à base de CBD. Suite à ses études en biologie et en médecine alternative, Julien a développé une passion pour les remèdes naturels, dont le CBD. En 2022, il intègre l’équipe du site Weedy.fr en qualité d’expert et de contributeur régulier. Grâce à son expertise scientifique et une écriture claire, Julien aide à démystifier les aspects complexes du CBD, tout en mettant en lumière ses bienfaits et applications potentielles à travers ses articles et participations à des conférences.\",\"sameAs\":[\"https:\\/\\/weedy.fr\",\"https:\\/\\/www.facebook.com\\/weedysocial\\/\",\"https:\\/\\/www.instagram.com\\/weedyfrance\",\"https:\\/\\/www.pinterest.fr\\/WeedyFrance\\/\"],\"honorificPrefix\":\"Mr\",\"birthDate\":\"1978-07-17\",\"gender\":\"male\",\"knowsAbout\":[\"CBD\",\"Cannabis\",\"Copywriter\"],\"knowsLanguage\":[\"French\"],\"jobTitle\":\"Editor-in-chief specializing in CBD\",\"worksFor\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/author\\/cbd_blog_owner\\/\"}]}</script>\n<!-- / Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Os benefícios do CBD para cães: tudo o que você precisa saber - Actualités CBD Blog - Weedy.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber/","og_locale":"fr_FR","og_type":"article","og_title":"🌱Os benefícios do CBD para cães: tudo o que você precisa saber - Weedy.Fr🌱","og_description":"O CDB, ou canabidiol, é um composto encontrado na planta cannabis e que desperta cada vez mais interesse pelas suas propriedades benéficas à saúde humana. Mas sabia que o CBD também pode ser benéfico para os nossos amigos cães? Neste artigo, exploraremos os benefícios potenciais do CBD para cães, bem como os cuidados que você [&hellip;]","og_url":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber/","og_site_name":"Actualités CBD Blog - Weedy.fr","article_publisher":"https://www.facebook.com/weedysocial","article_author":"https://www.facebook.com/weedysocial/","article_published_time":"2024-09-17T15:48:58+00:00","article_modified_time":"2024-09-17T15:48:59+00:00","og_image":[{"width":1456,"height":832,"url":"https://weedy.fr/en/blog/wp-content/uploads/2024/01/les-bienfaits-du-cbd-pour-les-chiens-tout-ce-quil-faut-savoir.jpg","type":"image/jpeg"}],"author":"Julien Cordobes","twitter_card":"summary_large_image","twitter_misc":{"Écrit par":"Julien Cordobes","Durée de lecture estimée":"5 minutes"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"Article","@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber/#article","isPartOf":{"@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber/"},"author":{"name":"Julien Cordobes","@id":"https://weedy.fr/blog/#/schema/person/72583fcd87d7cf46afe11d530945bc7e"},"headline":"Os benefícios do CBD para cães: tudo o que você precisa saber","datePublished":"2024-09-17T15:48:58+00:00","dateModified":"2024-09-17T15:48:59+00:00","mainEntityOfPage":{"@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber/"},"wordCount":1012,"publisher":{"@id":"https://weedy.fr/blog/#organization"},"image":{"@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/les-bienfaits-du-cbd-pour-les-chiens-tout-ce-quil-faut-savoir.jpg","articleSection":["Notícias sobre CBD"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber/","url":"https://weedy.fr/en/blog/pt/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber/","name":"Os benefícios do CBD para cães: tudo o que você precisa saber - Actualités CBD Blog - Weedy.fr","isPartOf":{"@id":"https://weedy.fr/blog/#website"},"primaryImageOfPage":{"@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber/#primaryimage"},"image":{"@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/les-bienfaits-du-cbd-pour-les-chiens-tout-ce-quil-faut-savoir.jpg","datePublished":"2024-09-17T15:48:58+00:00","dateModified":"2024-09-17T15:48:59+00:00","breadcrumb":{"@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https://weedy.fr/blog/pt/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber/#primaryimage","url":"https://weedy.fr/en/blog/wp-content/uploads/2024/01/les-bienfaits-du-cbd-pour-les-chiens-tout-ce-quil-faut-savoir.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/les-bienfaits-du-cbd-pour-les-chiens-tout-ce-quil-faut-savoir.jpg","width":1456,"height":832,"caption":"Les bienfaits du CBD pour les chiens : tout ce qu'il faut savoir"},{"@type":"BreadcrumbList","@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-para-caes-tudo-o-que-voce-precisa-saber/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https://weedy.fr/blog/"},{"@type":"ListItem","position":2,"name":"Notícias sobre CBD","item":"https://weedy.fr/blog/category/noticias-sobre-cbd-pt/"},{"@type":"ListItem","position":3,"name":"Os benefícios do CBD para cães: tudo o que você precisa saber"}]},{"@type":"WebSite","@id":"https://weedy.fr/blog/#website","url":"https://weedy.fr/en/blog/","name":"Actualités CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualité du CBD et du chanvre en France","publisher":{"@id":"https://weedy.fr/blog/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://weedy.fr/blog/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https://weedy.fr/blog/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https://weedy.fr/en/blog/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/#/schema/logo/image/","url":"https://weedy.fr/en/blog/wp-content/uploads/2024/05/logo-carre.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https://weedy.fr/blog/#/schema/logo/image/"},"sameAs":["https://www.facebook.com/weedysocial","https://www.instagram.com/weedyfrance/"],"description":"Leader en france sur la vente de produits à base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https://weedy.fr/blog/#/schema/person/72583fcd87d7cf46afe11d530945bc7e","name":"Julien Cordobes","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","url":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","caption":"Julien Cordobes"},"description":"Rédacteur en chef spécialisé en CBD Julien, né le 17 juillet 1978 en région Parisienne, est un éminent rédacteur et expert dans le domaine des produits à base de CBD. Suite à ses études en biologie et en médecine alternative, Julien a développé une passion pour les remèdes naturels, dont le CBD. En 2022, il intègre l’équipe du site Weedy.fr en qualité d’expert et de contributeur régulier. Grâce à son expertise scientifique et une écriture claire, Julien aide à démystifier les aspects complexes du CBD, tout en mettant en lumière ses bienfaits et applications potentielles à travers ses articles et participations à des conférences.","sameAs":["https://weedy.fr","https://www.facebook.com/weedysocial/","https://www.instagram.com/weedyfrance","https://www.pinterest.fr/WeedyFrance/"],"honorificPrefix":"Mr","birthDate":"1978-07-17","gender":"male","knowsAbout":["CBD","Cannabis","Copywriter"],"knowsLanguage":["French"],"jobTitle":"Editor-in-chief specializing in CBD","worksFor":"Weedy.fr","url":"https://weedy.fr/en/blog/author/cbd_blog_owner/"}]}},"_links":{"self":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts"}],"about":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/users/41"}],"replies":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/comments?post=359880"}],"version-history":[{"count":1,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359880/revisions"}],"predecessor-version":[{"id":359881,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359880/revisions/359881"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/media/351972"}],"wp:attachment":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/media?parent=359880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/categories?post=359880"},{"taxonomy":"post_tag","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/tags?post=359880"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}