{"id":360208,"date":"2024-09-17T17:56:34","date_gmt":"2024-09-17T15:56:34","guid":{"rendered":"https://weedy.fr/blog/?p=360208"},"modified":"2024-09-17T17:56:37","modified_gmt":"2024-09-17T15:56:37","slug":"glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario","status":"publish","type":"post","link":"https://weedy.fr/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/","title":{"rendered":"Glossário de cannabis: tudo o que você precisa saber sobre o vocabulário"},"content":{"rendered":"\n<p class=\"has-text-align-left\">O <strong><a href=\"http://weedy.fr/en\">maconha</a> </strong>é um <strong>planta complexa</strong>, com propriedades tão fascinantes quanto assustadoras. No entanto, só temos medo daquilo que não conhecemos. Este é um dos principais problemas da cannabis, quer seja <strong>legal ou não</strong>. É preciso dizer que com mais <strong>400 componentes químicos</strong>, até a comunidade científica às vezes fica perplexa com esta obra-prima botânica. Somam-se a isso uma infinidade de produtos derivados que acabam confundindo os leigos. <a href=\"https://weedy.fr/en\" data-internallinksmanager029f6b8e52c=\"8\" title=\"weedy\">Weedy.fr</a> reúne seus <strong>conhecimento do setor de cannabis</strong> em um único artigo e oferece uma <strong>glossário de cannabis</strong> o que permitirá que você entenda melhor.</p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire</p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle</span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http://www.w3.org/2000/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"></path></svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http://www.w3.org/2000/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"></path></svg></span></span></span></a></span></div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 \"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https://weedy.fr/en/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#Glossario_de_cannabis_pelo_basico_a_planta\">Glossário de cannabis pelo básico: a planta</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https://weedy.fr/en/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#Cannabis_vs_canhamo_industrial\">Cannabis vs. cânhamo industrial</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https://weedy.fr/en/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#Luz_de_cannabis\">Luz de cannabis</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https://weedy.fr/en/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#Ingredientes_ativos_da_cannabis\">Ingredientes ativos da cannabis</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https://weedy.fr/en/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#Canabinoides\">Canabinóides</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https://weedy.fr/en/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#THC\">THC</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https://weedy.fr/en/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#CBD_canabidiol\">CBD (canabidiol)</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https://weedy.fr/en/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#Componentes_da_planta_cannabis\">Componentes da planta cannabis</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https://weedy.fr/en/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#Caules_e_folhas\">Caules e folhas</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https://weedy.fr/en/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#Flores\">Flores</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https://weedy.fr/en/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#Tricomas\">Tricomas</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https://weedy.fr/en/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#Terpenos\">Terpenos</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https://weedy.fr/en/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#Erva_de_cannabis\">Erva de cannabis</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https://weedy.fr/en/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#Maconha_maconha_maconha\">Maconha, maconha, maconha</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https://weedy.fr/en/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#Kif\">Kif</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https://weedy.fr/en/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#Resina_e_polen_de_cannabis\">Resina e pólen de cannabis</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https://weedy.fr/en/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#Haxixe\">Haxixe</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https://weedy.fr/en/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#merda\">merda</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https://weedy.fr/en/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#Polen\">Pólen</a></li></ul></li></ul></nav></div>\n<h2 class=\"wp-block-heading\" id=\"h-lexique-du-cannabis-par-les-bases-nbsp-le-plant\"><span class=\"ez-toc-section\" id=\"Glossario_de_cannabis_pelo_basico_a_planta\"></span>Glossário de cannabis pelo básico: a planta<span class=\"ez-toc-section-end\"></span></h2>\n\n\n<div class=\"wp-block-image size-full wp-image-48611\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https://weedy.fr/wp-content/uploads/2020/01/Fleurs-cannabis-sachet-min.jpg\" alt=\"Saco-flores-cannabis\" class=\"wp-image-48611\"><figcaption class=\"wp-element-caption\">Industrial ou recreativo, o cânhamo é a mesma família de plantas</figcaption></figure>\n</div>\n\n\n<h3 class=\"wp-block-heading\" id=\"h-cannabis-vs-chanvre-industriel\"><span class=\"ez-toc-section\" id=\"Cannabis_vs_canhamo_industrial\"></span>Cannabis vs. cânhamo industrial<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p class=\"has-text-align-left\">Vamos começar este glossário de cannabis com a própria espécie. À menção da palavra “ <strong>maconha</strong> « , fecham os ouvidos mais castos. Fale sobre <strong>cânhamo</strong> é, no entanto, bastante comum. No entanto, visualmente, estas duas plantas parecem perfeitamente idênticas. Não é surpreendente quando você sabe que cannabis significa cânhamo em latim e que às vezes é chamada simplesmente de “ <strong>cânhamo recreativo</strong> « . O único <strong>a diferença está na verdade nas folhas e flores</strong> que irá, no caso da cannabis, produzir uma resina rica em THC, a molécula psicoativa da cannabis, proibida em muitos países.</p>\n\n\n\n<p class=\"has-text-align-left\">Em última análise, a cannabis e o cânhamo são um <strong>mesma espécie de planta</strong>, que é conveniente distinguir no vocabulário para <strong>especificar a legalidade ou não do produto</strong>.</p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-cannabis-light\"><span class=\"ez-toc-section\" id=\"Luz_de_cannabis\"></span>Luz de cannabis<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p class=\"has-text-align-left\">O <strong>cannabis leve</strong> simplesmente designa uma planta cuja <strong>A produção de THC é naturalmente baixa</strong>, e geralmente está dentro da taxa legal imposta. Pelo contrário, a produção de outras moléculas, como <a href=\"https://weedy.fr/en\">CDB</a>, é encorajado.</p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-principes-actifs-du-cannabis\"><span class=\"ez-toc-section\" id=\"Ingredientes_ativos_da_cannabis\"></span>Ingredientes ativos da cannabis<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-cannabinoides\"><span class=\"ez-toc-section\" id=\"Canabinoides\"></span>Canabinóides<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p class=\"has-text-align-left\">A planta de cannabis é composta por numerosos <strong>substâncias químicas</strong>, agrupados sob o nome de <strong>canabinóides</strong>. Conhecidos pelos cientistas desde a década de 1960, os canabinóides atuam no corpo humano ativando o <strong>sistema endocanabinoide</strong> que intervém em particular no nosso <strong>sistemas nervoso e imunológico</strong>. Presentes às dezenas na planta, os canabinóides são, portanto, <strong>responsável por </strong><strong><a href=\"https://weedy.fr/en/blog/side-effects-of-cannabis/\">efeitos da cannabis</a> no corpo humano</strong>. No entanto, todos eles têm efeitos diferentes e nem todos foram ainda identificados.</p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-thc\"><span class=\"ez-toc-section\" id=\"THC\"></span>THC<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p>O <a href=\"https://weedy.fr/en/what-is-thc\"><strong>THC</strong>,</a> Ou <strong>Δ-9-tetrahidrocanabinol</strong> na versão completa, é certamente o canabinóide mais conhecido. Na verdade, é conhecido por sua <strong>efeitos psicoativos</strong> que deixam os consumidores chapados. Também <strong>viciante</strong>, ele é <strong>considerado narcótico</strong> pela maioria dos governos. <strong>A lei europeia limita assim a sua taxa a 0,2%</strong> para plantas autorizadas.</p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-cbd-cannabidiol\"><span class=\"ez-toc-section\" id=\"CBD_canabidiol\"></span>CBD (canabidiol)<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p class=\"has-text-align-left\">Ainda desconhecido do público em geral em meados da década de 2010, <a href=\"https://weedy.fr/en/what-is-cbd\">CDB</a> agora é quase tão conhecido como THC. Pelo contrário, ele é um <strong>canabinóide com efeitos calmantes</strong>, <strong>não psicoativo</strong> E <strong>não viciante</strong>. Às vezes é referido como <strong>cannabis legal</strong> ou cannabis light.</p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-composants-du-plant-de-cannabis\"><span class=\"ez-toc-section\" id=\"Componentes_da_planta_cannabis\"></span>Componentes da planta cannabis<span class=\"ez-toc-section-end\"></span></h2>\n\n\n<div class=\"wp-block-image size-full wp-image-48610\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https://weedy.fr/wp-content/uploads/2020/01/Cannabis-femelle-fleurs-trichomes-min.jpg\" alt=\"Cannabis-flores-femininas-tricomas\" class=\"wp-image-48610\"><figcaption class=\"wp-element-caption\">Flores carregadas de tricomas e terpenos crescem em plantas femininas de cannabis</figcaption></figure>\n</div>\n\n\n<h3 class=\"wp-block-heading\" id=\"h-tiges-et-feuilles\"><span class=\"ez-toc-section\" id=\"Caules_e_folhas\"></span>Caules e folhas<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p class=\"has-text-align-left\">A cannabis é uma planta anual cujas espécies são nativas da Ásia Central ou do Sul. Uma planta clássica consiste em <strong>haste principal</strong>, transportando água e nutrientes para o resto da planta. Do <strong>folhas simétricas</strong> com a forma bem conhecida crescem aos pares a partir do caule ou ramos principais. Servem para absorver luz, fonte de energia vital para a planta.</p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-fleurs\"><span class=\"ez-toc-section\" id=\"Flores\"></span>Flores<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p class=\"has-text-align-left\">Dependendo da espécie e do ambiente em que a planta cresce, o <strong>florescer</strong> chega mais ou menos rapidamente no ciclo de desenvolvimento. Ainda assim, tanto para uso recreativo como terapêutico, estas são as <strong>plantas femininas</strong> que são favorecidos para a produção de flores. Na verdade, se <strong>machos são úteis para polinização</strong>, eles também são menores. As fêmeas produzem <strong>flores grandes cheias de resina</strong> que pode ser seco inteiro ou usado para criar muitos outros produtos derivados. Clique aqui para <a href=\"https://weedy.fr/en/product-category/cbd-flowers/\">veja nossas flores CBD</a>.</p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-trichomes\"><span class=\"ez-toc-section\" id=\"Tricomas\"></span>Tricomas<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p class=\"has-text-align-left\">O <strong>tricomas</strong> são de <strong>pequenas vesículas</strong>, tipos de pêlos, presentes na epiderme da planta e principalmente nas cabeças. Desempenham um papel fundamental, uma vez que são <strong>responsável pela secreção de canabinóides, mas também de terpenos</strong>. Pegajosos, também estão cheios de resina. Comuns na botânica, os tricomas não são <a href=\"https://www.futura-sciences.com/planete/definitions/botanique-trichome-13330/\" target=\"_blank\" rel=\"noopener noreferrer\">não está presente apenas no cânhamo</a> e contribuir para o <strong>proteção de muitas espécies de plantas</strong> contra insetos, ressecamento e até raios UV.</p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-terpenes\"><span class=\"ez-toc-section\" id=\"Terpenos\"></span>Terpenos<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p class=\"has-text-align-left\">UM <strong>terpeno</strong> é um hidrocarboneto naturalmente presente na cannabis e em muitas outras plantas. <strong>Abundante em resina</strong>, O <a href=\"https://weedy.fr/en/blog/terpenes-cbd/\" target=\"_blank\" rel=\"noopener noreferrer\">terpenos</a> tem como principal característica ser <strong>odorífero</strong>. É, portanto, a eles que devemos o <strong>sabores e aromas especiais de cannabis</strong>. Existem muitos terpenos diferentes. Entre eles, encontramos <strong>borneol</strong> (mentol), <strong>limoneno</strong> (notas cítricas, predominantemente limão/laranja), <strong>pineno</strong> (agulhas de pinheiro), <strong>mirceno</strong> (terra, almíscar), <strong>beta-cariofileno</strong> (pimenta, especiarias, madeira) ou ainda <strong>linalol</strong> (lavanda, flores).</p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-herbe-de-cannabis\"><span class=\"ez-toc-section\" id=\"Erva_de_cannabis\"></span>Erva de cannabis<span class=\"ez-toc-section-end\"></span></h2>\n\n\n<div class=\"wp-block-image size-full wp-image-48612\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https://weedy.fr/wp-content/uploads/2020/01/Marijuana-beuh-weed-fumer-joint-min.jpg\" alt=\"Fumar maconha-maconha-erva\" class=\"wp-image-48612\"><figcaption class=\"wp-element-caption\">Maconha, erva, erva: tantos nomes para a mesma erva, justificando um léxico canábico completo</figcaption></figure>\n</div>\n\n\n<h3 class=\"wp-block-heading\" id=\"h-marijuana-beuh-weed\"><span class=\"ez-toc-section\" id=\"Maconha_maconha_maconha\"></span>Maconha, maconha, maconha<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p class=\"has-text-align-left\">A cannabis ganhou reputação por ser <a href=\"https://weedy.fr/en/blog/stop-smoking-cannabis/\"><strong>fumado em forma de baseado</strong>.</a> Todos os países, todas as culturas e todas as épocas históricas são afectadas pelo seu consumo. Não é de admirar que a erva tenha quase tantos nomes quanto os fumantes. Entre os mais difundidos, encontramos obviamente o famoso <strong>maconha</strong>, às vezes escrito maconha, que evoca a erva fumegante do <strong>Cânhamo indiano</strong>, simplesmente sinônimo de… cannabis. O círculo está fechado.</p>\n\n\n\n<p class=\"has-text-align-left\">As pessoas que mais falam francês falam frequentemente de <strong>Marie-Jeanne</strong>. Outros preferem mencionar o <strong>erva</strong> (verlan para grama) ou <strong>erva</strong>, um termo em inglês usado tanto para fumar maconha quanto para fumar maconha. <strong>Jaritataca</strong>, <strong>Sensimilia</strong>, <strong>maconha</strong>, <strong>colombiano</strong> e muitos outros completam a lista.</p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-kif\"><span class=\"ez-toc-section\" id=\"Kif\"></span>Kif<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p class=\"has-text-align-left\"><strong>Kif</strong> é um termo originário do Norte de África que designa um <strong>mistura de tabaco e erva cannabis</strong>. Originalmente, este termo árabe significa simplesmente “ <strong>prazer</strong> ”, ou “alegria”.</p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-resine-et-pollen-de-cannabis\"><span class=\"ez-toc-section\" id=\"Resina_e_polen_de_cannabis\"></span>Resina e pólen de cannabis<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-haschich\"><span class=\"ez-toc-section\" id=\"Haxixe\"></span>Haxixe<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p class=\"has-text-align-left\"><strong>Haxixe</strong> nada mais é do que um termo amplamente utilizado para descrever o <a href=\"https://weedy.fr/en/product-category/cbd-resins/\"><strong>resina de cannabis</strong></a>. Ao contrário da erva pura, o haxixe (ou haxixe) é obtido pela extração da resina diretamente da planta.</p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-shit\"><span class=\"ez-toc-section\" id=\"merda\"></span>merda<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p class=\"has-text-align-left\">O <strong>merda</strong> também é uma forma de resina, com a diferença de que o haxixe é considerado resina pura. Quando ele está <strong>corte</strong>, muitas vezes com ingredientes desconhecidos do consumidor, é chamado de merda.</p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-pollen\"><span class=\"ez-toc-section\" id=\"Polen\"></span>Pólen<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p class=\"has-text-align-left\">O <a href=\"https://weedy.fr/en/product-category/cbd-resins/\"><strong>pólen</strong></a>, Ou <strong>esquiva</strong>, é uma resina mais fina. Distingue-se, portanto, do haxixe por uma <strong>peneiramento mais fino</strong>, não deixando passar tricomas e restos de plantas. O produto é <strong>menos gorduroso que uma resina clássica</strong>e, portanto, mais pulverulento e menos pegajoso.</p>\n\n","protected":false},"excerpt":{"rendered":"<p>O maconha é um planta complexa, com propriedades tão fascinantes quanto assustadoras. No entanto, só temos medo daquilo que não conhecemos. Este é um dos principais problemas da cannabis, quer seja legal ou não. É preciso dizer que com mais 400 componentes químicos, até a comunidade científica às vezes fica perplexa com esta obra-prima botânica. [&hellip;]</p>\n","protected":false},"author":41,"featured_media":351750,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"padrão\n","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[701],"tags":[],"class_list":["post-360208","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultivo-de-cbd-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https://yoast.com/product/yoast-seo-premium-wordpress/ -->\n<title>Glossário de cannabis: maconha, merda, maconha, maconha e outros</title>\n<meta name=\"description\" content=\"Erva daninha, maconha, maconha, skuff: o vocabulário da cannabis é vago. Weedy reúne definições simples e úteis neste léxico da cannabis.\" />\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" />\n<link rel=\"canonical\" href=\"https://weedy.fr/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/\" />\n<meta property=\"og:locale\" content=\"fr_FR\" />\n<meta property=\"og:type\" content=\"article\" />\n<meta property=\"og:title\" content=\"🌱Glossário de cannabis: tudo o que você precisa saber sobre o vocabulário - Weedy.Fr🌱\" />\n<meta property=\"og:description\" content=\"Erva daninha, maconha, maconha, skuff: o vocabulário da cannabis é vago. Weedy reúne definições simples e úteis neste léxico da cannabis.\" />\n<meta property=\"og:url\" content=\"https://weedy.fr/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/\" />\n<meta property=\"og:site_name\" content=\"Actualités CBD Blog - Weedy.fr\" />\n<meta property=\"article:publisher\" content=\"https://www.facebook.com/weedysocial\" />\n<meta property=\"article:author\" content=\"https://www.facebook.com/weedysocial/\" />\n<meta property=\"article:published_time\" content=\"2024-09-17T15:56:34+00:00\" />\n<meta property=\"article:modified_time\" content=\"2024-09-17T15:56:37+00:00\" />\n<meta property=\"og:image\" content=\"https://weedy.fr/blog/wp-content/uploads/2020/02/lexique-cannabis-cbd-weedy.jpg\" />\n\t<meta property=\"og:image:width\" content=\"1600\" />\n\t<meta property=\"og:image:height\" content=\"800\" />\n\t<meta property=\"og:image:type\" content=\"image/jpeg\" />\n<meta name=\"author\" content=\"Julien Cordobes\" />\n<meta name=\"twitter:card\" content=\"summary_large_image\" />\n<meta name=\"twitter:label1\" content=\"Écrit par\" />\n\t<meta name=\"twitter:data1\" content=\"Julien Cordobes\" />\n\t<meta name=\"twitter:label2\" content=\"Durée de lecture estimée\" />\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" />\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\/\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario\\/#article\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario\\/\"},\"author\":{\"name\":\"Julien Cordobes\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/72583fcd87d7cf46afe11d530945bc7e\"},\"headline\":\"Glossário de cannabis: tudo o que você precisa saber sobre o vocabulário\",\"datePublished\":\"2024-09-17T15:56:34+00:00\",\"dateModified\":\"2024-09-17T15:56:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario\\/\"},\"wordCount\":1130,\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2020\\/02\\/lexique-cannabis-cbd-weedy.jpg\",\"articleSection\":[\"Cultivo de CBD\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario\\/\",\"name\":\"Glossário de cannabis: maconha, merda, maconha, maconha e outros\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2020\\/02\\/lexique-cannabis-cbd-weedy.jpg\",\"datePublished\":\"2024-09-17T15:56:34+00:00\",\"dateModified\":\"2024-09-17T15:56:37+00:00\",\"description\":\"Erva daninha, maconha, maconha, skuff: o vocabulário da cannabis é vago. Weedy reúne definições simples e úteis neste léxico da cannabis.\",\"breadcrumb\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\/\\/weedy.fr\\/blog\\/pt\\/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario\\/#primaryimage\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2020\\/02\\/lexique-cannabis-cbd-weedy.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2020\\/02\\/lexique-cannabis-cbd-weedy.jpg\",\"width\":1600,\"height\":800,\"caption\":\"lexique-cannabis-cbd-weedy\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cultivo de CBD\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/category\\/cultivo-de-cbd-pt\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Glossário de cannabis: tudo o que você precisa saber sobre o vocabulário\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"name\":\"Actualités CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualité du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\/\\/weedy.fr\\/blog\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\"},\"sameAs\":[\"https:\\/\\/www.facebook.com\\/weedysocial\",\"https:\\/\\/www.instagram.com\\/weedyfrance\\/\"],\"description\":\"Leader en france sur la vente de produits à base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/72583fcd87d7cf46afe11d530945bc7e\",\"name\":\"Julien Cordobes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"url\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"caption\":\"Julien Cordobes\"},\"description\":\"Rédacteur en chef spécialisé en CBD Julien, né le 17 juillet 1978 en région Parisienne, est un éminent rédacteur et expert dans le domaine des produits à base de CBD. Suite à ses études en biologie et en médecine alternative, Julien a développé une passion pour les remèdes naturels, dont le CBD. En 2022, il intègre l’équipe du site Weedy.fr en qualité d’expert et de contributeur régulier. Grâce à son expertise scientifique et une écriture claire, Julien aide à démystifier les aspects complexes du CBD, tout en mettant en lumière ses bienfaits et applications potentielles à travers ses articles et participations à des conférences.\",\"sameAs\":[\"https:\\/\\/weedy.fr\",\"https:\\/\\/www.facebook.com\\/weedysocial\\/\",\"https:\\/\\/www.instagram.com\\/weedyfrance\",\"https:\\/\\/www.pinterest.fr\\/WeedyFrance\\/\"],\"honorificPrefix\":\"Mr\",\"birthDate\":\"1978-07-17\",\"gender\":\"male\",\"knowsAbout\":[\"CBD\",\"Cannabis\",\"Copywriter\"],\"knowsLanguage\":[\"French\"],\"jobTitle\":\"Editor-in-chief specializing in CBD\",\"worksFor\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/author\\/cbd_blog_owner\\/\"}]}</script>\n<!-- / Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Glossário de cannabis: maconha, merda, maconha, maconha e outros","description":"Erva daninha, maconha, maconha, skuff: o vocabulário da cannabis é vago. Weedy reúne definições simples e úteis neste léxico da cannabis.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://weedy.fr/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/","og_locale":"fr_FR","og_type":"article","og_title":"🌱Glossário de cannabis: tudo o que você precisa saber sobre o vocabulário - Weedy.Fr🌱","og_description":"Erva daninha, maconha, maconha, skuff: o vocabulário da cannabis é vago. Weedy reúne definições simples e úteis neste léxico da cannabis.","og_url":"https://weedy.fr/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/","og_site_name":"Actualités CBD Blog - Weedy.fr","article_publisher":"https://www.facebook.com/weedysocial","article_author":"https://www.facebook.com/weedysocial/","article_published_time":"2024-09-17T15:56:34+00:00","article_modified_time":"2024-09-17T15:56:37+00:00","og_image":[{"width":1600,"height":800,"url":"https://weedy.fr/en/blog/wp-content/uploads/2020/02/lexique-cannabis-cbd-weedy.jpg","type":"image/jpeg"}],"author":"Julien Cordobes","twitter_card":"summary_large_image","twitter_misc":{"Écrit par":"Julien Cordobes","Durée de lecture estimée":"6 minutes"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"Article","@id":"https://weedy.fr/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#article","isPartOf":{"@id":"https://weedy.fr/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/"},"author":{"name":"Julien Cordobes","@id":"https://weedy.fr/blog/#/schema/person/72583fcd87d7cf46afe11d530945bc7e"},"headline":"Glossário de cannabis: tudo o que você precisa saber sobre o vocabulário","datePublished":"2024-09-17T15:56:34+00:00","dateModified":"2024-09-17T15:56:37+00:00","mainEntityOfPage":{"@id":"https://weedy.fr/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/"},"wordCount":1130,"publisher":{"@id":"https://weedy.fr/blog/#organization"},"image":{"@id":"https://weedy.fr/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2020/02/lexique-cannabis-cbd-weedy.jpg","articleSection":["Cultivo de CBD"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https://weedy.fr/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/","url":"https://weedy.fr/en/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/","name":"Glossário de cannabis: maconha, merda, maconha, maconha e outros","isPartOf":{"@id":"https://weedy.fr/blog/#website"},"primaryImageOfPage":{"@id":"https://weedy.fr/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#primaryimage"},"image":{"@id":"https://weedy.fr/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2020/02/lexique-cannabis-cbd-weedy.jpg","datePublished":"2024-09-17T15:56:34+00:00","dateModified":"2024-09-17T15:56:37+00:00","description":"Erva daninha, maconha, maconha, skuff: o vocabulário da cannabis é vago. Weedy reúne definições simples e úteis neste léxico da cannabis.","breadcrumb":{"@id":"https://weedy.fr/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https://weedy.fr/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#primaryimage","url":"https://weedy.fr/en/blog/wp-content/uploads/2020/02/lexique-cannabis-cbd-weedy.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2020/02/lexique-cannabis-cbd-weedy.jpg","width":1600,"height":800,"caption":"lexique-cannabis-cbd-weedy"},{"@type":"BreadcrumbList","@id":"https://weedy.fr/blog/pt/glossario-de-cannabis-tudo-o-que-voce-precisa-saber-sobre-o-vocabulario/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https://weedy.fr/blog/"},{"@type":"ListItem","position":2,"name":"Cultivo de CBD","item":"https://weedy.fr/blog/category/cultivo-de-cbd-pt/"},{"@type":"ListItem","position":3,"name":"Glossário de cannabis: tudo o que você precisa saber sobre o vocabulário"}]},{"@type":"WebSite","@id":"https://weedy.fr/blog/#website","url":"https://weedy.fr/en/blog/","name":"Actualités CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualité du CBD et du chanvre en France","publisher":{"@id":"https://weedy.fr/blog/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://weedy.fr/blog/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https://weedy.fr/blog/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https://weedy.fr/en/blog/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/#/schema/logo/image/","url":"https://weedy.fr/en/blog/wp-content/uploads/2024/05/logo-carre.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https://weedy.fr/blog/#/schema/logo/image/"},"sameAs":["https://www.facebook.com/weedysocial","https://www.instagram.com/weedyfrance/"],"description":"Leader en france sur la vente de produits à base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https://weedy.fr/blog/#/schema/person/72583fcd87d7cf46afe11d530945bc7e","name":"Julien Cordobes","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","url":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","caption":"Julien Cordobes"},"description":"Rédacteur en chef spécialisé en CBD Julien, né le 17 juillet 1978 en région Parisienne, est un éminent rédacteur et expert dans le domaine des produits à base de CBD. Suite à ses études en biologie et en médecine alternative, Julien a développé une passion pour les remèdes naturels, dont le CBD. En 2022, il intègre l’équipe du site Weedy.fr en qualité d’expert et de contributeur régulier. Grâce à son expertise scientifique et une écriture claire, Julien aide à démystifier les aspects complexes du CBD, tout en mettant en lumière ses bienfaits et applications potentielles à travers ses articles et participations à des conférences.","sameAs":["https://weedy.fr","https://www.facebook.com/weedysocial/","https://www.instagram.com/weedyfrance","https://www.pinterest.fr/WeedyFrance/"],"honorificPrefix":"Mr","birthDate":"1978-07-17","gender":"male","knowsAbout":["CBD","Cannabis","Copywriter"],"knowsLanguage":["French"],"jobTitle":"Editor-in-chief specializing in CBD","worksFor":"Weedy.fr","url":"https://weedy.fr/en/blog/author/cbd_blog_owner/"}]}},"_links":{"self":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/360208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts"}],"about":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/users/41"}],"replies":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/comments?post=360208"}],"version-history":[{"count":1,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/360208/revisions"}],"predecessor-version":[{"id":360209,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/360208/revisions/360209"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/media/351750"}],"wp:attachment":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/media?parent=360208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/categories?post=360208"},{"taxonomy":"post_tag","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/tags?post=360208"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}