{"id":360264,"date":"2024-09-17T17:58:53","date_gmt":"2024-09-17T15:58:53","guid":{"rendered":"https://weedy.fr/blog/?p=360264"},"modified":"2024-09-17T17:58:55","modified_gmt":"2024-09-17T15:58:55","slug":"o-que-e-uma-flor-cbd","status":"publish","type":"post","link":"https://weedy.fr/blog/pt/o-que-e-uma-flor-cbd/","title":{"rendered":"O que é uma flor CBD?"},"content":{"rendered":"\n<p>Lá <strong><a href=\"https://weedy.fr/en/product-category/cbd-flowers/\">Flor CBD</a></strong> é uma espécie emblemática da família Cannabaceae. Geralmente é utilizado para a produção de cânhamo industrial, sementes comestíveis e principalmente extratos ricos em canabinóides. A sua legalização gradual em todo o mundo torna-o particularmente popular no mercado. Se você deseja conhecer as virtudes desta flor, a oportunidade está dada a você. Descubra tudo o que você precisa saber sobre a flor <a href=\"https://weedy.fr/en\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> aqui.</p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire</p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle</span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http://www.w3.org/2000/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"></path></svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http://www.w3.org/2000/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"></path></svg></span></span></span></a></span></div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 \"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https://weedy.fr/en/blog/pt/o-que-e-uma-flor-cbd/#Qual_e_a_composicao_da_flor_CBD\">Qual é a composição da flor CBD?</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https://weedy.fr/en/blog/pt/o-que-e-uma-flor-cbd/#Quais_sao_as_categorias_de_flores_CBD\">Quais são as categorias de flores CBD?</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https://weedy.fr/en/blog/pt/o-que-e-uma-flor-cbd/#CBD_Hidroponico\">CBD Hidropônico</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https://weedy.fr/en/blog/pt/o-que-e-uma-flor-cbd/#Flor_interna_de_CBD\">Flor interna de CBD</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https://weedy.fr/en/blog/pt/o-que-e-uma-flor-cbd/#Resina_CBD\">Resina CBD</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https://weedy.fr/en/blog/pt/o-que-e-uma-flor-cbd/#Por_que_usar_flor_CBD\">Por que usar flor CBD?</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https://weedy.fr/en/blog/pt/o-que-e-uma-flor-cbd/#Flor_CBD_na_luta_contra_a_epilepsia\">Flor CBD na luta contra a epilepsia</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https://weedy.fr/en/blog/pt/o-que-e-uma-flor-cbd/#Flor_CBD_e_estresse\">Flor CBD e estresse</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https://weedy.fr/en/blog/pt/o-que-e-uma-flor-cbd/#Flor_CBD_para_um_sono_relaxante\">Flor CBD para um sono relaxante</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https://weedy.fr/en/blog/pt/o-que-e-uma-flor-cbd/#CBD_um_poderoso_antiinflamatorio\">CBD, um poderoso antiinflamatório</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https://weedy.fr/en/blog/pt/o-que-e-uma-flor-cbd/#Como_usar_a_flor_CBD\">Como usar a flor CBD?</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https://weedy.fr/en/blog/pt/o-que-e-uma-flor-cbd/#Infusao_de_flores_CBD\">Infusão de flores CBD</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https://weedy.fr/en/blog/pt/o-que-e-uma-flor-cbd/#Inalacao\">Inalação</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https://weedy.fr/en/blog/pt/o-que-e-uma-flor-cbd/#Corantes\">Corantes</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https://weedy.fr/en/blog/pt/o-que-e-uma-flor-cbd/#Topicos_baseados_em_CBD\">Tópicos baseados em CBD</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https://weedy.fr/en/blog/pt/o-que-e-uma-flor-cbd/#Doces_CBD\">Doces CBD</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https://weedy.fr/en/blog/pt/o-que-e-uma-flor-cbd/#A_legalidade_do_CBD\">A legalidade do CBD</a></li></ul></nav></div>\n<h2 class=\"wp-block-heading\" id=\"h-quelle-est-la-composition-de-la-fleur-de-cbd\"><span class=\"ez-toc-section\" id=\"Qual_e_a_composicao_da_flor_CBD\"></span>Qual é a composição da flor CBD?<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p>Também chamado de cânhamo de alto teor <a href=\"https://weedy.fr/en\">CDB</a> ou cannabis com baixo teor de THC, a flor <a href=\"https://weedy.fr/en\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> vem de uma categoria de cannabis chamada Sativa L. Ela difere da flor de cannabis com THC em sua consistência. Na verdade, a flor <a href=\"https://weedy.fr/en\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> não contém quaisquer substâncias psicotrópicas.</p>\n\n\n\n<p>É também isso que explica a ausência de efeitos secundários graves para a saúde destes consumidores. Além disso, esta flor também pode conter terpenos, flavóides, canabigerol e canabicromeno. No entanto, a sua presença em pequenas quantidades não impede a sua utilização para o fabrico de produtos puramente terapêuticos.</p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-quelles-sont-les-categories-de-fleur-de-cbd\"><span class=\"ez-toc-section\" id=\"Quais_sao_as_categorias_de_flores_CBD\"></span>Quais são as categorias de flores CBD?<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p>Se por uma razão ou outra você está pensando em usar flores CBD, é altamente recomendável conhecer essas diversas categorias. Este conhecimento prévio permitirá que você aprecie melhor os usos que pode fazer desta planta. Isso também permitirá que você saiba qual produto de cannabis com baixo teor de THC você deve usar para suas necessidades.</p>\n\n\n\n<p>Assim, entre outras substâncias ou produtos derivados da flor CBD que você deve conhecer, é possível citar:</p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-le-cbd-hydroponique\"><span class=\"ez-toc-section\" id=\"CBD_Hidroponico\"></span>CBD Hidropônico<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p>O <a href=\"https://weedy.fr/en/product-category/cbd-flowers/\">CBD Hidropônico</a> é na verdade um canabidiol extraído da cannabis legal e cultivado acima do solo. Este tipo de cultivo reúne todos os nutrientes fornecidos pela hidroponia à flor do CBD. Dependendo das suas preferências, é possível encontrar hidroponia em diversos sabores. Especificamente, você pode optar pelos sabores banana, frutas cítricas, café, abacaxi, cereja ou até chocolate.</p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-la-fleur-de-cbd-indoor\"><span class=\"ez-toc-section\" id=\"Flor_interna_de_CBD\"></span>Flor interna de CBD<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p>Se procura um cultivo que lhe permita ter controlo total da sua flor CBD, a de interior ou <a href=\"https://weedy.fr/en/product-category/cbd-flowers/indoor/\">interior</a> é feito para você. No entanto, esta técnica de cultivo requer um grande conhecimento de sua parte. Da semente à manutenção, deve-se seguir cuidadosamente os passos indicados para flores de CBD de interior.</p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-la-resine-de-cbd\"><span class=\"ez-toc-section\" id=\"Resina_CBD\"></span>Resina CBD<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p>Você teve um dia muito agitado e quer relaxar quando chegar em casa? Não há mais preocupações para você, <a href=\"https://weedy.fr/en/product-category/cbd-resins/\">Resina CBD</a> definitivamente irá ajudá-lo. É composto por um nível muito baixo de THC e evita os efeitos colaterais da cannabis clássica. Também deve ser lembrado que esta forma de cannabis está aprovada na Europa. Portanto, você pode levá-lo para qualquer lugar sem medo de represálias durante as buscas de rotina.</p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-pourquoi-utiliser-la-fleur-de-cbd\"><span class=\"ez-toc-section\" id=\"Por_que_usar_flor_CBD\"></span>Por que usar flor CBD?<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p>A flor CBD pode ser usada para diversos fins. Especificamente, segundo alguns usuários deste produto, esta flor pode atuar ativamente contra certas formas de epilepsia. Ao mesmo tempo, também pode ser uma solução válida contra ansiedade, inflamação, dor e perda de sono.</p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-la-fleur-de-cbd-dans-la-lutte-contre-l-epilepsie\"><span class=\"ez-toc-section\" id=\"Flor_CBD_na_luta_contra_a_epilepsia\"></span>Flor CBD na luta contra a epilepsia<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p>Uma das principais razões para usar a flor CBD é a sua capacidade de reduzir os sintomas da epilepsia. Com efeito, esta planta possui propriedades muito específicas que lhe permitem reduzir eficazmente os efeitos nocivos de certas formas específicas e especialmente raras de epilepsia. Por exemplo, experimentos aprovados pelo FDA indicam que esta planta pode atuar ativamente na síndrome de Dravet. Portanto, se sofre desta doença, considere adquirir CBD para aliviar os seus ataques.  </p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-la-fleur-de-cbd-et-le-stress\"><span class=\"ez-toc-section\" id=\"Flor_CBD_e_estresse\"></span>Flor CBD e estresse<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p>O estresse, na grande maioria dos casos, vem da pressão incomum que uma pessoa sente em uma área da vida diária. Concretamente, pode resultar de uma mudança no trabalho, problemas financeiros, vida a dois ou simplesmente problemas de saúde.</p>\n\n\n\n<p>O estresse quando mal administrado pode levar a sérios problemas de saúde. Pode afetar sua pressão arterial ou deixá-lo de muito mau humor. É por todas estas razões que o uso da flor CBD é altamente recomendado para combater o stress ou a ansiedade. Esses componentes naturais permitem influenciar os receptores cerebrais envolvidos na regulação do seu humor.</p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-la-fleur-de-cbd-pour-un-sommeil-relaxant\"><span class=\"ez-toc-section\" id=\"Flor_CBD_para_um_sono_relaxante\"></span>Flor CBD para um sono relaxante<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p>Você teve sono perturbado por dias? Ou o seu estado de saúde exige descanso máximo, mas você não consegue fechar os olhos? Considere usar flor CBD. Na verdade, os usuários desta flor afirmam que ela lhes permite dormir melhor. Isto certamente se deve à sua propriedade relaxante que permite relaxar. Portanto, não hesite em fazê-lo depois de um bom treino para dormir melhor.</p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-le-cbd-un-puissant-anti-inflammatoire\"><span class=\"ez-toc-section\" id=\"CBD_um_poderoso_antiinflamatorio\"></span>CBD, um poderoso antiinflamatório<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p>Provavelmente ainda não acabou as suas surpresas com as virtudes da flor CBD. Suas propriedades antiinflamatórias permitem prevenir inflamações como a artrite. Basta utilizá-lo de maneira adequada, de acordo com o conselho de um especialista. Acima de tudo, consulte o seu médico antes de começar.</p>\n\n\n\n<p>Além disso, o CBD também pode ser usado para aliviar a dor crónica. Na verdade, é um analgésico potencial. Como resultado, pode ajudá-lo a superar dores nas articulações, bem como possíveis casos de enxaqueca. A sua utilização é sobretudo sem efeitos secundários para a saúde, pois contém THC em quantidades muito pequenas.</p>\n\n\n\n<p>Em resumo, a flor CBD pode ser usada por ambos os motivos. Pode ser usado para aliviar certas doenças ou simplesmente para o seu bem-estar. A pesquisa continua a ser feita sobre esses componentes, a fim de descobrir ainda mais essas virtudes.</p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-comment-utiliser-la-fleur-de-cbd\"><span class=\"ez-toc-section\" id=\"Como_usar_a_flor_CBD\"></span>Como usar a flor CBD?<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p>Agora você está convencido das múltiplas virtudes da planta CBD, mas quer saber como usá-la adequadamente. Se sim, você deve saber que a flor CBD pode ser usada tanto em <a href=\"https://weedy.fr/en/product-category/food-cbd/cbd-infusions/\">infusão</a>, na inalação, em tinturas, topicamente ou melhor ainda, em forma de bala. Obviamente, a escolha do uso não é feita aleatoriamente. Geralmente depende do tipo de dor a ser aliviada.</p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-l-infusion-de-la-fleur-de-cbd\"><span class=\"ez-toc-section\" id=\"Infusao_de_flores_CBD\"></span>Infusão de flores CBD<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p>Se quiser usar a flor CBD para fins de relaxamento, a infusão é uma das melhores escolhas a fazer. É prático e simples de fazer. Além disso, você pode simplesmente fazer um chá de ervas com seu CBD para um uso ideal.</p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-l-inhalation\"><span class=\"ez-toc-section\" id=\"Inalacao\"></span>Inalação<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p>A inalação é considerada a forma mais rápida de usar a flor CBD. Utilizando um cachimbo ou vaporizador, permite uma rápida absorção e, por sua vez, um efeito imediato na saúde.</p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-les-teintures\"><span class=\"ez-toc-section\" id=\"Corantes\"></span>Corantes<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p>Se por um motivo ou outro você não quiser inalar ou infundir CBD, as tinturas podem ser muito práticas para você. Na verdade, as tinturas de CBD são líquidos da referida planta tomados por via sublingual. Tal como a inalação, permite uma rápida absorção dos componentes do CBD.</p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-les-topiques-a-base-de-cbd\"><span class=\"ez-toc-section\" id=\"Topicos_baseados_em_CBD\"></span>Tópicos baseados em CBD<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p>Para uso a longo prazo, usar CBD em forma tópica é uma ideia bastante original. Consiste em aplicar esta mistura localmente ou em toda a pele na forma de cremes ou bálsamos. Eles permitem que você combata eficazmente a inflamação e as dores no corpo.</p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-les-bonbons-cbd\"><span class=\"ez-toc-section\" id=\"Doces_CBD\"></span>Doces CBD<span class=\"ez-toc-section-end\"></span></h3>\n\n\n\n<p>Os doces CBD são muito populares no mercado, especialmente entre os jovens. Está disponível em diversas formas e sabores. Prático e muito moderno, permite-lhe beneficiar dos efeitos relaxantes do canabidiol contido na flor CBD. No entanto, recomenda-se não abusar desta forma específica de CBD.</p>\n\n\n\n<p> Em nenhuma circunstância deve ser colocado ao alcance das crianças e deve ser tomado com moderação pelos adultos. Tenha sempre em mente que <a href=\"https://weedy.fr/en/product-category/food-cbd/cbd-candies/\">doce</a> são principalmente CBD e podem ter efeitos negativos se você tomar muito.</p>\n\n\n\n<p>Além disso, você deve prestar atenção especial à qualidade dos doces à base de CBD se desejar obtê-los. O mercado hoje oferece tudo de bom, mas também de ruim nesta categoria.</p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-la-legalite-du-cbd\"><span class=\"ez-toc-section\" id=\"A_legalidade_do_CBD\"></span>A legalidade do CBD<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p>A legalidade da flor CBD e consequentemente dos produtos resultantes do seu processamento varia de um país para outro. Por exemplo, em França, certas farmácias disponibilizam aos seus clientes óleos CBD de muito boa qualidade.</p>\n\n\n\n<p>Por outro lado, noutros países a sua utilização é pura e simplesmente proibida. Por este motivo, antes de obter o seu CBD é importante verificar a legislação em vigor no seu país.</p>\n\n","protected":false},"excerpt":{"rendered":"<p>Lá Flor CBD é uma espécie emblemática da família Cannabaceae. Geralmente é utilizado para a produção de cânhamo industrial, sementes comestíveis e principalmente extratos ricos em canabinóides. A sua legalização gradual em todo o mundo torna-o particularmente popular no mercado. Se você deseja conhecer as virtudes desta flor, a oportunidade está dada a você. Descubra [&hellip;]</p>\n","protected":false},"author":97,"featured_media":351728,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[701],"tags":[],"class_list":["post-360264","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultivo-de-cbd-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https://yoast.com/product/yoast-seo-premium-wordpress/ -->\n<title>O que é uma flor CBD? - Actualités CBD Blog - Weedy.fr</title>\n<meta name=\"description\" content=\"Descubra o que é uma flor CBD, as suas características únicas e as suas variadas utilizações. Um guia completo para quem quer aprender sobre CBD\" />\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" />\n<link rel=\"canonical\" href=\"https://weedy.fr/blog/pt/o-que-e-uma-flor-cbd/\" />\n<meta property=\"og:locale\" content=\"fr_FR\" />\n<meta property=\"og:type\" content=\"article\" />\n<meta property=\"og:title\" content=\"🌱O que é uma flor CBD? - Weedy.Fr🌱\" />\n<meta property=\"og:description\" content=\"Descubra o que é uma flor CBD, as suas características únicas e as suas variadas utilizações. Um guia completo para quem quer aprender sobre CBD\" />\n<meta property=\"og:url\" content=\"https://weedy.fr/blog/pt/o-que-e-uma-flor-cbd/\" />\n<meta property=\"og:site_name\" content=\"Actualités CBD Blog - Weedy.fr\" />\n<meta property=\"article:publisher\" content=\"https://www.facebook.com/weedysocial\" />\n<meta property=\"article:published_time\" content=\"2024-09-17T15:58:53+00:00\" />\n<meta property=\"article:modified_time\" content=\"2024-09-17T15:58:55+00:00\" />\n<meta property=\"og:image\" content=\"https://weedy.fr/blog/wp-content/uploads/2023/10/fleur-cbd-est-quoi.jpg\" />\n\t<meta property=\"og:image:width\" content=\"1600\" />\n\t<meta property=\"og:image:height\" content=\"800\" />\n\t<meta property=\"og:image:type\" content=\"image/jpeg\" />\n<meta name=\"author\" content=\"arthur\" />\n<meta name=\"twitter:card\" content=\"summary_large_image\" />\n<meta name=\"twitter:label1\" content=\"Écrit par\" />\n\t<meta name=\"twitter:data1\" content=\"arthur\" />\n\t<meta name=\"twitter:label2\" content=\"Durée de lecture estimée\" />\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" />\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\/\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/o-que-e-uma-flor-cbd\\/#article\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/o-que-e-uma-flor-cbd\\/\"},\"author\":{\"name\":\"arthur\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/0a05724dbfcfa68f2ce947d2ebf0f435\"},\"headline\":\"O que é uma flor CBD?\",\"datePublished\":\"2024-09-17T15:58:53+00:00\",\"dateModified\":\"2024-09-17T15:58:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/o-que-e-uma-flor-cbd\\/\"},\"wordCount\":1424,\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/o-que-e-uma-flor-cbd\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2023\\/10\\/fleur-cbd-est-quoi.jpg\",\"articleSection\":[\"Cultivo de CBD\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/o-que-e-uma-flor-cbd\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/o-que-e-uma-flor-cbd\\/\",\"name\":\"O que é uma flor CBD? - Actualités CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/o-que-e-uma-flor-cbd\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/o-que-e-uma-flor-cbd\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2023\\/10\\/fleur-cbd-est-quoi.jpg\",\"datePublished\":\"2024-09-17T15:58:53+00:00\",\"dateModified\":\"2024-09-17T15:58:55+00:00\",\"description\":\"Descubra o que é uma flor CBD, as suas características únicas e as suas variadas utilizações. Um guia completo para quem quer aprender sobre CBD\",\"breadcrumb\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/o-que-e-uma-flor-cbd\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\/\\/weedy.fr\\/blog\\/pt\\/o-que-e-uma-flor-cbd\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/o-que-e-uma-flor-cbd\\/#primaryimage\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2023\\/10\\/fleur-cbd-est-quoi.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2023\\/10\\/fleur-cbd-est-quoi.jpg\",\"width\":1600,\"height\":800,\"caption\":\"fleur-cbd-est-quoi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/o-que-e-uma-flor-cbd\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cultivo de CBD\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/category\\/cultivo-de-cbd-pt\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"O que é uma flor CBD?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"name\":\"Actualités CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualité du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\/\\/weedy.fr\\/blog\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\"},\"sameAs\":[\"https:\\/\\/www.facebook.com\\/weedysocial\",\"https:\\/\\/www.instagram.com\\/weedyfrance\\/\"],\"description\":\"Leader en france sur la vente de produits à base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/0a05724dbfcfa68f2ce947d2ebf0f435\",\"name\":\"arthur\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"url\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"caption\":\"arthur\"},\"url\":\"https:\\/\\/weedy.fr\\/blog\\/author\\/arthur\\/\"}]}</script>\n<!-- / Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"O que é uma flor CBD? - Actualités CBD Blog - Weedy.fr","description":"Descubra o que é uma flor CBD, as suas características únicas e as suas variadas utilizações. Um guia completo para quem quer aprender sobre CBD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://weedy.fr/blog/pt/o-que-e-uma-flor-cbd/","og_locale":"fr_FR","og_type":"article","og_title":"🌱O que é uma flor CBD? - Weedy.Fr🌱","og_description":"Descubra o que é uma flor CBD, as suas características únicas e as suas variadas utilizações. Um guia completo para quem quer aprender sobre CBD","og_url":"https://weedy.fr/blog/pt/o-que-e-uma-flor-cbd/","og_site_name":"Actualités CBD Blog - Weedy.fr","article_publisher":"https://www.facebook.com/weedysocial","article_published_time":"2024-09-17T15:58:53+00:00","article_modified_time":"2024-09-17T15:58:55+00:00","og_image":[{"width":1600,"height":800,"url":"https://weedy.fr/en/blog/wp-content/uploads/2023/10/fleur-cbd-est-quoi.jpg","type":"image/jpeg"}],"author":"arthur","twitter_card":"summary_large_image","twitter_misc":{"Écrit par":"arthur","Durée de lecture estimée":"7 minutes"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"Article","@id":"https://weedy.fr/blog/pt/o-que-e-uma-flor-cbd/#article","isPartOf":{"@id":"https://weedy.fr/blog/pt/o-que-e-uma-flor-cbd/"},"author":{"name":"arthur","@id":"https://weedy.fr/blog/#/schema/person/0a05724dbfcfa68f2ce947d2ebf0f435"},"headline":"O que é uma flor CBD?","datePublished":"2024-09-17T15:58:53+00:00","dateModified":"2024-09-17T15:58:55+00:00","mainEntityOfPage":{"@id":"https://weedy.fr/blog/pt/o-que-e-uma-flor-cbd/"},"wordCount":1424,"publisher":{"@id":"https://weedy.fr/blog/#organization"},"image":{"@id":"https://weedy.fr/blog/pt/o-que-e-uma-flor-cbd/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2023/10/fleur-cbd-est-quoi.jpg","articleSection":["Cultivo de CBD"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https://weedy.fr/blog/pt/o-que-e-uma-flor-cbd/","url":"https://weedy.fr/en/blog/pt/o-que-e-uma-flor-cbd/","name":"O que é uma flor CBD? - Actualités CBD Blog - Weedy.fr","isPartOf":{"@id":"https://weedy.fr/blog/#website"},"primaryImageOfPage":{"@id":"https://weedy.fr/blog/pt/o-que-e-uma-flor-cbd/#primaryimage"},"image":{"@id":"https://weedy.fr/blog/pt/o-que-e-uma-flor-cbd/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2023/10/fleur-cbd-est-quoi.jpg","datePublished":"2024-09-17T15:58:53+00:00","dateModified":"2024-09-17T15:58:55+00:00","description":"Descubra o que é uma flor CBD, as suas características únicas e as suas variadas utilizações. Um guia completo para quem quer aprender sobre CBD","breadcrumb":{"@id":"https://weedy.fr/blog/pt/o-que-e-uma-flor-cbd/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https://weedy.fr/blog/pt/o-que-e-uma-flor-cbd/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/pt/o-que-e-uma-flor-cbd/#primaryimage","url":"https://weedy.fr/en/blog/wp-content/uploads/2023/10/fleur-cbd-est-quoi.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2023/10/fleur-cbd-est-quoi.jpg","width":1600,"height":800,"caption":"fleur-cbd-est-quoi"},{"@type":"BreadcrumbList","@id":"https://weedy.fr/blog/pt/o-que-e-uma-flor-cbd/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https://weedy.fr/blog/"},{"@type":"ListItem","position":2,"name":"Cultivo de CBD","item":"https://weedy.fr/blog/category/cultivo-de-cbd-pt/"},{"@type":"ListItem","position":3,"name":"O que é uma flor CBD?"}]},{"@type":"WebSite","@id":"https://weedy.fr/blog/#website","url":"https://weedy.fr/en/blog/","name":"Actualités CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualité du CBD et du chanvre en France","publisher":{"@id":"https://weedy.fr/blog/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://weedy.fr/blog/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https://weedy.fr/blog/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https://weedy.fr/en/blog/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/#/schema/logo/image/","url":"https://weedy.fr/en/blog/wp-content/uploads/2024/05/logo-carre.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https://weedy.fr/blog/#/schema/logo/image/"},"sameAs":["https://www.facebook.com/weedysocial","https://www.instagram.com/weedyfrance/"],"description":"Leader en france sur la vente de produits à base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https://weedy.fr/blog/#/schema/person/0a05724dbfcfa68f2ce947d2ebf0f435","name":"arthur","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://secure.gravatar.com/avatar/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","url":"https://secure.gravatar.com/avatar/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","caption":"arthur"},"url":"https://weedy.fr/en/blog/author/arthur/"}]}},"_links":{"self":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/360264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts"}],"about":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/users/97"}],"replies":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/comments?post=360264"}],"version-history":[{"count":1,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/360264/revisions"}],"predecessor-version":[{"id":360265,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/360264/revisions/360265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/media/351728"}],"wp:attachment":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/media?parent=360264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/categories?post=360264"},{"taxonomy":"post_tag","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/tags?post=360264"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}