{"id":360728,"date":"2024-09-17T18:17:03","date_gmt":"2024-09-17T16:17:03","guid":{"rendered":"https://weedy.fr/blog/?p=360728"},"modified":"2024-09-17T18:17:04","modified_gmt":"2024-09-17T16:17:04","slug":"quais-sao-os-efeitos-do-cbd-no-cerebro-2","status":"publish","type":"post","link":"https://weedy.fr/blog/pt/quais-sao-os-efeitos-do-cbd-no-cerebro-2/","title":{"rendered":"Quais são os efeitos do CBD no cérebro?"},"content":{"rendered":"<p>Conhecemos os efeitos relaxantes e analgésicos do canabidiol (<a href=\"https://weedy.fr/en\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a>). No entanto, os seus efeitos diretos no cérebro ainda são desconhecidos do público em geral. Vamos quebrar um tabu imediatamente: o <a href=\"https://weedy.fr/en\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> não é perigoso e não corre o risco de fazer você perder o dinheiro. Neste artigo explicamos como ele atua em nosso sistema cerebral, quais são os <strong>efeitos do <a href=\"https://weedy.fr/en\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> no cérebro</strong> e quais oportunidades estão sendo estudadas pela comunidade científica.</p>\n<p>Como bónus, recomendamos os melhores derivados de CBD.</p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire</p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle</span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http://www.w3.org/2000/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"></path></svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http://www.w3.org/2000/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"></path></svg></span></span></span></a></span></div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 \"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https://weedy.fr/en/blog/pt/quais-sao-os-efeitos-do-cbd-no-cerebro-2/#CBD_sistema_endocanabinoide_e_o_cerebro\">CBD, sistema endocanabinóide e o cérebro</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https://weedy.fr/en/blog/pt/quais-sao-os-efeitos-do-cbd-no-cerebro-2/#THC_e_CBD_diferentes_efeitos_no_cerebro\">THC e CBD, diferentes efeitos no cérebro</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https://weedy.fr/en/blog/pt/quais-sao-os-efeitos-do-cbd-no-cerebro-2/#Efeitos_do_CBD_no_cerebro\">Efeitos do CBD no cérebro</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https://weedy.fr/en/blog/pt/quais-sao-os-efeitos-do-cbd-no-cerebro-2/#O_CBD_pode_deixar_voce_chapado\">O CBD pode deixar você chapado?</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https://weedy.fr/en/blog/pt/quais-sao-os-efeitos-do-cbd-no-cerebro-2/#Efeitos_do_CBD_no_cerebro_que_oportunidades\">Efeitos do CBD no cérebro: que oportunidades?</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https://weedy.fr/en/blog/pt/quais-sao-os-efeitos-do-cbd-no-cerebro-2/#Qual_derivado_do_CBD_para_um_disturbio_cerebral\">Qual derivado do CBD para um distúrbio cerebral?</a></li></ul></nav></div>\n<h2><span class=\"ez-toc-section\" id=\"CBD_sistema_endocanabinoide_e_o_cerebro\"></span>CBD, sistema endocanabinóide e o cérebro<span class=\"ez-toc-section-end\"></span></h2>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-322415\" src=\"https://weedy.fr/wp-content/uploads/2022/09/Systeme-endocannabinoide-cerveau-min.jpg\" alt=\"sistema endocanabinóide cérebro min\" width=\"900\" height=\"506\"><br>\nOs efeitos do CBD nos humanos (e em todos os mamíferos) são possíveis graças à existência de <a href=\"https://weedy.fr/en/blog/systeme-endocannabinoide-definition/\">sistema endocanabinoide</a> (SECO). Simplificando, o SEC é um conjunto de receptores, chamados CB1 e CB2, espalhados por todo o nosso corpo, e particularmente no cérebro. Mais especificamente, os receptores CB1 fornecem uma <strong>acesso direto ao cérebro e medula espinhal</strong> (O <strong>sistema nervoso central</strong>), explicando os efeitos do CBD no cérebro (voltaremos a isso). Os receptores CB2 são mais direcionados e estão concentrados sobretudo no <strong>sistema imunológico</strong>, o baço e o sistema gastrointestinal. É em particular através da activação destes sensores que o CBD pode aliviar a dor.</p>\n<h2><span class=\"ez-toc-section\" id=\"THC_e_CBD_diferentes_efeitos_no_cerebro\"></span>THC e CBD, diferentes efeitos no cérebro<span class=\"ez-toc-section-end\"></span></h2>\n<p>Há muito que conhecemos as principais diferenças entre os efeitos do CBD e os do CBD. <a href=\"https://weedy.fr/en/blog/systeme-endocannabinoide-definition/\">THC</a>. Além disso, os dois canabinóides não são apenas diferentes, mas muitas vezes opostos. Tanto que tendemos a dizer que <strong>CBD é um antagonista do THC</strong> (tem efeitos opostos). E esta não é apenas uma forma de falar.</p>\n<h3><span class=\"ez-toc-section\" id=\"Efeitos_do_CBD_no_cerebro\"></span>Efeitos do CBD no cérebro<span class=\"ez-toc-section-end\"></span></h3>\n<p>UM <a href=\"https://www.ncbi.nlm.nih.gov/pmc/articles/PMC7858248/\" target=\"_blank\" rel=\"noopener\">estudo publicado em 2021</a> estava interessado no<strong>influência do canabidiol na função cerebral humana</strong>.</p>\n<p>Em pacientes saudáveis ​​(sem problemas cerebrais conhecidos), o elevado consumo de CBD tem <strong>conectividade fronto-estriatal melhorada</strong> em repouso (a parte do cérebro que lhe permite realizar tarefas), o que não acontecia (pelo menos não nas mesmas proporções) em indivíduos que consumiam THC ou placebo. Os efeitos do CBD no cérebro foram, mais uma vez, opostos aos do THC, em vários aspectos: <strong>processamento de emoções</strong>, <strong>memória verbal</strong>, <strong>inibição de resposta</strong> E <strong>processamento auditivo/visual</strong>. Cada uma destas ações requer também a intervenção de diferentes áreas do cérebro, o que nos permite concluir que o CBD não só tem efeitos no cérebro, mas também atua de forma oposta ao THC.</p>\n<p>Em pacientes com psicose ou com alto risco de psicose, o CBD também tem <strong>atividade cerebral modulada</strong>. Ele finalmente modificou o<a href=\"https://fr.wikipedia.org/wiki/Syst%C3%A8me_limbique\" target=\"_blank\" rel=\"noopener\">atividade límbica</a> (envolvido em <strong>emoções e memória</strong>) pacientes que sofrem de<a href=\"https://weedy.fr/en/blog/cbd-and-anxiety/\">ansiedade</a> e níveis modulados de metabólitos em pessoas com transtornos do espectro do autismo.<br>\n<img decoding=\"async\" class=\"size-full wp-image-322413\" src=\"https://weedy.fr/wp-content/uploads/2022/09/CBD-activite-du-cerveau-min.jpg\" alt=\"atividade cerebral cbd min\" width=\"900\" height=\"596\"></p>\n<h3><span class=\"ez-toc-section\" id=\"O_CBD_pode_deixar_voce_chapado\"></span>O CBD pode deixar você chapado?<span class=\"ez-toc-section-end\"></span></h3>\n<p>Não. Mais uma vez, o CBD atua de forma diametralmente oposta ao THC. Portanto, o CBD não pode deixar você chapado, independentemente da dose consumida. Na verdade não é <strong>nem psicoativo nem viciante</strong>. É possível que com o tempo o corpo reaja menos a uma determinada dose de CBD, mas sem o risco de desenvolver dependência. Em resumo, consumir CBD permite evitar <a href=\"https://weedy.fr/en/blog/side-effects-of-cannabis/\">efeitos colaterais da cannabis</a>, enquanto aproveita a maioria de suas vantagens.</p>\n<h2><span class=\"ez-toc-section\" id=\"Efeitos_do_CBD_no_cerebro_que_oportunidades\"></span>Efeitos do CBD no cérebro: que oportunidades?<span class=\"ez-toc-section-end\"></span></h2>\n<p>O mais interessante não é se o CBD tem efeitos no cérebro (e tem), mas sim como usá-los. Os cientistas estão particularmente interessados ​​no seu papel contra <strong>distúrbios neurodegenerativos</strong> como a doença de <a href=\"https://weedy.fr/en/blog/cannabis-cbd-and-parkinson/\">Parkinson</a> (que destrói gradualmente certos neurônios no cérebro), <a href=\"https://weedy.fr/en/blog/alzheimer-cbd/\">Doença de Alzheimer</a> (a forma mais comum de demência),<a href=\"https://weedy.fr/en/blog/cbd-and-epilepsy/\">epilepsia</a> ou o <a href=\"https://weedy.fr/en/blog/cbd-and-multiple-sclerosis/\">esclerose múltipla</a> (que afeta o sistema nervoso central). O <strong>efeitos neuroprotetores do CBD</strong> também pode ser útil para pessoas que sofrem de <a href=\"https://weedy.fr/en/blog/cbd-psychosis/\">psicose</a>.</p>\n<p>Infelizmente, a literatura científica disponível ainda é demasiado escassa para tirar conclusões sobre as oportunidades oferecidas pela <strong>CBD contra distúrbios cerebrais</strong>, ou em qualquer caso ligado ao seu funcionamento.</p>\n<p>Exceções à regra, três tipos de transtornos já se beneficiam <a href=\"https://weedy.fr/en/blog/cbd-treatment-for-pain/\">tratamentos com canabidiol</a> :</p>\n<ul>\n<li>Lá <strong>esclerose múltipla</strong> beneficia de um tratamento à base de canabinóides (Sativex, uma solução oral à base de THC e CBD). Autorizado em França desde 2014, continua, no entanto, extremamente difícil de obter.</li>\n<li>eu&rsquo;<strong>epilepsia infantil</strong>, quando não responde aos tratamentos habituais, às vezes também pode ser tratado com CBD.</li>\n<li>O <a href=\"https://weedy.fr/en/blog/cbd-and-neuropathy/\"><strong>dor neuropática</strong></a>, afetando todos os nervos fora do cérebro e da medula espinhal, também pode ser aliviada pelo CBD.</li>\n</ul>\n<p>No entanto, quaisquer que sejam os avanços da ciência, o CBD é sistematicamente considerado para <strong>reduzir a dor e outros sintomas</strong> dos distúrbios em questão. Portanto, não constitui <strong>sem esperança de recuperação</strong>, mas é antes uma forma de viver melhor com estas doenças, na sua maioria incuráveis, <a href=\"https://weedy.fr/en/blog/cbd-side-effects/\">sem efeitos adversos</a> ou quase.<br>\n<img decoding=\"async\" class=\"size-full wp-image-322414\" src=\"https://weedy.fr/wp-content/uploads/2022/09/Opportunites-effets-CBD-cerveau-min.jpg\" alt=\"efeitos de oportunidades cbd cérebro min\" width=\"900\" height=\"506\"></p>\n<h2><span class=\"ez-toc-section\" id=\"Qual_derivado_do_CBD_para_um_disturbio_cerebral\"></span>Qual derivado do CBD para um distúrbio cerebral?<span class=\"ez-toc-section-end\"></span></h2>\n<p>É aconselhável preferir <strong>derivados de CBD de qualidade</strong>, como os presentes no <a href=\"https://weedy.fr/en\">Loja CBD Weedy.fr</a>e padrões de consumo saudáveis.</p>\n<p>Este é o caso quando você consome seu CBD:</p>\n<ul>\n<li><strong>Rota sublingual</strong>: <a href=\"https://weedy.fr/en/product-category/cbd-oils/\">Óleo CBD</a></li>\n<li><strong>Trato digestivo</strong>: <a href=\"https://weedy.fr/en/product-category/food-cbd/\">CBD Alimentar</a></li>\n<li><strong>Infusão</strong>: <a href=\"https://weedy.fr/en/product-category/food-cbd/cbd-infusions/\">infusões de cânhamo</a>, <a href=\"https://weedy.fr/en/product-category/cbd-flowers/\">Flores CBD</a>, <a href=\"https://weedy.fr/en/product-category/cbd-resins/\">Resinas e pólenes CBD</a></li>\n</ul>\n<p>Prático de usar, dosar e oferecer concentrações variadas, o <strong>Óleos CBD</strong> são geralmente os mais utilizados em paralelo com um tratamento que afeta direta ou indiretamente o cérebro.</p>\n<p><em>Aviso: O CBD não é considerado um tratamento em França e pode causar </em><a href=\"https://weedy.fr/en/blog/cbd-and-anxiety/\"><em>interações medicamentosas</em></a><em> com certos tratamentos convencionais (particularmente antidepressivos). Peça conselho a um profissional de saúde antes de consumi-lo para um distúrbio cerebral. </em></p>\n","protected":false},"excerpt":{"rendered":"<p>Conhecemos os efeitos relaxantes e analgésicos do canabidiol (CBD). No entanto, os seus efeitos diretos no cérebro ainda são desconhecidos do público em geral. Vamos quebrar um tabu imediatamente: o CBD não é perigoso e não corre o risco de fazer você perder o dinheiro. Neste artigo explicamos como ele atua em nosso sistema cerebral, [&hellip;]</p>\n","protected":false},"author":41,"featured_media":352611,"comment_status":"open","ping_status":"closed","sticky":false,"template":"padrão\n","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[672],"tags":[],"class_list":["post-360728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude-e-bem-estar-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https://yoast.com/product/yoast-seo-premium-wordpress/ -->\n<title>Quais são os efeitos do CBD no cérebro? - Actualités CBD Blog - Weedy.fr</title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" />\n<link rel=\"canonical\" href=\"https://weedy.fr/blog/pt/quais-sao-os-efeitos-do-cbd-no-cerebro-2/\" />\n<meta property=\"og:locale\" content=\"fr_FR\" />\n<meta property=\"og:type\" content=\"article\" />\n<meta property=\"og:title\" content=\"🌱Quais são os efeitos do CBD no cérebro? - Weedy.Fr🌱\" />\n<meta property=\"og:description\" content=\"Conhecemos os efeitos relaxantes e analgésicos do canabidiol (CBD). No entanto, os seus efeitos diretos no cérebro ainda são desconhecidos do público em geral. Vamos quebrar um tabu imediatamente: o CBD não é perigoso e não corre o risco de fazer você perder o dinheiro. Neste artigo explicamos como ele atua em nosso sistema cerebral, [&hellip;]\" />\n<meta property=\"og:url\" content=\"https://weedy.fr/blog/pt/quais-sao-os-efeitos-do-cbd-no-cerebro-2/\" />\n<meta property=\"og:site_name\" content=\"Actualités CBD Blog - Weedy.fr\" />\n<meta property=\"article:publisher\" content=\"https://www.facebook.com/weedysocial\" />\n<meta property=\"article:author\" content=\"https://www.facebook.com/weedysocial/\" />\n<meta property=\"article:published_time\" content=\"2024-09-17T16:17:03+00:00\" />\n<meta property=\"article:modified_time\" content=\"2024-09-17T16:17:04+00:00\" />\n<meta property=\"og:image\" content=\"https://weedy.fr/blog/wp-content/uploads/2024/05/quels-sont-les-effets-du-cbd-sur-le-cerveau.jpg\" />\n\t<meta property=\"og:image:width\" content=\"1792\" />\n\t<meta property=\"og:image:height\" content=\"1024\" />\n\t<meta property=\"og:image:type\" content=\"image/jpeg\" />\n<meta name=\"author\" content=\"Julien Cordobes\" />\n<meta name=\"twitter:card\" content=\"summary_large_image\" />\n<meta name=\"twitter:label1\" content=\"Écrit par\" />\n\t<meta name=\"twitter:data1\" content=\"Julien Cordobes\" />\n\t<meta name=\"twitter:label2\" content=\"Durée de lecture estimée\" />\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" />\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\/\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/quais-sao-os-efeitos-do-cbd-no-cerebro-2\\/#article\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/quais-sao-os-efeitos-do-cbd-no-cerebro-2\\/\"},\"author\":{\"name\":\"Julien Cordobes\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/72583fcd87d7cf46afe11d530945bc7e\"},\"headline\":\"Quais são os efeitos do CBD no cérebro?\",\"datePublished\":\"2024-09-17T16:17:03+00:00\",\"dateModified\":\"2024-09-17T16:17:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/quais-sao-os-efeitos-do-cbd-no-cerebro-2\\/\"},\"wordCount\":979,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/quais-sao-os-efeitos-do-cbd-no-cerebro-2\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/quels-sont-les-effets-du-cbd-sur-le-cerveau.jpg\",\"articleSection\":[\"Saúde e Bem-estar\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\/\\/weedy.fr\\/blog\\/pt\\/quais-sao-os-efeitos-do-cbd-no-cerebro-2\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/quais-sao-os-efeitos-do-cbd-no-cerebro-2\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/quais-sao-os-efeitos-do-cbd-no-cerebro-2\\/\",\"name\":\"Quais são os efeitos do CBD no cérebro? - Actualités CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/quais-sao-os-efeitos-do-cbd-no-cerebro-2\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/quais-sao-os-efeitos-do-cbd-no-cerebro-2\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/quels-sont-les-effets-du-cbd-sur-le-cerveau.jpg\",\"datePublished\":\"2024-09-17T16:17:03+00:00\",\"dateModified\":\"2024-09-17T16:17:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/quais-sao-os-efeitos-do-cbd-no-cerebro-2\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\/\\/weedy.fr\\/blog\\/pt\\/quais-sao-os-efeitos-do-cbd-no-cerebro-2\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/quais-sao-os-efeitos-do-cbd-no-cerebro-2\\/#primaryimage\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/quels-sont-les-effets-du-cbd-sur-le-cerveau.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/quels-sont-les-effets-du-cbd-sur-le-cerveau.jpg\",\"width\":1792,\"height\":1024,\"caption\":\"What are the effects of CBD on the brain?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/quais-sao-os-efeitos-do-cbd-no-cerebro-2\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Saúde e Bem-estar\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/category\\/saude-e-bem-estar-pt\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Quais são os efeitos do CBD no cérebro?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"name\":\"Actualités CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualité du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\/\\/weedy.fr\\/blog\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\"},\"sameAs\":[\"https:\\/\\/www.facebook.com\\/weedysocial\",\"https:\\/\\/www.instagram.com\\/weedyfrance\\/\"],\"description\":\"Leader en france sur la vente de produits à base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/72583fcd87d7cf46afe11d530945bc7e\",\"name\":\"Julien Cordobes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"url\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"caption\":\"Julien Cordobes\"},\"description\":\"Rédacteur en chef spécialisé en CBD Julien, né le 17 juillet 1978 en région Parisienne, est un éminent rédacteur et expert dans le domaine des produits à base de CBD. Suite à ses études en biologie et en médecine alternative, Julien a développé une passion pour les remèdes naturels, dont le CBD. En 2022, il intègre l’équipe du site Weedy.fr en qualité d’expert et de contributeur régulier. Grâce à son expertise scientifique et une écriture claire, Julien aide à démystifier les aspects complexes du CBD, tout en mettant en lumière ses bienfaits et applications potentielles à travers ses articles et participations à des conférences.\",\"sameAs\":[\"https:\\/\\/weedy.fr\",\"https:\\/\\/www.facebook.com\\/weedysocial\\/\",\"https:\\/\\/www.instagram.com\\/weedyfrance\",\"https:\\/\\/www.pinterest.fr\\/WeedyFrance\\/\"],\"honorificPrefix\":\"Mr\",\"birthDate\":\"1978-07-17\",\"gender\":\"male\",\"knowsAbout\":[\"CBD\",\"Cannabis\",\"Copywriter\"],\"knowsLanguage\":[\"French\"],\"jobTitle\":\"Editor-in-chief specializing in CBD\",\"worksFor\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/author\\/cbd_blog_owner\\/\"}]}</script>\n<!-- / Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Quais são os efeitos do CBD no cérebro? - Actualités CBD Blog - Weedy.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://weedy.fr/blog/pt/quais-sao-os-efeitos-do-cbd-no-cerebro-2/","og_locale":"fr_FR","og_type":"article","og_title":"🌱Quais são os efeitos do CBD no cérebro? - Weedy.Fr🌱","og_description":"Conhecemos os efeitos relaxantes e analgésicos do canabidiol (CBD). No entanto, os seus efeitos diretos no cérebro ainda são desconhecidos do público em geral. Vamos quebrar um tabu imediatamente: o CBD não é perigoso e não corre o risco de fazer você perder o dinheiro. Neste artigo explicamos como ele atua em nosso sistema cerebral, [&hellip;]","og_url":"https://weedy.fr/blog/pt/quais-sao-os-efeitos-do-cbd-no-cerebro-2/","og_site_name":"Actualités CBD Blog - Weedy.fr","article_publisher":"https://www.facebook.com/weedysocial","article_author":"https://www.facebook.com/weedysocial/","article_published_time":"2024-09-17T16:17:03+00:00","article_modified_time":"2024-09-17T16:17:04+00:00","og_image":[{"width":1792,"height":1024,"url":"https://weedy.fr/en/blog/wp-content/uploads/2024/05/the-effects-of-cbd-on-the-brain.jpg","type":"image/jpeg"}],"author":"Julien Cordobes","twitter_card":"summary_large_image","twitter_misc":{"Écrit par":"Julien Cordobes","Durée de lecture estimée":"5 minutes"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"Article","@id":"https://weedy.fr/blog/pt/quais-sao-os-efeitos-do-cbd-no-cerebro-2/#article","isPartOf":{"@id":"https://weedy.fr/blog/pt/quais-sao-os-efeitos-do-cbd-no-cerebro-2/"},"author":{"name":"Julien Cordobes","@id":"https://weedy.fr/blog/#/schema/person/72583fcd87d7cf46afe11d530945bc7e"},"headline":"Quais são os efeitos do CBD no cérebro?","datePublished":"2024-09-17T16:17:03+00:00","dateModified":"2024-09-17T16:17:04+00:00","mainEntityOfPage":{"@id":"https://weedy.fr/blog/pt/quais-sao-os-efeitos-do-cbd-no-cerebro-2/"},"wordCount":979,"commentCount":0,"publisher":{"@id":"https://weedy.fr/blog/#organization"},"image":{"@id":"https://weedy.fr/blog/pt/quais-sao-os-efeitos-do-cbd-no-cerebro-2/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/quels-sont-les-effets-du-cbd-sur-le-cerveau.jpg","articleSection":["Saúde e Bem-estar"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https://weedy.fr/blog/pt/quais-sao-os-efeitos-do-cbd-no-cerebro-2/#respond"]}]},{"@type":"WebPage","@id":"https://weedy.fr/blog/pt/quais-sao-os-efeitos-do-cbd-no-cerebro-2/","url":"https://weedy.fr/en/blog/pt/quais-sao-os-efeitos-do-cbd-no-cerebro-2/","name":"Quais são os efeitos do CBD no cérebro? - Actualités CBD Blog - Weedy.fr","isPartOf":{"@id":"https://weedy.fr/blog/#website"},"primaryImageOfPage":{"@id":"https://weedy.fr/blog/pt/quais-sao-os-efeitos-do-cbd-no-cerebro-2/#primaryimage"},"image":{"@id":"https://weedy.fr/blog/pt/quais-sao-os-efeitos-do-cbd-no-cerebro-2/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/quels-sont-les-effets-du-cbd-sur-le-cerveau.jpg","datePublished":"2024-09-17T16:17:03+00:00","dateModified":"2024-09-17T16:17:04+00:00","breadcrumb":{"@id":"https://weedy.fr/blog/pt/quais-sao-os-efeitos-do-cbd-no-cerebro-2/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https://weedy.fr/blog/pt/quais-sao-os-efeitos-do-cbd-no-cerebro-2/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/pt/quais-sao-os-efeitos-do-cbd-no-cerebro-2/#primaryimage","url":"https://weedy.fr/en/blog/wp-content/uploads/2024/05/the-effects-of-cbd-on-the-brain.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/quels-sont-les-effets-du-cbd-sur-le-cerveau.jpg","width":1792,"height":1024,"caption":"What are the effects of CBD on the brain?"},{"@type":"BreadcrumbList","@id":"https://weedy.fr/blog/pt/quais-sao-os-efeitos-do-cbd-no-cerebro-2/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https://weedy.fr/blog/"},{"@type":"ListItem","position":2,"name":"Saúde e Bem-estar","item":"https://weedy.fr/blog/category/saude-e-bem-estar-pt/"},{"@type":"ListItem","position":3,"name":"Quais são os efeitos do CBD no cérebro?"}]},{"@type":"WebSite","@id":"https://weedy.fr/blog/#website","url":"https://weedy.fr/en/blog/","name":"Actualités CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualité du CBD et du chanvre en France","publisher":{"@id":"https://weedy.fr/blog/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://weedy.fr/blog/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https://weedy.fr/blog/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https://weedy.fr/en/blog/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/#/schema/logo/image/","url":"https://weedy.fr/en/blog/wp-content/uploads/2024/05/logo-carre.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https://weedy.fr/blog/#/schema/logo/image/"},"sameAs":["https://www.facebook.com/weedysocial","https://www.instagram.com/weedyfrance/"],"description":"Leader en france sur la vente de produits à base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https://weedy.fr/blog/#/schema/person/72583fcd87d7cf46afe11d530945bc7e","name":"Julien Cordobes","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","url":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","caption":"Julien Cordobes"},"description":"Rédacteur en chef spécialisé en CBD Julien, né le 17 juillet 1978 en région Parisienne, est un éminent rédacteur et expert dans le domaine des produits à base de CBD. Suite à ses études en biologie et en médecine alternative, Julien a développé une passion pour les remèdes naturels, dont le CBD. En 2022, il intègre l’équipe du site Weedy.fr en qualité d’expert et de contributeur régulier. Grâce à son expertise scientifique et une écriture claire, Julien aide à démystifier les aspects complexes du CBD, tout en mettant en lumière ses bienfaits et applications potentielles à travers ses articles et participations à des conférences.","sameAs":["https://weedy.fr","https://www.facebook.com/weedysocial/","https://www.instagram.com/weedyfrance","https://www.pinterest.fr/WeedyFrance/"],"honorificPrefix":"Mr","birthDate":"1978-07-17","gender":"male","knowsAbout":["CBD","Cannabis","Copywriter"],"knowsLanguage":["French"],"jobTitle":"Editor-in-chief specializing in CBD","worksFor":"Weedy.fr","url":"https://weedy.fr/en/blog/author/cbd_blog_owner/"}]}},"_links":{"self":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/360728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts"}],"about":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/users/41"}],"replies":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/comments?post=360728"}],"version-history":[{"count":1,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/360728/revisions"}],"predecessor-version":[{"id":360729,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/360728/revisions/360729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/media/352611"}],"wp:attachment":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/media?parent=360728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/categories?post=360728"},{"taxonomy":"post_tag","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/tags?post=360728"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}