{"id":360920,"date":"2024-09-17T18:28:40","date_gmt":"2024-09-17T16:28:40","guid":{"rendered":"https://weedy.fr/blog/?p=360920"},"modified":"2024-09-17T18:28:42","modified_gmt":"2024-09-17T16:28:42","slug":"borreliose-de-lyme-o-que-o-cbd-pode-fazer","status":"publish","type":"post","link":"https://weedy.fr/blog/pt/borreliose-de-lyme-o-que-o-cbd-pode-fazer/","title":{"rendered":"Borreliose de Lyme: o que o CBD pode fazer?"},"content":{"rendered":"<p>Transmitida por carraças, a borreliose de Lyme está cada vez mais disseminada na Europa. Em mais de 90% dos casos é tratado rapidamente e sem muitos problemas.</p>\n<p>Diagnosticada tarde demais, progride silenciosamente, até causar fadiga, dor e paralisia parcial. Infelizmente, é difícil controlá-lo. Conhecido por ser calmante e relaxante para os músculos, o canabidiol (<a href=\"https://weedy.fr/en\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a>) é então considerado uma forma não de curar a doença de Lyme, mas pelo menos de conviver melhor com ela, reduzindo a dor que causa.</p>\n<blockquote><p>Uma retrospectiva do que sabemos sobre <strong>consumo de <a href=\"https://weedy.fr/en\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> no contexto da borreliose de Lyme</strong>.</p></blockquote>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire</p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle</span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http://www.w3.org/2000/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"></path></svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http://www.w3.org/2000/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"></path></svg></span></span></span></a></span></div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 \"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https://weedy.fr/en/blog/pt/borreliose-de-lyme-o-que-o-cbd-pode-fazer/#Doenca_de_Lyme_em_resumo\">Doença de Lyme em resumo</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https://weedy.fr/en/blog/pt/borreliose-de-lyme-o-que-o-cbd-pode-fazer/#CBD_contra_a_doenca_de_Lyme_Explicacao_por_sintomas\">CBD contra a doença de Lyme? Explicação por sintomas</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https://weedy.fr/en/blog/pt/borreliose-de-lyme-o-que-o-cbd-pode-fazer/#CBD_para_reduzir_os_sintomas_da_borreliose_de_Lyme\">CBD para reduzir os sintomas da borreliose de Lyme?</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https://weedy.fr/en/blog/pt/borreliose-de-lyme-o-que-o-cbd-pode-fazer/#Como_usar_o_CBD_quando_voce_sofre_da_doenca_de_Lyme\">Como usar o CBD quando você sofre da doença de Lyme?</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https://weedy.fr/en/blog/pt/borreliose-de-lyme-o-que-o-cbd-pode-fazer/#Meu_cachorro_ou_gato_tem_doenca_de_Lyme_posso_dar_CBD_a_ele\">Meu cachorro ou gato tem doença de Lyme: posso dar CBD a ele?</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https://weedy.fr/en/blog/pt/borreliose-de-lyme-o-que-o-cbd-pode-fazer/#Para_concluir_a_doenca_de_Lyme_pode_ser_curada\">Para concluir: a doença de Lyme pode ser curada?</a></li></ul></nav></div>\n<h2><span class=\"ez-toc-section\" id=\"Doenca_de_Lyme_em_resumo\"></span>Doença de Lyme em resumo<span class=\"ez-toc-section-end\"></span></h2>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-289993\" src=\"https://weedy.fr/wp-content/uploads/2022/02/Piqure-de-tique-min.jpg\" alt=\"min picada de carrapato\" width=\"700\" height=\"466\"><br>\nA borreliose de Lyme, muitas vezes simplificada para doença de Lyme, é uma doença transmitida aos humanos por <strong>picada de um carrapato infectado</strong>. Algumas dezenas de milhares de franceses são diagnosticados a cada ano (<a href=\"https://www.santepubliquefrance.fr/les-actualites/2021/borreliose-de-lyme-donnees-epidemiologiques-2020\" target=\"_blank\" rel=\"noopener\">entre 25.000 e 68.000 por ano</a> durante o período 2009/2020). Mais especificamente, um ser humano pode contrair a doença de Lyme após uma picada dura de carrapato se este estiver infectado com um <strong>bactérias da família das espiroquetas</strong>. Na maioria das vezes benigno se diagnosticado em estágio inicial, pode levar a complicações graves quando tratado apenas em estágio avançado.</p>\n<h3><span class=\"ez-toc-section\" id=\"CBD_contra_a_doenca_de_Lyme_Explicacao_por_sintomas\"></span>CBD contra a doença de Lyme? Explicação por sintomas<span class=\"ez-toc-section-end\"></span></h3>\n<p>Para compreender melhor como o <a href=\"https://weedy.fr/en\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> poderia intervir no contexto da borreliose de Lyme, é importante concentrar-se primeiro no <strong>sintomas da doença</strong>. Vemos assim, no curto prazo:</p>\n<ul>\n<li><strong>Síndrome gripal</strong> (febre, calafrios, dores no corpo) uma a duas semanas após a picada,</li>\n<li><strong>Eritema migratório</strong> (placa vermelha estendendo-se ao redor da picada) no mês seguinte (30 a 60% dos casos),</li>\n</ul>\n<p>Ao que se pode acrescentar, no caso de uma forma mais avançada da doença:</p>\n<ul>\n<li>Dor nas articulações (especialmente nos joelhos),</li>\n<li>Paralisia localizada,</li>\n<li>Fraqueza muscular,</li>\n<li>Fadiga crônica,</li>\n<li>Mais raramente, outra forma de infecção (nos olhos, especialmente hepatite).</li>\n</ul>\n<p>Finalmente, é útil mencionar que a doença de Lyme é por vezes também apelidada de “grande imitadora”. Com efeito, quando a borreliose de Lyme atinge uma fase avançada (denominada fase terciária), pode ser acompanhada de todo o tipo de sintomas, tornando o seu diagnóstico mais difícil, uma vez que pode então ser <strong>confundido com outras patologias</strong>, como certas doenças neurodegenerativas, esclerose múltipla ou mesmo depressão.</p>\n<p>Estes sintomas, diversos mas muito variáveis ​​dependendo do indivíduo, levam-nos a questionar a<strong>interesse de </strong><strong>CDB</strong><strong> para aliviar a borreliose de Lyme</strong>. O canabidiol é de facto, entre outras coisas, conhecido pela sua <a href=\"https://weedy.fr/en/cbd-therapeutic-effects\">efeitos virtuosos</a>, incluindo <strong>propriedades anti-inflamatórias, antibacterianas e antidepressivas</strong>. Três aspectos a pelo menos considerar quando se trata de limitar os danos causados ​​pela doença.<br>\n<img decoding=\"async\" class=\"size-full wp-image-289991\" src=\"https://weedy.fr/wp-content/uploads/2022/02/Erytheme-migrand-tique-min.jpg\" alt=\"Eritema migratório carrapato min\" width=\"700\" height=\"525\"></p>\n<h2><span class=\"ez-toc-section\" id=\"CBD_para_reduzir_os_sintomas_da_borreliose_de_Lyme\"></span>CBD para reduzir os sintomas da borreliose de Lyme?<span class=\"ez-toc-section-end\"></span></h2>\n<p>Até à data, não existem estudos em grande escala que tenham provado que o CBD pode tratar a doença de Lyme. No entanto, a investigação já forneceu inúmeras respostas sobre os efeitos do CBD no corpo, nomeadamente através da sua ação no nosso corpo. <a href=\"https://weedy.fr/en/blog/systeme-endocannabinoide-definition/\">sistema endocanabinoide</a> (SECO). Parece, portanto, no mínimo, ajudar as pessoas a tolerar melhor vários dos sintomas da doença:</p>\n<ul>\n<li><strong>Anti-inflamatório</strong>: O CBD ajuda a reduzir a dor crônica. No entanto, a dor é sem dúvida o sintoma mais difícil da borreliose de Lyme para um grande número de pacientes.</li>\n<li><strong>Antibacteriano e antioxidante</strong>: o que permite ao CBD proteger as células contra ataques externos.</li>\n<li><strong>Impulso imunológico</strong>: o SEC desempenha um papel direto na nossa resposta imunológica.</li>\n<li><strong>Regulação do humor e do sono</strong>: permitindo que os pacientes de Lyme fiquem mais relaxados e <a href=\"https://weedy.fr/en/blog/sleep-well-with-cbd/\">durma melhor</a>, o CBD permite que você encontre um pouco de conforto no seu dia a dia.</li>\n</ul>\n<h2><span class=\"ez-toc-section\" id=\"Como_usar_o_CBD_quando_voce_sofre_da_doenca_de_Lyme\"></span>Como usar o CBD quando você sofre da doença de Lyme?<span class=\"ez-toc-section-end\"></span></h2>\n<p><img decoding=\"async\" class=\"size-full wp-image-289992\" src=\"https://weedy.fr/wp-content/uploads/2022/02/Huile-CBD-borreliose-de-Lyme-min.jpg\" alt=\"borreliose de lima de óleo cbd min\" width=\"700\" height=\"466\"><br>\nA forma mais saudável e fácil de beneficiar dos benefícios do CBD é, sem dúvida,<a href=\"https://weedy.fr/en/product-category/cbd-oils/\">Óleo CBD</a>. Disponível em frasco conta-gotas e cápsula, é muito fácil de dosar, para uso rápido e discreto a qualquer hora do dia. Se você vaporiza, também pode considerar usar <a href=\"https://weedy.fr/en/product-category/cbd-flowers/\">Flores CBD</a>, concentrados ou <a href=\"https://weedy.fr/en/product-category/cbd-resins/\">Resinas CBD</a>. Permitindo efeitos mais rápidos, a vaporização resulta na liberação de certas toxinas. Portanto, não é recomendado para quem não vaporiza e pode neste caso ser substituído pela infusão desses mesmos produtos com gordura. Se você estiver fazendo tratamento, relacionado ou não à doença de Lyme, converse com um médico sobre seu desejo de consumir CBD. Ele poderá aconselhá-lo e evitar os riscos de interações medicamentosas.</p>\n<h3><span class=\"ez-toc-section\" id=\"Meu_cachorro_ou_gato_tem_doenca_de_Lyme_posso_dar_CBD_a_ele\"></span>Meu cachorro ou gato tem doença de Lyme: posso dar CBD a ele?<span class=\"ez-toc-section-end\"></span></h3>\n<p>Mais conhecida em humanos, a borreliose também pode afetar muitas outras espécies, incluindo <strong>cães</strong> (com bastante frequência) e <strong>gatos</strong> (mais raro). Quanto a nós, pode ter repercussões significativas se não for tomada a tempo. À menor dúvida (eritema no animal, dor, claudicação), <strong>peça conselhos ao seu veterinário</strong>. Ele poderá aconselhá-lo sobre o tratamento a adotar. Para fases avançadas, o CBD pode, tal como nos humanos, ajudar a reduzir a dor e assim devolver um certo conforto de vida ao seu animal. Nosso óleo CBD para cães 3% e nosso óleo CBD para gatos 5% são particularmente adequados para nossos companheiros de quatro patas, com óleos aromatizados com carne e peixe, respectivamente. A administração é assim simplificada.</p>\n<h2><span class=\"ez-toc-section\" id=\"Para_concluir_a_doenca_de_Lyme_pode_ser_curada\"></span>Para concluir: a doença de Lyme pode ser curada?<span class=\"ez-toc-section-end\"></span></h2>\n<p>Sim, mas <strong>O CBD não é de forma alguma um tratamento reconhecido para a borreliose de Lyme</strong>. Tomar CBD não se destina, portanto, a curar a doença de Lyme e não deve substituir o <strong>tomando antibióticos</strong> uma vez feito o diagnóstico. O canabidiol pode, no entanto, <strong>aliviar a dor</strong> ligada à forma crônica da doença, principalmente em caso de diagnóstico tardio.</p>\n","protected":false},"excerpt":{"rendered":"<p>Transmitida por carraças, a borreliose de Lyme está cada vez mais disseminada na Europa. Em mais de 90% dos casos é tratado rapidamente e sem muitos problemas. Diagnosticada tarde demais, progride silenciosamente, até causar fadiga, dor e paralisia parcial. Infelizmente, é difícil controlá-lo. Conhecido por ser calmante e relaxante para os músculos, o canabidiol (CBD) [&hellip;]</p>\n","protected":false},"author":41,"featured_media":352632,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"padrão\n","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[672],"tags":[],"class_list":["post-360920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude-e-bem-estar-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https://yoast.com/product/yoast-seo-premium-wordpress/ -->\n<title>Borreliose de Lyme: o que o CBD pode fazer? - Actualités CBD Blog - Weedy.fr</title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" />\n<link rel=\"canonical\" href=\"https://weedy.fr/blog/pt/borreliose-de-lyme-o-que-o-cbd-pode-fazer/\" />\n<meta property=\"og:locale\" content=\"fr_FR\" />\n<meta property=\"og:type\" content=\"article\" />\n<meta property=\"og:title\" content=\"🌱Borreliose de Lyme: o que o CBD pode fazer? - Weedy.Fr🌱\" />\n<meta property=\"og:description\" content=\"Transmitida por carraças, a borreliose de Lyme está cada vez mais disseminada na Europa. Em mais de 90% dos casos é tratado rapidamente e sem muitos problemas. Diagnosticada tarde demais, progride silenciosamente, até causar fadiga, dor e paralisia parcial. Infelizmente, é difícil controlá-lo. Conhecido por ser calmante e relaxante para os músculos, o canabidiol (CBD) [&hellip;]\" />\n<meta property=\"og:url\" content=\"https://weedy.fr/blog/pt/borreliose-de-lyme-o-que-o-cbd-pode-fazer/\" />\n<meta property=\"og:site_name\" content=\"Actualités CBD Blog - Weedy.fr\" />\n<meta property=\"article:publisher\" content=\"https://www.facebook.com/weedysocial\" />\n<meta property=\"article:author\" content=\"https://www.facebook.com/weedysocial/\" />\n<meta property=\"article:published_time\" content=\"2024-09-17T16:28:40+00:00\" />\n<meta property=\"article:modified_time\" content=\"2024-09-17T16:28:42+00:00\" />\n<meta property=\"og:image\" content=\"https://weedy.fr/blog/wp-content/uploads/2024/05/borreliose-de-lyme-que-peut-le-cbd.jpg\" />\n\t<meta property=\"og:image:width\" content=\"1792\" />\n\t<meta property=\"og:image:height\" content=\"1024\" />\n\t<meta property=\"og:image:type\" content=\"image/jpeg\" />\n<meta name=\"author\" content=\"Julien Cordobes\" />\n<meta name=\"twitter:card\" content=\"summary_large_image\" />\n<meta name=\"twitter:label1\" content=\"Écrit par\" />\n\t<meta name=\"twitter:data1\" content=\"Julien Cordobes\" />\n\t<meta name=\"twitter:label2\" content=\"Durée de lecture estimée\" />\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" />\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\/\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/borreliose-de-lyme-o-que-o-cbd-pode-fazer\\/#article\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/borreliose-de-lyme-o-que-o-cbd-pode-fazer\\/\"},\"author\":{\"name\":\"Julien Cordobes\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/72583fcd87d7cf46afe11d530945bc7e\"},\"headline\":\"Borreliose de Lyme: o que o CBD pode fazer?\",\"datePublished\":\"2024-09-17T16:28:40+00:00\",\"dateModified\":\"2024-09-17T16:28:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/borreliose-de-lyme-o-que-o-cbd-pode-fazer\\/\"},\"wordCount\":1000,\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/borreliose-de-lyme-o-que-o-cbd-pode-fazer\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/borreliose-de-lyme-que-peut-le-cbd.jpg\",\"articleSection\":[\"Saúde e Bem-estar\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/borreliose-de-lyme-o-que-o-cbd-pode-fazer\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/borreliose-de-lyme-o-que-o-cbd-pode-fazer\\/\",\"name\":\"Borreliose de Lyme: o que o CBD pode fazer? - Actualités CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/borreliose-de-lyme-o-que-o-cbd-pode-fazer\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/borreliose-de-lyme-o-que-o-cbd-pode-fazer\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/borreliose-de-lyme-que-peut-le-cbd.jpg\",\"datePublished\":\"2024-09-17T16:28:40+00:00\",\"dateModified\":\"2024-09-17T16:28:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/borreliose-de-lyme-o-que-o-cbd-pode-fazer\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\/\\/weedy.fr\\/blog\\/pt\\/borreliose-de-lyme-o-que-o-cbd-pode-fazer\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/borreliose-de-lyme-o-que-o-cbd-pode-fazer\\/#primaryimage\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/borreliose-de-lyme-que-peut-le-cbd.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/borreliose-de-lyme-que-peut-le-cbd.jpg\",\"width\":1792,\"height\":1024,\"caption\":\"Lyme borreliosis: what can CBD do?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/borreliose-de-lyme-o-que-o-cbd-pode-fazer\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Saúde e Bem-estar\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/category\\/saude-e-bem-estar-pt\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Borreliose de Lyme: o que o CBD pode fazer?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"name\":\"Actualités CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualité du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\/\\/weedy.fr\\/blog\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\"},\"sameAs\":[\"https:\\/\\/www.facebook.com\\/weedysocial\",\"https:\\/\\/www.instagram.com\\/weedyfrance\\/\"],\"description\":\"Leader en france sur la vente de produits à base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/72583fcd87d7cf46afe11d530945bc7e\",\"name\":\"Julien Cordobes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"url\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"caption\":\"Julien Cordobes\"},\"description\":\"Rédacteur en chef spécialisé en CBD Julien, né le 17 juillet 1978 en région Parisienne, est un éminent rédacteur et expert dans le domaine des produits à base de CBD. Suite à ses études en biologie et en médecine alternative, Julien a développé une passion pour les remèdes naturels, dont le CBD. En 2022, il intègre l’équipe du site Weedy.fr en qualité d’expert et de contributeur régulier. Grâce à son expertise scientifique et une écriture claire, Julien aide à démystifier les aspects complexes du CBD, tout en mettant en lumière ses bienfaits et applications potentielles à travers ses articles et participations à des conférences.\",\"sameAs\":[\"https:\\/\\/weedy.fr\",\"https:\\/\\/www.facebook.com\\/weedysocial\\/\",\"https:\\/\\/www.instagram.com\\/weedyfrance\",\"https:\\/\\/www.pinterest.fr\\/WeedyFrance\\/\"],\"honorificPrefix\":\"Mr\",\"birthDate\":\"1978-07-17\",\"gender\":\"male\",\"knowsAbout\":[\"CBD\",\"Cannabis\",\"Copywriter\"],\"knowsLanguage\":[\"French\"],\"jobTitle\":\"Editor-in-chief specializing in CBD\",\"worksFor\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/author\\/cbd_blog_owner\\/\"}]}</script>\n<!-- / Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Borreliose de Lyme: o que o CBD pode fazer? - Actualités CBD Blog - Weedy.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://weedy.fr/blog/pt/borreliose-de-lyme-o-que-o-cbd-pode-fazer/","og_locale":"fr_FR","og_type":"article","og_title":"🌱Borreliose de Lyme: o que o CBD pode fazer? - Weedy.Fr🌱","og_description":"Transmitida por carraças, a borreliose de Lyme está cada vez mais disseminada na Europa. Em mais de 90% dos casos é tratado rapidamente e sem muitos problemas. Diagnosticada tarde demais, progride silenciosamente, até causar fadiga, dor e paralisia parcial. Infelizmente, é difícil controlá-lo. Conhecido por ser calmante e relaxante para os músculos, o canabidiol (CBD) [&hellip;]","og_url":"https://weedy.fr/blog/pt/borreliose-de-lyme-o-que-o-cbd-pode-fazer/","og_site_name":"Actualités CBD Blog - Weedy.fr","article_publisher":"https://www.facebook.com/weedysocial","article_author":"https://www.facebook.com/weedysocial/","article_published_time":"2024-09-17T16:28:40+00:00","article_modified_time":"2024-09-17T16:28:42+00:00","og_image":[{"width":1792,"height":1024,"url":"https://weedy.fr/en/blog/wp-content/uploads/2024/05/borreliose-de-lyme-que-peut-le-cbd.jpg","type":"image/jpeg"}],"author":"Julien Cordobes","twitter_card":"summary_large_image","twitter_misc":{"Écrit par":"Julien Cordobes","Durée de lecture estimée":"5 minutes"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"Article","@id":"https://weedy.fr/blog/pt/borreliose-de-lyme-o-que-o-cbd-pode-fazer/#article","isPartOf":{"@id":"https://weedy.fr/blog/pt/borreliose-de-lyme-o-que-o-cbd-pode-fazer/"},"author":{"name":"Julien Cordobes","@id":"https://weedy.fr/blog/#/schema/person/72583fcd87d7cf46afe11d530945bc7e"},"headline":"Borreliose de Lyme: o que o CBD pode fazer?","datePublished":"2024-09-17T16:28:40+00:00","dateModified":"2024-09-17T16:28:42+00:00","mainEntityOfPage":{"@id":"https://weedy.fr/blog/pt/borreliose-de-lyme-o-que-o-cbd-pode-fazer/"},"wordCount":1000,"publisher":{"@id":"https://weedy.fr/blog/#organization"},"image":{"@id":"https://weedy.fr/blog/pt/borreliose-de-lyme-o-que-o-cbd-pode-fazer/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/borreliose-de-lyme-que-peut-le-cbd.jpg","articleSection":["Saúde e Bem-estar"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https://weedy.fr/blog/pt/borreliose-de-lyme-o-que-o-cbd-pode-fazer/","url":"https://weedy.fr/en/blog/pt/borreliose-de-lyme-o-que-o-cbd-pode-fazer/","name":"Borreliose de Lyme: o que o CBD pode fazer? - Actualités CBD Blog - Weedy.fr","isPartOf":{"@id":"https://weedy.fr/blog/#website"},"primaryImageOfPage":{"@id":"https://weedy.fr/blog/pt/borreliose-de-lyme-o-que-o-cbd-pode-fazer/#primaryimage"},"image":{"@id":"https://weedy.fr/blog/pt/borreliose-de-lyme-o-que-o-cbd-pode-fazer/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/borreliose-de-lyme-que-peut-le-cbd.jpg","datePublished":"2024-09-17T16:28:40+00:00","dateModified":"2024-09-17T16:28:42+00:00","breadcrumb":{"@id":"https://weedy.fr/blog/pt/borreliose-de-lyme-o-que-o-cbd-pode-fazer/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https://weedy.fr/blog/pt/borreliose-de-lyme-o-que-o-cbd-pode-fazer/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/pt/borreliose-de-lyme-o-que-o-cbd-pode-fazer/#primaryimage","url":"https://weedy.fr/en/blog/wp-content/uploads/2024/05/borreliose-de-lyme-que-peut-le-cbd.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/borreliose-de-lyme-que-peut-le-cbd.jpg","width":1792,"height":1024,"caption":"Lyme borreliosis: what can CBD do?"},{"@type":"BreadcrumbList","@id":"https://weedy.fr/blog/pt/borreliose-de-lyme-o-que-o-cbd-pode-fazer/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https://weedy.fr/blog/"},{"@type":"ListItem","position":2,"name":"Saúde e Bem-estar","item":"https://weedy.fr/blog/category/saude-e-bem-estar-pt/"},{"@type":"ListItem","position":3,"name":"Borreliose de Lyme: o que o CBD pode fazer?"}]},{"@type":"WebSite","@id":"https://weedy.fr/blog/#website","url":"https://weedy.fr/en/blog/","name":"Actualités CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualité du CBD et du chanvre en France","publisher":{"@id":"https://weedy.fr/blog/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://weedy.fr/blog/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https://weedy.fr/blog/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https://weedy.fr/en/blog/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/#/schema/logo/image/","url":"https://weedy.fr/en/blog/wp-content/uploads/2024/05/logo-carre.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https://weedy.fr/blog/#/schema/logo/image/"},"sameAs":["https://www.facebook.com/weedysocial","https://www.instagram.com/weedyfrance/"],"description":"Leader en france sur la vente de produits à base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https://weedy.fr/blog/#/schema/person/72583fcd87d7cf46afe11d530945bc7e","name":"Julien Cordobes","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","url":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","caption":"Julien Cordobes"},"description":"Rédacteur en chef spécialisé en CBD Julien, né le 17 juillet 1978 en région Parisienne, est un éminent rédacteur et expert dans le domaine des produits à base de CBD. Suite à ses études en biologie et en médecine alternative, Julien a développé une passion pour les remèdes naturels, dont le CBD. En 2022, il intègre l’équipe du site Weedy.fr en qualité d’expert et de contributeur régulier. Grâce à son expertise scientifique et une écriture claire, Julien aide à démystifier les aspects complexes du CBD, tout en mettant en lumière ses bienfaits et applications potentielles à travers ses articles et participations à des conférences.","sameAs":["https://weedy.fr","https://www.facebook.com/weedysocial/","https://www.instagram.com/weedyfrance","https://www.pinterest.fr/WeedyFrance/"],"honorificPrefix":"Mr","birthDate":"1978-07-17","gender":"male","knowsAbout":["CBD","Cannabis","Copywriter"],"knowsLanguage":["French"],"jobTitle":"Editor-in-chief specializing in CBD","worksFor":"Weedy.fr","url":"https://weedy.fr/en/blog/author/cbd_blog_owner/"}]}},"_links":{"self":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/360920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts"}],"about":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/users/41"}],"replies":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/comments?post=360920"}],"version-history":[{"count":1,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/360920/revisions"}],"predecessor-version":[{"id":360921,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/360920/revisions/360921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/media/352632"}],"wp:attachment":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/media?parent=360920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/categories?post=360920"},{"taxonomy":"post_tag","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/tags?post=360920"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}