{"id":319886,"date":"2022-09-08T08:00:28","date_gmt":"2022-09-08T06:00:28","guid":{"rendered":"https://weedy.fr/?p=319886"},"modified":"2023-10-27T10:53:29","modified_gmt":"2023-10-27T08:53:29","slug":"duree-des-effets-du-cbd","status":"publish","type":"post","link":"https://weedy.fr/blog/duree-des-effets-du-cbd/","title":{"rendered":"Durée des effets du CBD : tout comprendre pour mieux profiter"},"content":{"rendered":"<p>Selon le produit utilisé, sa concentration en <a href=\"https://weedy.fr/es\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a>, la fréquence des prises mais aussi l’individu qui consomme, les effets du <a href=\"https://weedy.fr/es\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">cannabidiol</a> mettent plus ou moins de temps à se manifester. Ils peuvent également durer plus ou moins longtemps. Si nous réagissons tous différemment au <a href=\"https://weedy.fr/es\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">cannabidiol</a>, quelques informations de base restent néanmoins valables dans la grande majorité des cas.</p>\n<p>En les connaissant, il est donc possible de mieux comprendre quand prendre du CBD, sous quelle forme et pour quels effets. Voici tout ce qu&rsquo;il y a à savoir pour comprendre <strong>après combien de temps bénéficier des effets du CBD</strong>, <strong>combien de temps en profiter</strong> et <strong>après combien de temps en reprendre</strong>.</p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire</p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle</span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http://www.w3.org/2000/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"></path></svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http://www.w3.org/2000/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"></path></svg></span></span></span></a></span></div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 \"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https://weedy.fr/es/blog/duree-des-effets-du-cbd/#En_combien_de_temps_agit_le_CBD\">En combien de temps agit le CBD ?</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https://weedy.fr/es/blog/duree-des-effets-du-cbd/#Temps_avant_de_ressentir_les_effets_du_CBD_selon_le_mode_de_prise\">Temps avant de ressentir les effets du CBD selon le mode de prise</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https://weedy.fr/es/blog/duree-des-effets-du-cbd/#Influence_du_dosage_sur_le_temps_daction_du_CBD\">Influence du dosage sur le temps d&rsquo;action du CBD</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https://weedy.fr/es/blog/duree-des-effets-du-cbd/#Quelle_est_la_duree_des_effets_du_CBD\">Quelle est la durée des effets du CBD ?</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https://weedy.fr/es/blog/duree-des-effets-du-cbd/#Au_bout_de_combien_de_temps_reprendre_du_CBD\">Au bout de combien de temps reprendre du CBD ?</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https://weedy.fr/es/blog/duree-des-effets-du-cbd/#Pour_conclure_CBD_et_temps_daction\">Pour conclure : CBD et temps d&rsquo;action</a></li></ul></nav></div>\n<h2><span class=\"ez-toc-section\" id=\"En_combien_de_temps_agit_le_CBD\"></span>En combien de temps agit le CBD ?<span class=\"ez-toc-section-end\"></span></h2>\n<figure id=\"attachment_319888\" aria-describedby=\"caption-attachment-319888\" style=\"width: 900px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-319888\" src=\"https://weedy.fr/wp-content/uploads/2022/09/Duree-daction-CBD-min.jpg\" alt=\"durée d'action cbd min\" width=\"900\" height=\"674\"><figcaption id=\"caption-attachment-319888\" class=\"wp-caption-text\">Selon l’individu et le mode de prise, les effets du CBD mettent plus ou moins de temps à apparaître</figcaption></figure>\n<p>Nous vous l&rsquo;expliquions dans un précédent article, nous réagissons tous différemment au cannabidiol. La raison à cela est simple et elle porte un nom : la loi de l&rsquo;effet. Nous ne sommes en effet <strong>pas tous égaux face aux effets du CBD</strong>, et ce pour plusieurs raisons : patrimoine génétique, antécédents médicaux, fréquence de consommation notamment. Ainsi, même à produit et quantité identiques, il est possible que deux individus ressentent des <strong>effets à des moments légèrement différents</strong>.</p>\n<p>Néanmoins, le <strong>mode de prise</strong> reste l&rsquo;un des facteurs qui influence le plus le temps nécessaire au cannabidiol pour faire effet.</p>\n<h3><span class=\"ez-toc-section\" id=\"Temps_avant_de_ressentir_les_effets_du_CBD_selon_le_mode_de_prise\"></span>Temps avant de ressentir les effets du CBD selon le mode de prise<span class=\"ez-toc-section-end\"></span></h3>\n<ul>\n<li><strong>Combustion</strong>: <a href=\"https://weedy.fr/es/blog/fumer-huile-cbd/\">fumer du CBD</a> n’est ni conseillé ni autorisé. Cela a beau être le moyen le plus rapide d’obtenir des effets (ils sont <strong>quasi instantanés</strong>), c’est aussi la méthode de consommation la moins saine et, par conséquent, le plus dangereux pour la santé.</li>\n<li><strong>Inhalation</strong>: l’inhalation se rapproche de la combustion, en moins chaude et donc moins nocive (mais pas totalement saine pour autant). Si vous vapotez du cannabis light, les premiers effets devraient se manifester après <strong>15 à 30 minutes</strong>.</li>\n<li><strong>Voie sublinguale</strong> (sous la langue) : quelques gouttes d’<a href=\"https://weedy.fr/es/product-category/huiles-cbd/\" data-internallinksmanager029f6b8e52c=\"7\" title=\"huile cbd\">huile CBD</a> sous la lange entraînent des effets rapides (après <strong>une vingtaine de minutes</strong>), sans contre-indication particulière.</li>\n<li><strong>Voie orale</strong>: la voie orale demande un peu plus de temps (environ <strong>une heure</strong>) car il faut que la digestion commence son travail avant de ressentir les effets du CBD. Néanmoins, en raison du phénomène appelé <a href=\"https://www.sciencedirect.com/topics/pharmacology-toxicology-and-pharmaceutical-science/first-pass-effect\" target=\"_blank\" rel=\"noopener\">effet de premier passage</a>, il semble que les effets soient moins importants à dose équivalente qu’en passant par la voie sublinguale.</li>\n<li><strong>Application topique</strong> (locale) : pour décontracter les muscles ou <a href=\"https://weedy.fr/es/blog/bienfaits-cbd-pour-le-visage/\">prendre soin de la peau et du visage</a>, une application topique fait généralement effet en environ <strong>une heure</strong>, mais seulement à proximité de la zone sur laquelle le cannabidiol est appliqué.</li>\n</ul>\n<figure id=\"attachment_319889\" aria-describedby=\"caption-attachment-319889\" style=\"width: 900px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-full wp-image-319889\" src=\"https://weedy.fr/wp-content/uploads/2022/09/Vape-pour-des-effets-rapides-min.jpg\" alt=\"vape pour des effets rapides min\" width=\"900\" height=\"600\"><figcaption id=\"caption-attachment-319889\" class=\"wp-caption-text\">Vapoter du CBD propose des effets plus rapides, mais la voie sublinguale est plus saine</figcaption></figure>\n<h3><span class=\"ez-toc-section\" id=\"Influence_du_dosage_sur_le_temps_daction_du_CBD\"></span>Influence du dosage sur le temps d&rsquo;action du CBD<span class=\"ez-toc-section-end\"></span></h3>\n<p>Nous avons tous une connaissance qui est pompette à la première bière et cette autre qui enquille les digestifs comme si de rien n&rsquo;était. Bien que ne souffrant pas des mêmes <a href=\"https://weedy.fr/es/blog/effets-secondaires-cbd/\">effets secondaires</a> que l&rsquo;alcool ou que son cousin le <a href=\"https://weedy.fr/es/quest-ce-que-le-thc\">THC</a> (il n&rsquo;est <strong>ni addictif ni psychoactif</strong>), le CBD suit pourtant la même logique : il fait effet plus rapidement chez certaines personnes. Souvent, plutôt que de durée, il faut pourtant penser quantité. Une personne à la corpulence plus importante a généralement besoin de davantage de cannabidiol pour en ressentir les effets rapidement. De la même façon, une personne qui ne consomme pas souvent ressent généralement des <strong>effets plus marqués</strong> qu&rsquo;un consommateur régulier, dont le corps humain s&rsquo;habitue petit à petit à la présence de la molécule.</p>\n<p>Pour toutes ces raisons, il est important de <strong>rechercher le bon dosage en cannabidiol</strong> pour <em>vos</em> besoins particuliers. Là encore, il varie selon les individus. Notre guide dédié vous explique pas à pas comment <a href=\"https://weedy.fr/es/blog/cbd-et-dosage/\">bien doser votre CBD</a> et ce tout particulièrement si vous utilisez de l&rsquo;<a href=\"https://weedy.fr/es/product-category/huiles-cbd/\" data-internallinksmanager029f6b8e52c=\"7\" title=\"huile cbd\">huile CBD</a>, l’un des moyens les plus simples et efficaces de profiter des vertus du CBD.</p>\n<h2><span class=\"ez-toc-section\" id=\"Quelle_est_la_duree_des_effets_du_CBD\"></span>Quelle est la durée des effets du CBD ?<span class=\"ez-toc-section-end\"></span></h2>\n<figure id=\"attachment_319890\" aria-describedby=\"caption-attachment-319890\" style=\"width: 900px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-full wp-image-319890\" src=\"https://weedy.fr/wp-content/uploads/2022/09/Voie-sublinguale-duree-effets-CBD-min.jpg\" alt=\"voie sublinguale durée effets cbd min\" width=\"900\" height=\"600\"><figcaption id=\"caption-attachment-319890\" class=\"wp-caption-text\">Le type de produits au CBD influence le mode de prise et donc la durée des effets</figcaption></figure>\n<p>Là encore, la durée des effets du CBD est variable en fonction de la personne. Comme pour le temps nécessaire pour ressentir les premiers effets, le type de produit et donc le mode de prise jouent un rôle déterminant. L’inhalation, l’une des méthodes les plus rapides, n’est pourtant pas la plus efficace sur le long terme puisque les effets disparaissent en général en <strong>2 à 3 heures</strong>. La voie orale propose des effets diffus (<strong>4 à 6 heures en moyenne</strong>), mais globalement plus faibles que d’autres modes de prise. La voie sublinguale, elle aussi rapide, semble alors la plus conseillée lorsque l’on recherche des effets sur le corps tout entier puisqu’ils s’étendent plusieurs heures, pour certains utilisateurs <strong>jusqu’à 6 heures après la prise</strong>. Enfin, l’application locale, directement sur la peau, agit en moyenne <strong>2 à 4 heures</strong>, mais seulement sur la zone concernée.</p>\n<h2><span class=\"ez-toc-section\" id=\"Au_bout_de_combien_de_temps_reprendre_du_CBD\"></span>Au bout de combien de temps reprendre du CBD ?<span class=\"ez-toc-section-end\"></span></h2>\n<p>Lorsque l’on commence à prendre du cannabis light, il est parfois difficile de savoir si les effets ne sont pas encore arrivés ou au contraire si le dosage est trop faible. Selon le produit utilisé, vous devriez désormais savoir à quoi vous attendre. Par mesure de précaution, il est toutefois recommandé d’<strong>attendre au moins 2 à 3 heures entre deux prises</strong>, histoire de donner une chance à votre corps d’assimiler le cannabidiol. Il existe également des <a href=\"https://weedy.fr/es/product/patchs-cbd-20-mg\">patchs au CBD</a> qui assurent une <strong>diffusion lente et diffuse</strong> de la molécule. Un seul patch peut alors dispenser suffisamment de cannabidiol pour 24 heures.</p>\n<h2><span class=\"ez-toc-section\" id=\"Pour_conclure_CBD_et_temps_daction\"></span>Pour conclure : CBD et temps d&rsquo;action<span class=\"ez-toc-section-end\"></span></h2>\n<table>\n<tbody>\n<tr>\n<td width=\"164\"><strong>Mode de prise</strong></td>\n<td width=\"158\"><strong>Temps d’action</strong></td>\n<td width=\"156\"><strong>Durée des effets</strong></td>\n<td width=\"141\"><strong>Produits au CBD</strong></td>\n</tr>\n<tr>\n<td width=\"164\"><strong>Inhalation</strong></td>\n<td width=\"158\">15 à 30 minutes</td>\n<td width=\"156\">2-3 heures</td>\n<td width=\"141\"><a href=\"https://weedy.fr/es/product-category/e-liquides-cbd/\">E-liquides CBD</a></td>\n</tr>\n<tr>\n<td width=\"164\"><strong>Voie sublinguale</strong></td>\n<td width=\"158\">Environ 20 min</td>\n<td width=\"156\">Jusqu’à 6 heures</td>\n<td width=\"141\"><a href=\"https://weedy.fr/es/product-category/huiles-cbd/\">Huiles CBD</a></td>\n</tr>\n<tr>\n<td width=\"164\"><strong>Voie orale</strong></td>\n<td width=\"158\">Environ 1h</td>\n<td width=\"156\">4-6 heures</td>\n<td width=\"141\"><a href=\"https://weedy.fr/es/product-category/fleurs-de-cbd/\">Fleurs CBD</a>, <a href=\"https://weedy.fr/es/product-category/resines-cbd/\">Résines CBD</a>, <a href=\"https://weedy.fr/es/product-category/cbd-alimentaire/infusions-cbd/\">Infusions CBD</a></td>\n</tr>\n<tr>\n<td width=\"164\"><strong>Application cutanée</strong></td>\n<td width=\"158\">Environ 1h</td>\n<td width=\"156\">2-4 heures</td>\n<td width=\"141\"><a href=\"https://weedy.fr/es/product-category/cosmetiques-cbd/\">Cosmétiques CBD</a></td>\n</tr>\n</tbody>\n</table>\n<p>&nbsp;</p>\n","protected":false},"excerpt":{"rendered":"<p>Selon le produit utilisé, sa concentration en CBD, la fréquence des prises mais aussi l’individu qui consomme, les effets du cannabidiol mettent plus ou moins de temps à se manifester. Ils peuvent également durer plus ou moins longtemps. Si nous réagissons tous différemment au cannabidiol, quelques informations de base restent néanmoins valables dans la grande [&hellip;]</p>\n","protected":false},"author":41,"featured_media":352614,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[364],"tags":[],"class_list":["post-319886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sante-cbd"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https://yoast.com/product/yoast-seo-premium-wordpress/ -->\n<title>Durée des effets du CBD : tout comprendre pour mieux profiter - Actualités CBD Blog - Weedy.fr</title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" />\n<link rel=\"canonical\" href=\"https://weedy.fr/blog/duree-des-effets-du-cbd/\" />\n<meta property=\"og:locale\" content=\"fr_FR\" />\n<meta property=\"og:type\" content=\"article\" />\n<meta property=\"og:title\" content=\"🌱Durée des effets du CBD : tout comprendre pour mieux profiter - Weedy.Fr🌱\" />\n<meta property=\"og:description\" content=\"Selon le produit utilisé, sa concentration en CBD, la fréquence des prises mais aussi l’individu qui consomme, les effets du cannabidiol mettent plus ou moins de temps à se manifester. Ils peuvent également durer plus ou moins longtemps. Si nous réagissons tous différemment au cannabidiol, quelques informations de base restent néanmoins valables dans la grande [&hellip;]\" />\n<meta property=\"og:url\" content=\"https://weedy.fr/blog/duree-des-effets-du-cbd/\" />\n<meta property=\"og:site_name\" content=\"Actualités CBD Blog - Weedy.fr\" />\n<meta property=\"article:publisher\" content=\"https://www.facebook.com/weedysocial\" />\n<meta property=\"article:author\" content=\"https://www.facebook.com/weedysocial/\" />\n<meta property=\"article:published_time\" content=\"2022-09-08T06:00:28+00:00\" />\n<meta property=\"article:modified_time\" content=\"2023-10-27T08:53:29+00:00\" />\n<meta property=\"og:image\" content=\"https://weedy.fr/blog/wp-content/uploads/2024/05/logo-carre.jpg\" />\n\t<meta property=\"og:image:width\" content=\"582\" />\n\t<meta property=\"og:image:height\" content=\"582\" />\n\t<meta property=\"og:image:type\" content=\"image/jpeg\" />\n<meta name=\"author\" content=\"Julien Cordobes\" />\n<meta name=\"twitter:card\" content=\"summary_large_image\" />\n<meta name=\"twitter:label1\" content=\"Écrit par\" />\n\t<meta name=\"twitter:data1\" content=\"Julien Cordobes\" />\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\/\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/duree-des-effets-du-cbd\\/#article\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/duree-des-effets-du-cbd\\/\"},\"author\":{\"name\":\"Julien Cordobes\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/72583fcd87d7cf46afe11d530945bc7e\"},\"headline\":\"Durée des effets du CBD : tout comprendre pour mieux profiter\",\"datePublished\":\"2022-09-08T06:00:28+00:00\",\"dateModified\":\"2023-10-27T08:53:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/duree-des-effets-du-cbd\\/\"},\"wordCount\":1095,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/duree-des-effets-du-cbd\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/duree-des-effets-du-cbd-tout-comprendre-pour-mieux-profiter.jpg\",\"articleSection\":[\"Santé &amp; Bien-être\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\/\\/weedy.fr\\/blog\\/duree-des-effets-du-cbd\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/duree-des-effets-du-cbd\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/duree-des-effets-du-cbd\\/\",\"name\":\"Durée des effets du CBD : tout comprendre pour mieux profiter - Actualités CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/duree-des-effets-du-cbd\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/duree-des-effets-du-cbd\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/duree-des-effets-du-cbd-tout-comprendre-pour-mieux-profiter.jpg\",\"datePublished\":\"2022-09-08T06:00:28+00:00\",\"dateModified\":\"2023-10-27T08:53:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/duree-des-effets-du-cbd\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\/\\/weedy.fr\\/blog\\/duree-des-effets-du-cbd\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/duree-des-effets-du-cbd\\/#primaryimage\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/duree-des-effets-du-cbd-tout-comprendre-pour-mieux-profiter.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/duree-des-effets-du-cbd-tout-comprendre-pour-mieux-profiter.jpg\",\"width\":1792,\"height\":1024,\"caption\":\"Duration of the effects of CBD: understand everything to benefit better\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/duree-des-effets-du-cbd\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culture du CBD\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/category\\/culture-cbd\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Santé &amp; Bien-être\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/category\\/culture-cbd\\/sante-cbd\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Durée des effets du CBD : tout comprendre pour mieux profiter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"name\":\"Actualités CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualité du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\/\\/weedy.fr\\/blog\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\"},\"sameAs\":[\"https:\\/\\/www.facebook.com\\/weedysocial\",\"https:\\/\\/www.instagram.com\\/weedyfrance\\/\"],\"description\":\"Leader en france sur la vente de produits à base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/72583fcd87d7cf46afe11d530945bc7e\",\"name\":\"Julien Cordobes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"url\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"caption\":\"Julien Cordobes\"},\"description\":\"Rédacteur en chef spécialisé en CBD Julien, né le 17 juillet 1978 en région Parisienne, est un éminent rédacteur et expert dans le domaine des produits à base de CBD. Suite à ses études en biologie et en médecine alternative, Julien a développé une passion pour les remèdes naturels, dont le CBD. En 2022, il intègre l’équipe du site Weedy.fr en qualité d’expert et de contributeur régulier. Grâce à son expertise scientifique et une écriture claire, Julien aide à démystifier les aspects complexes du CBD, tout en mettant en lumière ses bienfaits et applications potentielles à travers ses articles et participations à des conférences.\",\"sameAs\":[\"https:\\/\\/weedy.fr\",\"https:\\/\\/www.facebook.com\\/weedysocial\\/\",\"https:\\/\\/www.instagram.com\\/weedyfrance\",\"https:\\/\\/www.pinterest.fr\\/WeedyFrance\\/\"],\"honorificPrefix\":\"Mr\",\"birthDate\":\"1978-07-17\",\"gender\":\"male\",\"knowsAbout\":[\"CBD\",\"Cannabis\",\"Copywriter\"],\"knowsLanguage\":[\"French\"],\"jobTitle\":\"Editor-in-chief specializing in CBD\",\"worksFor\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/author\\/cbd_blog_owner\\/\"}]}</script>\n<!-- / Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Durée des effets du CBD : tout comprendre pour mieux profiter - Actualités CBD Blog - Weedy.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://weedy.fr/blog/duree-des-effets-du-cbd/","og_locale":"fr_FR","og_type":"article","og_title":"🌱Durée des effets du CBD : tout comprendre pour mieux profiter - Weedy.Fr🌱","og_description":"Selon le produit utilisé, sa concentration en CBD, la fréquence des prises mais aussi l’individu qui consomme, les effets du cannabidiol mettent plus ou moins de temps à se manifester. Ils peuvent également durer plus ou moins longtemps. Si nous réagissons tous différemment au cannabidiol, quelques informations de base restent néanmoins valables dans la grande [&hellip;]","og_url":"https://weedy.fr/blog/duree-des-effets-du-cbd/","og_site_name":"Actualités CBD Blog - Weedy.fr","article_publisher":"https://www.facebook.com/weedysocial","article_author":"https://www.facebook.com/weedysocial/","article_published_time":"2022-09-08T06:00:28+00:00","article_modified_time":"2023-10-27T08:53:29+00:00","og_image":[{"width":582,"height":582,"url":"https://weedy.fr/es/blog/wp-content/uploads/2024/05/logo-carre.jpg","type":"image/jpeg"}],"author":"Julien Cordobes","twitter_card":"summary_large_image","twitter_misc":{"Écrit par":"Julien Cordobes"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"Article","@id":"https://weedy.fr/blog/duree-des-effets-du-cbd/#article","isPartOf":{"@id":"https://weedy.fr/blog/duree-des-effets-du-cbd/"},"author":{"name":"Julien Cordobes","@id":"https://weedy.fr/blog/#/schema/person/72583fcd87d7cf46afe11d530945bc7e"},"headline":"Durée des effets du CBD : tout comprendre pour mieux profiter","datePublished":"2022-09-08T06:00:28+00:00","dateModified":"2023-10-27T08:53:29+00:00","mainEntityOfPage":{"@id":"https://weedy.fr/blog/duree-des-effets-du-cbd/"},"wordCount":1095,"commentCount":0,"publisher":{"@id":"https://weedy.fr/blog/#organization"},"image":{"@id":"https://weedy.fr/blog/duree-des-effets-du-cbd/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/duree-des-effets-du-cbd-tout-comprendre-pour-mieux-profiter.jpg","articleSection":["Santé &amp; Bien-être"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https://weedy.fr/blog/duree-des-effets-du-cbd/#respond"]}]},{"@type":"WebPage","@id":"https://weedy.fr/blog/duree-des-effets-du-cbd/","url":"https://weedy.fr/es/blog/duree-des-effets-du-cbd/","name":"Durée des effets du CBD : tout comprendre pour mieux profiter - Actualités CBD Blog - Weedy.fr","isPartOf":{"@id":"https://weedy.fr/blog/#website"},"primaryImageOfPage":{"@id":"https://weedy.fr/blog/duree-des-effets-du-cbd/#primaryimage"},"image":{"@id":"https://weedy.fr/blog/duree-des-effets-du-cbd/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/duree-des-effets-du-cbd-tout-comprendre-pour-mieux-profiter.jpg","datePublished":"2022-09-08T06:00:28+00:00","dateModified":"2023-10-27T08:53:29+00:00","breadcrumb":{"@id":"https://weedy.fr/blog/duree-des-effets-du-cbd/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https://weedy.fr/blog/duree-des-effets-du-cbd/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/duree-des-effets-du-cbd/#primaryimage","url":"https://weedy.fr/es/blog/wp-content/uploads/2024/05/duree-des-effets-du-cbd-tout-comprendre-pour-mieux-profiter.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/duree-des-effets-du-cbd-tout-comprendre-pour-mieux-profiter.jpg","width":1792,"height":1024,"caption":"Duration of the effects of CBD: understand everything to benefit better"},{"@type":"BreadcrumbList","@id":"https://weedy.fr/blog/duree-des-effets-du-cbd/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https://weedy.fr/blog/"},{"@type":"ListItem","position":2,"name":"Culture du CBD","item":"https://weedy.fr/blog/category/culture-cbd/"},{"@type":"ListItem","position":3,"name":"Santé &amp; Bien-être","item":"https://weedy.fr/blog/category/culture-cbd/sante-cbd/"},{"@type":"ListItem","position":4,"name":"Durée des effets du CBD : tout comprendre pour mieux profiter"}]},{"@type":"WebSite","@id":"https://weedy.fr/blog/#website","url":"https://weedy.fr/es/blog/","name":"Actualités CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualité du CBD et du chanvre en France","publisher":{"@id":"https://weedy.fr/blog/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://weedy.fr/blog/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https://weedy.fr/blog/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https://weedy.fr/es/blog/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/#/schema/logo/image/","url":"https://weedy.fr/es/blog/wp-content/uploads/2024/05/logo-carre.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https://weedy.fr/blog/#/schema/logo/image/"},"sameAs":["https://www.facebook.com/weedysocial","https://www.instagram.com/weedyfrance/"],"description":"Leader en france sur la vente de produits à base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https://weedy.fr/blog/#/schema/person/72583fcd87d7cf46afe11d530945bc7e","name":"Julien Cordobes","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","url":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","caption":"Julien Cordobes"},"description":"Rédacteur en chef spécialisé en CBD Julien, né le 17 juillet 1978 en région Parisienne, est un éminent rédacteur et expert dans le domaine des produits à base de CBD. Suite à ses études en biologie et en médecine alternative, Julien a développé une passion pour les remèdes naturels, dont le CBD. En 2022, il intègre l’équipe du site Weedy.fr en qualité d’expert et de contributeur régulier. Grâce à son expertise scientifique et une écriture claire, Julien aide à démystifier les aspects complexes du CBD, tout en mettant en lumière ses bienfaits et applications potentielles à travers ses articles et participations à des conférences.","sameAs":["https://weedy.fr","https://www.facebook.com/weedysocial/","https://www.instagram.com/weedyfrance","https://www.pinterest.fr/WeedyFrance/"],"honorificPrefix":"Mr","birthDate":"1978-07-17","gender":"male","knowsAbout":["CBD","Cannabis","Copywriter"],"knowsLanguage":["French"],"jobTitle":"Editor-in-chief specializing in CBD","worksFor":"Weedy.fr","url":"https://weedy.fr/es/blog/author/cbd_blog_owner/"}]}},"_links":{"self":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/319886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts"}],"about":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/users/41"}],"replies":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/comments?post=319886"}],"version-history":[{"count":1,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/319886/revisions"}],"predecessor-version":[{"id":351347,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/319886/revisions/351347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/media/352614"}],"wp:attachment":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/media?parent=319886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/categories?post=319886"},{"taxonomy":"post_tag","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/tags?post=319886"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}