{"id":358816,"date":"2024-09-17T17:27:41","date_gmt":"2024-09-17T15:27:41","guid":{"rendered":"https://weedy.fr/blog/?p=358816"},"modified":"2024-09-17T17:27:42","modified_gmt":"2024-09-17T15:27:42","slug":"duracao-da-presenca-de-cbd-na-saliva-e-na-urina","status":"publish","type":"post","link":"https://weedy.fr/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/","title":{"rendered":"Duração da presença de CBD na saliva e na urina"},"content":{"rendered":"<p>O consumo de <a href=\"https://weedy.fr/es\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a>, ou canabidiol, tornou-se popular com a sua crescente adoção para vários benefícios potenciais para a saúde. Seja por gosto pessoal ou por uso terapêutico, permanece uma dúvida frequente: por quanto tempo o <a href=\"https://weedy.fr/es\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> permanece detectável na saliva e na urina? Este artigo propõe explorar esta questão em detalhes.</p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire</p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle</span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http://www.w3.org/2000/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"></path></svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http://www.w3.org/2000/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"></path></svg></span></span></span></a></span></div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 \"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https://weedy.fr/es/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/#Periodo_de_deteccao_de_CBD_na_saliva\">Período de detecção de CBD na saliva</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https://weedy.fr/es/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/#Fatores_que_influenciam_a_duracao_da_presenca_de_CBD_na_saliva\">Fatores que influenciam a duração da presença de CBD na saliva</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https://weedy.fr/es/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/#Duracao_especifica_da_deteccao_na_saliva_apos_o_consumo\">Duração específica da detecção na saliva após o consumo</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https://weedy.fr/es/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/#Periodo_de_deteccao_de_CBD_na_urina\">Período de detecção de CBD na urina</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https://weedy.fr/es/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/#Duracao_media_da_presenca_na_urina\">Duração média da presença na urina</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https://weedy.fr/es/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/#Diferencas_entre_usuarios_regulares_e_ocasionais\">Diferenças entre usuários regulares e ocasionais</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https://weedy.fr/es/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/#Mecanismos_de_eliminacao_do_CBD_do_corpo\">Mecanismos de eliminação do CBD do corpo</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https://weedy.fr/es/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/#Como_funcionam_os_canabinoides_no_sangue\">Como funcionam os canabinóides no sangue</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https://weedy.fr/es/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/#Excrecao_pela_saliva_urina_e_outros_meios\">Excreção pela saliva, urina e outros meios</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https://weedy.fr/es/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/#Testes_de_drogas_o_que_voce_precisa_saber_para_os_consumidores_de_CBD\">Testes de drogas: o que você precisa saber para os consumidores de CBD</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https://weedy.fr/es/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/#Distincao_entre_THC_e_CBD\">Distinção entre THC e CBD</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https://weedy.fr/es/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/#Regras_e_recomendacoes_sobre_testes_de_saliva_e_urina\">Regras e recomendações sobre testes de saliva e urina</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https://weedy.fr/es/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/#Comparacao_com_outras_substancias\">Comparação com outras substâncias</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https://weedy.fr/es/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/#CBD_vs_THC_tempo_de_deteccao_diferente\">CBD vs THC: tempo de detecção diferente</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https://weedy.fr/es/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/#Visao_geral_de_outros_canabinoides_comuns\">Visão geral de outros canabinóides comuns</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https://weedy.fr/es/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/#Conclusao_parcial_e_perspectivas_futuras\">Conclusão parcial e perspectivas futuras</a></li></ul></nav></div>\n<h2><span class=\"ez-toc-section\" id=\"Periodo_de_deteccao_de_CBD_na_saliva\"></span>Período de detecção de CBD na saliva<span class=\"ez-toc-section-end\"></span></h2>\n<h3><span class=\"ez-toc-section\" id=\"Fatores_que_influenciam_a_duracao_da_presenca_de_CBD_na_saliva\"></span>Fatores que influenciam a duração da presença de CBD na saliva<span class=\"ez-toc-section-end\"></span></h3>\n<p>Vários elementos podem influenciar o período durante o qual o <a href=\"https://weedy.fr/es\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> permanece na saliva:</p>\n<ul>\n<li><strong>Frequência de consumo</strong> : O uso regular de CBD aumentará a duração da sua presença na saliva.</li>\n<li><strong>A dose consumida</strong> : Doses mais altas aumentarão o tempo de detecção.</li>\n<li><strong>Taxa metabólica</strong> : Pessoas com metabolismo rápido eliminarão o CBD mais rapidamente do que aquelas com metabolismo lento.</li>\n<li><strong>O modo de consumo</strong> : O método de ingestão também desempenha um papel (óleos, cápsulas, vaporização).</li>\n</ul>\n<h3><span class=\"ez-toc-section\" id=\"Duracao_especifica_da_deteccao_na_saliva_apos_o_consumo\"></span>Duração específica da detecção na saliva após o consumo<span class=\"ez-toc-section-end\"></span></h3>\n<p>Geralmente, o CBD pode ser detectado na saliva durante aproximadamente 24 a 48 horas após a última utilização. No entanto, este período pode variar muito dependendo dos fatores mencionados acima. Estudos sugerem que, para fins de testes de drogas, que não são comuns no CBD, este intervalo de tempo parece bastante curto.</p>\n<h2><span class=\"ez-toc-section\" id=\"Periodo_de_deteccao_de_CBD_na_urina\"></span>Período de detecção de CBD na urina<span class=\"ez-toc-section-end\"></span></h2>\n<h3><span class=\"ez-toc-section\" id=\"Duracao_media_da_presenca_na_urina\"></span>Duração média da presença na urina<span class=\"ez-toc-section-end\"></span></h3>\n<p>O período de detecção do CBD na urina é diferente e muitas vezes mais longo do que na saliva. Para uma única administração, o CBD pode estar presente na urina durante até três dias. No entanto, para um utilizador frequente ou regular, esta duração pode ser prolongada até várias semanas.</p>\n<h3><span class=\"ez-toc-section\" id=\"Diferencas_entre_usuarios_regulares_e_ocasionais\"></span>Diferenças entre usuários regulares e ocasionais<span class=\"ez-toc-section-end\"></span></h3>\n<p>Existe uma distinção notável entre consumidores regulares e aqueles que consomem CBD ocasionalmente:</p>\n<ul>\n<li>Para um utilizador ocasional, o CBD pode ser detetável na urina durante três a cinco dias.</li>\n<li>Para um utilizador regular (que consome diariamente), os vestígios de CBD podem persistir durante duas a três semanas.</li>\n</ul>\n<h2><span class=\"ez-toc-section\" id=\"Mecanismos_de_eliminacao_do_CBD_do_corpo\"></span>Mecanismos de eliminação do CBD do corpo<span class=\"ez-toc-section-end\"></span></h2>\n<h3><span class=\"ez-toc-section\" id=\"Como_funcionam_os_canabinoides_no_sangue\"></span>Como funcionam os canabinóides no sangue<span class=\"ez-toc-section-end\"></span></h3>\n<p>Após a ingestão, o CBD é absorvido pela corrente sanguínea. O fígado então o metaboliza antes de ser excretado. Curiosamente, o CBD tende a concentrar-se nos tecidos adiposos, prolongando a sua permanência no corpo.</p>\n<h3><span class=\"ez-toc-section\" id=\"Excrecao_pela_saliva_urina_e_outros_meios\"></span>Excreção pela saliva, urina e outros meios<span class=\"ez-toc-section-end\"></span></h3>\n<p>A eliminação do CBD pode ser feita por diferentes vias:</p>\n<ul>\n<li><strong>Saliva</strong> : Como mencionado, o CBD pode ser detectado na saliva num período de tempo bastante curto, geralmente de algumas horas a alguns dias.</li>\n<li><strong>Urina</strong> : Excreção mais lenta em comparação com outros fluidos corporais, especialmente marcada para consumidores regulares.</li>\n<li><strong>Banquetas</strong> : Uma porção significativa do CBD é eliminada através do sistema digestivo.</li>\n</ul>\n<h2><span class=\"ez-toc-section\" id=\"Testes_de_drogas_o_que_voce_precisa_saber_para_os_consumidores_de_CBD\"></span>Testes de drogas: o que você precisa saber para os consumidores de CBD<span class=\"ez-toc-section-end\"></span></h2>\n<h3><span class=\"ez-toc-section\" id=\"Distincao_entre_THC_e_CBD\"></span>Distinção entre THC e CBD<span class=\"ez-toc-section-end\"></span></h3>\n<p>É crucial compreender que os testes de drogas mais comuns procuram identificar o THC, o principal componente psicoativo da cannabis, e não o CBD. No entanto, alguns produtos de CBD podem conter vestígios de THC, o suficiente para desencadear um teste de THC positivo se consumidos em grandes quantidades.</p>\n<h3><span class=\"ez-toc-section\" id=\"Regras_e_recomendacoes_sobre_testes_de_saliva_e_urina\"></span>Regras e recomendações sobre testes de saliva e urina<span class=\"ez-toc-section-end\"></span></h3>\n<p>Embora os testes específicos do CBD sejam raros, os empregadores ou organizações podem utilizar testes de saliva ou urina em circunstâncias especiais. Aqui estão alguns pontos a serem considerados:</p>\n<ul>\n<li><strong>Legalidade e conformidade</strong> : Verifique sempre as leis locais relativas a produtos que contêm CBD e certifique-se de escolher produtos compatíveis, sem resíduos significativos de THC.</li>\n<li><strong>Transparência com autoridades</strong> : Em caso de dúvidas ou testes planejados, mantenha comunicação aberta em relação ao consumo de CBD.</li>\n</ul>\n<h2><span class=\"ez-toc-section\" id=\"Comparacao_com_outras_substancias\"></span>Comparação com outras substâncias<span class=\"ez-toc-section-end\"></span></h2>\n<h3><span class=\"ez-toc-section\" id=\"CBD_vs_THC_tempo_de_deteccao_diferente\"></span>CBD vs THC: tempo de detecção diferente<span class=\"ez-toc-section-end\"></span></h3>\n<p>O THC, ao contrário do CBD, permanece detectável por muito mais tempo. Assim, embora o CBD esteja frequentemente presente nos mesmos produtos, o THC acumula-se mais nas gorduras corporais, particularmente com o uso regular. Também estará mais sujeito a variações dependendo do indivíduo e de seus hábitos.</p>\n<h3><span class=\"ez-toc-section\" id=\"Visao_geral_de_outros_canabinoides_comuns\"></span>Visão geral de outros canabinóides comuns<span class=\"ez-toc-section-end\"></span></h3>\n<p>Outros canabinóides como o <a href=\"https://weedy.fr/es/blog/cbn-un-cannabinoide-peu-connu-mais-puissant/\" data-internallinksmanager029f6b8e52c=\"9\" title=\"cbn - cannabinol\">CBN</a> (canabinol) também têm persistência variável no corpo, mas geralmente seguem os mesmos princípios biológicos. O período necessário para excreção também dependerá da frequência e do método de consumo, semelhante ao CBD e ao THC.</p>\n<h2><span class=\"ez-toc-section\" id=\"Conclusao_parcial_e_perspectivas_futuras\"></span>Conclusão parcial e perspectivas futuras<span class=\"ez-toc-section-end\"></span></h2>\n<p>Este guia cobre o tempo geral de detecção do CBD na saliva e na urina e tenta fornecer conselhos práticos para consumidores habituais e ocasionais. Lembre-se que estas durações não são universais; Cada organismo processa moléculas de maneira diferente.</p>\n","protected":false},"excerpt":{"rendered":"<p>O consumo de CBD, ou canabidiol, tornou-se popular com a sua crescente adoção para vários benefícios potenciais para a saúde. Seja por gosto pessoal ou por uso terapêutico, permanece uma dúvida frequente: por quanto tempo o CBD permanece detectável na saliva e na urina? Este artigo propõe explorar esta questão em detalhes. Período de detecção [&hellip;]</p>\n","protected":false},"author":95,"featured_media":352733,"comment_status":"closed","ping_status":"open","sticky":false,"template":"padrão\n","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[672],"tags":[],"class_list":["post-358816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude-e-bem-estar-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https://yoast.com/product/yoast-seo-premium-wordpress/ -->\n<title>Duração da presença de CBD na saliva e na urina - Actualités CBD Blog - Weedy.fr</title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" />\n<link rel=\"canonical\" href=\"https://weedy.fr/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/\" />\n<meta property=\"og:locale\" content=\"fr_FR\" />\n<meta property=\"og:type\" content=\"article\" />\n<meta property=\"og:title\" content=\"🌱Duração da presença de CBD na saliva e na urina - Weedy.Fr🌱\" />\n<meta property=\"og:description\" content=\"O consumo de CBD, ou canabidiol, tornou-se popular com a sua crescente adoção para vários benefícios potenciais para a saúde. Seja por gosto pessoal ou por uso terapêutico, permanece uma dúvida frequente: por quanto tempo o CBD permanece detectável na saliva e na urina? Este artigo propõe explorar esta questão em detalhes. Período de detecção [&hellip;]\" />\n<meta property=\"og:url\" content=\"https://weedy.fr/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/\" />\n<meta property=\"og:site_name\" content=\"Actualités CBD Blog - Weedy.fr\" />\n<meta property=\"article:publisher\" content=\"https://www.facebook.com/weedysocial\" />\n<meta property=\"article:published_time\" content=\"2024-09-17T15:27:41+00:00\" />\n<meta property=\"article:modified_time\" content=\"2024-09-17T15:27:42+00:00\" />\n<meta property=\"og:image\" content=\"https://weedy.fr/blog/wp-content/uploads/2024/06/duree-de-presence-du-cbd-dans-la-salive-et-lurine.jpg\" />\n\t<meta property=\"og:image:width\" content=\"1456\" />\n\t<meta property=\"og:image:height\" content=\"816\" />\n\t<meta property=\"og:image:type\" content=\"image/jpeg\" />\n<meta name=\"author\" content=\"Alexandre Lacarré\" />\n<meta name=\"twitter:card\" content=\"summary_large_image\" />\n<meta name=\"twitter:label1\" content=\"Écrit par\" />\n\t<meta name=\"twitter:data1\" content=\"Alexandre Lacarré\" />\n\t<meta name=\"twitter:label2\" content=\"Durée de lecture estimée\" />\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" />\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\/\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/duracao-da-presenca-de-cbd-na-saliva-e-na-urina\\/#article\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/duracao-da-presenca-de-cbd-na-saliva-e-na-urina\\/\"},\"author\":{\"name\":\"Alexandre Lacarré\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/54c87d7e580413b08a5b875474a54f4e\"},\"headline\":\"Duração da presença de CBD na saliva e na urina\",\"datePublished\":\"2024-09-17T15:27:41+00:00\",\"dateModified\":\"2024-09-17T15:27:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/duracao-da-presenca-de-cbd-na-saliva-e-na-urina\\/\"},\"wordCount\":853,\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/duracao-da-presenca-de-cbd-na-saliva-e-na-urina\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/06\\/duree-de-presence-du-cbd-dans-la-salive-et-lurine.jpg\",\"articleSection\":[\"Saúde e Bem-estar\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/duracao-da-presenca-de-cbd-na-saliva-e-na-urina\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/duracao-da-presenca-de-cbd-na-saliva-e-na-urina\\/\",\"name\":\"Duração da presença de CBD na saliva e na urina - Actualités CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/duracao-da-presenca-de-cbd-na-saliva-e-na-urina\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/duracao-da-presenca-de-cbd-na-saliva-e-na-urina\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/06\\/duree-de-presence-du-cbd-dans-la-salive-et-lurine.jpg\",\"datePublished\":\"2024-09-17T15:27:41+00:00\",\"dateModified\":\"2024-09-17T15:27:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/duracao-da-presenca-de-cbd-na-saliva-e-na-urina\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\/\\/weedy.fr\\/blog\\/pt\\/duracao-da-presenca-de-cbd-na-saliva-e-na-urina\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/duracao-da-presenca-de-cbd-na-saliva-e-na-urina\\/#primaryimage\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/06\\/duree-de-presence-du-cbd-dans-la-salive-et-lurine.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/06\\/duree-de-presence-du-cbd-dans-la-salive-et-lurine.jpg\",\"width\":1456,\"height\":816,\"caption\":\"Durée de présence du cbd dans la salive et l'urine, estime, cbd, salive\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/duracao-da-presenca-de-cbd-na-saliva-e-na-urina\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Saúde e Bem-estar\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/category\\/saude-e-bem-estar-pt\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Duração da presença de CBD na saliva e na urina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"name\":\"Actualités CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualité du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\/\\/weedy.fr\\/blog\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\"},\"sameAs\":[\"https:\\/\\/www.facebook.com\\/weedysocial\",\"https:\\/\\/www.instagram.com\\/weedyfrance\\/\"],\"description\":\"Leader en france sur la vente de produits à base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/54c87d7e580413b08a5b875474a54f4e\",\"name\":\"Alexandre Lacarré\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g\",\"url\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g\",\"caption\":\"Alexandre Lacarré\"},\"description\":\"Alexandre Lacarré est reconnu comme un leader innovant et influent dans l'industrie du cannabidiol (CBD). Alexandre a débuté sa carrière dans le secteur des biotechnologies, où il a acquis une expertise précieuse en recherche et développement. Passionné par les potentiels thérapeutiques des composés naturels, il s'est rapidement orienté vers l'industrie naissante du CBD.\",\"sameAs\":[\"https:\\/\\/www.linkedin.com\\/in\\/alexandre-henri-lacarr-785850186\\/\"],\"honorificPrefix\":\"Mr\",\"gender\":\"homme\",\"knowsAbout\":[\"CBD\",\"Cannabis\",\"Copywriter\"],\"worksFor\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/author\\/fiacre\\/\"}]}</script>\n<!-- / Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Duração da presença de CBD na saliva e na urina - Actualités CBD Blog - Weedy.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://weedy.fr/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/","og_locale":"fr_FR","og_type":"article","og_title":"🌱Duração da presença de CBD na saliva e na urina - Weedy.Fr🌱","og_description":"O consumo de CBD, ou canabidiol, tornou-se popular com a sua crescente adoção para vários benefícios potenciais para a saúde. Seja por gosto pessoal ou por uso terapêutico, permanece uma dúvida frequente: por quanto tempo o CBD permanece detectável na saliva e na urina? Este artigo propõe explorar esta questão em detalhes. Período de detecção [&hellip;]","og_url":"https://weedy.fr/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/","og_site_name":"Actualités CBD Blog - Weedy.fr","article_publisher":"https://www.facebook.com/weedysocial","article_published_time":"2024-09-17T15:27:41+00:00","article_modified_time":"2024-09-17T15:27:42+00:00","og_image":[{"width":1456,"height":816,"url":"https://weedy.fr/es/blog/wp-content/uploads/2024/06/duree-de-presence-du-cbd-dans-la-salive-et-lurine.jpg","type":"image/jpeg"}],"author":"Alexandre Lacarré","twitter_card":"summary_large_image","twitter_misc":{"Écrit par":"Alexandre Lacarré","Durée de lecture estimée":"4 minutes"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"Article","@id":"https://weedy.fr/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/#article","isPartOf":{"@id":"https://weedy.fr/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/"},"author":{"name":"Alexandre Lacarré","@id":"https://weedy.fr/blog/#/schema/person/54c87d7e580413b08a5b875474a54f4e"},"headline":"Duração da presença de CBD na saliva e na urina","datePublished":"2024-09-17T15:27:41+00:00","dateModified":"2024-09-17T15:27:42+00:00","mainEntityOfPage":{"@id":"https://weedy.fr/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/"},"wordCount":853,"publisher":{"@id":"https://weedy.fr/blog/#organization"},"image":{"@id":"https://weedy.fr/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/06/duree-de-presence-du-cbd-dans-la-salive-et-lurine.jpg","articleSection":["Saúde e Bem-estar"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https://weedy.fr/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/","url":"https://weedy.fr/es/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/","name":"Duração da presença de CBD na saliva e na urina - Actualités CBD Blog - Weedy.fr","isPartOf":{"@id":"https://weedy.fr/blog/#website"},"primaryImageOfPage":{"@id":"https://weedy.fr/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/#primaryimage"},"image":{"@id":"https://weedy.fr/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/06/duree-de-presence-du-cbd-dans-la-salive-et-lurine.jpg","datePublished":"2024-09-17T15:27:41+00:00","dateModified":"2024-09-17T15:27:42+00:00","breadcrumb":{"@id":"https://weedy.fr/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https://weedy.fr/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/#primaryimage","url":"https://weedy.fr/es/blog/wp-content/uploads/2024/06/duree-de-presence-du-cbd-dans-la-salive-et-lurine.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/06/duree-de-presence-du-cbd-dans-la-salive-et-lurine.jpg","width":1456,"height":816,"caption":"Durée de présence du cbd dans la salive et l'urine, estime, cbd, salive"},{"@type":"BreadcrumbList","@id":"https://weedy.fr/blog/pt/duracao-da-presenca-de-cbd-na-saliva-e-na-urina/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https://weedy.fr/blog/"},{"@type":"ListItem","position":2,"name":"Saúde e Bem-estar","item":"https://weedy.fr/blog/category/saude-e-bem-estar-pt/"},{"@type":"ListItem","position":3,"name":"Duração da presença de CBD na saliva e na urina"}]},{"@type":"WebSite","@id":"https://weedy.fr/blog/#website","url":"https://weedy.fr/es/blog/","name":"Actualités CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualité du CBD et du chanvre en France","publisher":{"@id":"https://weedy.fr/blog/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://weedy.fr/blog/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https://weedy.fr/blog/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https://weedy.fr/es/blog/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/#/schema/logo/image/","url":"https://weedy.fr/es/blog/wp-content/uploads/2024/05/logo-carre.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https://weedy.fr/blog/#/schema/logo/image/"},"sameAs":["https://www.facebook.com/weedysocial","https://www.instagram.com/weedyfrance/"],"description":"Leader en france sur la vente de produits à base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https://weedy.fr/blog/#/schema/person/54c87d7e580413b08a5b875474a54f4e","name":"Alexandre Lacarré","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://secure.gravatar.com/avatar/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g","url":"https://secure.gravatar.com/avatar/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g","caption":"Alexandre Lacarré"},"description":"Alexandre Lacarré est reconnu comme un leader innovant et influent dans l'industrie du cannabidiol (CBD). Alexandre a débuté sa carrière dans le secteur des biotechnologies, où il a acquis une expertise précieuse en recherche et développement. Passionné par les potentiels thérapeutiques des composés naturels, il s'est rapidement orienté vers l'industrie naissante du CBD.","sameAs":["https://www.linkedin.com/in/alexandre-henri-lacarr-785850186/"],"honorificPrefix":"Mr","gender":"homme","knowsAbout":["CBD","Cannabis","Copywriter"],"worksFor":"Weedy.fr","url":"https://weedy.fr/es/blog/author/fiacre/"}]}},"_links":{"self":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/358816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts"}],"about":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/users/95"}],"replies":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/comments?post=358816"}],"version-history":[{"count":1,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/358816/revisions"}],"predecessor-version":[{"id":358817,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/358816/revisions/358817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/media/352733"}],"wp:attachment":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/media?parent=358816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/categories?post=358816"},{"taxonomy":"post_tag","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/tags?post=358816"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}