{"id":359368,"date":"2024-09-17T17:39:40","date_gmt":"2024-09-17T15:39:40","guid":{"rendered":"https://weedy.fr/blog/?p=359368"},"modified":"2024-09-17T17:39:40","modified_gmt":"2024-09-17T15:39:40","slug":"cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar","status":"publish","type":"post","link":"https://weedy.fr/blog/pt/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar/","title":{"rendered":"CBD e Pilates: uma combinação vencedora para o seu bem-estar"},"content":{"rendered":"<p>Na nossa busca pelo bem-estar e equilíbrio, a procura por métodos suaves e naturais está em constante progresso. Nesse contexto, <strong><a href=\"https://weedy.fr/es\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> e Pilates se destacam como duas abordagens complementares</strong> para trazer relaxamento, relaxamento e vitalidade ao nosso corpo e mente. Mas como pode a combinação de <a href=\"https://weedy.fr/es\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> e Pilates criar uma sinergia benéfica? Descubra os potenciais benefícios desta combinação para melhorar a sua qualidade de vida.</p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire</p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle</span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http://www.w3.org/2000/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"></path></svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http://www.w3.org/2000/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"></path></svg></span></span></span></a></span></div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 \"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https://weedy.fr/es/blog/pt/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar/#CBD_uma_molecula_com_multiplas_virtudes\">CBD: uma molécula com múltiplas virtudes</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https://weedy.fr/es/blog/pt/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar/#Um_poderoso_anti-inflamatorio\">Um poderoso anti-inflamatório</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https://weedy.fr/es/blog/pt/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar/#Propriedades_ansioliticas_e_relaxantes\">Propriedades ansiolíticas e relaxantes</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https://weedy.fr/es/blog/pt/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar/#Pilates_um_metodo_suave_para_fortalecer_o_corpo_e_a_mente\">Pilates: um método suave para fortalecer o corpo e a mente</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https://weedy.fr/es/blog/pt/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar/#Trabalho_aprofundado_para_fortalecer_e_suavizar_os_musculos\">Trabalho aprofundado para fortalecer e suavizar os músculos</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https://weedy.fr/es/blog/pt/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar/#Uma_ferramenta_valiosa_para_controlar_o_estresse_e_melhorar_a_postura\">Uma ferramenta valiosa para controlar o estresse e melhorar a postura</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https://weedy.fr/es/blog/pt/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar/#A_sinergia_entre_CBD_e_Pilates_maximizando_os_beneficios\">A sinergia entre CBD e Pilates: maximizando os benefícios</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https://weedy.fr/es/blog/pt/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar/#Como_combinar_o_CBD_com_a_sua_pratica_de_Pilates\">Como combinar o CBD com a sua prática de Pilates?</a></li></ul></li></ul></nav></div>\n<h2><span class=\"ez-toc-section\" id=\"CBD_uma_molecula_com_multiplas_virtudes\"></span>CBD: uma molécula com múltiplas virtudes<span class=\"ez-toc-section-end\"></span></h2>\n<p>Derivado do cânhamo, o canabidiol (<a href=\"https://weedy.fr/es\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a>) é um composto natural que está atraindo interesse crescente pelas suas potenciais propriedades terapêuticas. Ao contrário do THC, o seu homólogo psicoativo presente na cannabis, <strong>O CBD não causa efeitos psicotrópicos e possui um excelente perfil de segurança</strong>. É, portanto, legal em muitos países, incluindo a França, e está disponível em diferentes formas, como óleos, cremes ou cápsulas.</p>\n<h3><span class=\"ez-toc-section\" id=\"Um_poderoso_anti-inflamatorio\"></span>Um poderoso anti-inflamatório<span class=\"ez-toc-section-end\"></span></h3>\n<p>O CBD é conhecido pela sua capacidade de reduzir a inflamação, através da sua interação com o sistema endocanabinóide (ECS). Este último desempenha um papel importante na regulação das nossas funções fisiológicas, particularmente em termos de inflamação.<strong> O CBD poderia assim ajudar a aliviar várias dores inflamatórias</strong>, variando de dores a distúrbios intestinais.</p>\n<h3><span class=\"ez-toc-section\" id=\"Propriedades_ansioliticas_e_relaxantes\"></span>Propriedades ansiolíticas e relaxantes<span class=\"ez-toc-section-end\"></span></h3>\n<p>O CBD também atua no nosso sistema nervoso central, onde ajuda a regular a nossa percepção da dor e das nossas emoções. Estudos mostraram que <strong>O CBD tem efeitos ansiolíticos e relaxantes facilitando a gestão do stress e da ansiedade</strong>. Também pode promover um sono mais reparador e melhor recuperação pós-exercício.</p>\n<h2><span class=\"ez-toc-section\" id=\"Pilates_um_metodo_suave_para_fortalecer_o_corpo_e_a_mente\"></span>Pilates: um método suave para fortalecer o corpo e a mente<span class=\"ez-toc-section-end\"></span></h2>\n<p>Inventado na década de 1920 por Joseph Pilates, o Pilates é uma disciplina física baseada em movimentos precisos e fluidos realizados com respiração controlada. Reconhecido pelos seus benefícios na saúde física e mental, este método suave visa harmonizar o corpo e a mente, melhorando a postura, a flexibilidade e a força muscular.</p>\n<h3><span class=\"ez-toc-section\" id=\"Trabalho_aprofundado_para_fortalecer_e_suavizar_os_musculos\"></span>Trabalho aprofundado para fortalecer e suavizar os músculos<span class=\"ez-toc-section-end\"></span></h3>\n<p>O Pilates permite trabalhar todos os músculos do corpo, com especial destaque para a cintura abdominal e a coluna. Também trabalha os músculos profundos através da implementação de respiração específica. <strong>Esta abordagem abrangente ajuda a construir um corpo forte e flexível, ao mesmo tempo que previne dores e desequilíbrios musculares.</strong>.</p>\n<h3><span class=\"ez-toc-section\" id=\"Uma_ferramenta_valiosa_para_controlar_o_estresse_e_melhorar_a_postura\"></span>Uma ferramenta valiosa para controlar o estresse e melhorar a postura<span class=\"ez-toc-section-end\"></span></h3>\n<p>Pilates também é uma ótima maneira de aliviar o estresse e acalmar a mente. Sua prática regular promove <strong>concentração, relaxamento e melhor gestão das emoções</strong>. Além disso, ao melhorar a nossa postura e a nossa consciência corporal, o Pilates ajuda-nos a adotar comportamentos mais saudáveis ​​para preservar o nosso bem-estar diário.</p>\n<h2><span class=\"ez-toc-section\" id=\"A_sinergia_entre_CBD_e_Pilates_maximizando_os_beneficios\"></span>A sinergia entre CBD e Pilates: maximizando os benefícios<span class=\"ez-toc-section-end\"></span></h2>\n<p>Dadas as respectivas virtudes do CBD e do Pilates, é interessante considerar a sua combinação para optimizar o nosso bem-estar. Aqui estão algumas idéias sobre como essa combinação pode ser benéfica:</p>\n<ol>\n<li><strong>Acalma a dor e a inflamação:</strong> O CBD pode ajudar a reduzir a inflamação e aliviar dores associadas à prática de Pilates, promovendo assim uma recuperação ideal.</li>\n<li><strong>Facilitar o relaxamento:</strong> Os efeitos relaxantes do CBD combinados com a respiração controlada do Pilates ajudam a libertar a tensão física e mental, criando um estado ideal de relaxamento.</li>\n<li><strong>Melhorar a qualidade do sono:</strong> Ao acalmar o corpo e a mente, a dupla CBD-Pilates promove um sono reparador, essencial para uma boa saúde e melhor disposição durante as sessões de Pilates.</li>\n<li><strong>Fortalecer a concentração:</strong> O efeito ansiolítico do CBD pode promover melhor concentração na prática de Pilates, permitindo que os movimentos sejam realizados com mais precisão e eficiência.</li>\n</ol>\n<h3><span class=\"ez-toc-section\" id=\"Como_combinar_o_CBD_com_a_sua_pratica_de_Pilates\"></span>Como combinar o CBD com a sua prática de Pilates?<span class=\"ez-toc-section-end\"></span></h3>\n<p>Para beneficiar plenamente dos benefícios combinados do CBD e do Pilates, pode integrar o CBD na sua rotina diária de diferentes formas:</p>\n<ul>\n<li><strong>Óleo CBD:</strong> Consuma algumas gotas de óleo CBD debaixo da língua antes ou depois da sessão de Pilates para ajudar no relaxamento e na recuperação.</li>\n<li><strong>Creme ou bálsamo CBD:</strong> Aplique um produto tópico de CBD em áreas doloridas ou tensas para aliviar a inflamação e acelerar a cicatrização.</li>\n<li><strong>Cápsulas de CBD:</strong> Tome cápsulas de CBD regularmente para beneficiar dos seus efeitos anti-inflamatórios e relaxantes a longo prazo.</li>\n</ul>\n<p>É importante escolher produtos de qualidade que contenham CBD puro e sem THC, respeitando as dosagens recomendadas. Não hesite em consultar o seu médico para determinar se o uso do CBD é adequado às suas necessidades e para ajustar as dosagens de acordo com os seus sentimentos.</p>\n","protected":false},"excerpt":{"rendered":"<p>Na nossa busca pelo bem-estar e equilíbrio, a procura por métodos suaves e naturais está em constante progresso. Nesse contexto, CBD e Pilates se destacam como duas abordagens complementares para trazer relaxamento, relaxamento e vitalidade ao nosso corpo e mente. Mas como pode a combinação de CBD e Pilates criar uma sinergia benéfica? Descubra os [&hellip;]</p>\n","protected":false},"author":95,"featured_media":351990,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[675],"tags":[],"class_list":["post-359368","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-sobre-cbd-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https://yoast.com/product/yoast-seo-premium-wordpress/ -->\n<title>CBD e Pilates: uma combinação vencedora para o seu bem-estar - Actualités CBD Blog - Weedy.fr</title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" />\n<link rel=\"canonical\" href=\"https://weedy.fr/blog/pt/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar/\" />\n<meta property=\"og:locale\" content=\"fr_FR\" />\n<meta property=\"og:type\" content=\"article\" />\n<meta property=\"og:title\" content=\"🌱CBD e Pilates: uma combinação vencedora para o seu bem-estar - Weedy.Fr🌱\" />\n<meta property=\"og:description\" content=\"Na nossa busca pelo bem-estar e equilíbrio, a procura por métodos suaves e naturais está em constante progresso. Nesse contexto, CBD e Pilates se destacam como duas abordagens complementares para trazer relaxamento, relaxamento e vitalidade ao nosso corpo e mente. Mas como pode a combinação de CBD e Pilates criar uma sinergia benéfica? Descubra os [&hellip;]\" />\n<meta property=\"og:url\" content=\"https://weedy.fr/blog/pt/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar/\" />\n<meta property=\"og:site_name\" content=\"Actualités CBD Blog - Weedy.fr\" />\n<meta property=\"article:publisher\" content=\"https://www.facebook.com/weedysocial\" />\n<meta property=\"article:published_time\" content=\"2024-09-17T15:39:40+00:00\" />\n<meta property=\"og:image\" content=\"https://weedy.fr/blog/wp-content/uploads/2024/01/le-cbd-et-le-pilates-une-combinaison-gagnante-pour-votre-bien-etre.jpg\" />\n\t<meta property=\"og:image:width\" content=\"1456\" />\n\t<meta property=\"og:image:height\" content=\"832\" />\n\t<meta property=\"og:image:type\" content=\"image/jpeg\" />\n<meta name=\"author\" content=\"Alexandre Lacarré\" />\n<meta name=\"twitter:card\" content=\"summary_large_image\" />\n<meta name=\"twitter:label1\" content=\"Écrit par\" />\n\t<meta name=\"twitter:data1\" content=\"Alexandre Lacarré\" />\n\t<meta name=\"twitter:label2\" content=\"Durée de lecture estimée\" />\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" />\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\/\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar\\/#article\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar\\/\"},\"author\":{\"name\":\"Alexandre Lacarré\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/54c87d7e580413b08a5b875474a54f4e\"},\"headline\":\"CBD e Pilates: uma combinação vencedora para o seu bem-estar\",\"datePublished\":\"2024-09-17T15:39:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar\\/\"},\"wordCount\":838,\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/le-cbd-et-le-pilates-une-combinaison-gagnante-pour-votre-bien-etre.jpg\",\"articleSection\":[\"Notícias sobre CBD\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar\\/\",\"name\":\"CBD e Pilates: uma combinação vencedora para o seu bem-estar - Actualités CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/le-cbd-et-le-pilates-une-combinaison-gagnante-pour-votre-bien-etre.jpg\",\"datePublished\":\"2024-09-17T15:39:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar\\/#primaryimage\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/le-cbd-et-le-pilates-une-combinaison-gagnante-pour-votre-bien-etre.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/le-cbd-et-le-pilates-une-combinaison-gagnante-pour-votre-bien-etre.jpg\",\"width\":1456,\"height\":832,\"caption\":\"Le CBD et le Pilates : une combinaison gagnante pour votre bien-être\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notícias sobre CBD\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/category\\/noticias-sobre-cbd-pt\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CBD e Pilates: uma combinação vencedora para o seu bem-estar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"name\":\"Actualités CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualité du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\/\\/weedy.fr\\/blog\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\"},\"sameAs\":[\"https:\\/\\/www.facebook.com\\/weedysocial\",\"https:\\/\\/www.instagram.com\\/weedyfrance\\/\"],\"description\":\"Leader en france sur la vente de produits à base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/54c87d7e580413b08a5b875474a54f4e\",\"name\":\"Alexandre Lacarré\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g\",\"url\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g\",\"caption\":\"Alexandre Lacarré\"},\"description\":\"Alexandre Lacarré est reconnu comme un leader innovant et influent dans l'industrie du cannabidiol (CBD). Alexandre a débuté sa carrière dans le secteur des biotechnologies, où il a acquis une expertise précieuse en recherche et développement. Passionné par les potentiels thérapeutiques des composés naturels, il s'est rapidement orienté vers l'industrie naissante du CBD.\",\"sameAs\":[\"https:\\/\\/www.linkedin.com\\/in\\/alexandre-henri-lacarr-785850186\\/\"],\"honorificPrefix\":\"Mr\",\"gender\":\"homme\",\"knowsAbout\":[\"CBD\",\"Cannabis\",\"Copywriter\"],\"worksFor\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/author\\/fiacre\\/\"}]}</script>\n<!-- / Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"CBD e Pilates: uma combinação vencedora para o seu bem-estar - Actualités CBD Blog - Weedy.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://weedy.fr/blog/pt/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar/","og_locale":"fr_FR","og_type":"article","og_title":"🌱CBD e Pilates: uma combinação vencedora para o seu bem-estar - Weedy.Fr🌱","og_description":"Na nossa busca pelo bem-estar e equilíbrio, a procura por métodos suaves e naturais está em constante progresso. Nesse contexto, CBD e Pilates se destacam como duas abordagens complementares para trazer relaxamento, relaxamento e vitalidade ao nosso corpo e mente. Mas como pode a combinação de CBD e Pilates criar uma sinergia benéfica? Descubra os [&hellip;]","og_url":"https://weedy.fr/blog/pt/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar/","og_site_name":"Actualités CBD Blog - Weedy.fr","article_publisher":"https://www.facebook.com/weedysocial","article_published_time":"2024-09-17T15:39:40+00:00","og_image":[{"width":1456,"height":832,"url":"https://weedy.fr/es/blog/wp-content/uploads/2024/01/le-cbd-et-le-pilates-une-combinaison-gagnante-pour-votre-bien-etre.jpg","type":"image/jpeg"}],"author":"Alexandre Lacarré","twitter_card":"summary_large_image","twitter_misc":{"Écrit par":"Alexandre Lacarré","Durée de lecture estimée":"4 minutes"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"Article","@id":"https://weedy.fr/blog/pt/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar/#article","isPartOf":{"@id":"https://weedy.fr/blog/pt/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar/"},"author":{"name":"Alexandre Lacarré","@id":"https://weedy.fr/blog/#/schema/person/54c87d7e580413b08a5b875474a54f4e"},"headline":"CBD e Pilates: uma combinação vencedora para o seu bem-estar","datePublished":"2024-09-17T15:39:40+00:00","mainEntityOfPage":{"@id":"https://weedy.fr/blog/pt/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar/"},"wordCount":838,"publisher":{"@id":"https://weedy.fr/blog/#organization"},"image":{"@id":"https://weedy.fr/blog/pt/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/le-cbd-et-le-pilates-une-combinaison-gagnante-pour-votre-bien-etre.jpg","articleSection":["Notícias sobre CBD"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https://weedy.fr/blog/pt/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar/","url":"https://weedy.fr/es/blog/pt/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar/","name":"CBD e Pilates: uma combinação vencedora para o seu bem-estar - Actualités CBD Blog - Weedy.fr","isPartOf":{"@id":"https://weedy.fr/blog/#website"},"primaryImageOfPage":{"@id":"https://weedy.fr/blog/pt/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar/#primaryimage"},"image":{"@id":"https://weedy.fr/blog/pt/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/le-cbd-et-le-pilates-une-combinaison-gagnante-pour-votre-bien-etre.jpg","datePublished":"2024-09-17T15:39:40+00:00","breadcrumb":{"@id":"https://weedy.fr/blog/pt/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https://weedy.fr/blog/pt/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/pt/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar/#primaryimage","url":"https://weedy.fr/es/blog/wp-content/uploads/2024/01/le-cbd-et-le-pilates-une-combinaison-gagnante-pour-votre-bien-etre.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/le-cbd-et-le-pilates-une-combinaison-gagnante-pour-votre-bien-etre.jpg","width":1456,"height":832,"caption":"Le CBD et le Pilates : une combinaison gagnante pour votre bien-être"},{"@type":"BreadcrumbList","@id":"https://weedy.fr/blog/pt/cbd-e-pilates-uma-combinacao-vencedora-para-o-seu-bem-estar/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https://weedy.fr/blog/"},{"@type":"ListItem","position":2,"name":"Notícias sobre CBD","item":"https://weedy.fr/blog/category/noticias-sobre-cbd-pt/"},{"@type":"ListItem","position":3,"name":"CBD e Pilates: uma combinação vencedora para o seu bem-estar"}]},{"@type":"WebSite","@id":"https://weedy.fr/blog/#website","url":"https://weedy.fr/es/blog/","name":"Actualités CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualité du CBD et du chanvre en France","publisher":{"@id":"https://weedy.fr/blog/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://weedy.fr/blog/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https://weedy.fr/blog/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https://weedy.fr/es/blog/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/#/schema/logo/image/","url":"https://weedy.fr/es/blog/wp-content/uploads/2024/05/logo-carre.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https://weedy.fr/blog/#/schema/logo/image/"},"sameAs":["https://www.facebook.com/weedysocial","https://www.instagram.com/weedyfrance/"],"description":"Leader en france sur la vente de produits à base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https://weedy.fr/blog/#/schema/person/54c87d7e580413b08a5b875474a54f4e","name":"Alexandre Lacarré","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://secure.gravatar.com/avatar/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g","url":"https://secure.gravatar.com/avatar/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g","caption":"Alexandre Lacarré"},"description":"Alexandre Lacarré est reconnu comme un leader innovant et influent dans l'industrie du cannabidiol (CBD). Alexandre a débuté sa carrière dans le secteur des biotechnologies, où il a acquis une expertise précieuse en recherche et développement. Passionné par les potentiels thérapeutiques des composés naturels, il s'est rapidement orienté vers l'industrie naissante du CBD.","sameAs":["https://www.linkedin.com/in/alexandre-henri-lacarr-785850186/"],"honorificPrefix":"Mr","gender":"homme","knowsAbout":["CBD","Cannabis","Copywriter"],"worksFor":"Weedy.fr","url":"https://weedy.fr/es/blog/author/fiacre/"}]}},"_links":{"self":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts"}],"about":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/users/95"}],"replies":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/comments?post=359368"}],"version-history":[{"count":1,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359368/revisions"}],"predecessor-version":[{"id":359369,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359368/revisions/359369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/media/351990"}],"wp:attachment":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/media?parent=359368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/categories?post=359368"},{"taxonomy":"post_tag","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/tags?post=359368"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}