{"id":359456,"date":"2024-09-17T17:41:25","date_gmt":"2024-09-17T15:41:25","guid":{"rendered":"https://weedy.fr/blog/?p=359456"},"modified":"2024-09-17T17:41:26","modified_gmt":"2024-09-17T15:41:26","slug":"os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor","status":"publish","type":"post","link":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor/","title":{"rendered":"Os benefícios do CBD no golfe: melhore a sua concentração, reduza a ansiedade e a dor"},"content":{"rendered":"<p>O golfe é um esporte de precisão e concentração. Para se destacar nesta área, é necessário controlar as emoções e administrar o estresse. Hoje, cada vez mais golfistas recorrem ao <a href=\"https://weedy.fr/es\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> para os ajudar a encontrar o estado de espírito ideal no green. <a href=\"https://weedy.fr/es\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a>, ou canabidiol, é um componente não psicoativo encontrado na cannabis que possui muitos <strong>benefícios na saúde mental e física.</strong> Neste artigo, discutiremos os principais benefícios do <a href=\"https://weedy.fr/es\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> para os golfistas e como esta substância pode ajudá-lo a melhorar o seu desempenho e bem-estar geral.</p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire</p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle</span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http://www.w3.org/2000/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"></path></svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http://www.w3.org/2000/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"></path></svg></span></span></span></a></span></div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 \"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https://weedy.fr/es/blog/pt/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor/#Melhor_concentracao_gracas_ao_CBD\">Melhor concentração graças ao CBD</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https://weedy.fr/es/blog/pt/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor/#Como_integrar_o_CBD_para_fortalecer_a_sua_concentracao\">Como integrar o CBD para fortalecer a sua concentração</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https://weedy.fr/es/blog/pt/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor/#Reducao_da_ansiedade_gracas_ao_CBD\">Redução da ansiedade graças ao CBD</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https://weedy.fr/es/blog/pt/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor/#Algumas_recomendacoes_para_usar_CBD_para_ansiedade_no_golfe\">Algumas recomendações para usar CBD para ansiedade no golfe</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https://weedy.fr/es/blog/pt/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor/#Tratamento_da_dor_com_CBD\">Tratamento da dor com CBD</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https://weedy.fr/es/blog/pt/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor/#Como_usar_o_CBD_para_aliviar_a_dor_do_golfe\">Como usar o CBD para aliviar a dor do golfe</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https://weedy.fr/es/blog/pt/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor/#Em_resumo_CBD_uma_ajuda_versatil_para_golfistas\">Em resumo: CBD, uma ajuda versátil para golfistas</a></li></ul></nav></div>\n<h2><span class=\"ez-toc-section\" id=\"Melhor_concentracao_gracas_ao_CBD\"></span>Melhor concentração graças ao CBD<span class=\"ez-toc-section-end\"></span></h2>\n<p>A concentração é fundamental quando se trata de acertar a bola com precisão e avaliar distâncias, condições de jogo e obstáculos. Os golfistas devem ser capazes de permanecer completamente concentrados por longos períodos de tempo, às vezes até várias horas. No entanto, o stress, a fadiga, as dores musculares e articulares podem comprometer esta preciosa concentração.</p>\n<p>Estudos mostram que o CBD pode ter efeitos benéficos na concentração. Na verdade, atua no sistema endocanabinóide, que desempenha um papel crucial na regulação das nossas funções cognitivas. Graças a estas propriedades, o CBD poderia melhorar a nossa capacidade de permanecer atento e concentrado.</p>\n<h3><span class=\"ez-toc-section\" id=\"Como_integrar_o_CBD_para_fortalecer_a_sua_concentracao\"></span>Como integrar o CBD para fortalecer a sua concentração<span class=\"ez-toc-section-end\"></span></h3>\n<ul>\n<li><strong>Use cápsulas de CBD:</strong> Os suplementos alimentares de CBD são simples de dosar e fáceis de incluir na rotina diária. Permitem obter uma dosagem precisa e regular, ideal para ajudar a manter um elevado nível de concentração a longo prazo.</li>\n<li><strong>Dê preferência a produtos com infusão de CBD:</strong> Existem também produtos desenvolvidos especificamente para golfistas com ingredientes que podem promover o foco, como barras energéticas, bebidas e chicletes com infusão de CBD.</li>\n</ul>\n<h2><span class=\"ez-toc-section\" id=\"Reducao_da_ansiedade_gracas_ao_CBD\"></span>Redução da ansiedade graças ao CBD<span class=\"ez-toc-section-end\"></span></h2>\n<p>A ansiedade é um grande problema que afeta muitos atletas, incluindo jogadores de golfe. Na verdade, as competições e a pressão dos resultados podem contribuir para aumentar os níveis de stress e prejudicar o desempenho. O CBD demonstrou ser eficaz na redução da ansiedade e do stress em indivíduos que sofrem de perturbações de ansiedade, particularmente ao atuar nos recetores serotoninérgicos.</p>\n<h3><span class=\"ez-toc-section\" id=\"Algumas_recomendacoes_para_usar_CBD_para_ansiedade_no_golfe\"></span>Algumas recomendações para usar CBD para ansiedade no golfe<span class=\"ez-toc-section-end\"></span></h3>\n<ul>\n<li><strong>Opte por óleos CBD sublinguais:</strong> Eles oferecem um método de administração rápido e eficaz para controlar a ansiedade. Colocadas sob a língua, as gotas de óleo são rapidamente absorvidas pela mucosa oral e podem proporcionar alívio quase imediato.</li>\n<li><strong>Experimente os inaladores CBD:</strong> Para uma ação ainda mais rápida, os inaladores ou vaporizadores de CBD podem ser uma boa opção. Permitem a absorção direta nos pulmões e a rápida difusão dos canabinóides no sangue, tornando-os uma solução de eleição para aliviar a ansiedade imediatamente antes de um jogo ou torneio.</li>\n</ul>\n<h2><span class=\"ez-toc-section\" id=\"Tratamento_da_dor_com_CBD\"></span>Tratamento da dor com CBD<span class=\"ez-toc-section-end\"></span></h2>\n<p>O golfe exerce muita pressão sobre o corpo e pode causar vários tipos de dores musculares e articulares. Muitos golfistas procuram formas naturais e eficazes de controlar a dor sem recorrer aos medicamentos tradicionais (anti-inflamatórios não esteróides). O CBD pode satisfazer esta expectativa graças às suas propriedades anti-inflamatórias e analgésicas.</p>\n<h3><span class=\"ez-toc-section\" id=\"Como_usar_o_CBD_para_aliviar_a_dor_do_golfe\"></span>Como usar o CBD para aliviar a dor do golfe<span class=\"ez-toc-section-end\"></span></h3>\n<ul>\n<li><strong>Aplique bálsamos e cremes tópicos de CBD:</strong> Estes produtos permitem a aplicação localizada em áreas doloridas e atuam diretamente nos receptores canabinóides da pele para aliviar a dor e a inflamação.</li>\n<li><strong>Consumir cápsulas de CBD:</strong> Para o controle geral da dor, as cápsulas de CBD ingeridas oferecem uma dosagem precisa e regular que ajuda a controlar a inflamação e as dores musculares e articulares.</li>\n</ul>\n<h2><span class=\"ez-toc-section\" id=\"Em_resumo_CBD_uma_ajuda_versatil_para_golfistas\"></span>Em resumo: CBD, uma ajuda versátil para golfistas<span class=\"ez-toc-section-end\"></span></h2>\n<p>Quer se trate de melhorar o foco, reduzir a ansiedade ou controlar a dor, o CBD pode proporcionar muitos benefícios aos golfistas. É importante escolher produtos de qualidade e consultar um profissional de saúde para determinar a dosagem adequada de acordo com suas necessidades específicas. Com o uso adequado do CBD, você poderá desfrutar plenamente do golfe, mantendo seu bem-estar físico e mental.</p>\n","protected":false},"excerpt":{"rendered":"<p>O golfe é um esporte de precisão e concentração. Para se destacar nesta área, é necessário controlar as emoções e administrar o estresse. Hoje, cada vez mais golfistas recorrem ao CBD para os ajudar a encontrar o estado de espírito ideal no green. CBD, ou canabidiol, é um componente não psicoativo encontrado na cannabis que [&hellip;]</p>\n","protected":false},"author":97,"featured_media":351980,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[675],"tags":[],"class_list":["post-359456","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-sobre-cbd-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https://yoast.com/product/yoast-seo-premium-wordpress/ -->\n<title>Os benefícios do CBD no golfe: melhore a sua concentração, reduza a ansiedade e a dor - Actualités CBD Blog - Weedy.fr</title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" />\n<link rel=\"canonical\" href=\"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor/\" />\n<meta property=\"og:locale\" content=\"fr_FR\" />\n<meta property=\"og:type\" content=\"article\" />\n<meta property=\"og:title\" content=\"🌱Os benefícios do CBD no golfe: melhore a sua concentração, reduza a ansiedade e a dor - Weedy.Fr🌱\" />\n<meta property=\"og:description\" content=\"O golfe é um esporte de precisão e concentração. Para se destacar nesta área, é necessário controlar as emoções e administrar o estresse. Hoje, cada vez mais golfistas recorrem ao CBD para os ajudar a encontrar o estado de espírito ideal no green. CBD, ou canabidiol, é um componente não psicoativo encontrado na cannabis que [&hellip;]\" />\n<meta property=\"og:url\" content=\"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor/\" />\n<meta property=\"og:site_name\" content=\"Actualités CBD Blog - Weedy.fr\" />\n<meta property=\"article:publisher\" content=\"https://www.facebook.com/weedysocial\" />\n<meta property=\"article:published_time\" content=\"2024-09-17T15:41:25+00:00\" />\n<meta property=\"article:modified_time\" content=\"2024-09-17T15:41:26+00:00\" />\n<meta property=\"og:image\" content=\"https://weedy.fr/blog/wp-content/uploads/2024/01/les-bienfaits-du-cbd-sur-le-golf-ameliorez-votre-concentration-reduisez-lanxiete-et-la-douleur.jpg\" />\n\t<meta property=\"og:image:width\" content=\"1456\" />\n\t<meta property=\"og:image:height\" content=\"832\" />\n\t<meta property=\"og:image:type\" content=\"image/jpeg\" />\n<meta name=\"author\" content=\"arthur\" />\n<meta name=\"twitter:card\" content=\"summary_large_image\" />\n<meta name=\"twitter:label1\" content=\"Écrit par\" />\n\t<meta name=\"twitter:data1\" content=\"arthur\" />\n\t<meta name=\"twitter:label2\" content=\"Durée de lecture estimée\" />\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" />\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\/\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor\\/#article\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor\\/\"},\"author\":{\"name\":\"arthur\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/0a05724dbfcfa68f2ce947d2ebf0f435\"},\"headline\":\"Os benefícios do CBD no golfe: melhore a sua concentração, reduza a ansiedade e a dor\",\"datePublished\":\"2024-09-17T15:41:25+00:00\",\"dateModified\":\"2024-09-17T15:41:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor\\/\"},\"wordCount\":738,\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/les-bienfaits-du-cbd-sur-le-golf-ameliorez-votre-concentration-reduisez-lanxiete-et-la-douleur.jpg\",\"articleSection\":[\"Notícias sobre CBD\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor\\/\",\"name\":\"Os benefícios do CBD no golfe: melhore a sua concentração, reduza a ansiedade e a dor - Actualités CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/les-bienfaits-du-cbd-sur-le-golf-ameliorez-votre-concentration-reduisez-lanxiete-et-la-douleur.jpg\",\"datePublished\":\"2024-09-17T15:41:25+00:00\",\"dateModified\":\"2024-09-17T15:41:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor\\/#primaryimage\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/les-bienfaits-du-cbd-sur-le-golf-ameliorez-votre-concentration-reduisez-lanxiete-et-la-douleur.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/les-bienfaits-du-cbd-sur-le-golf-ameliorez-votre-concentration-reduisez-lanxiete-et-la-douleur.jpg\",\"width\":1456,\"height\":832,\"caption\":\"Les bienfaits du CBD sur le golf : améliorez votre concentration, réduisez l'anxiété et la douleur\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notícias sobre CBD\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/category\\/noticias-sobre-cbd-pt\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Os benefícios do CBD no golfe: melhore a sua concentração, reduza a ansiedade e a dor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"name\":\"Actualités CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualité du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\/\\/weedy.fr\\/blog\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\"},\"sameAs\":[\"https:\\/\\/www.facebook.com\\/weedysocial\",\"https:\\/\\/www.instagram.com\\/weedyfrance\\/\"],\"description\":\"Leader en france sur la vente de produits à base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/0a05724dbfcfa68f2ce947d2ebf0f435\",\"name\":\"arthur\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"url\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"caption\":\"arthur\"},\"url\":\"https:\\/\\/weedy.fr\\/blog\\/author\\/arthur\\/\"}]}</script>\n<!-- / Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Os benefícios do CBD no golfe: melhore a sua concentração, reduza a ansiedade e a dor - Actualités CBD Blog - Weedy.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor/","og_locale":"fr_FR","og_type":"article","og_title":"🌱Os benefícios do CBD no golfe: melhore a sua concentração, reduza a ansiedade e a dor - Weedy.Fr🌱","og_description":"O golfe é um esporte de precisão e concentração. Para se destacar nesta área, é necessário controlar as emoções e administrar o estresse. Hoje, cada vez mais golfistas recorrem ao CBD para os ajudar a encontrar o estado de espírito ideal no green. CBD, ou canabidiol, é um componente não psicoativo encontrado na cannabis que [&hellip;]","og_url":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor/","og_site_name":"Actualités CBD Blog - Weedy.fr","article_publisher":"https://www.facebook.com/weedysocial","article_published_time":"2024-09-17T15:41:25+00:00","article_modified_time":"2024-09-17T15:41:26+00:00","og_image":[{"width":1456,"height":832,"url":"https://weedy.fr/es/blog/wp-content/uploads/2024/01/les-bienfaits-du-cbd-sur-le-golf-ameliorez-votre-concentration-reduisez-lanxiete-et-la-douleur.jpg","type":"image/jpeg"}],"author":"arthur","twitter_card":"summary_large_image","twitter_misc":{"Écrit par":"arthur","Durée de lecture estimée":"4 minutes"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"Article","@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor/#article","isPartOf":{"@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor/"},"author":{"name":"arthur","@id":"https://weedy.fr/blog/#/schema/person/0a05724dbfcfa68f2ce947d2ebf0f435"},"headline":"Os benefícios do CBD no golfe: melhore a sua concentração, reduza a ansiedade e a dor","datePublished":"2024-09-17T15:41:25+00:00","dateModified":"2024-09-17T15:41:26+00:00","mainEntityOfPage":{"@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor/"},"wordCount":738,"publisher":{"@id":"https://weedy.fr/blog/#organization"},"image":{"@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/les-bienfaits-du-cbd-sur-le-golf-ameliorez-votre-concentration-reduisez-lanxiete-et-la-douleur.jpg","articleSection":["Notícias sobre CBD"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor/","url":"https://weedy.fr/es/blog/pt/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor/","name":"Os benefícios do CBD no golfe: melhore a sua concentração, reduza a ansiedade e a dor - Actualités CBD Blog - Weedy.fr","isPartOf":{"@id":"https://weedy.fr/blog/#website"},"primaryImageOfPage":{"@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor/#primaryimage"},"image":{"@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/les-bienfaits-du-cbd-sur-le-golf-ameliorez-votre-concentration-reduisez-lanxiete-et-la-douleur.jpg","datePublished":"2024-09-17T15:41:25+00:00","dateModified":"2024-09-17T15:41:26+00:00","breadcrumb":{"@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor/#primaryimage","url":"https://weedy.fr/es/blog/wp-content/uploads/2024/01/les-bienfaits-du-cbd-sur-le-golf-ameliorez-votre-concentration-reduisez-lanxiete-et-la-douleur.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/les-bienfaits-du-cbd-sur-le-golf-ameliorez-votre-concentration-reduisez-lanxiete-et-la-douleur.jpg","width":1456,"height":832,"caption":"Les bienfaits du CBD sur le golf : améliorez votre concentration, réduisez l'anxiété et la douleur"},{"@type":"BreadcrumbList","@id":"https://weedy.fr/blog/pt/os-beneficios-do-cbd-no-golfe-melhore-a-sua-concentracao-reduza-a-ansiedade-e-a-dor/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https://weedy.fr/blog/"},{"@type":"ListItem","position":2,"name":"Notícias sobre CBD","item":"https://weedy.fr/blog/category/noticias-sobre-cbd-pt/"},{"@type":"ListItem","position":3,"name":"Os benefícios do CBD no golfe: melhore a sua concentração, reduza a ansiedade e a dor"}]},{"@type":"WebSite","@id":"https://weedy.fr/blog/#website","url":"https://weedy.fr/es/blog/","name":"Actualités CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualité du CBD et du chanvre en France","publisher":{"@id":"https://weedy.fr/blog/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://weedy.fr/blog/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https://weedy.fr/blog/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https://weedy.fr/es/blog/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/#/schema/logo/image/","url":"https://weedy.fr/es/blog/wp-content/uploads/2024/05/logo-carre.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https://weedy.fr/blog/#/schema/logo/image/"},"sameAs":["https://www.facebook.com/weedysocial","https://www.instagram.com/weedyfrance/"],"description":"Leader en france sur la vente de produits à base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https://weedy.fr/blog/#/schema/person/0a05724dbfcfa68f2ce947d2ebf0f435","name":"arthur","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://secure.gravatar.com/avatar/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","url":"https://secure.gravatar.com/avatar/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","caption":"arthur"},"url":"https://weedy.fr/es/blog/author/arthur/"}]}},"_links":{"self":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts"}],"about":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/users/97"}],"replies":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/comments?post=359456"}],"version-history":[{"count":1,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359456/revisions"}],"predecessor-version":[{"id":359457,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359456/revisions/359457"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/media/351980"}],"wp:attachment":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/media?parent=359456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/categories?post=359456"},{"taxonomy":"post_tag","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/tags?post=359456"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}