{"id":359504,"date":"2024-09-17T17:42:13","date_gmt":"2024-09-17T15:42:13","guid":{"rendered":"https://weedy.fr/blog/?p=359504"},"modified":"2024-09-17T17:42:14","modified_gmt":"2024-09-17T15:42:14","slug":"icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr","status":"publish","type":"post","link":"https://weedy.fr/blog/pt/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr/","title":{"rendered":"ICBC retorna a Barcelona em março de 2024, Weedy.fr"},"content":{"rendered":"<p>O prestigiado <strong>Conferência Internacional de Negócios sobre Cannabis (ICBC)</strong> fará o seu grande regresso à capital catalã em março de 2024. Este evento imperdível da indústria da canábis volta a unir forças com a Spannabis, a maior exposição europeia sobre o tema, para oferecer aos visitantes e profissionais uma experiência única.</p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire</p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle</span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http://www.w3.org/2000/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"></path></svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http://www.w3.org/2000/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"></path></svg></span></span></span></a></span></div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 \"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https://weedy.fr/es/blog/pt/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr/#Um_grande_evento_para_players_do_setor\">Um grande evento para players do setor</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https://weedy.fr/es/blog/pt/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr/#Um_programa_rico_e_diversificado\">Um programa rico e diversificado</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https://weedy.fr/es/blog/pt/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr/#A_parceria_com_a_Spannabis_uma_sinergia_de_sucesso\">A parceria com a Spannabis: uma sinergia de sucesso</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https://weedy.fr/es/blog/pt/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr/#Por_que_ir_para_ICBC_e_Spannabis\">Por que ir para ICBC e Spannabis?</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https://weedy.fr/es/blog/pt/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr/#Um_evento_imperdivel_para_os_jogadores_franceses_de_cannabis\">Um evento imperdível para os jogadores franceses de cannabis</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https://weedy.fr/es/blog/pt/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr/#Como_beneficiar_de_taxas_preferenciais\">Como beneficiar de taxas preferenciais?</a></li></ul></li></ul></nav></div>\n<h2><span class=\"ez-toc-section\" id=\"Um_grande_evento_para_players_do_setor\"></span>Um grande evento para players do setor<span class=\"ez-toc-section-end\"></span></h2>\n<p>O ICBC é considerado um evento líder no mundo da cannabis, reunindo centenas de players internacionais todos os anos. Este evento oferece um cenário ideal para interações de negócios e networking. Na verdade, a conferência não só permite descobrir as últimas inovações e tendências em cannabis, mas também estabelecer parcerias estratégicas ou encontrar novos clientes.</p>\n<h3><span class=\"ez-toc-section\" id=\"Um_programa_rico_e_diversificado\"></span>Um programa rico e diversificado<span class=\"ez-toc-section-end\"></span></h3>\n<p>Para esta nova edição, a programação do ICBC promete ser mais uma vez rica e variada. No cardápio, <strong>conferências, debates e workshops</strong> liderado por especialistas do setor que abordarão temas como:</p>\n<ul>\n<li>Avanços legislativos e regulamentares na Europa e em todo o mundo</li>\n<li>Perspectivas de crescimento do mercado e oportunidades de negócios</li>\n<li>Inovações tecnológicas e seu impacto na indústria</li>\n<li>Medicina da cannabis e suas aplicações terapêuticas</li>\n<li>Os desafios da produção sustentável e ética.</li>\n</ul>\n<p>Este programa permitirá aos participantes expandir o seu conhecimento do mercado de cannabis e manter-se atualizados sobre as últimas tendências e oportunidades.</p>\n<h2><span class=\"ez-toc-section\" id=\"A_parceria_com_a_Spannabis_uma_sinergia_de_sucesso\"></span>A parceria com a Spannabis: uma sinergia de sucesso<span class=\"ez-toc-section-end\"></span></h2>\n<p>Um dos grandes trunfos do ICBC Barcelona reside na parceria com o <strong>Spanabis</strong>, que é a principal feira europeia dedicada à cannabis. Esta colaboração oferece aos visitantes uma experiência única, combinando o rigor das conferências e debates oferecidos pelo ICBC com a emoção do espetáculo Spannabis. Os participantes terão a oportunidade de descobrir os principais expositores e produtos do mercado, enriquecendo ao mesmo tempo a sua rede profissional.</p>\n<h3><span class=\"ez-toc-section\" id=\"Por_que_ir_para_ICBC_e_Spannabis\"></span>Por que ir para ICBC e Spannabis?<span class=\"ez-toc-section-end\"></span></h3>\n<p>Se você atua na indústria da cannabis, a combinação ICBC &#8211; Spannabis representa uma oportunidade de ouro para:</p>\n<ul>\n<li>Fortaleça a sua presença no mercado internacional</li>\n<li>Conecte-se com profissionais de todo o mundo</li>\n<li>Divulgue seus produtos ou serviços a um público-alvo</li>\n<li>Desenvolva suas habilidades e conhecimentos sobre cannabis</li>\n<li>Identifique novas oportunidades de negócios</li>\n</ul>\n<p>Tudo isto num ambiente amigável e descontraído, propício ao intercâmbio e à criação de vínculos duradouros.</p>\n<h2><span class=\"ez-toc-section\" id=\"Um_evento_imperdivel_para_os_jogadores_franceses_de_cannabis\"></span>Um evento imperdível para os jogadores franceses de cannabis<span class=\"ez-toc-section-end\"></span></h2>\n<p>A presença francesa é esperada em força nesta nova edição. Os profissionais franceses terão a oportunidade de se inspirar nas melhores práticas europeias e internacionais em cannabis, ao mesmo tempo que constroem uma rede sólida dentro da comunidade do cânhamo. Em suma, o<strong>ICBC Barcelona 2024</strong> e os Spannabis combinados representam uma experiência única e imperdível para todos os entusiastas e profissionais do setor.</p>\n<h3><span class=\"ez-toc-section\" id=\"Como_beneficiar_de_taxas_preferenciais\"></span>Como beneficiar de taxas preferenciais?<span class=\"ez-toc-section-end\"></span></h3>\n<p>Para permitir que o maior número possível de pessoas beneficie deste evento excecional, os organizadores estão a oferecer tarifas para madrugadores até 21 de fevereiro. Você pode se beneficiar de uma redução de 25% usando o código promocional <strong>NewsweedTake25</strong> ou seguindo o link fornecido em seu site. Não perca a oportunidade de participar neste grande encontro da indústria da cannabis na Europa e em todo o mundo.</p>\n<p>Então, quem estará presente em Barcelona em março de 2024 para participar do ICBC e do Spannabis? Por favor, compartilhe seus comentários e entusiasmo conosco!</p>\n","protected":false},"excerpt":{"rendered":"<p>O prestigiado Conferência Internacional de Negócios sobre Cannabis (ICBC) fará o seu grande regresso à capital catalã em março de 2024. Este evento imperdível da indústria da canábis volta a unir forças com a Spannabis, a maior exposição europeia sobre o tema, para oferecer aos visitantes e profissionais uma experiência única. Um grande evento para [&hellip;]</p>\n","protected":false},"author":97,"featured_media":352045,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[675],"tags":[],"class_list":["post-359504","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-sobre-cbd-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https://yoast.com/product/yoast-seo-premium-wordpress/ -->\n<title>ICBC retorna a Barcelona em março de 2024, Weedy.fr - Actualités CBD Blog - Weedy.fr</title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" />\n<link rel=\"canonical\" href=\"https://weedy.fr/blog/pt/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr/\" />\n<meta property=\"og:locale\" content=\"fr_FR\" />\n<meta property=\"og:type\" content=\"article\" />\n<meta property=\"og:title\" content=\"🌱ICBC retorna a Barcelona em março de 2024, Weedy.fr - Weedy.Fr🌱\" />\n<meta property=\"og:description\" content=\"O prestigiado Conferência Internacional de Negócios sobre Cannabis (ICBC) fará o seu grande regresso à capital catalã em março de 2024. Este evento imperdível da indústria da canábis volta a unir forças com a Spannabis, a maior exposição europeia sobre o tema, para oferecer aos visitantes e profissionais uma experiência única. Um grande evento para [&hellip;]\" />\n<meta property=\"og:url\" content=\"https://weedy.fr/blog/pt/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr/\" />\n<meta property=\"og:site_name\" content=\"Actualités CBD Blog - Weedy.fr\" />\n<meta property=\"article:publisher\" content=\"https://www.facebook.com/weedysocial\" />\n<meta property=\"article:published_time\" content=\"2024-09-17T15:42:13+00:00\" />\n<meta property=\"article:modified_time\" content=\"2024-09-17T15:42:14+00:00\" />\n<meta property=\"og:image\" content=\"https://weedy.fr/blog/wp-content/uploads/2024/01/licbc-revient-a-barcelone-en-mars-2024-weedy.fr_.jpg\" />\n\t<meta property=\"og:image:width\" content=\"1456\" />\n\t<meta property=\"og:image:height\" content=\"832\" />\n\t<meta property=\"og:image:type\" content=\"image/jpeg\" />\n<meta name=\"author\" content=\"arthur\" />\n<meta name=\"twitter:card\" content=\"summary_large_image\" />\n<meta name=\"twitter:label1\" content=\"Écrit par\" />\n\t<meta name=\"twitter:data1\" content=\"arthur\" />\n\t<meta name=\"twitter:label2\" content=\"Durée de lecture estimée\" />\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" />\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\/\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr\\/#article\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr\\/\"},\"author\":{\"name\":\"arthur\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/0a05724dbfcfa68f2ce947d2ebf0f435\"},\"headline\":\"ICBC retorna a Barcelona em março de 2024, Weedy.fr\",\"datePublished\":\"2024-09-17T15:42:13+00:00\",\"dateModified\":\"2024-09-17T15:42:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr\\/\"},\"wordCount\":605,\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/licbc-revient-a-barcelone-en-mars-2024-weedy.fr_.jpg\",\"articleSection\":[\"Notícias sobre CBD\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr\\/\",\"name\":\"ICBC retorna a Barcelona em março de 2024, Weedy.fr - Actualités CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/licbc-revient-a-barcelone-en-mars-2024-weedy.fr_.jpg\",\"datePublished\":\"2024-09-17T15:42:13+00:00\",\"dateModified\":\"2024-09-17T15:42:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\/\\/weedy.fr\\/blog\\/pt\\/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr\\/#primaryimage\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/licbc-revient-a-barcelone-en-mars-2024-weedy.fr_.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/licbc-revient-a-barcelone-en-mars-2024-weedy.fr_.jpg\",\"width\":1456,\"height\":832,\"caption\":\"L'ICBC revient à Barcelone en mars 2024, Weedy.fr\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notícias sobre CBD\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/category\\/noticias-sobre-cbd-pt\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ICBC retorna a Barcelona em março de 2024, Weedy.fr\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"name\":\"Actualités CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualité du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\/\\/weedy.fr\\/blog\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\"},\"sameAs\":[\"https:\\/\\/www.facebook.com\\/weedysocial\",\"https:\\/\\/www.instagram.com\\/weedyfrance\\/\"],\"description\":\"Leader en france sur la vente de produits à base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/0a05724dbfcfa68f2ce947d2ebf0f435\",\"name\":\"arthur\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"url\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"caption\":\"arthur\"},\"url\":\"https:\\/\\/weedy.fr\\/blog\\/author\\/arthur\\/\"}]}</script>\n<!-- / Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ICBC retorna a Barcelona em março de 2024, Weedy.fr - Actualités CBD Blog - Weedy.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://weedy.fr/blog/pt/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr/","og_locale":"fr_FR","og_type":"article","og_title":"🌱ICBC retorna a Barcelona em março de 2024, Weedy.fr - Weedy.Fr🌱","og_description":"O prestigiado Conferência Internacional de Negócios sobre Cannabis (ICBC) fará o seu grande regresso à capital catalã em março de 2024. Este evento imperdível da indústria da canábis volta a unir forças com a Spannabis, a maior exposição europeia sobre o tema, para oferecer aos visitantes e profissionais uma experiência única. Um grande evento para [&hellip;]","og_url":"https://weedy.fr/blog/pt/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr/","og_site_name":"Actualités CBD Blog - Weedy.fr","article_publisher":"https://www.facebook.com/weedysocial","article_published_time":"2024-09-17T15:42:13+00:00","article_modified_time":"2024-09-17T15:42:14+00:00","og_image":[{"width":1456,"height":832,"url":"https://weedy.fr/es/blog/wp-content/uploads/2024/01/licbc-revient-a-barcelone-en-mars-2024-weedy.fr_.jpg","type":"image/jpeg"}],"author":"arthur","twitter_card":"summary_large_image","twitter_misc":{"Écrit par":"arthur","Durée de lecture estimée":"3 minutes"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"Article","@id":"https://weedy.fr/blog/pt/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr/#article","isPartOf":{"@id":"https://weedy.fr/blog/pt/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr/"},"author":{"name":"arthur","@id":"https://weedy.fr/blog/#/schema/person/0a05724dbfcfa68f2ce947d2ebf0f435"},"headline":"ICBC retorna a Barcelona em março de 2024, Weedy.fr","datePublished":"2024-09-17T15:42:13+00:00","dateModified":"2024-09-17T15:42:14+00:00","mainEntityOfPage":{"@id":"https://weedy.fr/blog/pt/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr/"},"wordCount":605,"publisher":{"@id":"https://weedy.fr/blog/#organization"},"image":{"@id":"https://weedy.fr/blog/pt/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/licbc-revient-a-barcelone-en-mars-2024-weedy.fr_.jpg","articleSection":["Notícias sobre CBD"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https://weedy.fr/blog/pt/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr/","url":"https://weedy.fr/es/blog/pt/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr/","name":"ICBC retorna a Barcelona em março de 2024, Weedy.fr - Actualités CBD Blog - Weedy.fr","isPartOf":{"@id":"https://weedy.fr/blog/#website"},"primaryImageOfPage":{"@id":"https://weedy.fr/blog/pt/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr/#primaryimage"},"image":{"@id":"https://weedy.fr/blog/pt/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/licbc-revient-a-barcelone-en-mars-2024-weedy.fr_.jpg","datePublished":"2024-09-17T15:42:13+00:00","dateModified":"2024-09-17T15:42:14+00:00","breadcrumb":{"@id":"https://weedy.fr/blog/pt/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https://weedy.fr/blog/pt/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/pt/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr/#primaryimage","url":"https://weedy.fr/es/blog/wp-content/uploads/2024/01/licbc-revient-a-barcelone-en-mars-2024-weedy.fr_.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/licbc-revient-a-barcelone-en-mars-2024-weedy.fr_.jpg","width":1456,"height":832,"caption":"L'ICBC revient à Barcelone en mars 2024, Weedy.fr"},{"@type":"BreadcrumbList","@id":"https://weedy.fr/blog/pt/icbc-retorna-a-barcelona-em-marco-de-2024-weedy-fr/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https://weedy.fr/blog/"},{"@type":"ListItem","position":2,"name":"Notícias sobre CBD","item":"https://weedy.fr/blog/category/noticias-sobre-cbd-pt/"},{"@type":"ListItem","position":3,"name":"ICBC retorna a Barcelona em março de 2024, Weedy.fr"}]},{"@type":"WebSite","@id":"https://weedy.fr/blog/#website","url":"https://weedy.fr/es/blog/","name":"Actualités CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualité du CBD et du chanvre en France","publisher":{"@id":"https://weedy.fr/blog/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://weedy.fr/blog/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https://weedy.fr/blog/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https://weedy.fr/es/blog/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/#/schema/logo/image/","url":"https://weedy.fr/es/blog/wp-content/uploads/2024/05/logo-carre.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https://weedy.fr/blog/#/schema/logo/image/"},"sameAs":["https://www.facebook.com/weedysocial","https://www.instagram.com/weedyfrance/"],"description":"Leader en france sur la vente de produits à base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https://weedy.fr/blog/#/schema/person/0a05724dbfcfa68f2ce947d2ebf0f435","name":"arthur","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://secure.gravatar.com/avatar/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","url":"https://secure.gravatar.com/avatar/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","caption":"arthur"},"url":"https://weedy.fr/es/blog/author/arthur/"}]}},"_links":{"self":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts"}],"about":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/users/97"}],"replies":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/comments?post=359504"}],"version-history":[{"count":1,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359504/revisions"}],"predecessor-version":[{"id":359505,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359504/revisions/359505"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/media/352045"}],"wp:attachment":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/media?parent=359504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/categories?post=359504"},{"taxonomy":"post_tag","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/tags?post=359504"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}