{"id":359632,"date":"2024-09-17T17:44:33","date_gmt":"2024-09-17T15:44:33","guid":{"rendered":"https://weedy.fr/blog/?p=359632"},"modified":"2024-09-17T17:44:33","modified_gmt":"2024-09-17T15:44:33","slug":"interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber","status":"publish","type":"post","link":"https://weedy.fr/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/","title":{"rendered":"Interações medicamentosas com CBD: tudo o que você precisa saber"},"content":{"rendered":"<p>O canabidiol, mais conhecido como <a href=\"https://weedy.fr/es\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a>, é um componente da canábis que está a crescer em popularidade devido aos seus muitos benefícios para a saúde. À medida que o burburinho em torno do <a href=\"https://weedy.fr/es\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> continua a crescer, é essencial estudar as suas possíveis interações com vários medicamentos. Neste artigo discutiremos as principais interações medicamentosas relacionadas ao <a href=\"https://weedy.fr/es\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> e daremos dicas para minimizar esses efeitos.</p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire</p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle</span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http://www.w3.org/2000/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"></path></svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http://www.w3.org/2000/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"></path></svg></span></span></span></a></span></div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 \"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https://weedy.fr/es/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/#Porque_e_que_o_CBD_pode_interagir_com_medicamentos\">Porque é que o CBD pode interagir com medicamentos?</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https://weedy.fr/es/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/#Categorias_de_medicamentos_que_podem_ser_afetados_pelo_CBD\">Categorias de medicamentos que podem ser afetados pelo CBD</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https://weedy.fr/es/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/#1_Analgesicos\">1. Analgésicos</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https://weedy.fr/es/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/#2_Medicamentos_cardiovasculares\">2. Medicamentos cardiovasculares</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https://weedy.fr/es/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/#3_Ansioliticos_e_antidepressivos\">3. Ansiolíticos e antidepressivos</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https://weedy.fr/es/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/#4_Medicamentos_anticonvulsivantes\">4. Medicamentos anticonvulsivantes</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https://weedy.fr/es/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/#5_Antibioticos\">5. Antibióticos</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https://weedy.fr/es/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/#Como_minimizar_as_interacoes_entre_o_CBD_e_os_medicamentos\">Como minimizar as interações entre o CBD e os medicamentos?</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https://weedy.fr/es/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/#Resumindo\">Resumindo</a></li></ul></nav></div>\n<h2><span class=\"ez-toc-section\" id=\"Porque_e_que_o_CBD_pode_interagir_com_medicamentos\"></span>Porque é que o CBD pode interagir com medicamentos?<span class=\"ez-toc-section-end\"></span></h2>\n<p>O CBD tem a capacidade de interagir com muitos medicamentos porque é metabolizado por certas enzimas encontradas no fígado. De fato, <strong>o sistema enzimático do citocromo P450 (CYP450) é responsável pela degradação de muitas moléculas, incluindo CBD e certos medicamentos</strong>.</p>\n<p>Quando o CBD é consumido, pode inibir parcial ou completamente a atividade de certas enzimas CYP450, o que pode levar a uma redução no metabolismo dos medicamentos afetados. Como resultado, isto pode alterar a sua concentração no sangue e causar efeitos indesejados.</p>\n<h2><span class=\"ez-toc-section\" id=\"Categorias_de_medicamentos_que_podem_ser_afetados_pelo_CBD\"></span>Categorias de medicamentos que podem ser afetados pelo CBD<span class=\"ez-toc-section-end\"></span></h2>\n<p>Existem várias categorias de medicamentos que são metabolizados pelo CYP450 e, portanto, potencialmente afetados pelo CBD. Abaixo abordaremos alguns dos exemplos mais comuns:</p>\n<h3><span class=\"ez-toc-section\" id=\"1_Analgesicos\"></span>1. Analgésicos<span class=\"ez-toc-section-end\"></span></h3>\n<p>A morfina e a codeína são dois exemplos de opioides que podem ter o seu metabolismo afetado pelo CBD. Isto pode levar a um aumento dos seus efeitos ou a uma amplificação dos efeitos secundários.</p>\n<h3><span class=\"ez-toc-section\" id=\"2_Medicamentos_cardiovasculares\"></span>2. Medicamentos cardiovasculares<span class=\"ez-toc-section-end\"></span></h3>\n<p>Os bloqueadores beta, como o atenolol ou o propranolol, bem como os anticoagulantes como a varfarina, também são afetados por esta interação com o CBD. Uma concentração muito alta desses medicamentos no sangue pode causar complicações cardíacas.</p>\n<h3><span class=\"ez-toc-section\" id=\"3_Ansioliticos_e_antidepressivos\"></span>3. Ansiolíticos e antidepressivos<span class=\"ez-toc-section-end\"></span></h3>\n<p>Medicamentos como diazepam, alprazolam ou inibidores seletivos da recaptação de serotonina (ISRS), como fluoxetina ou sertralina, também podem ser afetados pelo CBD.</p>\n<h3><span class=\"ez-toc-section\" id=\"4_Medicamentos_anticonvulsivantes\"></span>4. Medicamentos anticonvulsivantes<span class=\"ez-toc-section-end\"></span></h3>\n<p>O CBD é frequentemente utilizado como complemento aos tratamentos para a epilepsia, particularmente pelos seus efeitos anti-inflamatórios e anticonvulsivantes. No entanto, também pode interagir com medicamentos como carbamazepina, fenitoína ou valproato.</p>\n<h3><span class=\"ez-toc-section\" id=\"5_Antibioticos\"></span>5. Antibióticos<span class=\"ez-toc-section-end\"></span></h3>\n<p>Alguns antibióticos, como a claritromicina ou a eritromicina, também são metabolizados pelo CYP450 e podem, portanto, ser afetados pelo consumo de CBD.</p>\n<h2><span class=\"ez-toc-section\" id=\"Como_minimizar_as_interacoes_entre_o_CBD_e_os_medicamentos\"></span>Como minimizar as interações entre o CBD e os medicamentos?<span class=\"ez-toc-section-end\"></span></h2>\n<p>É importante ter em conta estas possíveis interacções ao utilizar o CBD em adição ao tratamento medicamentoso. Aqui estão algumas dicas para reduzir os riscos:</p>\n<ol>\n<li><strong>Consulte um profissional de saúde:</strong> Antes de iniciar a suplementação com CBD, é sempre recomendável consultar o seu médico ou farmacêutico para discutir possíveis interações com os seus tratamentos atuais.</li>\n<li><strong>Comece com doses baixas:</strong> Para reduzir o risco de interação, pode ser aconselhável começar com pequenas doses de CBD e aumentar gradualmente de acordo com os efeitos experimentados e as recomendações do seu médico.</li>\n<li><strong>Evite tomar medicamentos e CBD:</strong> Tomar CBD e medicamentos em horários diferentes do dia pode ajudar a reduzir as chances de interação dessas substâncias.</li>\n<li><strong>Acompanhe regularmente:</strong> Ao tomar CBD além de seus medicamentos regulares, certifique-se de acompanhar regularmente seu médico para detectar quaisquer alterações na concentração de medicamentos no sangue e ajustar as doses, se necessário.</li>\n</ol>\n<h2><span class=\"ez-toc-section\" id=\"Resumindo\"></span>Resumindo<span class=\"ez-toc-section-end\"></span></h2>\n<p>O CBD é uma molécula com muitos benefícios, mas também pode interagir com certos medicamentos devido ao seu metabolismo pelo sistema enzimático do citocromo P450. As principais categorias de medicamentos em causa incluem analgésicos, medicamentos cardiovasculares, ansiolíticos e antidepressivos, anticonvulsivantes e antibióticos.</p>\n<p>Para minimizar o risco de interação, é essencial consultar um profissional de saúde antes de iniciar a suplementação com CBD, começar com doses baixas, espaçar a ingestão de medicamentos e fazer um acompanhamento regular.</p>\n","protected":false},"excerpt":{"rendered":"<p>O canabidiol, mais conhecido como CBD, é um componente da canábis que está a crescer em popularidade devido aos seus muitos benefícios para a saúde. À medida que o burburinho em torno do CBD continua a crescer, é essencial estudar as suas possíveis interações com vários medicamentos. Neste artigo discutiremos as principais interações medicamentosas relacionadas [&hellip;]</p>\n","protected":false},"author":41,"featured_media":352112,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[672],"tags":[],"class_list":["post-359632","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude-e-bem-estar-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https://yoast.com/product/yoast-seo-premium-wordpress/ -->\n<title>Interações medicamentosas com CBD: tudo o que você precisa saber - Actualités CBD Blog - Weedy.fr</title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" />\n<link rel=\"canonical\" href=\"https://weedy.fr/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/\" />\n<meta property=\"og:locale\" content=\"fr_FR\" />\n<meta property=\"og:type\" content=\"article\" />\n<meta property=\"og:title\" content=\"🌱Interações medicamentosas com CBD: tudo o que você precisa saber - Weedy.Fr🌱\" />\n<meta property=\"og:description\" content=\"O canabidiol, mais conhecido como CBD, é um componente da canábis que está a crescer em popularidade devido aos seus muitos benefícios para a saúde. À medida que o burburinho em torno do CBD continua a crescer, é essencial estudar as suas possíveis interações com vários medicamentos. Neste artigo discutiremos as principais interações medicamentosas relacionadas [&hellip;]\" />\n<meta property=\"og:url\" content=\"https://weedy.fr/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/\" />\n<meta property=\"og:site_name\" content=\"Actualités CBD Blog - Weedy.fr\" />\n<meta property=\"article:publisher\" content=\"https://www.facebook.com/weedysocial\" />\n<meta property=\"article:author\" content=\"https://www.facebook.com/weedysocial/\" />\n<meta property=\"article:published_time\" content=\"2024-09-17T15:44:33+00:00\" />\n<meta property=\"og:image\" content=\"https://weedy.fr/blog/wp-content/uploads/2024/01/interactions-entre-le-cbd-et-les-medicaments-tout-ce-que-vous-devez-savoir.jpg\" />\n\t<meta property=\"og:image:width\" content=\"1456\" />\n\t<meta property=\"og:image:height\" content=\"832\" />\n\t<meta property=\"og:image:type\" content=\"image/jpeg\" />\n<meta name=\"author\" content=\"Julien Cordobes\" />\n<meta name=\"twitter:card\" content=\"summary_large_image\" />\n<meta name=\"twitter:label1\" content=\"Écrit par\" />\n\t<meta name=\"twitter:data1\" content=\"Julien Cordobes\" />\n\t<meta name=\"twitter:label2\" content=\"Durée de lecture estimée\" />\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" />\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\/\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber\\/#article\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber\\/\"},\"author\":{\"name\":\"Julien Cordobes\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/72583fcd87d7cf46afe11d530945bc7e\"},\"headline\":\"Interações medicamentosas com CBD: tudo o que você precisa saber\",\"datePublished\":\"2024-09-17T15:44:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber\\/\"},\"wordCount\":649,\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/interactions-entre-le-cbd-et-les-medicaments-tout-ce-que-vous-devez-savoir.jpg\",\"articleSection\":[\"Saúde e Bem-estar\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber\\/\",\"name\":\"Interações medicamentosas com CBD: tudo o que você precisa saber - Actualités CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/interactions-entre-le-cbd-et-les-medicaments-tout-ce-que-vous-devez-savoir.jpg\",\"datePublished\":\"2024-09-17T15:44:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber\\/#primaryimage\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/interactions-entre-le-cbd-et-les-medicaments-tout-ce-que-vous-devez-savoir.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/interactions-entre-le-cbd-et-les-medicaments-tout-ce-que-vous-devez-savoir.jpg\",\"width\":1456,\"height\":832,\"caption\":\"Interactions entre le CBD et les médicaments : tout ce que vous devez savoir, cannabis, réaction, médicament\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Saúde e Bem-estar\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/category\\/saude-e-bem-estar-pt\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Interações medicamentosas com CBD: tudo o que você precisa saber\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"name\":\"Actualités CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualité du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\/\\/weedy.fr\\/blog\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\"},\"sameAs\":[\"https:\\/\\/www.facebook.com\\/weedysocial\",\"https:\\/\\/www.instagram.com\\/weedyfrance\\/\"],\"description\":\"Leader en france sur la vente de produits à base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/72583fcd87d7cf46afe11d530945bc7e\",\"name\":\"Julien Cordobes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"url\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"caption\":\"Julien Cordobes\"},\"description\":\"Rédacteur en chef spécialisé en CBD Julien, né le 17 juillet 1978 en région Parisienne, est un éminent rédacteur et expert dans le domaine des produits à base de CBD. Suite à ses études en biologie et en médecine alternative, Julien a développé une passion pour les remèdes naturels, dont le CBD. En 2022, il intègre l’équipe du site Weedy.fr en qualité d’expert et de contributeur régulier. Grâce à son expertise scientifique et une écriture claire, Julien aide à démystifier les aspects complexes du CBD, tout en mettant en lumière ses bienfaits et applications potentielles à travers ses articles et participations à des conférences.\",\"sameAs\":[\"https:\\/\\/weedy.fr\",\"https:\\/\\/www.facebook.com\\/weedysocial\\/\",\"https:\\/\\/www.instagram.com\\/weedyfrance\",\"https:\\/\\/www.pinterest.fr\\/WeedyFrance\\/\"],\"honorificPrefix\":\"Mr\",\"birthDate\":\"1978-07-17\",\"gender\":\"male\",\"knowsAbout\":[\"CBD\",\"Cannabis\",\"Copywriter\"],\"knowsLanguage\":[\"French\"],\"jobTitle\":\"Editor-in-chief specializing in CBD\",\"worksFor\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/author\\/cbd_blog_owner\\/\"}]}</script>\n<!-- / Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Interações medicamentosas com CBD: tudo o que você precisa saber - Actualités CBD Blog - Weedy.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://weedy.fr/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/","og_locale":"fr_FR","og_type":"article","og_title":"🌱Interações medicamentosas com CBD: tudo o que você precisa saber - Weedy.Fr🌱","og_description":"O canabidiol, mais conhecido como CBD, é um componente da canábis que está a crescer em popularidade devido aos seus muitos benefícios para a saúde. À medida que o burburinho em torno do CBD continua a crescer, é essencial estudar as suas possíveis interações com vários medicamentos. Neste artigo discutiremos as principais interações medicamentosas relacionadas [&hellip;]","og_url":"https://weedy.fr/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/","og_site_name":"Actualités CBD Blog - Weedy.fr","article_publisher":"https://www.facebook.com/weedysocial","article_author":"https://www.facebook.com/weedysocial/","article_published_time":"2024-09-17T15:44:33+00:00","og_image":[{"width":1456,"height":832,"url":"https://weedy.fr/es/blog/wp-content/uploads/2024/01/interactions-entre-le-cbd-et-les-medicaments-tout-ce-que-vous-devez-savoir.jpg","type":"image/jpeg"}],"author":"Julien Cordobes","twitter_card":"summary_large_image","twitter_misc":{"Écrit par":"Julien Cordobes","Durée de lecture estimée":"3 minutes"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"Article","@id":"https://weedy.fr/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/#article","isPartOf":{"@id":"https://weedy.fr/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/"},"author":{"name":"Julien Cordobes","@id":"https://weedy.fr/blog/#/schema/person/72583fcd87d7cf46afe11d530945bc7e"},"headline":"Interações medicamentosas com CBD: tudo o que você precisa saber","datePublished":"2024-09-17T15:44:33+00:00","mainEntityOfPage":{"@id":"https://weedy.fr/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/"},"wordCount":649,"publisher":{"@id":"https://weedy.fr/blog/#organization"},"image":{"@id":"https://weedy.fr/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/interactions-entre-le-cbd-et-les-medicaments-tout-ce-que-vous-devez-savoir.jpg","articleSection":["Saúde e Bem-estar"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https://weedy.fr/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/","url":"https://weedy.fr/es/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/","name":"Interações medicamentosas com CBD: tudo o que você precisa saber - Actualités CBD Blog - Weedy.fr","isPartOf":{"@id":"https://weedy.fr/blog/#website"},"primaryImageOfPage":{"@id":"https://weedy.fr/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/#primaryimage"},"image":{"@id":"https://weedy.fr/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/interactions-entre-le-cbd-et-les-medicaments-tout-ce-que-vous-devez-savoir.jpg","datePublished":"2024-09-17T15:44:33+00:00","breadcrumb":{"@id":"https://weedy.fr/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https://weedy.fr/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/#primaryimage","url":"https://weedy.fr/es/blog/wp-content/uploads/2024/01/interactions-entre-le-cbd-et-les-medicaments-tout-ce-que-vous-devez-savoir.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/interactions-entre-le-cbd-et-les-medicaments-tout-ce-que-vous-devez-savoir.jpg","width":1456,"height":832,"caption":"Interactions entre le CBD et les médicaments : tout ce que vous devez savoir, cannabis, réaction, médicament"},{"@type":"BreadcrumbList","@id":"https://weedy.fr/blog/pt/interacoes-medicamentosas-com-cbd-tudo-o-que-voce-precisa-saber/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https://weedy.fr/blog/"},{"@type":"ListItem","position":2,"name":"Saúde e Bem-estar","item":"https://weedy.fr/blog/category/saude-e-bem-estar-pt/"},{"@type":"ListItem","position":3,"name":"Interações medicamentosas com CBD: tudo o que você precisa saber"}]},{"@type":"WebSite","@id":"https://weedy.fr/blog/#website","url":"https://weedy.fr/es/blog/","name":"Actualités CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualité du CBD et du chanvre en France","publisher":{"@id":"https://weedy.fr/blog/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://weedy.fr/blog/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https://weedy.fr/blog/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https://weedy.fr/es/blog/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/#/schema/logo/image/","url":"https://weedy.fr/es/blog/wp-content/uploads/2024/05/logo-carre.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https://weedy.fr/blog/#/schema/logo/image/"},"sameAs":["https://www.facebook.com/weedysocial","https://www.instagram.com/weedyfrance/"],"description":"Leader en france sur la vente de produits à base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https://weedy.fr/blog/#/schema/person/72583fcd87d7cf46afe11d530945bc7e","name":"Julien Cordobes","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","url":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","caption":"Julien Cordobes"},"description":"Rédacteur en chef spécialisé en CBD Julien, né le 17 juillet 1978 en région Parisienne, est un éminent rédacteur et expert dans le domaine des produits à base de CBD. Suite à ses études en biologie et en médecine alternative, Julien a développé une passion pour les remèdes naturels, dont le CBD. En 2022, il intègre l’équipe du site Weedy.fr en qualité d’expert et de contributeur régulier. Grâce à son expertise scientifique et une écriture claire, Julien aide à démystifier les aspects complexes du CBD, tout en mettant en lumière ses bienfaits et applications potentielles à travers ses articles et participations à des conférences.","sameAs":["https://weedy.fr","https://www.facebook.com/weedysocial/","https://www.instagram.com/weedyfrance","https://www.pinterest.fr/WeedyFrance/"],"honorificPrefix":"Mr","birthDate":"1978-07-17","gender":"male","knowsAbout":["CBD","Cannabis","Copywriter"],"knowsLanguage":["French"],"jobTitle":"Editor-in-chief specializing in CBD","worksFor":"Weedy.fr","url":"https://weedy.fr/es/blog/author/cbd_blog_owner/"}]}},"_links":{"self":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts"}],"about":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/users/41"}],"replies":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/comments?post=359632"}],"version-history":[{"count":1,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359632/revisions"}],"predecessor-version":[{"id":359633,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359632/revisions/359633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/media/352112"}],"wp:attachment":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/media?parent=359632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/categories?post=359632"},{"taxonomy":"post_tag","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/tags?post=359632"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}