{"id":360936,"date":"2024-09-17T18:31:11","date_gmt":"2024-09-17T16:31:11","guid":{"rendered":"https://weedy.fr/blog/?p=360936"},"modified":"2024-09-17T18:31:12","modified_gmt":"2024-09-17T16:31:12","slug":"voce-pode-ter-uma-overdose-de-cbd","status":"publish","type":"post","link":"https://weedy.fr/blog/pt/voce-pode-ter-uma-overdose-de-cbd/","title":{"rendered":"Você pode ter uma overdose de CBD?"},"content":{"rendered":"<p>Lemos com frequência, e com razão: o <a href=\"https://weedy.fr/es\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> é uma molécula que, mesmo sendo extraída da cannabis, não é psicoativa nem viciante. Diz-se também que não tem efeitos colaterais conhecidos. No entanto, uma questão é abordada com menos frequência: é possível fazer uma <strong>Overdose de <a href=\"https://weedy.fr/es\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a></strong> ? Além da própria possibilidade de tomar muito <a href=\"https://weedy.fr/es\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a>, de que quantidade podemos falar <strong>dose (muito) alta de canabidiol </strong>? Isso é o que explicamos a você neste artigo.</p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire</p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle</span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http://www.w3.org/2000/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"></path></svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http://www.w3.org/2000/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"></path></svg></span></span></span></a></span></div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 \"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https://weedy.fr/es/blog/pt/voce-pode-ter-uma-overdose-de-cbd/#Nao_voce_nao_pode_ter_uma_overdose_de_CBD\">Não, você não pode ter uma overdose de CBD</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https://weedy.fr/es/blog/pt/voce-pode-ter-uma-overdose-de-cbd/#Riscos_de_overdose_de_CBD\">Riscos de overdose de CBD</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https://weedy.fr/es/blog/pt/voce-pode-ter-uma-overdose-de-cbd/#Principais_riscos_de_overdose_de_CBD\">Principais riscos de overdose de CBD</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https://weedy.fr/es/blog/pt/voce-pode-ter-uma-overdose-de-cbd/#Quando_uma_dose_de_CBD_e_muito_alta\">Quando uma dose de CBD é muito alta?</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https://weedy.fr/es/blog/pt/voce-pode-ter-uma-overdose-de-cbd/#Dosando_seu_CBD_corretamente\">Dosando seu CBD corretamente</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https://weedy.fr/es/blog/pt/voce-pode-ter-uma-overdose-de-cbd/#Existem_casos_de_overdose_de_CBD_na_Internet_Como_isso_e_possivel\">Existem casos de overdose de CBD na Internet. Como isso é possível?</a></li></ul></nav></div>\n<h2><span class=\"ez-toc-section\" id=\"Nao_voce_nao_pode_ter_uma_overdose_de_CBD\"></span>Não, você não pode ter uma overdose de CBD<span class=\"ez-toc-section-end\"></span></h2>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-289880\" src=\"https://weedy.fr/wp-content/uploads/2022/02/On-ne-peut-pas-faire-doverdose-de-CBD-min.jpg\" alt=\"você não pode ter uma overdose de CBD min\" width=\"700\" height=\"393\"><br>\nPor definição, overdose (ou sobredosagem) é o consumo de dose excessiva de determinada substância (geralmente um medicamento), com risco de causar a morte. Para começar, <strong>O </strong><a href=\"https://weedy.fr/es\"><strong>CDB</strong></a><strong> não é uma droga</strong>, nem mesmo um narcótico. Também não foi relatado nenhum caso em que o consumo de CBD tenha colocado diretamente em perigo a saúde de um consumidor ou causado a morte.</p>\n<p>Entre aqueles conhecidos por serem responsáveis ​​por overdoses, no entanto, encontramos <strong>drogas</strong> (heroína, cocaína, anfetaminas),<strong>álcool</strong> (cujo sintoma é coma alcoólico) e <strong>drogas</strong> incluindo certos ansiolíticos e analgésicos (morfina, codeína).</p>\n<p>O <a href=\"https://weedy.fr/es/quest-ce-que-le-thc\">THC</a> pode causar efeitos colaterais mais graves (delírio, aumento da frequência cardíaca, vômito), mas <strong>nenhuma overdose fatal foi observada</strong>. Existem alguns casos raros de morte envolvendo o uso de maconha. Contudo, não foi estabelecida nenhuma ligação directa de causa e efeito e, se os ingredientes activos da marijuana desempenharam um papel, parece mais provável que seja apenas um <strong>papel secundário</strong> agravando uma condição pré-existente (problema cardíaco no sujeito em particular).</p>\n<p>Resposta curta para uma pergunta complexa: <strong>você não pode ter uma overdose de cannabis CBD</strong>, cujos níveis de THC são muito baixos para arriscar uma overdose de qualquer maneira (<a href=\"https://weedy.fr/es/blog/taux-de-cbd/\">0,3% de THC máximo</a> dentro da UE para cannabis legal).</p>\n<h2><span class=\"ez-toc-section\" id=\"Riscos_de_overdose_de_CBD\"></span>Riscos de overdose de CBD<span class=\"ez-toc-section-end\"></span></h2>\n<p>O CBD, mesmo em doses elevadas, não é tóxico. No entanto, pode levar ao aparecimento de certos <a href=\"https://weedy.fr/es/blog/effets-secondaires-cbd/\">efeitos colaterais</a>. No entanto, geralmente desaparecem por si próprios assim que o canabidiol é digerido, algumas horas depois de o tomar.</p>\n<h3><span class=\"ez-toc-section\" id=\"Principais_riscos_de_overdose_de_CBD\"></span>Principais riscos de overdose de CBD<span class=\"ez-toc-section-end\"></span></h3>\n<ul>\n<li>Diarréia,</li>\n<li>Vômito,</li>\n<li>Sonolência,</li>\n<li>Boca pastosa.</li>\n</ul>\n<h2><span class=\"ez-toc-section\" id=\"Quando_uma_dose_de_CBD_e_muito_alta\"></span>Quando uma dose de CBD é muito alta?<span class=\"ez-toc-section-end\"></span></h2>\n<p><img decoding=\"async\" class=\"size-full wp-image-289881\" src=\"https://weedy.fr/wp-content/uploads/2022/02/Trop-haute-dose-de-CBD-min.jpg\" alt=\"dose muito alta de CBD min\" width=\"700\" height=\"468\"><br>\nBoas notícias para todos os amantes do CBD: é preciso (muito) muito CBD para atingir uma dose demasiado elevada de CBD. Embora a literatura científica ainda seja escassa sobre o assunto, <a href=\"https://www.ncbi.nlm.nih.gov/pmc/articles/PMC5569602/\">Estudo de 2017</a> <em></em> nos fornece os primeiros elementos de uma resposta. O estudo é interessante na medida em que combina novos dados com estudos preliminares realizados em 2011, nomeadamente no contexto da administração de altas doses de CBD, para uso crónico. Doses variando <strong>até 1.500 miligramas por dia</strong> demonstraram assim ser bem tolerados pelos humanos.</p>\n<p>Para efeito de comparação, uma garrafa inteira do nosso <a href=\"https://weedy.fr/es/product/huile-de-cbd-20-a-lhuile-de-chanvre-30ml\">óleo de cânhamo orgânico com 20% CBD</a>, um dos mais concentrados, contém tudo e tudo <strong>200 miligramas de CBD</strong>. O risco de atingir acidentalmente uma dose de 1.500 miligramas é, portanto, próximo de 0.</p>\n<p>Ainda falando sobre altas doses de CBD, um <a href=\"https://www.sciencedirect.com/science/article/abs/pii/S1474442215003798\" target=\"_blank\" rel=\"noopener\">Estudo de 2016</a> <em></em>estava interessado na ação da CBD em <a href=\"https://weedy.fr/es/blog/cbd-et-epilepsie/\">crises epilépticas</a> crianças, particularmente aquelas afetadas pelas síndromes de Dravet e Lennox-Gastaut. A dose inicial de <strong>5 mg/kg/dia</strong> foi gradualmente aumentado para <strong>50 mg/kg/dia</strong> em pacientes que toleraram.</p>\n<h2><span class=\"ez-toc-section\" id=\"Dosando_seu_CBD_corretamente\"></span>Dosando seu CBD corretamente<span class=\"ez-toc-section-end\"></span></h2>\n<p><em>Para efeitos maximizados, é importante encontrar a dose certa de CBD</em></p>\n<p>Portanto, é improvável uma overdose de CBD. No entanto, tomar mais CBD do que o absolutamente necessário pode levar a uma forma de dependência no corpo, que exigirá cada vez mais CBD para sentir os efeitos. O <a href=\"https://weedy.fr/es/blog/pourquoi-le-cbd-est-il-si-cher/\">Preço do CBD</a> também é relativamente alto. Recomenda-se, portanto, limitar-se ao necessário, tanto em termos dos seus efeitos como do ponto de vista puramente económico. Portanto, recomenda-se começar com uma pequena quantidade e depois aumentar aos poucos até obter os efeitos desejados.</p>\n<p>Se o <a href=\"https://weedy.fr/es/blog/lire-letiquette-dun-produit-au-cbd/\">lendo o rótulo do seu produto CBD</a> não lhe dá indicações precisas, pode, por exemplo, começar com uma dose de 10 a 20 miligramas de CBD nos primeiros dias e depois aumentar, se necessário, 5 a 10 miligramas por dia. Nosso guia dedicado ao assunto também ajuda você a determinar o <a href=\"https://weedy.fr/es/blog/cbd-et-dosage/\">quantidade ideal de CBD</a> Para <em>seu</em> precisa.</p>\n<h2><span class=\"ez-toc-section\" id=\"Existem_casos_de_overdose_de_CBD_na_Internet_Como_isso_e_possivel\"></span>Existem casos de overdose de CBD na Internet. Como isso é possível?<span class=\"ez-toc-section-end\"></span></h2>\n<p>Seja na Internet ou de boca em boca, há rumores que são difíceis de morrer. Alguns até se tornaram lendas urbanas e alguns deles mencionam casos de overdose de CBD. Quando nos aprofundamos um pouco mais neste tipo de caso, geralmente chegamos à conclusão de que a pessoa em causa tinha <strong>usou outras substâncias</strong>, voluntariamente ou não. O risco de um produto ser rotulado como CBD mas esconder outra coisa existe de facto, especialmente quando a sua origem não pode ser rastreada. Pode então conter outros ingredientes, muitas vezes de má qualidade.</p>\n<p>Sobre este assunto, alertamos você contra <strong>produtos sintéticos</strong>, cujo <a href=\"https://weedy.fr/es/blog/cbd-naturel-ou-cbd-de-synthese/\">cannabis sintética</a>, infelizmente comum nos Estados Unidos e às vezes visto na Europa.</p>\n<p>Para garantir que você não corre nenhum risco, é aconselhável comprar cannabis CBD apenas de revendedores respeitáveis, <strong>garantindo a rastreabilidade e legalidade de seus produtos</strong>. É o caso da <a href=\"https://weedy.fr/es\" data-internallinksmanager029f6b8e52c=\"8\" title=\"weedy\">Weedy.fr</a>, pioneira na venda de CBD de qualidade em França e na Europa. Se pretende consumir CBD sem riscos, garantindo ao mesmo tempo o controlo total da lista de ingredientes utilizados, a nossa loja online oferece-lhe uma gama diversificada e regularmente verificada.</p>\n","protected":false},"excerpt":{"rendered":"<p>Lemos com frequência, e com razão: o CBD é uma molécula que, mesmo sendo extraída da cannabis, não é psicoativa nem viciante. Diz-se também que não tem efeitos colaterais conhecidos. No entanto, uma questão é abordada com menos frequência: é possível fazer uma Overdose de CBD ? Além da própria possibilidade de tomar muito CBD, [&hellip;]</p>\n","protected":false},"author":41,"featured_media":352634,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"padrão\n","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[672],"tags":[],"class_list":["post-360936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude-e-bem-estar-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https://yoast.com/product/yoast-seo-premium-wordpress/ -->\n<title>Você pode ter uma overdose de CBD? - Actualités CBD Blog - Weedy.fr</title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" />\n<link rel=\"canonical\" href=\"https://weedy.fr/blog/pt/voce-pode-ter-uma-overdose-de-cbd/\" />\n<meta property=\"og:locale\" content=\"fr_FR\" />\n<meta property=\"og:type\" content=\"article\" />\n<meta property=\"og:title\" content=\"🌱Você pode ter uma overdose de CBD? - Weedy.Fr🌱\" />\n<meta property=\"og:description\" content=\"Lemos com frequência, e com razão: o CBD é uma molécula que, mesmo sendo extraída da cannabis, não é psicoativa nem viciante. Diz-se também que não tem efeitos colaterais conhecidos. No entanto, uma questão é abordada com menos frequência: é possível fazer uma Overdose de CBD ? Além da própria possibilidade de tomar muito CBD, [&hellip;]\" />\n<meta property=\"og:url\" content=\"https://weedy.fr/blog/pt/voce-pode-ter-uma-overdose-de-cbd/\" />\n<meta property=\"og:site_name\" content=\"Actualités CBD Blog - Weedy.fr\" />\n<meta property=\"article:publisher\" content=\"https://www.facebook.com/weedysocial\" />\n<meta property=\"article:author\" content=\"https://www.facebook.com/weedysocial/\" />\n<meta property=\"article:published_time\" content=\"2024-09-17T16:31:11+00:00\" />\n<meta property=\"article:modified_time\" content=\"2024-09-17T16:31:12+00:00\" />\n<meta property=\"og:image\" content=\"https://weedy.fr/blog/wp-content/uploads/2024/05/peut-on-faire-une-overdose-de-cbd.jpg\" />\n\t<meta property=\"og:image:width\" content=\"1792\" />\n\t<meta property=\"og:image:height\" content=\"1024\" />\n\t<meta property=\"og:image:type\" content=\"image/jpeg\" />\n<meta name=\"author\" content=\"Julien Cordobes\" />\n<meta name=\"twitter:card\" content=\"summary_large_image\" />\n<meta name=\"twitter:label1\" content=\"Écrit par\" />\n\t<meta name=\"twitter:data1\" content=\"Julien Cordobes\" />\n\t<meta name=\"twitter:label2\" content=\"Durée de lecture estimée\" />\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" />\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\/\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/voce-pode-ter-uma-overdose-de-cbd\\/#article\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/voce-pode-ter-uma-overdose-de-cbd\\/\"},\"author\":{\"name\":\"Julien Cordobes\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/72583fcd87d7cf46afe11d530945bc7e\"},\"headline\":\"Você pode ter uma overdose de CBD?\",\"datePublished\":\"2024-09-17T16:31:11+00:00\",\"dateModified\":\"2024-09-17T16:31:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/voce-pode-ter-uma-overdose-de-cbd\\/\"},\"wordCount\":938,\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/voce-pode-ter-uma-overdose-de-cbd\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/peut-on-faire-une-overdose-de-cbd.jpg\",\"articleSection\":[\"Saúde e Bem-estar\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/voce-pode-ter-uma-overdose-de-cbd\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/voce-pode-ter-uma-overdose-de-cbd\\/\",\"name\":\"Você pode ter uma overdose de CBD? - Actualités CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/voce-pode-ter-uma-overdose-de-cbd\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/voce-pode-ter-uma-overdose-de-cbd\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/peut-on-faire-une-overdose-de-cbd.jpg\",\"datePublished\":\"2024-09-17T16:31:11+00:00\",\"dateModified\":\"2024-09-17T16:31:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/voce-pode-ter-uma-overdose-de-cbd\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\/\\/weedy.fr\\/blog\\/pt\\/voce-pode-ter-uma-overdose-de-cbd\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/voce-pode-ter-uma-overdose-de-cbd\\/#primaryimage\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/peut-on-faire-une-overdose-de-cbd.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/peut-on-faire-une-overdose-de-cbd.jpg\",\"width\":1792,\"height\":1024,\"caption\":\"Can you overdose on CBD?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/voce-pode-ter-uma-overdose-de-cbd\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Saúde e Bem-estar\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/category\\/saude-e-bem-estar-pt\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Você pode ter uma overdose de CBD?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"name\":\"Actualités CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualité du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\/\\/weedy.fr\\/blog\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\"},\"sameAs\":[\"https:\\/\\/www.facebook.com\\/weedysocial\",\"https:\\/\\/www.instagram.com\\/weedyfrance\\/\"],\"description\":\"Leader en france sur la vente de produits à base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/72583fcd87d7cf46afe11d530945bc7e\",\"name\":\"Julien Cordobes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"url\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"caption\":\"Julien Cordobes\"},\"description\":\"Rédacteur en chef spécialisé en CBD Julien, né le 17 juillet 1978 en région Parisienne, est un éminent rédacteur et expert dans le domaine des produits à base de CBD. Suite à ses études en biologie et en médecine alternative, Julien a développé une passion pour les remèdes naturels, dont le CBD. En 2022, il intègre l’équipe du site Weedy.fr en qualité d’expert et de contributeur régulier. Grâce à son expertise scientifique et une écriture claire, Julien aide à démystifier les aspects complexes du CBD, tout en mettant en lumière ses bienfaits et applications potentielles à travers ses articles et participations à des conférences.\",\"sameAs\":[\"https:\\/\\/weedy.fr\",\"https:\\/\\/www.facebook.com\\/weedysocial\\/\",\"https:\\/\\/www.instagram.com\\/weedyfrance\",\"https:\\/\\/www.pinterest.fr\\/WeedyFrance\\/\"],\"honorificPrefix\":\"Mr\",\"birthDate\":\"1978-07-17\",\"gender\":\"male\",\"knowsAbout\":[\"CBD\",\"Cannabis\",\"Copywriter\"],\"knowsLanguage\":[\"French\"],\"jobTitle\":\"Editor-in-chief specializing in CBD\",\"worksFor\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/author\\/cbd_blog_owner\\/\"}]}</script>\n<!-- / Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Você pode ter uma overdose de CBD? - Actualités CBD Blog - Weedy.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://weedy.fr/blog/pt/voce-pode-ter-uma-overdose-de-cbd/","og_locale":"fr_FR","og_type":"article","og_title":"🌱Você pode ter uma overdose de CBD? - Weedy.Fr🌱","og_description":"Lemos com frequência, e com razão: o CBD é uma molécula que, mesmo sendo extraída da cannabis, não é psicoativa nem viciante. Diz-se também que não tem efeitos colaterais conhecidos. No entanto, uma questão é abordada com menos frequência: é possível fazer uma Overdose de CBD ? Além da própria possibilidade de tomar muito CBD, [&hellip;]","og_url":"https://weedy.fr/blog/pt/voce-pode-ter-uma-overdose-de-cbd/","og_site_name":"Actualités CBD Blog - Weedy.fr","article_publisher":"https://www.facebook.com/weedysocial","article_author":"https://www.facebook.com/weedysocial/","article_published_time":"2024-09-17T16:31:11+00:00","article_modified_time":"2024-09-17T16:31:12+00:00","og_image":[{"width":1792,"height":1024,"url":"https://weedy.fr/es/blog/wp-content/uploads/2024/05/peut-on-faire-une-overdose-de-cbd.jpg","type":"image/jpeg"}],"author":"Julien Cordobes","twitter_card":"summary_large_image","twitter_misc":{"Écrit par":"Julien Cordobes","Durée de lecture estimée":"5 minutes"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"Article","@id":"https://weedy.fr/blog/pt/voce-pode-ter-uma-overdose-de-cbd/#article","isPartOf":{"@id":"https://weedy.fr/blog/pt/voce-pode-ter-uma-overdose-de-cbd/"},"author":{"name":"Julien Cordobes","@id":"https://weedy.fr/blog/#/schema/person/72583fcd87d7cf46afe11d530945bc7e"},"headline":"Você pode ter uma overdose de CBD?","datePublished":"2024-09-17T16:31:11+00:00","dateModified":"2024-09-17T16:31:12+00:00","mainEntityOfPage":{"@id":"https://weedy.fr/blog/pt/voce-pode-ter-uma-overdose-de-cbd/"},"wordCount":938,"publisher":{"@id":"https://weedy.fr/blog/#organization"},"image":{"@id":"https://weedy.fr/blog/pt/voce-pode-ter-uma-overdose-de-cbd/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/peut-on-faire-une-overdose-de-cbd.jpg","articleSection":["Saúde e Bem-estar"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https://weedy.fr/blog/pt/voce-pode-ter-uma-overdose-de-cbd/","url":"https://weedy.fr/es/blog/pt/voce-pode-ter-uma-overdose-de-cbd/","name":"Você pode ter uma overdose de CBD? - Actualités CBD Blog - Weedy.fr","isPartOf":{"@id":"https://weedy.fr/blog/#website"},"primaryImageOfPage":{"@id":"https://weedy.fr/blog/pt/voce-pode-ter-uma-overdose-de-cbd/#primaryimage"},"image":{"@id":"https://weedy.fr/blog/pt/voce-pode-ter-uma-overdose-de-cbd/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/peut-on-faire-une-overdose-de-cbd.jpg","datePublished":"2024-09-17T16:31:11+00:00","dateModified":"2024-09-17T16:31:12+00:00","breadcrumb":{"@id":"https://weedy.fr/blog/pt/voce-pode-ter-uma-overdose-de-cbd/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https://weedy.fr/blog/pt/voce-pode-ter-uma-overdose-de-cbd/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/pt/voce-pode-ter-uma-overdose-de-cbd/#primaryimage","url":"https://weedy.fr/es/blog/wp-content/uploads/2024/05/peut-on-faire-une-overdose-de-cbd.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/peut-on-faire-une-overdose-de-cbd.jpg","width":1792,"height":1024,"caption":"Can you overdose on CBD?"},{"@type":"BreadcrumbList","@id":"https://weedy.fr/blog/pt/voce-pode-ter-uma-overdose-de-cbd/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https://weedy.fr/blog/"},{"@type":"ListItem","position":2,"name":"Saúde e Bem-estar","item":"https://weedy.fr/blog/category/saude-e-bem-estar-pt/"},{"@type":"ListItem","position":3,"name":"Você pode ter uma overdose de CBD?"}]},{"@type":"WebSite","@id":"https://weedy.fr/blog/#website","url":"https://weedy.fr/es/blog/","name":"Actualités CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualité du CBD et du chanvre en France","publisher":{"@id":"https://weedy.fr/blog/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://weedy.fr/blog/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https://weedy.fr/blog/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https://weedy.fr/es/blog/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/#/schema/logo/image/","url":"https://weedy.fr/es/blog/wp-content/uploads/2024/05/logo-carre.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https://weedy.fr/blog/#/schema/logo/image/"},"sameAs":["https://www.facebook.com/weedysocial","https://www.instagram.com/weedyfrance/"],"description":"Leader en france sur la vente de produits à base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https://weedy.fr/blog/#/schema/person/72583fcd87d7cf46afe11d530945bc7e","name":"Julien Cordobes","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","url":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","caption":"Julien Cordobes"},"description":"Rédacteur en chef spécialisé en CBD Julien, né le 17 juillet 1978 en région Parisienne, est un éminent rédacteur et expert dans le domaine des produits à base de CBD. Suite à ses études en biologie et en médecine alternative, Julien a développé une passion pour les remèdes naturels, dont le CBD. En 2022, il intègre l’équipe du site Weedy.fr en qualité d’expert et de contributeur régulier. Grâce à son expertise scientifique et une écriture claire, Julien aide à démystifier les aspects complexes du CBD, tout en mettant en lumière ses bienfaits et applications potentielles à travers ses articles et participations à des conférences.","sameAs":["https://weedy.fr","https://www.facebook.com/weedysocial/","https://www.instagram.com/weedyfrance","https://www.pinterest.fr/WeedyFrance/"],"honorificPrefix":"Mr","birthDate":"1978-07-17","gender":"male","knowsAbout":["CBD","Cannabis","Copywriter"],"knowsLanguage":["French"],"jobTitle":"Editor-in-chief specializing in CBD","worksFor":"Weedy.fr","url":"https://weedy.fr/es/blog/author/cbd_blog_owner/"}]}},"_links":{"self":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/360936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts"}],"about":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/users/41"}],"replies":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/comments?post=360936"}],"version-history":[{"count":1,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/360936/revisions"}],"predecessor-version":[{"id":360937,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/360936/revisions/360937"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/media/352634"}],"wp:attachment":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/media?parent=360936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/categories?post=360936"},{"taxonomy":"post_tag","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/tags?post=360936"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}