{"id":358944,"date":"2024-09-17T17:30:42","date_gmt":"2024-09-17T15:30:42","guid":{"rendered":"https://weedy.fr/blog/?p=358944"},"modified":"2024-09-17T17:30:43","modified_gmt":"2024-09-17T15:30:43","slug":"cbd-e-seus-efeitos-beneficos-no-figado","status":"publish","type":"post","link":"https://weedy.fr/blog/pt/cbd-e-seus-efeitos-beneficos-no-figado/","title":{"rendered":"CBD e seus efeitos benéficos no fígado"},"content":{"rendered":"<p>Na busca por produtos naturais para melhorar a nossa saúde, muitos estão interessados ​​nos benefícios do canabidiol (<a href=\"https://weedy.fr/nl\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a>). O <a href=\"https://weedy.fr/nl\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> é um composto encontrado na cannabis que atrai cada vez mais interesse entre investigadores e consumidores. Ao contrário do seu primo THC, não causa efeitos psicoativos ou « altos ». Muitos estudos foram realizados sobre as potenciais propriedades terapêuticas do <a href=\"https://weedy.fr/nl\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a>, inclusive em áreas como ansiedade, dor crónica e até epilepsia. Mas e os seus efeitos no fígado? O CBD é bom para esta importante glândula do nosso corpo? Este artigo explora a investigação existente e o potencial do CBD para o nosso fígado.</p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire</p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle</span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http://www.w3.org/2000/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"></path></svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http://www.w3.org/2000/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"></path></svg></span></span></span></a></span></div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 \"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https://weedy.fr/nl/blog/pt/cbd-e-seus-efeitos-beneficos-no-figado/#Compreendendo_o_papel_do_figado_em_nosso_corpo\">Compreendendo o papel do fígado em nosso corpo</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https://weedy.fr/nl/blog/pt/cbd-e-seus-efeitos-beneficos-no-figado/#CBD_e_protecao_do_figado_o_que_dizem_os_estudos\">CBD e proteção do fígado: o que dizem os estudos?</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https://weedy.fr/nl/blog/pt/cbd-e-seus-efeitos-beneficos-no-figado/#Efeitos_antiinflamatorios\">Efeitos antiinflamatórios</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https://weedy.fr/nl/blog/pt/cbd-e-seus-efeitos-beneficos-no-figado/#Protecao_contra_lesoes_induzidas_pelo_alcool\">Proteção contra lesões induzidas pelo álcool</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https://weedy.fr/nl/blog/pt/cbd-e-seus-efeitos-beneficos-no-figado/#Efeitos_no_figado_gorduroso\">Efeitos no fígado gorduroso</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https://weedy.fr/nl/blog/pt/cbd-e-seus-efeitos-beneficos-no-figado/#Quanto_CBD_para_proteger_seu_figado\">Quanto CBD para proteger seu fígado?</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https://weedy.fr/nl/blog/pt/cbd-e-seus-efeitos-beneficos-no-figado/#As_diferentes_formas_de_CBD\">As diferentes formas de CBD</a></li></ul></nav></div>\n<h2><span class=\"ez-toc-section\" id=\"Compreendendo_o_papel_do_figado_em_nosso_corpo\"></span>Compreendendo o papel do fígado em nosso corpo<span class=\"ez-toc-section-end\"></span></h2>\n<p>O fígado desempenha uma infinidade de funções essenciais para o bom funcionamento do nosso corpo. Entre estes, encontramos:</p>\n<ul>\n<li>a produção de bile, necessária para a digestão das gorduras,</li>\n<li>a regulação do metabolismo de carboidratos, lipídios e proteínas,</li>\n<li>o armazenamento de certas vitaminas e minerais,</li>\n<li>a eliminação de toxinas e resíduos do processo digestivo,</li>\n<li>a síntese de fatores de coagulação sanguínea.</li>\n</ul>\n<p>Portanto, é essencial proteger a saúde do nosso fígado para garantir o funcionamento ideal de todo o corpo. Muitos fatores podem afetar a saúde do fígado, como dieta inadequada, consumo de álcool e certos medicamentos.</p>\n<h2><span class=\"ez-toc-section\" id=\"CBD_e_protecao_do_figado_o_que_dizem_os_estudos\"></span>CBD e proteção do fígado: o que dizem os estudos?<span class=\"ez-toc-section-end\"></span></h2>\n<p>Algumas pesquisas examinaram os efeitos do CBD no fígado, com resultados encorajadores.</p>\n<h3><span class=\"ez-toc-section\" id=\"Efeitos_antiinflamatorios\"></span>Efeitos antiinflamatórios<span class=\"ez-toc-section-end\"></span></h3>\n<p>Uma das principais causas de doença hepática é a inflamação crônica do fígado. O CBD reconheceu propriedades anti-inflamatórias que podem ajudar a reduzir esta inflamação e, assim, prevenir certas doenças hepáticas. Vários estudos demonstraram que o CBD pode reduzir a produção de citocinas inflamatórias no fígado e prevenir a progressão da fibrose hepática, um fenómeno ligado a muitas doenças hepáticas crónicas.</p>\n<h3><span class=\"ez-toc-section\" id=\"Protecao_contra_lesoes_induzidas_pelo_alcool\"></span>Proteção contra lesões induzidas pelo álcool<span class=\"ez-toc-section-end\"></span></h3>\n<p>O consumo excessivo de álcool pode causar danos ao fígado, inclusive causando inflamação e estresse oxidativo. As propriedades antioxidantes do CBD podem ajudar a fortalecer as defesas naturais do fígado contra estes danos. Um estudo em ratos descobriu que o CBD poderia aliviar os danos hepáticos induzidos pelo álcool.</p>\n<h3><span class=\"ez-toc-section\" id=\"Efeitos_no_figado_gorduroso\"></span>Efeitos no fígado gorduroso<span class=\"ez-toc-section-end\"></span></h3>\n<p>A doença hepática gordurosa é uma condição caracterizada pelo acúmulo de gordura nas células do fígado. As propriedades anti-inflamatórias e antioxidantes do CBD também podem ser benéficas nesta área. Um estudo em ratos mostrou que o CBD pode reduzir os marcadores da doença hepática gordurosa, promovendo a lipólise, um processo pelo qual os lípidos são decompostos e utilizados como fonte de energia.</p>\n<h2><span class=\"ez-toc-section\" id=\"Quanto_CBD_para_proteger_seu_figado\"></span>Quanto CBD para proteger seu fígado?<span class=\"ez-toc-section-end\"></span></h2>\n<p>Ainda é muito cedo para estabelecer definitivamente qual a dose de CBD que seria apropriada para apoiar a saúde do fígado. Isto pode depender de muitos factores, incluindo peso, idade, metabolismo individual ou a possível presença de doenças hepáticas pré-existentes.</p>\n<p>No entanto, é importante notar que geralmente o CBD é considerado como tendo um bom perfil de segurança. Estudos demonstraram que doses de até 1.500 mg de CBD por dia são bem toleradas em humanos. No entanto, podem ocorrer efeitos colaterais, como fadiga, diarreia ou alteração do apetite.</p>\n<p>Recomenda-se começar com uma dose baixa de CBD e aumentar gradualmente à medida que os seus efeitos progridem. Também pode ser útil consultar um profissional de saúde, que poderá aconselhá-lo com base na sua situação.</p>\n<h2><span class=\"ez-toc-section\" id=\"As_diferentes_formas_de_CBD\"></span>As diferentes formas de CBD<span class=\"ez-toc-section-end\"></span></h2>\n<p>O CBD está disponível em diversas formas no mercado, adaptadas às diferentes necessidades e preferências:</p>\n<ul>\n<li><strong>Óleo CBD</strong> : concentrado em CBD, geralmente é consumido por via sublingual (algumas gotas debaixo da língua) ou misturado com alimentos,</li>\n<li><strong>Cápsulas de CBD</strong> : fáceis de engolir e dosados ​​com precisão, permitem um controle preciso da quantidade de CBD ingerida,</li>\n<li><strong>Cristais de CBD</strong> : apresentando maior concentração de CBD, podem ser misturados aos alimentos, diluídos em óleo vegetal ou mesmo vaporizados,</li>\n<li><strong>Pasta CBD</strong> : comercializado na forma de extrato puro com alto teor de CBD, é utilizado principalmente para aplicações tópicas (aplicação direta na pele).</li>\n</ul>\n<p>É portanto adequado avaliar as opções disponíveis e escolher aquela que melhor se adapta às suas necessidades e expectativas relativamente à utilização do CBD para a protecção do seu fígado.</p>\n","protected":false},"excerpt":{"rendered":"<p>Na busca por produtos naturais para melhorar a nossa saúde, muitos estão interessados ​​nos benefícios do canabidiol (CBD). O CBD é um composto encontrado na cannabis que atrai cada vez mais interesse entre investigadores e consumidores. Ao contrário do seu primo THC, não causa efeitos psicoativos ou « altos ». Muitos estudos foram realizados sobre as potenciais [&hellip;]</p>\n","protected":false},"author":95,"featured_media":352141,"comment_status":"closed","ping_status":"open","sticky":false,"template":"padrão\n","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[675],"tags":[],"class_list":["post-358944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-sobre-cbd-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https://yoast.com/product/yoast-seo-premium-wordpress/ -->\n<title>CBD e seus efeitos benéficos no fígado - Actualités CBD Blog - Weedy.fr</title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" />\n<link rel=\"canonical\" href=\"https://weedy.fr/blog/pt/cbd-e-seus-efeitos-beneficos-no-figado/\" />\n<meta property=\"og:locale\" content=\"fr_FR\" />\n<meta property=\"og:type\" content=\"article\" />\n<meta property=\"og:title\" content=\"🌱CBD e seus efeitos benéficos no fígado - Weedy.Fr🌱\" />\n<meta property=\"og:description\" content=\"Na busca por produtos naturais para melhorar a nossa saúde, muitos estão interessados ​​nos benefícios do canabidiol (CBD). O CBD é um composto encontrado na cannabis que atrai cada vez mais interesse entre investigadores e consumidores. Ao contrário do seu primo THC, não causa efeitos psicoativos ou « altos ». Muitos estudos foram realizados sobre as potenciais [&hellip;]\" />\n<meta property=\"og:url\" content=\"https://weedy.fr/blog/pt/cbd-e-seus-efeitos-beneficos-no-figado/\" />\n<meta property=\"og:site_name\" content=\"Actualités CBD Blog - Weedy.fr\" />\n<meta property=\"article:publisher\" content=\"https://www.facebook.com/weedysocial\" />\n<meta property=\"article:published_time\" content=\"2024-09-17T15:30:42+00:00\" />\n<meta property=\"article:modified_time\" content=\"2024-09-17T15:30:43+00:00\" />\n<meta property=\"og:image\" content=\"https://weedy.fr/blog/wp-content/uploads/2024/01/le-cbd-et-ses-effets-benefiques-sur-le-foie.jpg\" />\n\t<meta property=\"og:image:width\" content=\"1456\" />\n\t<meta property=\"og:image:height\" content=\"832\" />\n\t<meta property=\"og:image:type\" content=\"image/jpeg\" />\n<meta name=\"author\" content=\"Alexandre Lacarré\" />\n<meta name=\"twitter:card\" content=\"summary_large_image\" />\n<meta name=\"twitter:label1\" content=\"Écrit par\" />\n\t<meta name=\"twitter:data1\" content=\"Alexandre Lacarré\" />\n\t<meta name=\"twitter:label2\" content=\"Durée de lecture estimée\" />\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" />\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\/\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cbd-e-seus-efeitos-beneficos-no-figado\\/#article\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cbd-e-seus-efeitos-beneficos-no-figado\\/\"},\"author\":{\"name\":\"Alexandre Lacarré\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/54c87d7e580413b08a5b875474a54f4e\"},\"headline\":\"CBD e seus efeitos benéficos no fígado\",\"datePublished\":\"2024-09-17T15:30:42+00:00\",\"dateModified\":\"2024-09-17T15:30:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cbd-e-seus-efeitos-beneficos-no-figado\\/\"},\"wordCount\":772,\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cbd-e-seus-efeitos-beneficos-no-figado\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/le-cbd-et-ses-effets-benefiques-sur-le-foie.jpg\",\"articleSection\":[\"Notícias sobre CBD\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cbd-e-seus-efeitos-beneficos-no-figado\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cbd-e-seus-efeitos-beneficos-no-figado\\/\",\"name\":\"CBD e seus efeitos benéficos no fígado - Actualités CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cbd-e-seus-efeitos-beneficos-no-figado\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cbd-e-seus-efeitos-beneficos-no-figado\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/le-cbd-et-ses-effets-benefiques-sur-le-foie.jpg\",\"datePublished\":\"2024-09-17T15:30:42+00:00\",\"dateModified\":\"2024-09-17T15:30:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cbd-e-seus-efeitos-beneficos-no-figado\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cbd-e-seus-efeitos-beneficos-no-figado\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cbd-e-seus-efeitos-beneficos-no-figado\\/#primaryimage\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/le-cbd-et-ses-effets-benefiques-sur-le-foie.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/le-cbd-et-ses-effets-benefiques-sur-le-foie.jpg\",\"width\":1456,\"height\":832,\"caption\":\"Le CBD et ses effets bénéfiques sur le foie, foie, santé, études\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cbd-e-seus-efeitos-beneficos-no-figado\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notícias sobre CBD\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/category\\/noticias-sobre-cbd-pt\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CBD e seus efeitos benéficos no fígado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"name\":\"Actualités CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualité du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\/\\/weedy.fr\\/blog\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\"},\"sameAs\":[\"https:\\/\\/www.facebook.com\\/weedysocial\",\"https:\\/\\/www.instagram.com\\/weedyfrance\\/\"],\"description\":\"Leader en france sur la vente de produits à base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/54c87d7e580413b08a5b875474a54f4e\",\"name\":\"Alexandre Lacarré\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g\",\"url\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g\",\"caption\":\"Alexandre Lacarré\"},\"description\":\"Alexandre Lacarré est reconnu comme un leader innovant et influent dans l'industrie du cannabidiol (CBD). Alexandre a débuté sa carrière dans le secteur des biotechnologies, où il a acquis une expertise précieuse en recherche et développement. Passionné par les potentiels thérapeutiques des composés naturels, il s'est rapidement orienté vers l'industrie naissante du CBD.\",\"sameAs\":[\"https:\\/\\/www.linkedin.com\\/in\\/alexandre-henri-lacarr-785850186\\/\"],\"honorificPrefix\":\"Mr\",\"gender\":\"homme\",\"knowsAbout\":[\"CBD\",\"Cannabis\",\"Copywriter\"],\"worksFor\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/author\\/fiacre\\/\"}]}</script>\n<!-- / Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"CBD e seus efeitos benéficos no fígado - Actualités CBD Blog - Weedy.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://weedy.fr/blog/pt/cbd-e-seus-efeitos-beneficos-no-figado/","og_locale":"fr_FR","og_type":"article","og_title":"🌱CBD e seus efeitos benéficos no fígado - Weedy.Fr🌱","og_description":"Na busca por produtos naturais para melhorar a nossa saúde, muitos estão interessados ​​nos benefícios do canabidiol (CBD). O CBD é um composto encontrado na cannabis que atrai cada vez mais interesse entre investigadores e consumidores. Ao contrário do seu primo THC, não causa efeitos psicoativos ou « altos ». Muitos estudos foram realizados sobre as potenciais [&hellip;]","og_url":"https://weedy.fr/blog/pt/cbd-e-seus-efeitos-beneficos-no-figado/","og_site_name":"Actualités CBD Blog - Weedy.fr","article_publisher":"https://www.facebook.com/weedysocial","article_published_time":"2024-09-17T15:30:42+00:00","article_modified_time":"2024-09-17T15:30:43+00:00","og_image":[{"width":1456,"height":832,"url":"https://weedy.fr/nl/blog/wp-content/uploads/2024/01/le-cbd-et-ses-effets-benefiques-sur-le-foie.jpg","type":"image/jpeg"}],"author":"Alexandre Lacarré","twitter_card":"summary_large_image","twitter_misc":{"Écrit par":"Alexandre Lacarré","Durée de lecture estimée":"4 minutes"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"Article","@id":"https://weedy.fr/blog/pt/cbd-e-seus-efeitos-beneficos-no-figado/#article","isPartOf":{"@id":"https://weedy.fr/blog/pt/cbd-e-seus-efeitos-beneficos-no-figado/"},"author":{"name":"Alexandre Lacarré","@id":"https://weedy.fr/blog/#/schema/person/54c87d7e580413b08a5b875474a54f4e"},"headline":"CBD e seus efeitos benéficos no fígado","datePublished":"2024-09-17T15:30:42+00:00","dateModified":"2024-09-17T15:30:43+00:00","mainEntityOfPage":{"@id":"https://weedy.fr/blog/pt/cbd-e-seus-efeitos-beneficos-no-figado/"},"wordCount":772,"publisher":{"@id":"https://weedy.fr/blog/#organization"},"image":{"@id":"https://weedy.fr/blog/pt/cbd-e-seus-efeitos-beneficos-no-figado/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/le-cbd-et-ses-effets-benefiques-sur-le-foie.jpg","articleSection":["Notícias sobre CBD"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https://weedy.fr/blog/pt/cbd-e-seus-efeitos-beneficos-no-figado/","url":"https://weedy.fr/nl/blog/pt/cbd-e-seus-efeitos-beneficos-no-figado/","name":"CBD e seus efeitos benéficos no fígado - Actualités CBD Blog - Weedy.fr","isPartOf":{"@id":"https://weedy.fr/blog/#website"},"primaryImageOfPage":{"@id":"https://weedy.fr/blog/pt/cbd-e-seus-efeitos-beneficos-no-figado/#primaryimage"},"image":{"@id":"https://weedy.fr/blog/pt/cbd-e-seus-efeitos-beneficos-no-figado/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/le-cbd-et-ses-effets-benefiques-sur-le-foie.jpg","datePublished":"2024-09-17T15:30:42+00:00","dateModified":"2024-09-17T15:30:43+00:00","breadcrumb":{"@id":"https://weedy.fr/blog/pt/cbd-e-seus-efeitos-beneficos-no-figado/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https://weedy.fr/blog/pt/cbd-e-seus-efeitos-beneficos-no-figado/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/pt/cbd-e-seus-efeitos-beneficos-no-figado/#primaryimage","url":"https://weedy.fr/nl/blog/wp-content/uploads/2024/01/le-cbd-et-ses-effets-benefiques-sur-le-foie.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/le-cbd-et-ses-effets-benefiques-sur-le-foie.jpg","width":1456,"height":832,"caption":"Le CBD et ses effets bénéfiques sur le foie, foie, santé, études"},{"@type":"BreadcrumbList","@id":"https://weedy.fr/blog/pt/cbd-e-seus-efeitos-beneficos-no-figado/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https://weedy.fr/blog/"},{"@type":"ListItem","position":2,"name":"Notícias sobre CBD","item":"https://weedy.fr/blog/category/noticias-sobre-cbd-pt/"},{"@type":"ListItem","position":3,"name":"CBD e seus efeitos benéficos no fígado"}]},{"@type":"WebSite","@id":"https://weedy.fr/blog/#website","url":"https://weedy.fr/nl/blog/","name":"Actualités CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualité du CBD et du chanvre en France","publisher":{"@id":"https://weedy.fr/blog/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://weedy.fr/blog/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https://weedy.fr/blog/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https://weedy.fr/nl/blog/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/#/schema/logo/image/","url":"https://weedy.fr/nl/blog/wp-content/uploads/2024/05/logo-carre.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https://weedy.fr/blog/#/schema/logo/image/"},"sameAs":["https://www.facebook.com/weedysocial","https://www.instagram.com/weedyfrance/"],"description":"Leader en france sur la vente de produits à base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https://weedy.fr/blog/#/schema/person/54c87d7e580413b08a5b875474a54f4e","name":"Alexandre Lacarré","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://secure.gravatar.com/avatar/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g","url":"https://secure.gravatar.com/avatar/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g","caption":"Alexandre Lacarré"},"description":"Alexandre Lacarré est reconnu comme un leader innovant et influent dans l'industrie du cannabidiol (CBD). Alexandre a débuté sa carrière dans le secteur des biotechnologies, où il a acquis une expertise précieuse en recherche et développement. Passionné par les potentiels thérapeutiques des composés naturels, il s'est rapidement orienté vers l'industrie naissante du CBD.","sameAs":["https://www.linkedin.com/in/alexandre-henri-lacarr-785850186/"],"honorificPrefix":"Mr","gender":"homme","knowsAbout":["CBD","Cannabis","Copywriter"],"worksFor":"Weedy.fr","url":"https://weedy.fr/nl/blog/author/fiacre/"}]}},"_links":{"self":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/358944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts"}],"about":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/users/95"}],"replies":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/comments?post=358944"}],"version-history":[{"count":1,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/358944/revisions"}],"predecessor-version":[{"id":358945,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/358944/revisions/358945"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/media/352141"}],"wp:attachment":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/media?parent=358944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/categories?post=358944"},{"taxonomy":"post_tag","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/tags?post=358944"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}