{"id":359280,"date":"2024-09-17T17:37:52","date_gmt":"2024-09-17T15:37:52","guid":{"rendered":"https://weedy.fr/blog/?p=359280"},"modified":"2024-09-17T17:37:53","modified_gmt":"2024-09-17T15:37:53","slug":"cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber","status":"publish","type":"post","link":"https://weedy.fr/blog/pt/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber/","title":{"rendered":"Cobertura do CBD pela previdência social: o que você precisa saber"},"content":{"rendered":"<p>O <a href=\"https://weedy.fr/nl\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a>, ou canabidiol, é um composto da planta cannabis que está a atrair um interesse crescente pelos seus potenciais benefícios terapêuticos. Neste artigo, estamos interessados ​​na seguinte questão: <strong>O <a href=\"https://weedy.fr/nl\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> é coberto pela segurança social em França?</strong></p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire</p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle</span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http://www.w3.org/2000/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"></path></svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http://www.w3.org/2000/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"></path></svg></span></span></span></a></span></div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 \"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https://weedy.fr/nl/blog/pt/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber/#CBD_e_legislacao_francesa\">CBD e legislação francesa</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https://weedy.fr/nl/blog/pt/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber/#Autorizacao_de_determinados_medicamentos_a_base_de_canabinoides\">Autorização de determinados medicamentos à base de canabinóides</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https://weedy.fr/nl/blog/pt/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber/#CBD_e_seguranca_social_francesa\">CBD e segurança social francesa</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https://weedy.fr/nl/blog/pt/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber/#Perspectivas_de_desenvolvimento\">Perspectivas de desenvolvimento</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https://weedy.fr/nl/blog/pt/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber/#Alternativas_atuais\">Alternativas atuais</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https://weedy.fr/nl/blog/pt/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber/#Compre_CBD_on-line\">Compre CBD on-line</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https://weedy.fr/nl/blog/pt/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber/#Recorra_a_produtos_naturais_alternativos\">Recorra a produtos naturais alternativos</a></li></ul></li></ul></nav></div>\n<h2><span class=\"ez-toc-section\" id=\"CBD_e_legislacao_francesa\"></span>CBD e legislação francesa<span class=\"ez-toc-section-end\"></span></h2>\n<p>Em França, a legislação em torno da CDB é complexa. Embora esta substância venha da cannabis, ela não tem os mesmos efeitos psicotrópicos que seu primo THC (tetrahidrocanabinol). O <a href=\"https://weedy.fr/nl\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> não é, portanto, considerado um medicamento.</p>\n<p>No entanto, a sua venda e utilização estão sujeitas a controlos rigorosos em França. Para que um produto que contém CBD seja legal no território, deve cumprir vários critérios:</p>\n<ul>\n<li>Contém menos de 0,2% de THC.</li>\n<li>Seja de variedades de cannabis autorizadas.</li>\n<li>Não destinado ao consumo.</li>\n</ul>\n<p>Por outras palavras, apenas produtos feitos de cânhamo industrial – uma variedade de cannabis com um teor muito baixo de THC – podem ser comercializados em França.</p>\n<h3><span class=\"ez-toc-section\" id=\"Autorizacao_de_determinados_medicamentos_a_base_de_canabinoides\"></span>Autorização de determinados medicamentos à base de canabinóides<span class=\"ez-toc-section-end\"></span></h3>\n<p>Além disso, desde 2013, a França autorizou o uso de certos medicamentos à base de canabinóides. Isto diz respeito em particular ao <strong>Sativex</strong>, um spray oral prescrito para tratar a espasticidade relacionada à esclerose múltipla. No entanto, este produto ainda não é comercializado devido a um desacordo sobre o seu preço de venda entre as autoridades competentes e a empresa farmacêutica que o produz.</p>\n<h2><span class=\"ez-toc-section\" id=\"CBD_e_seguranca_social_francesa\"></span>CBD e segurança social francesa<span class=\"ez-toc-section-end\"></span></h2>\n<p>Para que um tratamento seja coberto pela segurança social, deve constar de uma lista de medicamentos reembolsáveis. Este registo depende de vários critérios, incluindo a reconhecida utilidade terapêutica, o interesse económico para a comunidade e o cumprimento das boas práticas de fabrico.</p>\n<p>Atualmente, nenhum medicamento contendo apenas CBD está incluído nesta lista em França. Portanto, <strong>a segurança social não cobre tratamentos baseados apenas no CBD</strong>.</p>\n<p>No entanto, como mencionado anteriormente, o Sativex, que contém THC e CBD, é autorizado em França sob certas condições. Se este medicamento fosse comercializado, poderia ser coberto pela segurança social.</p>\n<h3><span class=\"ez-toc-section\" id=\"Perspectivas_de_desenvolvimento\"></span>Perspectivas de desenvolvimento<span class=\"ez-toc-section-end\"></span></h3>\n<p>O reconhecimento dos potenciais benefícios terapêuticos do CBD poderia levar as autoridades francesas a modificar a sua posição relativamente à sua utilização. Na verdade, muitos países, como o Canadá ou a Suíça, já adotaram legislação mais permissiva em relação ao CBD e à sua prescrição médica.</p>\n<p>Estudos científicos demonstraram que o <strong>O CBD pode ser eficaz no tratamento de certas condições</strong>, como epilepsia, dor crônica, ansiedade ou mesmo distúrbios do sono. Estão em curso ensaios clínicos para avaliar o benefício terapêutico do canabidiol, e é possível que um dia esta substância seja reconhecida como um medicamento de pleno direito e reembolsável pela segurança social.</p>\n<h2><span class=\"ez-toc-section\" id=\"Alternativas_atuais\"></span>Alternativas atuais<span class=\"ez-toc-section-end\"></span></h2>\n<p>Embora o CBD não seja coberto pela segurança social, existem formas de obter o CBD de forma legal e segura em França.</p>\n<h3><span class=\"ez-toc-section\" id=\"Compre_CBD_on-line\"></span>Compre CBD on-line<span class=\"ez-toc-section-end\"></span></h3>\n<p>Uma das opções mais comuns é comprar CBD online. Muitas lojas online oferecem uma gama variada de produtos à base de CBD, tais como óleos, cápsulas e até e-líquidos para cigarros eletrónicos. Estes produtos são geralmente obtidos a partir de cânhamo industrial respeitando a legislação francesa.</p>\n<ul>\n<li>Verifique a legalidade: Antes de comprar CBD online, é aconselhável verificar se o produto está em conformidade com a regulamentação em vigor (teor de THC inferior a 0,2%).</li>\n<li>Análise laboratorial: Recomenda-se também escolher produtos que tenham sido submetidos a testes laboratoriais para confirmar a sua qualidade e conteúdo de CBD.</li>\n</ul>\n<h3><span class=\"ez-toc-section\" id=\"Recorra_a_produtos_naturais_alternativos\"></span>Recorra a produtos naturais alternativos<span class=\"ez-toc-section-end\"></span></h3>\n<p>Existem também outras plantas com propriedades relaxantes ou ansiolíticas, que podem ser utilizadas como alternativas ao CBD. Por exemplo :</p>\n<ul>\n<li>Valeriana: Esta erva é usada há muito tempo por seu efeito calmante e pode ajudar a combater a ansiedade e os distúrbios do sono.</li>\n<li>Erva de São João: Esta planta tem leve ação antidepressiva e pode ser tomada na forma de suplemento alimentar.</li>\n<li>Espinheiro: Possui propriedades calmantes e é utilizado para aliviar palpitações cardíacas e insônia.</li>\n</ul>\n<p>Por fim, é importante lembrar que a melhor forma de tratar uma condição ou sintoma continua sendo a consulta com um profissional de saúde, que poderá orientá-lo para o tratamento adequado à sua situação e às suas necessidades.</p>\n","protected":false},"excerpt":{"rendered":"<p>O CBD, ou canabidiol, é um composto da planta cannabis que está a atrair um interesse crescente pelos seus potenciais benefícios terapêuticos. Neste artigo, estamos interessados ​​na seguinte questão: O CBD é coberto pela segurança social em França? CBD e legislação francesa Em França, a legislação em torno da CDB é complexa. Embora esta substância [&hellip;]</p>\n","protected":false},"author":95,"featured_media":352201,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[675],"tags":[],"class_list":["post-359280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-sobre-cbd-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https://yoast.com/product/yoast-seo-premium-wordpress/ -->\n<title>Cobertura do CBD pela previdência social: o que você precisa saber - Actualités CBD Blog - Weedy.fr</title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" />\n<link rel=\"canonical\" href=\"https://weedy.fr/blog/pt/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber/\" />\n<meta property=\"og:locale\" content=\"fr_FR\" />\n<meta property=\"og:type\" content=\"article\" />\n<meta property=\"og:title\" content=\"🌱Cobertura do CBD pela previdência social: o que você precisa saber - Weedy.Fr🌱\" />\n<meta property=\"og:description\" content=\"O CBD, ou canabidiol, é um composto da planta cannabis que está a atrair um interesse crescente pelos seus potenciais benefícios terapêuticos. Neste artigo, estamos interessados ​​na seguinte questão: O CBD é coberto pela segurança social em França? CBD e legislação francesa Em França, a legislação em torno da CDB é complexa. Embora esta substância [&hellip;]\" />\n<meta property=\"og:url\" content=\"https://weedy.fr/blog/pt/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber/\" />\n<meta property=\"og:site_name\" content=\"Actualités CBD Blog - Weedy.fr\" />\n<meta property=\"article:publisher\" content=\"https://www.facebook.com/weedysocial\" />\n<meta property=\"article:published_time\" content=\"2024-09-17T15:37:52+00:00\" />\n<meta property=\"article:modified_time\" content=\"2024-09-17T15:37:53+00:00\" />\n<meta property=\"og:image\" content=\"https://weedy.fr/blog/wp-content/uploads/2024/01/la-prise-en-charge-du-cbd-par-la-securite-sociale-ce-quil-faut-savoir.jpg\" />\n\t<meta property=\"og:image:width\" content=\"1456\" />\n\t<meta property=\"og:image:height\" content=\"832\" />\n\t<meta property=\"og:image:type\" content=\"image/jpeg\" />\n<meta name=\"author\" content=\"Alexandre Lacarré\" />\n<meta name=\"twitter:card\" content=\"summary_large_image\" />\n<meta name=\"twitter:label1\" content=\"Écrit par\" />\n\t<meta name=\"twitter:data1\" content=\"Alexandre Lacarré\" />\n\t<meta name=\"twitter:label2\" content=\"Durée de lecture estimée\" />\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" />\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\/\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber\\/#article\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber\\/\"},\"author\":{\"name\":\"Alexandre Lacarré\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/54c87d7e580413b08a5b875474a54f4e\"},\"headline\":\"Cobertura do CBD pela previdência social: o que você precisa saber\",\"datePublished\":\"2024-09-17T15:37:52+00:00\",\"dateModified\":\"2024-09-17T15:37:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber\\/\"},\"wordCount\":756,\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/la-prise-en-charge-du-cbd-par-la-securite-sociale-ce-quil-faut-savoir.jpg\",\"articleSection\":[\"Notícias sobre CBD\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber\\/\",\"name\":\"Cobertura do CBD pela previdência social: o que você precisa saber - Actualités CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/la-prise-en-charge-du-cbd-par-la-securite-sociale-ce-quil-faut-savoir.jpg\",\"datePublished\":\"2024-09-17T15:37:52+00:00\",\"dateModified\":\"2024-09-17T15:37:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber\\/#primaryimage\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/la-prise-en-charge-du-cbd-par-la-securite-sociale-ce-quil-faut-savoir.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/la-prise-en-charge-du-cbd-par-la-securite-sociale-ce-quil-faut-savoir.jpg\",\"width\":1456,\"height\":832,\"caption\":\"La prise en charge du CBD par la sécurité sociale : ce qu'il faut savoir, cbd, composé, traitement\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notícias sobre CBD\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/category\\/noticias-sobre-cbd-pt\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cobertura do CBD pela previdência social: o que você precisa saber\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"name\":\"Actualités CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualité du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\/\\/weedy.fr\\/blog\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\"},\"sameAs\":[\"https:\\/\\/www.facebook.com\\/weedysocial\",\"https:\\/\\/www.instagram.com\\/weedyfrance\\/\"],\"description\":\"Leader en france sur la vente de produits à base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/54c87d7e580413b08a5b875474a54f4e\",\"name\":\"Alexandre Lacarré\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g\",\"url\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g\",\"caption\":\"Alexandre Lacarré\"},\"description\":\"Alexandre Lacarré est reconnu comme un leader innovant et influent dans l'industrie du cannabidiol (CBD). Alexandre a débuté sa carrière dans le secteur des biotechnologies, où il a acquis une expertise précieuse en recherche et développement. Passionné par les potentiels thérapeutiques des composés naturels, il s'est rapidement orienté vers l'industrie naissante du CBD.\",\"sameAs\":[\"https:\\/\\/www.linkedin.com\\/in\\/alexandre-henri-lacarr-785850186\\/\"],\"honorificPrefix\":\"Mr\",\"gender\":\"homme\",\"knowsAbout\":[\"CBD\",\"Cannabis\",\"Copywriter\"],\"worksFor\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/author\\/fiacre\\/\"}]}</script>\n<!-- / Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cobertura do CBD pela previdência social: o que você precisa saber - Actualités CBD Blog - Weedy.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://weedy.fr/blog/pt/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber/","og_locale":"fr_FR","og_type":"article","og_title":"🌱Cobertura do CBD pela previdência social: o que você precisa saber - Weedy.Fr🌱","og_description":"O CBD, ou canabidiol, é um composto da planta cannabis que está a atrair um interesse crescente pelos seus potenciais benefícios terapêuticos. Neste artigo, estamos interessados ​​na seguinte questão: O CBD é coberto pela segurança social em França? CBD e legislação francesa Em França, a legislação em torno da CDB é complexa. Embora esta substância [&hellip;]","og_url":"https://weedy.fr/blog/pt/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber/","og_site_name":"Actualités CBD Blog - Weedy.fr","article_publisher":"https://www.facebook.com/weedysocial","article_published_time":"2024-09-17T15:37:52+00:00","article_modified_time":"2024-09-17T15:37:53+00:00","og_image":[{"width":1456,"height":832,"url":"https://weedy.fr/nl/blog/wp-content/uploads/2024/01/la-prise-en-charge-du-cbd-par-la-securite-sociale-ce-quil-faut-savoir.jpg","type":"image/jpeg"}],"author":"Alexandre Lacarré","twitter_card":"summary_large_image","twitter_misc":{"Écrit par":"Alexandre Lacarré","Durée de lecture estimée":"4 minutes"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"Article","@id":"https://weedy.fr/blog/pt/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber/#article","isPartOf":{"@id":"https://weedy.fr/blog/pt/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber/"},"author":{"name":"Alexandre Lacarré","@id":"https://weedy.fr/blog/#/schema/person/54c87d7e580413b08a5b875474a54f4e"},"headline":"Cobertura do CBD pela previdência social: o que você precisa saber","datePublished":"2024-09-17T15:37:52+00:00","dateModified":"2024-09-17T15:37:53+00:00","mainEntityOfPage":{"@id":"https://weedy.fr/blog/pt/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber/"},"wordCount":756,"publisher":{"@id":"https://weedy.fr/blog/#organization"},"image":{"@id":"https://weedy.fr/blog/pt/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/la-prise-en-charge-du-cbd-par-la-securite-sociale-ce-quil-faut-savoir.jpg","articleSection":["Notícias sobre CBD"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https://weedy.fr/blog/pt/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber/","url":"https://weedy.fr/nl/blog/pt/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber/","name":"Cobertura do CBD pela previdência social: o que você precisa saber - Actualités CBD Blog - Weedy.fr","isPartOf":{"@id":"https://weedy.fr/blog/#website"},"primaryImageOfPage":{"@id":"https://weedy.fr/blog/pt/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber/#primaryimage"},"image":{"@id":"https://weedy.fr/blog/pt/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/la-prise-en-charge-du-cbd-par-la-securite-sociale-ce-quil-faut-savoir.jpg","datePublished":"2024-09-17T15:37:52+00:00","dateModified":"2024-09-17T15:37:53+00:00","breadcrumb":{"@id":"https://weedy.fr/blog/pt/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https://weedy.fr/blog/pt/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/pt/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber/#primaryimage","url":"https://weedy.fr/nl/blog/wp-content/uploads/2024/01/la-prise-en-charge-du-cbd-par-la-securite-sociale-ce-quil-faut-savoir.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/la-prise-en-charge-du-cbd-par-la-securite-sociale-ce-quil-faut-savoir.jpg","width":1456,"height":832,"caption":"La prise en charge du CBD par la sécurité sociale : ce qu'il faut savoir, cbd, composé, traitement"},{"@type":"BreadcrumbList","@id":"https://weedy.fr/blog/pt/cobertura-do-cbd-pela-previdencia-social-o-que-voce-precisa-saber/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https://weedy.fr/blog/"},{"@type":"ListItem","position":2,"name":"Notícias sobre CBD","item":"https://weedy.fr/blog/category/noticias-sobre-cbd-pt/"},{"@type":"ListItem","position":3,"name":"Cobertura do CBD pela previdência social: o que você precisa saber"}]},{"@type":"WebSite","@id":"https://weedy.fr/blog/#website","url":"https://weedy.fr/nl/blog/","name":"Actualités CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualité du CBD et du chanvre en France","publisher":{"@id":"https://weedy.fr/blog/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://weedy.fr/blog/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https://weedy.fr/blog/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https://weedy.fr/nl/blog/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/#/schema/logo/image/","url":"https://weedy.fr/nl/blog/wp-content/uploads/2024/05/logo-carre.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https://weedy.fr/blog/#/schema/logo/image/"},"sameAs":["https://www.facebook.com/weedysocial","https://www.instagram.com/weedyfrance/"],"description":"Leader en france sur la vente de produits à base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https://weedy.fr/blog/#/schema/person/54c87d7e580413b08a5b875474a54f4e","name":"Alexandre Lacarré","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://secure.gravatar.com/avatar/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g","url":"https://secure.gravatar.com/avatar/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/e5ede08fa6bfcbfc59ce9a91c3db2da4d48324aacb4d3157006c217cb2a2b125?s=96&d=mm&r=g","caption":"Alexandre Lacarré"},"description":"Alexandre Lacarré est reconnu comme un leader innovant et influent dans l'industrie du cannabidiol (CBD). Alexandre a débuté sa carrière dans le secteur des biotechnologies, où il a acquis une expertise précieuse en recherche et développement. Passionné par les potentiels thérapeutiques des composés naturels, il s'est rapidement orienté vers l'industrie naissante du CBD.","sameAs":["https://www.linkedin.com/in/alexandre-henri-lacarr-785850186/"],"honorificPrefix":"Mr","gender":"homme","knowsAbout":["CBD","Cannabis","Copywriter"],"worksFor":"Weedy.fr","url":"https://weedy.fr/nl/blog/author/fiacre/"}]}},"_links":{"self":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts"}],"about":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/users/95"}],"replies":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/comments?post=359280"}],"version-history":[{"count":1,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359280/revisions"}],"predecessor-version":[{"id":359281,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359280/revisions/359281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/media/352201"}],"wp:attachment":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/media?parent=359280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/categories?post=359280"},{"taxonomy":"post_tag","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/tags?post=359280"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}