{"id":359488,"date":"2024-09-17T17:41:57","date_gmt":"2024-09-17T15:41:57","guid":{"rendered":"https://weedy.fr/blog/?p=359488"},"modified":"2024-09-17T17:41:58","modified_gmt":"2024-09-17T15:41:58","slug":"a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2","status":"publish","type":"post","link":"https://weedy.fr/blog/pt/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2/","title":{"rendered":"A melhor receita de panqueca CBD para celebrar a Candelária"},"content":{"rendered":"\n<p>A Candelária é um feriado cristão que celebra a apresentação de Jesus no templo e, portanto, é comemorado no dia 2 de fevereiro. Também é conhecido como Festival das Luzes, onde velas são acesas para simbolizar a purificação através da luz. Mas hoje a Candelária é mais conhecida por ser uma oportunidade para preparar e saborear deliciosas panquecas! Então porque não experimentar uma nova receita este ano adicionando um ingrediente muito moderno: <strong><a href=\"https://weedy.fr/nl\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> (canabidiol)</strong> ? Aqui está a melhor receita de panqueca <a href=\"https://weedy.fr/nl\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> para você se deliciar durante a Candelária.</p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire</p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle</span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http://www.w3.org/2000/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"></path></svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http://www.w3.org/2000/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"></path></svg></span></span></span></a></span></div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 \"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https://weedy.fr/nl/blog/pt/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2/#Ingredientes_necessarios\">Ingredientes necessários</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https://weedy.fr/nl/blog/pt/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2/#Fazendo_a_massa_de_panqueca\">Fazendo a massa de panqueca</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https://weedy.fr/nl/blog/pt/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2/#Cozinhar_panquecas\">Cozinhar panquecas</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https://weedy.fr/nl/blog/pt/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2/#Cobertura_de_panqueca_CBD\">Cobertura de panqueca CBD</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https://weedy.fr/nl/blog/pt/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2/#Os_beneficios_do_CBD_em_panquecas\">Os benefícios do CBD em panquecas</a></li></ul></nav></div>\n<h2 class=\"wp-block-heading\" id=\"h-ingredients-necessaires\"><span class=\"ez-toc-section\" id=\"Ingredientes_necessarios\"></span>Ingredientes necessários<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p>Para fazer a sua receita de panqueca <a href=\"https://weedy.fr/nl\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a>, aqui está a lista de ingredientes que você vai precisar:</p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>250g de farinha</strong></li>\n\n\n\n<li>50cl de leite</li>\n\n\n\n<li>3 ovos</li>\n\n\n\n<li>1 pitada de sal</li>\n\n\n\n<li>4 colheres de sopa de óleo ou manteiga derretida</li>\n\n\n\n<li><strong>1 garrafa de óleo CBD</strong>, com a concentração de sua preferência</li>\n</ul>\n\n\n\n<p>Tenha o cuidado de escolher óleo CBD de qualidade de uma empresa reconhecida para garantir a autenticidade do produto e evitar qualquer risco à sua saúde.</p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-realisation-de-la-pate-a-crepes\"><span class=\"ez-toc-section\" id=\"Fazendo_a_massa_de_panqueca\"></span>Fazendo a massa de panqueca<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p>Siga os passos abaixo para fazer sua massa de panqueca CBD:</p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Em uma saladeira, misture a farinha e o sal.</strong></li>\n\n\n\n<li>Em seguida adicione os ovos e misture até obter uma massa homogênea.</li>\n\n\n\n<li>Adicione gradualmente o leite, continuando a mexer.</li>\n\n\n\n<li>Quando a massa estiver lisa, adicione o óleo ou a manteiga derretida e também algumas gotas de óleo CBD (dependendo do seu gosto e dos efeitos desejados).</li>\n</ol>\n\n\n\n<p>Depois de incorporados todos os ingredientes, deixe a massa descansar por cerca de 30 minutos. Isto permitirá que os sabores do CBD sejam efetivamente incorporados na preparação e que as panquecas fiquem mais macias.</p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-cuisson-des-crepes\"><span class=\"ez-toc-section\" id=\"Cozinhar_panquecas\"></span>Cozinhar panquecas<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p>Para preparar suas panquecas CBD, siga estes passos:</p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Aqueça uma frigideira antiaderente em fogo médio.</li>\n\n\n\n<li>Verifique se a panela está quente o suficiente, colocando uma pequena quantidade de massa &#8211; se começar a cozinhar sem grudar, a temperatura está correta.</li>\n\n\n\n<li>Despeje uma pequena concha de massa na panela, virando-a para espalhar a massa uniformemente e obter uma panqueca fina.</li>\n\n\n\n<li><strong>Cozinhe cada lado da panqueca</strong> por cerca de 1 a 2 minutos, até a panqueca ficar dourada.</li>\n\n\n\n<li>Repita os passos anteriores com a massa restante, untando levemente a forma entre cada panqueca, se necessário.</li>\n</ol>\n\n\n\n<p>Note que é possível ajustar a quantidade de CBD utilizada na receita dependendo dos efeitos desejados. Para um efeito leve, reduza a concentração de óleo adicionado à massa; para um efeito mais pronunciado, não hesite em adicionar algumas gotas adicionais ao preparo ou mesmo diretamente nas panquecas depois de cozidas.</p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-garniture-des-crepes-au-cbd\"><span class=\"ez-toc-section\" id=\"Cobertura_de_panqueca_CBD\"></span>Cobertura de panqueca CBD<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p>Para completar esta deliciosa receita, basta escolher a sua cobertura preferida! Algumas ideias:</p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mel ou xarope de bordo para um toque doce</li>\n\n\n\n<li>Geléia de frutas para um sabor picante</li>\n\n\n\n<li>Chocolate derretido para quem gosta de doces</li>\n\n\n\n<li>Fatias de banana e/ou nozes trituradas para dar consistência</li>\n\n\n\n<li>Uma bola de sorvete de baunilha ou um pouco de chantilly para ainda mais indulgência</li>\n</ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-les-bienfaits-du-cbd-dans-les-crepes\"><span class=\"ez-toc-section\" id=\"Os_beneficios_do_CBD_em_panquecas\"></span>Os benefícios do CBD em panquecas<span class=\"ez-toc-section-end\"></span></h2>\n\n\n\n<p>Adicionar <strong>CBD para suas panquecas de Candelária oferece vários benefícios</strong>, como:</p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Propriedades relaxantes e calmantes, que podem ajudar a aliviar o estresse, a ansiedade ou certas dores.</li>\n\n\n\n<li>Efeito antiinflamatório natural, benéfico para pessoas que sofrem de problemas articulares ou musculares.</li>\n\n\n\n<li>Melhoria potencial no sono e uma sensação geral de bem-estar.</li>\n</ul>\n\n\n\n<p>É importante notar que o CBD não tem os mesmos efeitos psicoativos que o THC (que causa o “efeito alto”), mas sim virtudes terapêuticas a descobrir ao preparar estas deliciosas panquecas de CBD para a Candelária!</p>\n\n","protected":false},"excerpt":{"rendered":"<p>A Candelária é um feriado cristão que celebra a apresentação de Jesus no templo e, portanto, é comemorado no dia 2 de fevereiro. Também é conhecido como Festival das Luzes, onde velas são acesas para simbolizar a purificação através da luz. Mas hoje a Candelária é mais conhecida por ser uma oportunidade para preparar e [&hellip;]</p>\n","protected":false},"author":97,"featured_media":352132,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[669,858],"tags":[],"class_list":["post-359488","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estilo-de-vida-cbd-pt","category-receita-de-cbd-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https://yoast.com/product/yoast-seo-premium-wordpress/ -->\n<title>Receita de Candelária: Panquecas CBD para um banquete relaxante</title>\n<meta name=\"description\" content=\"Descubra a nossa receita de panquecas CBD, aliando tradição e bem-estar. Ingredientes de qualidade, passos simples e dicas para uma experiência de degustação única.\" />\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" />\n<link rel=\"canonical\" href=\"https://weedy.fr/blog/pt/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2/\" />\n<meta property=\"og:locale\" content=\"fr_FR\" />\n<meta property=\"og:type\" content=\"article\" />\n<meta property=\"og:title\" content=\"🌱A melhor receita de panqueca CBD para celebrar a Candelária - Weedy.Fr🌱\" />\n<meta property=\"og:description\" content=\"Descubra a nossa receita de panquecas CBD, aliando tradição e bem-estar. Ingredientes de qualidade, passos simples e dicas para uma experiência de degustação única.\" />\n<meta property=\"og:url\" content=\"https://weedy.fr/blog/pt/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2/\" />\n<meta property=\"og:site_name\" content=\"Actualités CBD Blog - Weedy.fr\" />\n<meta property=\"article:publisher\" content=\"https://www.facebook.com/weedysocial\" />\n<meta property=\"article:published_time\" content=\"2024-09-17T15:41:57+00:00\" />\n<meta property=\"article:modified_time\" content=\"2024-09-17T15:41:58+00:00\" />\n<meta property=\"og:image\" content=\"https://weedy.fr/blog/wp-content/uploads/2024/01/crepe-cannabis-chandeleur.jpg\" />\n\t<meta property=\"og:image:width\" content=\"1300\" />\n\t<meta property=\"og:image:height\" content=\"867\" />\n\t<meta property=\"og:image:type\" content=\"image/jpeg\" />\n<meta name=\"author\" content=\"arthur\" />\n<meta name=\"twitter:card\" content=\"summary_large_image\" />\n<meta name=\"twitter:label1\" content=\"Écrit par\" />\n\t<meta name=\"twitter:data1\" content=\"arthur\" />\n\t<meta name=\"twitter:label2\" content=\"Durée de lecture estimée\" />\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" />\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\/\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2\\/#article\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2\\/\"},\"author\":{\"name\":\"arthur\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/0a05724dbfcfa68f2ce947d2ebf0f435\"},\"headline\":\"A melhor receita de panqueca CBD para celebrar a Candelária\",\"datePublished\":\"2024-09-17T15:41:57+00:00\",\"dateModified\":\"2024-09-17T15:41:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2\\/\"},\"wordCount\":607,\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/crepe-cannabis-chandeleur.jpg\",\"articleSection\":[\"Estilo de vida CBD\",\"Receita de CBD\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2\\/\",\"name\":\"Receita de Candelária: Panquecas CBD para um banquete relaxante\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/crepe-cannabis-chandeleur.jpg\",\"datePublished\":\"2024-09-17T15:41:57+00:00\",\"dateModified\":\"2024-09-17T15:41:58+00:00\",\"description\":\"Descubra a nossa receita de panquecas CBD, aliando tradição e bem-estar. Ingredientes de qualidade, passos simples e dicas para uma experiência de degustação única.\",\"breadcrumb\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\/\\/weedy.fr\\/blog\\/pt\\/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2\\/#primaryimage\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/crepe-cannabis-chandeleur.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/crepe-cannabis-chandeleur.jpg\",\"width\":1300,\"height\":867,\"caption\":\"Recette crèpes au CBD\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estilo de vida CBD\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/category\\/estilo-de-vida-cbd-pt\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"A melhor receita de panqueca CBD para celebrar a Candelária\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"name\":\"Actualités CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualité du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\/\\/weedy.fr\\/blog\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\"},\"sameAs\":[\"https:\\/\\/www.facebook.com\\/weedysocial\",\"https:\\/\\/www.instagram.com\\/weedyfrance\\/\"],\"description\":\"Leader en france sur la vente de produits à base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/0a05724dbfcfa68f2ce947d2ebf0f435\",\"name\":\"arthur\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"url\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g\",\"caption\":\"arthur\"},\"url\":\"https:\\/\\/weedy.fr\\/blog\\/author\\/arthur\\/\"}]}</script>\n<!-- / Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Receita de Candelária: Panquecas CBD para um banquete relaxante","description":"Descubra a nossa receita de panquecas CBD, aliando tradição e bem-estar. Ingredientes de qualidade, passos simples e dicas para uma experiência de degustação única.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://weedy.fr/blog/pt/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2/","og_locale":"fr_FR","og_type":"article","og_title":"🌱A melhor receita de panqueca CBD para celebrar a Candelária - Weedy.Fr🌱","og_description":"Descubra a nossa receita de panquecas CBD, aliando tradição e bem-estar. Ingredientes de qualidade, passos simples e dicas para uma experiência de degustação única.","og_url":"https://weedy.fr/blog/pt/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2/","og_site_name":"Actualités CBD Blog - Weedy.fr","article_publisher":"https://www.facebook.com/weedysocial","article_published_time":"2024-09-17T15:41:57+00:00","article_modified_time":"2024-09-17T15:41:58+00:00","og_image":[{"width":1300,"height":867,"url":"https://weedy.fr/nl/blog/wp-content/uploads/2024/01/crepe-cannabis-chandeleur.jpg","type":"image/jpeg"}],"author":"arthur","twitter_card":"summary_large_image","twitter_misc":{"Écrit par":"arthur","Durée de lecture estimée":"3 minutes"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"Article","@id":"https://weedy.fr/blog/pt/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2/#article","isPartOf":{"@id":"https://weedy.fr/blog/pt/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2/"},"author":{"name":"arthur","@id":"https://weedy.fr/blog/#/schema/person/0a05724dbfcfa68f2ce947d2ebf0f435"},"headline":"A melhor receita de panqueca CBD para celebrar a Candelária","datePublished":"2024-09-17T15:41:57+00:00","dateModified":"2024-09-17T15:41:58+00:00","mainEntityOfPage":{"@id":"https://weedy.fr/blog/pt/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2/"},"wordCount":607,"publisher":{"@id":"https://weedy.fr/blog/#organization"},"image":{"@id":"https://weedy.fr/blog/pt/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/crepe-cannabis-chandeleur.jpg","articleSection":["Estilo de vida CBD","Receita de CBD"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https://weedy.fr/blog/pt/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2/","url":"https://weedy.fr/nl/blog/pt/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2/","name":"Receita de Candelária: Panquecas CBD para um banquete relaxante","isPartOf":{"@id":"https://weedy.fr/blog/#website"},"primaryImageOfPage":{"@id":"https://weedy.fr/blog/pt/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2/#primaryimage"},"image":{"@id":"https://weedy.fr/blog/pt/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/crepe-cannabis-chandeleur.jpg","datePublished":"2024-09-17T15:41:57+00:00","dateModified":"2024-09-17T15:41:58+00:00","description":"Descubra a nossa receita de panquecas CBD, aliando tradição e bem-estar. Ingredientes de qualidade, passos simples e dicas para uma experiência de degustação única.","breadcrumb":{"@id":"https://weedy.fr/blog/pt/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https://weedy.fr/blog/pt/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/pt/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2/#primaryimage","url":"https://weedy.fr/nl/blog/wp-content/uploads/2024/01/crepe-cannabis-chandeleur.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/crepe-cannabis-chandeleur.jpg","width":1300,"height":867,"caption":"Recette crèpes au CBD"},{"@type":"BreadcrumbList","@id":"https://weedy.fr/blog/pt/a-melhor-receita-de-panqueca-cbd-para-celebrar-a-candelaria-2/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https://weedy.fr/blog/"},{"@type":"ListItem","position":2,"name":"Estilo de vida CBD","item":"https://weedy.fr/blog/category/estilo-de-vida-cbd-pt/"},{"@type":"ListItem","position":3,"name":"A melhor receita de panqueca CBD para celebrar a Candelária"}]},{"@type":"WebSite","@id":"https://weedy.fr/blog/#website","url":"https://weedy.fr/nl/blog/","name":"Actualités CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualité du CBD et du chanvre en France","publisher":{"@id":"https://weedy.fr/blog/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://weedy.fr/blog/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https://weedy.fr/blog/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https://weedy.fr/nl/blog/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/#/schema/logo/image/","url":"https://weedy.fr/nl/blog/wp-content/uploads/2024/05/logo-carre.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https://weedy.fr/blog/#/schema/logo/image/"},"sameAs":["https://www.facebook.com/weedysocial","https://www.instagram.com/weedyfrance/"],"description":"Leader en france sur la vente de produits à base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https://weedy.fr/blog/#/schema/person/0a05724dbfcfa68f2ce947d2ebf0f435","name":"arthur","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://secure.gravatar.com/avatar/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","url":"https://secure.gravatar.com/avatar/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/5492d9c9d06e584450143c20df70ba9391e6f2d50969b291a092b75f8230628a?s=96&d=mm&r=g","caption":"arthur"},"url":"https://weedy.fr/nl/blog/author/arthur/"}]}},"_links":{"self":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts"}],"about":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/users/97"}],"replies":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/comments?post=359488"}],"version-history":[{"count":1,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359488/revisions"}],"predecessor-version":[{"id":359489,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359488/revisions/359489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/media/352132"}],"wp:attachment":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/media?parent=359488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/categories?post=359488"},{"taxonomy":"post_tag","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/tags?post=359488"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}