{"id":359592,"date":"2024-09-17T17:43:50","date_gmt":"2024-09-17T15:43:50","guid":{"rendered":"https://weedy.fr/blog/?p=359592"},"modified":"2024-09-17T17:43:51","modified_gmt":"2024-09-17T15:43:51","slug":"interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber","status":"publish","type":"post","link":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber/","title":{"rendered":"Interação entre CBD e levotiroxina sódica: o que você precisa saber"},"content":{"rendered":"<p>O <strong>Canabidiol (<a href=\"https://weedy.fr/nl\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a>)</strong> é uma substância encontrada nas plantas de cannabis que está ganhando popularidade pelos seus efeitos na saúde. Na verdade, é conhecido pelas suas propriedades relaxantes, anti-inflamatórias e analgésicas. Por sua vez, o <strong>levotiroxina sódica</strong> é um medicamento prescrito para pessoas que sofrem de hipotireoidismo grave ou coma mixedematoso.</p>\n<p>Embora a utilização do <a href=\"https://weedy.fr/nl\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> esteja a tornar-se mais generalizada, existem muitas questões relacionadas com as suas possíveis interações com outros medicamentos, como antibióticos ou mesmo tratamentos para a dor. Este artigo pretende, assim, lançar luz sobre o assunto relativo à<strong>interação entre <a href=\"https://weedy.fr/nl\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> e levotiroxina sódica</strong>.</p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire</p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle</span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http://www.w3.org/2000/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"></path></svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http://www.w3.org/2000/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"></path></svg></span></span></span></a></span></div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 \"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https://weedy.fr/nl/blog/pt/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber/#CBD_e_interacoes_medicamentosas_uma_visao_geral\">CBD e interações medicamentosas: uma visão geral</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https://weedy.fr/nl/blog/pt/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber/#CBD_e_levotiroxina_sodica_quais_interacoes\">CBD e levotiroxina sódica: quais interações?</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https://weedy.fr/nl/blog/pt/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber/#Possiveis_efeitos_colaterais_de_interacoes_medicamentosas\">Possíveis efeitos colaterais de interações medicamentosas</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https://weedy.fr/nl/blog/pt/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber/#O_papel_dos_profissionais_de_saude_na_prevencao_de_interacoes_medicamentosas\">O papel dos profissionais de saúde na prevenção de interações medicamentosas</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https://weedy.fr/nl/blog/pt/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber/#CBD_e_levotiroxina_sodica_para_uma_melhor_compreensao_das_interacoes_medicamentosas\">CBD e levotiroxina sódica: para uma melhor compreensão das interações medicamentosas</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https://weedy.fr/nl/blog/pt/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber/#A_necessidade_de_mais_pesquisas\">A necessidade de mais pesquisas</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https://weedy.fr/nl/blog/pt/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber/#Uma_colaboracao_entre_pesquisadores_profissionais_de_saude_e_pacientes\">Uma colaboração entre pesquisadores, profissionais de saúde e pacientes</a></li></ul></li></ul></nav></div>\n<h2><span class=\"ez-toc-section\" id=\"CBD_e_interacoes_medicamentosas_uma_visao_geral\"></span>CBD e interações medicamentosas: uma visão geral<span class=\"ez-toc-section-end\"></span></h2>\n<p>Em primeiro lugar, é essencial compreender como podem ocorrer as interações medicamentosas, para melhor compreender os potenciais riscos associados ao consumo conjunto de CBD e levotiroxina sódica. Uma das principais causas de interações medicamentosas é o metabolismo pelas enzimas hepáticas. Estes permitem ao organismo eliminar substâncias ingeridas, mas também podem causar efeitos indesejáveis ​​em caso de inibição ou indução de certas enzimas.</p>\n<p>Assim, vários estudos têm demonstrado que o <strong>O CBD pode interagir com outros medicamentos</strong>, nomeadamente pela inibição das enzimas do citocromo P450 hepático (CYP450). Essa inibição resulta em uma redução na capacidade do organismo de metabolizar certos medicamentos, podendo causar efeitos indesejados.</p>\n<h2><span class=\"ez-toc-section\" id=\"CBD_e_levotiroxina_sodica_quais_interacoes\"></span>CBD e levotiroxina sódica: quais interações?<span class=\"ez-toc-section-end\"></span></h2>\n<p>A levotiroxina sódica é um medicamento pertencente à classe dos hormônios tireoidianos sintéticos, utilizado no tratamento do hipotireoidismo. Este medicamento está envolvido em diversas reações enzimáticas hepáticas, mais especificamente nas do CYP450.</p>\n<p>Embora os dados disponíveis ainda sejam limitados, alguns estudos sugerem que a interação entre <strong>CBD e levotiroxina sódica</strong> seria mínima ou mesmo inexistente. No entanto, alguns cuidados devem ser tomados:</p>\n<ul>\n<li>Recomenda-se espaçar a tomada do medicamento e do CBD em 2 a 4 horas para minimizar possíveis interferências entre as duas substâncias.</li>\n<li>Deve-se também ter cuidado ao consumir produtos de CBD contendo quantidades variadas de THC (delta-9-tetrahidrocanabinol), pois o THC pode influenciar o equilíbrio hormonal e interromper o tratamento com levotiroxina.</li>\n</ul>\n<h3><span class=\"ez-toc-section\" id=\"Possiveis_efeitos_colaterais_de_interacoes_medicamentosas\"></span>Possíveis efeitos colaterais de interações medicamentosas<span class=\"ez-toc-section-end\"></span></h3>\n<p>Embora as evidências que apoiam uma interação entre o CBD e a levotiroxina sódica sejam limitadas, é importante notar que algumas combinações de medicamentos podem ser mais ou menos perigosas. </p>\n<p>Alguns <strong>interações medicamentosas</strong> pode causar efeitos indesejáveis ​​como:</p>\n<ul>\n<li>Uma redução na eficácia do tratamento.</li>\n<li>Um risco aumentado de complicações associadas à ingestão conjunta de várias substâncias (epilepsia, riscos cardíacos, etc.).</li>\n<li>A ocorrência de contraindicações para determinados tratamentos, que podem comprometer a saúde do paciente.</li>\n</ul>\n<h2><span class=\"ez-toc-section\" id=\"O_papel_dos_profissionais_de_saude_na_prevencao_de_interacoes_medicamentosas\"></span>O papel dos profissionais de saúde na prevenção de interações medicamentosas<span class=\"ez-toc-section-end\"></span></h2>\n<p>Diante da possibilidade de interação entre o CBD e a levotiroxina sódica, é fundamental falar com o seu médico ou farmacêutico. Este último poderá aconselhá-lo para evitar perigos potenciais e garantir que o seu tratamento não seja comprometido pelo uso do CBD.</p>\n<p>Partilhar os seus hábitos de consumo de produtos de CBD com um profissional de saúde também permite mantê-los informados sobre a evolução das utilizações terapêuticas dos canabinóides, para que possam estar plenamente conscientes dos riscos ou benefícios que estes produtos podem ter para os seus pacientes.</p>\n<h2><span class=\"ez-toc-section\" id=\"CBD_e_levotiroxina_sodica_para_uma_melhor_compreensao_das_interacoes_medicamentosas\"></span>CBD e levotiroxina sódica: para uma melhor compreensão das interações medicamentosas<span class=\"ez-toc-section-end\"></span></h2>\n<p>Hoje, embora ainda existam muitas áreas cinzentas sobre as possíveis interacções entre o CBD e a levotiroxina sódica, a investigação está a progredir para fornecer respostas sobre este assunto. Os experimentos realizados até o momento mostram que o<strong>a interação entre essas duas substâncias parece mínima</strong>.</p>\n<h3><span class=\"ez-toc-section\" id=\"A_necessidade_de_mais_pesquisas\"></span>A necessidade de mais pesquisas<span class=\"ez-toc-section-end\"></span></h3>\n<p>A crescente popularidade do CBD está a criar uma necessidade crescente de estudos científicos para compreender melhor como esta substância interage com outros medicamentos. Quando se trata de interações medicamentosas, cada caso é único e por isso é necessário considerar todas as combinações possíveis para garantir a segurança do usuário.</p>\n<p>É essencial que os investigadores continuem a estudar as diferentes formas como o CBD pode interagir com vários tratamentos medicamentosos, a fim de prevenir quaisquer riscos para a saúde pública associados à toma destas substâncias em conjunto.</p>\n<h3><span class=\"ez-toc-section\" id=\"Uma_colaboracao_entre_pesquisadores_profissionais_de_saude_e_pacientes\"></span>Uma colaboração entre pesquisadores, profissionais de saúde e pacientes<span class=\"ez-toc-section-end\"></span></h3>\n<p>Para aprofundar o nosso conhecimento nesta área é fundamental que profissionais de saúde, investigadores e doentes colaborem. Este trabalho colaborativo permitirá avaliar com maior precisão possíveis interações entre o CBD e os diversos medicamentos prescritos, de forma a garantir a segurança dos consumidores e evitar complicações médicas desnecessárias.</p>\n","protected":false},"excerpt":{"rendered":"<p>O Canabidiol (CBD) é uma substância encontrada nas plantas de cannabis que está ganhando popularidade pelos seus efeitos na saúde. Na verdade, é conhecido pelas suas propriedades relaxantes, anti-inflamatórias e analgésicas. Por sua vez, o levotiroxina sódica é um medicamento prescrito para pessoas que sofrem de hipotireoidismo grave ou coma mixedematoso. Embora a utilização do [&hellip;]</p>\n","protected":false},"author":41,"featured_media":352066,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[672],"tags":[],"class_list":["post-359592","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude-e-bem-estar-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https://yoast.com/product/yoast-seo-premium-wordpress/ -->\n<title>Interação entre CBD e levotiroxina sódica: o que você precisa saber - Actualités CBD Blog - Weedy.fr</title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" />\n<link rel=\"canonical\" href=\"https://weedy.fr/blog/pt/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber/\" />\n<meta property=\"og:locale\" content=\"fr_FR\" />\n<meta property=\"og:type\" content=\"article\" />\n<meta property=\"og:title\" content=\"🌱Interação entre CBD e levotiroxina sódica: o que você precisa saber - Weedy.Fr🌱\" />\n<meta property=\"og:description\" content=\"O Canabidiol (CBD) é uma substância encontrada nas plantas de cannabis que está ganhando popularidade pelos seus efeitos na saúde. Na verdade, é conhecido pelas suas propriedades relaxantes, anti-inflamatórias e analgésicas. Por sua vez, o levotiroxina sódica é um medicamento prescrito para pessoas que sofrem de hipotireoidismo grave ou coma mixedematoso. Embora a utilização do [&hellip;]\" />\n<meta property=\"og:url\" content=\"https://weedy.fr/blog/pt/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber/\" />\n<meta property=\"og:site_name\" content=\"Actualités CBD Blog - Weedy.fr\" />\n<meta property=\"article:publisher\" content=\"https://www.facebook.com/weedysocial\" />\n<meta property=\"article:author\" content=\"https://www.facebook.com/weedysocial/\" />\n<meta property=\"article:published_time\" content=\"2024-09-17T15:43:50+00:00\" />\n<meta property=\"article:modified_time\" content=\"2024-09-17T15:43:51+00:00\" />\n<meta property=\"og:image\" content=\"https://weedy.fr/blog/wp-content/uploads/2024/01/interaction-entre-le-cbd-et-la-levothyroxine-sodique-ce-quil-faut-savoir.jpg\" />\n\t<meta property=\"og:image:width\" content=\"1456\" />\n\t<meta property=\"og:image:height\" content=\"832\" />\n\t<meta property=\"og:image:type\" content=\"image/jpeg\" />\n<meta name=\"author\" content=\"Julien Cordobes\" />\n<meta name=\"twitter:card\" content=\"summary_large_image\" />\n<meta name=\"twitter:label1\" content=\"Écrit par\" />\n\t<meta name=\"twitter:data1\" content=\"Julien Cordobes\" />\n\t<meta name=\"twitter:label2\" content=\"Durée de lecture estimée\" />\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" />\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\/\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber\\/#article\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber\\/\"},\"author\":{\"name\":\"Julien Cordobes\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/72583fcd87d7cf46afe11d530945bc7e\"},\"headline\":\"Interação entre CBD e levotiroxina sódica: o que você precisa saber\",\"datePublished\":\"2024-09-17T15:43:50+00:00\",\"dateModified\":\"2024-09-17T15:43:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber\\/\"},\"wordCount\":824,\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/interaction-entre-le-cbd-et-la-levothyroxine-sodique-ce-quil-faut-savoir.jpg\",\"articleSection\":[\"Saúde e Bem-estar\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber\\/\",\"name\":\"Interação entre CBD e levotiroxina sódica: o que você precisa saber - Actualités CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/interaction-entre-le-cbd-et-la-levothyroxine-sodique-ce-quil-faut-savoir.jpg\",\"datePublished\":\"2024-09-17T15:43:50+00:00\",\"dateModified\":\"2024-09-17T15:43:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber\\/#primaryimage\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/interaction-entre-le-cbd-et-la-levothyroxine-sodique-ce-quil-faut-savoir.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/01\\/interaction-entre-le-cbd-et-la-levothyroxine-sodique-ce-quil-faut-savoir.jpg\",\"width\":1456,\"height\":832,\"caption\":\"Interaction entre le CBD et la lévothyroxine sodique : ce qu'il faut savoir, keywords: allié, traitement, interaction, substances, effets, médicaments, dangers, épilepsie, risques cardiaques, contre-indications, métabolites, enzymes hépatiques, douleur, hypothyroïdie sévère, coma myxoedémateux, mélange hyperthyroïdie et cannabis, medical marijuana, antibiotics, covid-19 therapies, pharmacopoeia section, herbal medicines, dietary supplements, nutraceuticals, drug dosage, weight loss purposes, therapeutic goods order 2017, sodium poisoning, cannabis use and drug-drug interaction risk, cbd oil and cannabis tinctures for pain and anxiety\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Saúde e Bem-estar\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/category\\/saude-e-bem-estar-pt\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Interação entre CBD e levotiroxina sódica: o que você precisa saber\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"name\":\"Actualités CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualité du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\/\\/weedy.fr\\/blog\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\"},\"sameAs\":[\"https:\\/\\/www.facebook.com\\/weedysocial\",\"https:\\/\\/www.instagram.com\\/weedyfrance\\/\"],\"description\":\"Leader en france sur la vente de produits à base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/72583fcd87d7cf46afe11d530945bc7e\",\"name\":\"Julien Cordobes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"url\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"caption\":\"Julien Cordobes\"},\"description\":\"Rédacteur en chef spécialisé en CBD Julien, né le 17 juillet 1978 en région Parisienne, est un éminent rédacteur et expert dans le domaine des produits à base de CBD. Suite à ses études en biologie et en médecine alternative, Julien a développé une passion pour les remèdes naturels, dont le CBD. En 2022, il intègre l’équipe du site Weedy.fr en qualité d’expert et de contributeur régulier. Grâce à son expertise scientifique et une écriture claire, Julien aide à démystifier les aspects complexes du CBD, tout en mettant en lumière ses bienfaits et applications potentielles à travers ses articles et participations à des conférences.\",\"sameAs\":[\"https:\\/\\/weedy.fr\",\"https:\\/\\/www.facebook.com\\/weedysocial\\/\",\"https:\\/\\/www.instagram.com\\/weedyfrance\",\"https:\\/\\/www.pinterest.fr\\/WeedyFrance\\/\"],\"honorificPrefix\":\"Mr\",\"birthDate\":\"1978-07-17\",\"gender\":\"male\",\"knowsAbout\":[\"CBD\",\"Cannabis\",\"Copywriter\"],\"knowsLanguage\":[\"French\"],\"jobTitle\":\"Editor-in-chief specializing in CBD\",\"worksFor\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/author\\/cbd_blog_owner\\/\"}]}</script>\n<!-- / Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Interação entre CBD e levotiroxina sódica: o que você precisa saber - Actualités CBD Blog - Weedy.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber/","og_locale":"fr_FR","og_type":"article","og_title":"🌱Interação entre CBD e levotiroxina sódica: o que você precisa saber - Weedy.Fr🌱","og_description":"O Canabidiol (CBD) é uma substância encontrada nas plantas de cannabis que está ganhando popularidade pelos seus efeitos na saúde. Na verdade, é conhecido pelas suas propriedades relaxantes, anti-inflamatórias e analgésicas. Por sua vez, o levotiroxina sódica é um medicamento prescrito para pessoas que sofrem de hipotireoidismo grave ou coma mixedematoso. Embora a utilização do [&hellip;]","og_url":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber/","og_site_name":"Actualités CBD Blog - Weedy.fr","article_publisher":"https://www.facebook.com/weedysocial","article_author":"https://www.facebook.com/weedysocial/","article_published_time":"2024-09-17T15:43:50+00:00","article_modified_time":"2024-09-17T15:43:51+00:00","og_image":[{"width":1456,"height":832,"url":"https://weedy.fr/nl/blog/wp-content/uploads/2024/01/interaction-entre-le-cbd-et-la-levothyroxine-sodique-ce-quil-faut-savoir.jpg","type":"image/jpeg"}],"author":"Julien Cordobes","twitter_card":"summary_large_image","twitter_misc":{"Écrit par":"Julien Cordobes","Durée de lecture estimée":"4 minutes"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"Article","@id":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber/#article","isPartOf":{"@id":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber/"},"author":{"name":"Julien Cordobes","@id":"https://weedy.fr/blog/#/schema/person/72583fcd87d7cf46afe11d530945bc7e"},"headline":"Interação entre CBD e levotiroxina sódica: o que você precisa saber","datePublished":"2024-09-17T15:43:50+00:00","dateModified":"2024-09-17T15:43:51+00:00","mainEntityOfPage":{"@id":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber/"},"wordCount":824,"publisher":{"@id":"https://weedy.fr/blog/#organization"},"image":{"@id":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/interaction-entre-le-cbd-et-la-levothyroxine-sodique-ce-quil-faut-savoir.jpg","articleSection":["Saúde e Bem-estar"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber/","url":"https://weedy.fr/nl/blog/pt/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber/","name":"Interação entre CBD e levotiroxina sódica: o que você precisa saber - Actualités CBD Blog - Weedy.fr","isPartOf":{"@id":"https://weedy.fr/blog/#website"},"primaryImageOfPage":{"@id":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber/#primaryimage"},"image":{"@id":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/interaction-entre-le-cbd-et-la-levothyroxine-sodique-ce-quil-faut-savoir.jpg","datePublished":"2024-09-17T15:43:50+00:00","dateModified":"2024-09-17T15:43:51+00:00","breadcrumb":{"@id":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https://weedy.fr/blog/pt/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber/#primaryimage","url":"https://weedy.fr/nl/blog/wp-content/uploads/2024/01/interaction-entre-le-cbd-et-la-levothyroxine-sodique-ce-quil-faut-savoir.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/01/interaction-entre-le-cbd-et-la-levothyroxine-sodique-ce-quil-faut-savoir.jpg","width":1456,"height":832,"caption":"Interaction entre le CBD et la lévothyroxine sodique : ce qu'il faut savoir, keywords: allié, traitement, interaction, substances, effets, médicaments, dangers, épilepsie, risques cardiaques, contre-indications, métabolites, enzymes hépatiques, douleur, hypothyroïdie sévère, coma myxoedémateux, mélange hyperthyroïdie et cannabis, medical marijuana, antibiotics, covid-19 therapies, pharmacopoeia section, herbal medicines, dietary supplements, nutraceuticals, drug dosage, weight loss purposes, therapeutic goods order 2017, sodium poisoning, cannabis use and drug-drug interaction risk, cbd oil and cannabis tinctures for pain and anxiety"},{"@type":"BreadcrumbList","@id":"https://weedy.fr/blog/pt/interacao-entre-cbd-e-levotiroxina-sodica-o-que-voce-precisa-saber/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https://weedy.fr/blog/"},{"@type":"ListItem","position":2,"name":"Saúde e Bem-estar","item":"https://weedy.fr/blog/category/saude-e-bem-estar-pt/"},{"@type":"ListItem","position":3,"name":"Interação entre CBD e levotiroxina sódica: o que você precisa saber"}]},{"@type":"WebSite","@id":"https://weedy.fr/blog/#website","url":"https://weedy.fr/nl/blog/","name":"Actualités CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualité du CBD et du chanvre en France","publisher":{"@id":"https://weedy.fr/blog/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://weedy.fr/blog/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https://weedy.fr/blog/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https://weedy.fr/nl/blog/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/#/schema/logo/image/","url":"https://weedy.fr/nl/blog/wp-content/uploads/2024/05/logo-carre.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https://weedy.fr/blog/#/schema/logo/image/"},"sameAs":["https://www.facebook.com/weedysocial","https://www.instagram.com/weedyfrance/"],"description":"Leader en france sur la vente de produits à base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https://weedy.fr/blog/#/schema/person/72583fcd87d7cf46afe11d530945bc7e","name":"Julien Cordobes","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","url":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","caption":"Julien Cordobes"},"description":"Rédacteur en chef spécialisé en CBD Julien, né le 17 juillet 1978 en région Parisienne, est un éminent rédacteur et expert dans le domaine des produits à base de CBD. Suite à ses études en biologie et en médecine alternative, Julien a développé une passion pour les remèdes naturels, dont le CBD. En 2022, il intègre l’équipe du site Weedy.fr en qualité d’expert et de contributeur régulier. Grâce à son expertise scientifique et une écriture claire, Julien aide à démystifier les aspects complexes du CBD, tout en mettant en lumière ses bienfaits et applications potentielles à travers ses articles et participations à des conférences.","sameAs":["https://weedy.fr","https://www.facebook.com/weedysocial/","https://www.instagram.com/weedyfrance","https://www.pinterest.fr/WeedyFrance/"],"honorificPrefix":"Mr","birthDate":"1978-07-17","gender":"male","knowsAbout":["CBD","Cannabis","Copywriter"],"knowsLanguage":["French"],"jobTitle":"Editor-in-chief specializing in CBD","worksFor":"Weedy.fr","url":"https://weedy.fr/nl/blog/author/cbd_blog_owner/"}]}},"_links":{"self":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts"}],"about":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/users/41"}],"replies":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/comments?post=359592"}],"version-history":[{"count":1,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359592/revisions"}],"predecessor-version":[{"id":359593,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/359592/revisions/359593"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/media/352066"}],"wp:attachment":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/media?parent=359592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/categories?post=359592"},{"taxonomy":"post_tag","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/tags?post=359592"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}