{"id":360528,"date":"2024-09-17T18:05:01","date_gmt":"2024-09-17T16:05:01","guid":{"rendered":"https://weedy.fr/blog/?p=360528"},"modified":"2024-09-17T18:05:02","modified_gmt":"2024-09-17T16:05:02","slug":"oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas","status":"publish","type":"post","link":"https://weedy.fr/blog/pt/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas/","title":{"rendered":"Óleo CBD de espectro completo ou amplo? As diferenças."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"360528\" class=\"elementor elementor-360528\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1465b0e2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1465b0e2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c61693a\" data-id=\"4c61693a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36d75f76 elementor-widget elementor-widget-text-editor\" data-id=\"36d75f76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tComme si les nombreux sigles associés au <a href=\"https://weedy.fr/nl\" data-internallinksmanager029f6b8e52c=\"1\" title=\"CBD - cannabidiol\">CBD</a> et aux dérivés du cannabis légal en général ne suffisaient pas, voilà que les étiquettes s’amusent à donner certaines indications en anglais.\n\nLes plus courantes d’entre elles ? « <strong><a href=\"https://weedy.fr/nl/product-category/huiles-cbd/\" data-internallinksmanager029f6b8e52c=\"7\" title=\"huile cbd\">Huile CBD</a> full spectrum</strong> » et « <strong><a href=\"https://weedy.fr/nl/product-category/huiles-cbd/\" data-internallinksmanager029f6b8e52c=\"7\" title=\"huile cbd\">Huile CBD</a> broad spectrum</strong> ». Pardon ?\n<p style=\"text-align: center;\"><iframe class=\"giphy-embed\" src=\"https://giphy.com/embed/2wgTJVJi2aSotGG7wU\" width=\"480\" height=\"454\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"></iframe></p>\nRassurez-vous, rien de bien compliqué et aucun risque à choisir l’une plutôt que l’autre. Quelques détails permettent néanmoins de distinguer ces deux produits dont la recette varie légèrement.\n\n<a href=\"https://weedy.fr/nl\" data-internallinksmanager029f6b8e52c=\"8\" title=\"weedy\">Weedy.fr</a> vous explique et vous aide à <strong>bien choisir</strong>, selon votre situation particulière.\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire</p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle</span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #43b981;color:#43b981\" xmlns=\"http://www.w3.org/2000/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"></path></svg><svg style=\"fill: #43b981;color:#43b981\" class=\"arrow-unsorted-368013\" xmlns=\"http://www.w3.org/2000/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"></path></svg></span></span></span></a></span></div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1 \"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https://weedy.fr/nl/blog/pt/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas/#Huile_CBD_full_spectrum_ou_broad_spectrum_definitions\">Huile CBD full spectrum ou broad spectrum, definitions</a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https://weedy.fr/nl/blog/pt/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas/#Huile_CBD_full_spectrum\">Huile CBD full spectrum</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https://weedy.fr/nl/blog/pt/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas/#Huile_CBD_broad_spectrum\">Huile CBD broad spectrum</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https://weedy.fr/nl/blog/pt/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas/#Les_derives_au_cannabidiol_appartiennent-il_forcement_a_lune_de_ces_categories\">Les dérivés au cannabidiol appartiennent-il forcément à l&rsquo;une de ces catégories ?</a></li></ul></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https://weedy.fr/nl/blog/pt/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas/#Lhuile_de_CBD_full_spectrum_contient-elle_du_THC\">L&rsquo;huile de CBD full spectrum contient-elle du THC ?</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https://weedy.fr/nl/blog/pt/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas/#Quelle_est_lhuile_de_CBD_la_plus_efficace\">Quelle est l&rsquo;huile de CBD la plus efficace ?</a></li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https://weedy.fr/nl/blog/pt/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas/#Quand_privilegier_une_huile_CBD_broad_spectrum_ou_full_spectrum\">Quand privilégier une huile CBD broad spectrum ou full spectrum ?</a></li></ul></nav></div>\n<h2><span class=\"ez-toc-section\" id=\"Huile_CBD_full_spectrum_ou_broad_spectrum_definitions\"></span>Huile CBD full spectrum ou broad spectrum, definitions<span class=\"ez-toc-section-end\"></span></h2>\n<figure id=\"attachment_339785\" aria-describedby=\"caption-attachment-339785\" style=\"width: 900px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-339785\" src=\"https://weedy.fr/wp-content/uploads/2023/04/Plus-de-composants-du-cannabis-dans-une-huile-CBD-full-spectrum-min.jpg\" alt=\"plus de composants du cannabis dans une huile cbd full spectrum min\" width=\"900\" height=\"585\"><figcaption id=\"caption-attachment-339785\" class=\"wp-caption-text\">Une <a href=\"https://weedy.fr/nl/product-category/huiles-cbd/\" data-internallinksmanager029f6b8e52c=\"7\" title=\"huile cbd\">huile CBD</a> full spectrum contient plus de composants de la fleur de cannabis que l’huile broad spectrum</figcaption></figure>\n<h3><span class=\"ez-toc-section\" id=\"Huile_CBD_full_spectrum\"></span>Huile CBD full spectrum<span class=\"ez-toc-section-end\"></span></h3>\nL’<a href=\"https://weedy.fr/nl/product-category/huiles-cbd/huile-cbd-full-spectrum/\">huile CBD full spectrum</a>, pour <strong>spectre complet</strong>, est un produit dérivé du cannabis légal composée d’une base d’huile végétale (souvent de l’<a href=\"https://weedy.fr/nl/blog/tout-savoir-sur-lhuile-de-chanvre/\">huile de chanvre</a> ou de l’<a href=\"https://weedy.fr/nl/blog/quest-ce-que-lhuile-mct/\">huile MCT</a>, produite à partir de la matière grasse de la noix de coco). À cette base est ensuite ajoutée une extraction des composés actifs présents dans les trichomes des fleurs de chanvre.\n\nParmi eux, on retrouve bien évidemment le cannabidiol (CBD), mais également <strong>l’ensemble des cannabinoïdes</strong> naturellement produits par la plante (<a href=\"https://weedy.fr/nl/blog/cbg-definition/\">CBG</a>, <a href=\"https://weedy.fr/nl/blog/quest-ce-que-le-cbn-cannabinol/\">CBN</a>, <a href=\"https://weedy.fr/nl/blog/quest-ce-que-le-cbc/\">CBC</a> et même le <a href=\"https://weedy.fr/nl/quest-ce-que-le-thc\">THC</a>).\n\nEn plus des cannabinoïdes, les <a href=\"https://weedy.fr/nl/blog/terpenes-cbd/\">terpènes</a> et flavonoïdes sont eux aussi conservés. Ils contribuent notamment à l’odeur et au goût de la plante. Ces molécules, toutes ensemble, créent une synergie appelée <a href=\"https://weedy.fr/nl/blog/effet-dentourage/\">effet d&rsquo;entourage</a>. Cela permet des <strong>effets plus larges et marqués</strong> qu’en isolant les différents éléments. Le <strong>bouquet aromatique</strong> est également plus intéressant.\n<blockquote>Pour résumer, une <a href=\"https://weedy.fr/nl/product-category/huiles-cbd/\" data-internallinksmanager029f6b8e52c=\"7\" title=\"huile cbd\">huile CBD</a> full spectrum regroupe l’ensemble des composés actifs du chanvre sous la forme d’une <strong>huile facile à doser, à transporter et à utiliser</strong>.</blockquote>\n<h3><span class=\"ez-toc-section\" id=\"Huile_CBD_broad_spectrum\"></span>Huile CBD broad spectrum<span class=\"ez-toc-section-end\"></span></h3>\nL’<a href=\"https://weedy.fr/nl/product-category/huiles-cbd/\" data-internallinksmanager029f6b8e52c=\"7\" title=\"huile cbd\">huile CBD</a> broad spectrum, pour <strong>spectre large</strong>, reprend le même principe, à l’exception près que certains composants sont volontairement écartés. Dans la très grande majorité des cas, un <a href=\"https://weedy.fr/nl/blog/comprendre-les-cannabinoides-tout-sur-ces-composes-fascinants/\" data-internallinksmanager029f6b8e52c=\"10\" title=\"cannabinoïde\">cannabinoïde</a> en particulier est retiré et n’entre donc pas dans la composition du produit fini : le <strong>tétrahydrocannabinol</strong>.\n\nPlus connu sous l’abréviation THC, il est le <a href=\"https://weedy.fr/nl/blog/comprendre-les-cannabinoides-tout-sur-ces-composes-fascinants/\" data-internallinksmanager029f6b8e52c=\"10\" title=\"cannabinoïde\">cannabinoïde</a> responsable des <strong>effets planants</strong> de la marijuana mais aussi du <strong>risque d’addiction</strong> qu’encourent ses consommateurs. D’ailleurs, <a href=\"https://weedy.fr/nl/blog/differences-entre-cbd-thc/\">le THC et le CBD</a> ont des effets bien différents. Ce sont ces différences qui justifient que le premier est considéré comme un stupéfiant et que le second est 100% légal.\n\nPar abus de langage, certaines marques vantent les mérites de leurs produits à spectre complet, tout en précisant qu’ils <strong>ne contiennent pas de THC</strong> : il s’agit alors en fait de dérivés broad spectrum. Dans les faits, cela <strong>ne change pas grand-chose pour le consommateur</strong>, ni en regard des effets provoqués, ni de leur santé. Nous y revenons dans un instant.\n<h3><span class=\"ez-toc-section\" id=\"Les_derives_au_cannabidiol_appartiennent-il_forcement_a_lune_de_ces_categories\"></span>Les dérivés au cannabidiol appartiennent-il forcément à l&rsquo;une de ces catégories ?<span class=\"ez-toc-section-end\"></span></h3>\nEh bien non, il existe une troisième catégorie, que vous avez sûrement déjà rencontrée si vous vous intéressez aux produits dérivés du cannabis légal. Cette troisième catégorie est l&rsquo;isolat de CBD. Elle englobe les dérivés qui ne contiennent <strong>que du cannabidiol</strong> et aucun autre cannabinoïde, ni d&rsquo;ailleurs de flavonoïdes ou de terpènes.\n\nLes isolats, comme certaines huiles mais aussi les <a href=\"https://weedy.fr/nl/product/cristaux-cbd\">cristaux de CBD</a>, sont très pratiques pour des besoins concentrés autour des <strong>bienfaits du CBD seul</strong>. Ils permettent également de <strong>faire facilement ses propres produits au CBD</strong>. Néanmoins, leurs effets sont limités par rapport à une huile CBD broad spectrum ou full spectrum. Ils garantissent néanmoins un produit <strong>sans THC</strong>.\n\n<figure id=\"attachment_339784\" aria-describedby=\"caption-attachment-339784\" style=\"width: 900px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-full wp-image-339784\" src=\"https://weedy.fr/wp-content/uploads/2023/04/Effets-huile-CBD-full-spectrum-broad-spectrum-min.jpg\" alt=\"effets huile cbd full spectrum broad spectrum min\" width=\"900\" height=\"900\"><figcaption id=\"caption-attachment-339784\" class=\"wp-caption-text\">Les différentes huiles CBD proposent des effets plus ou moins ciblés</figcaption></figure>\n<h2><span class=\"ez-toc-section\" id=\"Lhuile_de_CBD_full_spectrum_contient-elle_du_THC\"></span>L&rsquo;huile de CBD full spectrum contient-elle du THC ?<span class=\"ez-toc-section-end\"></span></h2>\nTechniquement, oui. Néanmoins, la présence de THC est strictement régulée par les législations des différents pays. Au sein de l’Union européenne, le droit supranational vaut et c’est donc la <a href=\"https://univ-droit.fr/recherche/actualites-de-la-recherche/manifestations/45779-droit-de-l-ue-et-jurisprudence-en-matiere-de-cbd\" target=\"_blank\" rel=\"noopener\">cour européenne</a> qui a le dernier mot. Ainsi, si le taux de CBD n’est pas régulé (la molécule ne présente aucun danger majeur), le <a href=\"https://weedy.fr/nl/blog/taux-de-cbd/\">taux de THC</a> ne peut quant à lui <strong>pas dépasser 0,3%</strong>.\n\nPlus précisément, seuls les plants de chanvre inscrits sur une liste officiel et dont le taux de THC (dans le plant, pas dans le produit fini) reste en dessous de 0,3% sont autorisés à la culture et à la commercialisation.\n\nUne huile de CBD full spectrum contient ainsi <strong>tout au plus des traces de THC</strong> et les revendeurs sérieux doivent vous fournir les certificats d’analyse prouvant la quantité.\n<blockquote>L’huile de CBD full spectrum n’est pas conséquent <strong>pas dangereuse</strong> et n’entraîne <strong>pas de risque connu</strong> à cause de sa très faible teneur en THC.</blockquote>\n<h2><span class=\"ez-toc-section\" id=\"Quelle_est_lhuile_de_CBD_la_plus_efficace\"></span>Quelle est l&rsquo;huile de CBD la plus efficace ?<span class=\"ez-toc-section-end\"></span></h2>\n<figure id=\"attachment_339782\" aria-describedby=\"caption-attachment-339782\" style=\"width: 900px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-full wp-image-339782\" src=\"https://weedy.fr/wp-content/uploads/2023/04/A-chaque-besoin-son-huile-CBD-min.jpg\" alt=\"À chaque besoin son huile cbd min\" width=\"900\" height=\"600\"><figcaption id=\"caption-attachment-339782\" class=\"wp-caption-text\">À chaque besoin son huile CBD</figcaption></figure>\n\nCela dépend des besoins et de l’individu, principalement parce que, selon la loi de l’effet, nous réagissons tous différemment aux cannabinoïdes.\n\nLorsque l’on commence à s’intéresser au CBD, il peut ainsi être intéressant de <strong>tester plusieurs produits</strong> afin de mieux comprendre comment notre système endocannabinoïde répond et lequel d’entre eux est le plus efficace.\n\nEn théorie et à concentration égale, une huile CBD full spectrum propose néanmoins des <strong>effets légèrement plus marqués</strong> qu’une huile CBD broad spectrum. Les deux sont, selon le même principe, <strong>plus efficaces qu’un isolat</strong> ou un dérivé à base d’isolat de CBD.\n\n<em>Vous souhaitez un dérivé de qualité ? Découvrez toutes nos </em><a href=\"https://weedy.fr/nl/product-category/huiles-cbd/\"><em>huiles CBD</em></a><em>. </em>\n<h2><span class=\"ez-toc-section\" id=\"Quand_privilegier_une_huile_CBD_broad_spectrum_ou_full_spectrum\"></span>Quand privilégier une huile CBD broad spectrum ou full spectrum ?<span class=\"ez-toc-section-end\"></span></h2>\n<figure id=\"attachment_339783\" aria-describedby=\"caption-attachment-339783\" style=\"width: 900px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-339783\" src=\"https://weedy.fr/wp-content/uploads/2023/04/Choisir-son-huile-CBD-selon-ses-besoins-min.jpg\" alt=\"choisir son huile cbd selon ses besoins min\" width=\"900\" height=\"1124\"><figcaption id=\"caption-attachment-339783\" class=\"wp-caption-text\">L’utilisation des huiles broad spectrum et full spectrum dépend des besoins</figcaption></figure>\n\nSi vous êtes à la recherche d’un produit complet, polyvalent et capable de tirer le meilleur de l’effet d’entourage, vous avez tout intérêt à <strong>privilégier les huiles CBD full spectrum et broad spectrum</strong>.\n\nCe peut notamment être le cas pour soulager des douleurs qui sont en plus source de stress ou de problèmes de sommeil. Pensez à vérifier la liste des cannabinoïdes présents dans l’huile en question, tous ont leurs spécificités. Voici les principales :\n<ul>\n \t<li><strong>CBD</strong>: antidouleur, antioxydant, décontractant musculaire.</li>\n \t<li><strong><a href=\"https://weedy.fr/nl/blog/tout-savoir-sur-le-cbg-le-cannabinoide-oublie-du-cannabis/\" data-internallinksmanager029f6b8e52c=\"11\" title=\"cbg - cannabigerol\">CBG</a></strong>: antibactérien, anti-inflammatoire, capable d’agir sur les récepteurs de la sérotonine (le « cannabinoïde des sportifs »).</li>\n \t<li><strong><a href=\"https://weedy.fr/nl/blog/cbn-un-cannabinoide-peu-connu-mais-puissant/\" data-internallinksmanager029f6b8e52c=\"9\" title=\"cbn - cannabinol\">CBN</a></strong>: anti-inflammatoire, anxiolytique, sédatif (le cannabinoïde des troubles du sommeil).</li>\n \t<li><strong>CBC</strong>: antimicrobien, antifongique, antalgique.</li>\n</ul>\t\t\t\t\t\t\t\t</div>\n\t\t\t\t</div>\n\t\t\t\t\t</div>\n\t\t</div>\n\t\t\t\t\t</div>\n\t\t</section>\n\t\t\t\t</div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Como se não bastassem as inúmeras siglas associadas ao CBD e aos derivados legais da cannabis em geral, os rótulos divertem-se dando certas indicações em inglês. O mais comum deles? “ Óleo CBD de espectro completo  » E  » Óleo CBD de amplo espectro « . Perdão? Fique tranquilo, nada muito complicado e nenhum risco em [&hellip;]</p>\n","protected":false},"author":41,"featured_media":352589,"comment_status":"open","ping_status":"closed","sticky":false,"template":"padrão\n","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","footnotes":""},"categories":[701],"tags":[],"class_list":["post-360528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultivo-de-cbd-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https://yoast.com/product/yoast-seo-premium-wordpress/ -->\n<title>Óleo CBD de espectro completo ou amplo? As diferenças. - Actualités CBD Blog - Weedy.fr</title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" />\n<link rel=\"canonical\" href=\"https://weedy.fr/blog/pt/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas/\" />\n<meta property=\"og:locale\" content=\"fr_FR\" />\n<meta property=\"og:type\" content=\"article\" />\n<meta property=\"og:title\" content=\"🌱Óleo CBD de espectro completo ou amplo? As diferenças. - Weedy.Fr🌱\" />\n<meta property=\"og:description\" content=\"Como se não bastassem as inúmeras siglas associadas ao CBD e aos derivados legais da cannabis em geral, os rótulos divertem-se dando certas indicações em inglês. O mais comum deles? “ Óleo CBD de espectro completo  » E  » Óleo CBD de amplo espectro « . Perdão? Fique tranquilo, nada muito complicado e nenhum risco em [&hellip;]\" />\n<meta property=\"og:url\" content=\"https://weedy.fr/blog/pt/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas/\" />\n<meta property=\"og:site_name\" content=\"Actualités CBD Blog - Weedy.fr\" />\n<meta property=\"article:publisher\" content=\"https://www.facebook.com/weedysocial\" />\n<meta property=\"article:author\" content=\"https://www.facebook.com/weedysocial/\" />\n<meta property=\"article:published_time\" content=\"2024-09-17T16:05:01+00:00\" />\n<meta property=\"article:modified_time\" content=\"2024-09-17T16:05:02+00:00\" />\n<meta property=\"og:image\" content=\"https://weedy.fr/blog/wp-content/uploads/2024/05/huile-cbd-full-spectrum-ou-broad-spectrum-les-differences.jpg\" />\n\t<meta property=\"og:image:width\" content=\"1792\" />\n\t<meta property=\"og:image:height\" content=\"1024\" />\n\t<meta property=\"og:image:type\" content=\"image/jpeg\" />\n<meta name=\"author\" content=\"Julien Cordobes\" />\n<meta name=\"twitter:card\" content=\"summary_large_image\" />\n<meta name=\"twitter:label1\" content=\"Écrit par\" />\n\t<meta name=\"twitter:data1\" content=\"Julien Cordobes\" />\n\t<meta name=\"twitter:label2\" content=\"Durée de lecture estimée\" />\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" />\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\/\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas\\/#article\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas\\/\"},\"author\":{\"name\":\"Julien Cordobes\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/72583fcd87d7cf46afe11d530945bc7e\"},\"headline\":\"Óleo CBD de espectro completo ou amplo? As diferenças.\",\"datePublished\":\"2024-09-17T16:05:01+00:00\",\"dateModified\":\"2024-09-17T16:05:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas\\/\"},\"wordCount\":1010,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/huile-cbd-full-spectrum-ou-broad-spectrum-les-differences.jpg\",\"articleSection\":[\"Cultivo de CBD\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\/\\/weedy.fr\\/blog\\/pt\\/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas\\/\",\"name\":\"Óleo CBD de espectro completo ou amplo? As diferenças. - Actualités CBD Blog - Weedy.fr\",\"isPartOf\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/huile-cbd-full-spectrum-ou-broad-spectrum-les-differences.jpg\",\"datePublished\":\"2024-09-17T16:05:01+00:00\",\"dateModified\":\"2024-09-17T16:05:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\/\\/weedy.fr\\/blog\\/pt\\/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas\\/#primaryimage\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/huile-cbd-full-spectrum-ou-broad-spectrum-les-differences.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/huile-cbd-full-spectrum-ou-broad-spectrum-les-differences.jpg\",\"width\":1792,\"height\":1024,\"caption\":\"Full spectrum or broad spectrum CBD oil?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/pt\\/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"CBD Blog\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cultivo de CBD\",\"item\":\"https:\\/\\/weedy.fr\\/blog\\/category\\/cultivo-de-cbd-pt\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Óleo CBD de espectro completo ou amplo? As diferenças.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#website\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"name\":\"Actualités CBD Blog - Weedy.fr\",\"description\":\"Le meilleur de l&#039;actualité du CBD et du chanvre en France\",\"publisher\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\"},\"alternateName\":\"Weedy.fr\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\/\\/weedy.fr\\/blog\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#organization\",\"name\":\"Weedy.fr\",\"alternateName\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"contentUrl\":\"https:\\/\\/weedy.fr\\/blog\\/wp-content\\/uploads\\/2024\\/05\\/logo-carre.jpg\",\"width\":582,\"height\":582,\"caption\":\"Weedy.fr\"},\"image\":{\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/logo\\/image\\/\"},\"sameAs\":[\"https:\\/\\/www.facebook.com\\/weedysocial\",\"https:\\/\\/www.instagram.com\\/weedyfrance\\/\"],\"description\":\"Leader en france sur la vente de produits à base de CBD\",\"email\":\"support@weedy.fr\",\"telephone\":\"0187651030\",\"legalName\":\"Weedy.fr\"},{\"@type\":\"Person\",\"@id\":\"https:\\/\\/weedy.fr\\/blog\\/#\\/schema\\/person\\/72583fcd87d7cf46afe11d530945bc7e\",\"name\":\"Julien Cordobes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"url\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\/\\/secure.gravatar.com\\/avatar\\/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g\",\"caption\":\"Julien Cordobes\"},\"description\":\"Rédacteur en chef spécialisé en CBD Julien, né le 17 juillet 1978 en région Parisienne, est un éminent rédacteur et expert dans le domaine des produits à base de CBD. Suite à ses études en biologie et en médecine alternative, Julien a développé une passion pour les remèdes naturels, dont le CBD. En 2022, il intègre l’équipe du site Weedy.fr en qualité d’expert et de contributeur régulier. Grâce à son expertise scientifique et une écriture claire, Julien aide à démystifier les aspects complexes du CBD, tout en mettant en lumière ses bienfaits et applications potentielles à travers ses articles et participations à des conférences.\",\"sameAs\":[\"https:\\/\\/weedy.fr\",\"https:\\/\\/www.facebook.com\\/weedysocial\\/\",\"https:\\/\\/www.instagram.com\\/weedyfrance\",\"https:\\/\\/www.pinterest.fr\\/WeedyFrance\\/\"],\"honorificPrefix\":\"Mr\",\"birthDate\":\"1978-07-17\",\"gender\":\"male\",\"knowsAbout\":[\"CBD\",\"Cannabis\",\"Copywriter\"],\"knowsLanguage\":[\"French\"],\"jobTitle\":\"Editor-in-chief specializing in CBD\",\"worksFor\":\"Weedy.fr\",\"url\":\"https:\\/\\/weedy.fr\\/blog\\/author\\/cbd_blog_owner\\/\"}]}</script>\n<!-- / Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Óleo CBD de espectro completo ou amplo? As diferenças. - Actualités CBD Blog - Weedy.fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://weedy.fr/blog/pt/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas/","og_locale":"fr_FR","og_type":"article","og_title":"🌱Óleo CBD de espectro completo ou amplo? As diferenças. - Weedy.Fr🌱","og_description":"Como se não bastassem as inúmeras siglas associadas ao CBD e aos derivados legais da cannabis em geral, os rótulos divertem-se dando certas indicações em inglês. O mais comum deles? “ Óleo CBD de espectro completo  » E  » Óleo CBD de amplo espectro « . Perdão? Fique tranquilo, nada muito complicado e nenhum risco em [&hellip;]","og_url":"https://weedy.fr/blog/pt/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas/","og_site_name":"Actualités CBD Blog - Weedy.fr","article_publisher":"https://www.facebook.com/weedysocial","article_author":"https://www.facebook.com/weedysocial/","article_published_time":"2024-09-17T16:05:01+00:00","article_modified_time":"2024-09-17T16:05:02+00:00","og_image":[{"width":1792,"height":1024,"url":"https://weedy.fr/nl/blog/wp-content/uploads/2024/05/huile-cbd-full-spectrum-ou-broad-spectrum-les-differences.jpg","type":"image/jpeg"}],"author":"Julien Cordobes","twitter_card":"summary_large_image","twitter_misc":{"Écrit par":"Julien Cordobes","Durée de lecture estimée":"5 minutes"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"Article","@id":"https://weedy.fr/blog/pt/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas/#article","isPartOf":{"@id":"https://weedy.fr/blog/pt/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas/"},"author":{"name":"Julien Cordobes","@id":"https://weedy.fr/blog/#/schema/person/72583fcd87d7cf46afe11d530945bc7e"},"headline":"Óleo CBD de espectro completo ou amplo? As diferenças.","datePublished":"2024-09-17T16:05:01+00:00","dateModified":"2024-09-17T16:05:02+00:00","mainEntityOfPage":{"@id":"https://weedy.fr/blog/pt/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas/"},"wordCount":1010,"commentCount":0,"publisher":{"@id":"https://weedy.fr/blog/#organization"},"image":{"@id":"https://weedy.fr/blog/pt/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/huile-cbd-full-spectrum-ou-broad-spectrum-les-differences.jpg","articleSection":["Cultivo de CBD"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https://weedy.fr/blog/pt/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas/#respond"]}]},{"@type":"WebPage","@id":"https://weedy.fr/blog/pt/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas/","url":"https://weedy.fr/nl/blog/pt/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas/","name":"Óleo CBD de espectro completo ou amplo? As diferenças. - Actualités CBD Blog - Weedy.fr","isPartOf":{"@id":"https://weedy.fr/blog/#website"},"primaryImageOfPage":{"@id":"https://weedy.fr/blog/pt/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas/#primaryimage"},"image":{"@id":"https://weedy.fr/blog/pt/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas/#primaryimage"},"thumbnailUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/huile-cbd-full-spectrum-ou-broad-spectrum-les-differences.jpg","datePublished":"2024-09-17T16:05:01+00:00","dateModified":"2024-09-17T16:05:02+00:00","breadcrumb":{"@id":"https://weedy.fr/blog/pt/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https://weedy.fr/blog/pt/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/pt/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas/#primaryimage","url":"https://weedy.fr/nl/blog/wp-content/uploads/2024/05/huile-cbd-full-spectrum-ou-broad-spectrum-les-differences.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/huile-cbd-full-spectrum-ou-broad-spectrum-les-differences.jpg","width":1792,"height":1024,"caption":"Full spectrum or broad spectrum CBD oil?"},{"@type":"BreadcrumbList","@id":"https://weedy.fr/blog/pt/oleo-cbd-de-espectro-completo-ou-amplo-as-diferencas/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"CBD Blog","item":"https://weedy.fr/blog/"},{"@type":"ListItem","position":2,"name":"Cultivo de CBD","item":"https://weedy.fr/blog/category/cultivo-de-cbd-pt/"},{"@type":"ListItem","position":3,"name":"Óleo CBD de espectro completo ou amplo? As diferenças."}]},{"@type":"WebSite","@id":"https://weedy.fr/blog/#website","url":"https://weedy.fr/nl/blog/","name":"Actualités CBD Blog - Weedy.fr","description":"Le meilleur de l&#039;actualité du CBD et du chanvre en France","publisher":{"@id":"https://weedy.fr/blog/#organization"},"alternateName":"Weedy.fr","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://weedy.fr/blog/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https://weedy.fr/blog/#organization","name":"Weedy.fr","alternateName":"Weedy.fr","url":"https://weedy.fr/nl/blog/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://weedy.fr/blog/#/schema/logo/image/","url":"https://weedy.fr/nl/blog/wp-content/uploads/2024/05/logo-carre.jpg","contentUrl":"https://weedy.fr/blog/wp-content/uploads/2024/05/logo-carre.jpg","width":582,"height":582,"caption":"Weedy.fr"},"image":{"@id":"https://weedy.fr/blog/#/schema/logo/image/"},"sameAs":["https://www.facebook.com/weedysocial","https://www.instagram.com/weedyfrance/"],"description":"Leader en france sur la vente de produits à base de CBD","email":"support@weedy.fr","telephone":"0187651030","legalName":"Weedy.fr"},{"@type":"Person","@id":"https://weedy.fr/blog/#/schema/person/72583fcd87d7cf46afe11d530945bc7e","name":"Julien Cordobes","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","url":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/39c7124515a22e18b96324fe7087f17d145ba095086413a586717853860bd09b?s=96&d=mm&r=g","caption":"Julien Cordobes"},"description":"Rédacteur en chef spécialisé en CBD Julien, né le 17 juillet 1978 en région Parisienne, est un éminent rédacteur et expert dans le domaine des produits à base de CBD. Suite à ses études en biologie et en médecine alternative, Julien a développé une passion pour les remèdes naturels, dont le CBD. En 2022, il intègre l’équipe du site Weedy.fr en qualité d’expert et de contributeur régulier. Grâce à son expertise scientifique et une écriture claire, Julien aide à démystifier les aspects complexes du CBD, tout en mettant en lumière ses bienfaits et applications potentielles à travers ses articles et participations à des conférences.","sameAs":["https://weedy.fr","https://www.facebook.com/weedysocial/","https://www.instagram.com/weedyfrance","https://www.pinterest.fr/WeedyFrance/"],"honorificPrefix":"Mr","birthDate":"1978-07-17","gender":"male","knowsAbout":["CBD","Cannabis","Copywriter"],"knowsLanguage":["French"],"jobTitle":"Editor-in-chief specializing in CBD","worksFor":"Weedy.fr","url":"https://weedy.fr/nl/blog/author/cbd_blog_owner/"}]}},"_links":{"self":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/360528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/posts"}],"about":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/users/41"}],"replies":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/comments?post=360528"}],"version-history":[{"count":1,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/360528/revisions"}],"predecessor-version":[{"id":360529,"href":"https://weedy.fr/blog/wp-json/wp/v2/posts/360528/revisions/360529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/media/352589"}],"wp:attachment":[{"href":"https://weedy.fr/blog/wp-json/wp/v2/media?parent=360528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/categories?post=360528"},{"taxonomy":"post_tag","embeddable":true,"href":"https://weedy.fr/blog/wp-json/wp/v2/tags?post=360528"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}